{"id":975345,"date":"2018-04-09T03:29:05","date_gmt":"2018-04-09T03:29:05","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=975345"},"modified":"2018-04-09T03:29:05","modified_gmt":"2018-04-09T03:29:05","slug":"viktor-orban-gana-las-elecciones-en-hungria","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/","title":{"rendered":"Viktor Orban gana las elecciones en Hungr\u00eda"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-583110\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2014\/08\/6560500w-336x320.jpg\" alt=\"\" width=\"336\" height=\"320\" \/>Budapest, 8 abr (dpa) &#8211; El conservador jefe de Gobierno Viktor Orban gan\u00f3 las elecciones parlamentarias en Hungr\u00eda con el 49,2 por ciento de los votos, inform\u00f3 hoy a oficina electoral en Budapest tras el recuento del 85 por ciento de los sufragios.<\/p>\n<p>Los analistas electorales estiman que su partido Fidesz obtendr\u00e1 hasta 134 de los 199 esca\u00f1os del Parlamento. De esta forma, Orban, un pol\u00edtico derechista, nacionalista y eur\u00f3fobo podr\u00eda volver a asegurarse una mayor\u00eda de dos tercios, con la que se puede cambiar la Constituci\u00f3n, para su cuarto mandato, el tercero consecutivo en su carrera pol\u00edtica.<\/p>\n<p>Hace cuatro a\u00f1os, Fidesz obtuvo 133 esca\u00f1os con el 43 por ciento de los votos.<\/p>\n<p>\u00abGanamos\u00bb, dijo Orban a sus seguidores poco despu\u00e9s de que se conocieran los resultados. \u00abQueridos amigos, tenemos una gran batalla detr\u00e1s nuestro, nos hemos asegurado una victoria hist\u00f3rica&#8230;tuvimos una oportunidad, creamos una oportunidad para poder proteger a Hungr\u00eda\u00bb, se\u00f1al\u00f3 y a\u00f1adi\u00f3: \u00abLa alta participaci\u00f3n deja cualquier duda en suspenso\u00bb.<\/p>\n<p>El partido radical de derecha Jobbik (\u00abLos mejores\u00bb) se convirti\u00f3 en la principal oposici\u00f3n con el 19,9 por ciento de los votos (26 esca\u00f1os), seguido del Partido Socialista H\u00fangaro (MSZP) con el 12 por ciento (20).<\/p>\n<p>Los votos de unos 270.000 electores que no votaron en su residencia habitual se recontar\u00e1n reci\u00e9n la semana que viene.<\/p>\n<p>La difusi\u00f3n de los primeros resultados parciales se retras\u00f3 varias horas por demoras en dos locales electorales de Budapest. La participaci\u00f3n fue, con alrededor del 70 por ciento de los votantes, inusualmente alta.<\/p>\n<p>Orban, fuerte detractor de la entrada de migrantes y el m\u00e1s duro cr\u00edtico de la pol\u00edtica migratoria de la Uni\u00f3n Europea (UE), habla continuamente del tema migratorio, acusando con frecuencia al multimillonario estadounidense de origen h\u00fangaro George Soros.<\/p>\n<p>El primer ministro acusa a Soros, un superviviente del Holocausto, de mover los hilos de la UE y dirigir una masa migratoria de musulmanes a Europa. El objetivo de Soros ser\u00eda robar al pueblo del Viejo Continente su \u00abidentidad nacional y cristiana\u00bb, asegura el pol\u00edtico.<\/p>\n<p>El primer ministro ha convertido su teor\u00eda conspiratoria en un mantra en todo el pa\u00eds, que sirve tambi\u00e9n como medio para difamar a las organizaciones civiles cr\u00edticas con el Gobierno, algunas de las cuales son apoyadas por Soros, un millonario de 87 a\u00f1os que aboga por la democracia y los derechos humanos en el mundo.<\/p>\n<p>La oposici\u00f3n acusa a Orban de desmantelar la democracia y de derivar recursos estatales y fondos europeos hacia oligarcas que le son afines. La Oficina Europea de Lucha contra el Fraude (Olaf) est\u00e1 investigando numerosos casos de supuestas malversaciones en Hungr\u00eda, en uno de los cuales estar\u00eda implicado el yerno de Orban.<\/p>\n<p>El primer ministro rechaza todas las acusaciones y se adjudica como logros de gesti\u00f3n el notable aumento de los salarios reales y el descenso del desempleo.<\/p>\n<p>El derecho electoral h\u00fangaro favorece al partido m\u00e1s fuerte, que en este caso es el Fidesz: 106 de los 199 esca\u00f1os en juego se entregan en distritos electorales \u00fanicos, donde basta ser el partido m\u00e1s votado para llevarse el mandato directo.<\/p>\n<p>En la UE se parte de la base de que un nuevo Gobierno de Orban generar\u00e1 m\u00e1s conflictos entre Budapest y Bruselas, sobre todo por el tema migratorio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Budapest, 8 abr (dpa) &#8211; El conservador jefe de Gobierno Viktor Orban gan\u00f3 las elecciones parlamentarias en Hungr\u00eda con el 49,2 por ciento de los votos, inform\u00f3 hoy a oficina electoral en Budapest tras el recuento del 85 por ciento de los sufragios. Los analistas electorales estiman que su partido Fidesz obtendr\u00e1 hasta 134 de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":583110,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-975345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Budapest, 8 abr (dpa) - El conservador jefe de Gobierno Viktor Orban gan\u00f3 las elecciones parlamentarias en Hungr\u00eda con el 49,2 por ciento de los votos, inform\u00f3 hoy a oficina electoral en Budapest tras el recuento del 85 por ciento de los sufragios. Los analistas electorales estiman que su partido Fidesz obtendr\u00e1 hasta 134 de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Viktor Orban gana las elecciones en Hungr\u00eda - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Budapest, 8 abr (dpa) - El conservador jefe de Gobierno Viktor Orban gan\u00f3 las elecciones parlamentarias en Hungr\u00eda con el 49,2 por ciento de los votos, inform\u00f3 hoy a oficina electoral en Budapest tras el recuento del 85 por ciento de los sufragios. Los analistas electorales estiman que su partido Fidesz obtendr\u00e1 hasta 134 de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"actualidad\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-04-09T03:29:05+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-04-09T03:29:05+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Viktor Orban gana las elecciones en Hungr\u00eda - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Budapest, 8 abr (dpa) - El conservador jefe de Gobierno Viktor Orban gan\u00f3 las elecciones parlamentarias en Hungr\u00eda con el 49,2 por ciento de los votos, inform\u00f3 hoy a oficina electoral en Budapest tras el recuento del 85 por ciento de los sufragios. Los analistas electorales estiman que su partido Fidesz obtendr\u00e1 hasta 134 de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/viktor-orban-gana-las-elecciones-en-hungria\\\/#blogposting\",\"name\":\"Viktor Orban gana las elecciones en Hungr\\u00eda - El Digital de Asturias\",\"headline\":\"Viktor Orban gana las elecciones en Hungr\\u00eda\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":583110},\"datePublished\":\"2018-04-09T03:29:05+02:00\",\"dateModified\":\"2018-04-09T03:29:05+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/viktor-orban-gana-las-elecciones-en-hungria\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/viktor-orban-gana-las-elecciones-en-hungria\\\/#webpage\"},\"articleSection\":\"Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/viktor-orban-gana-las-elecciones-en-hungria\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/viktor-orban-gana-las-elecciones-en-hungria\\\/#listItem\",\"name\":\"Viktor Orban gana las elecciones en Hungr\\u00eda\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/viktor-orban-gana-las-elecciones-en-hungria\\\/#listItem\",\"position\":3,\"name\":\"Viktor Orban gana las elecciones en Hungr\\u00eda\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/viktor-orban-gana-las-elecciones-en-hungria\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/viktor-orban-gana-las-elecciones-en-hungria\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/viktor-orban-gana-las-elecciones-en-hungria\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/viktor-orban-gana-las-elecciones-en-hungria\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/viktor-orban-gana-las-elecciones-en-hungria\\\/\",\"name\":\"Viktor Orban gana las elecciones en Hungr\\u00eda - El Digital de Asturias\",\"description\":\"Budapest, 8 abr (dpa) - El conservador jefe de Gobierno Viktor Orban gan\\u00f3 las elecciones parlamentarias en Hungr\\u00eda con el 49,2 por ciento de los votos, inform\\u00f3 hoy a oficina electoral en Budapest tras el recuento del 85 por ciento de los sufragios. Los analistas electorales estiman que su partido Fidesz obtendr\\u00e1 hasta 134 de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/viktor-orban-gana-las-elecciones-en-hungria\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":583110,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/viktor-orban-gana-las-elecciones-en-hungria\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/viktor-orban-gana-las-elecciones-en-hungria\\\/#mainImage\"},\"datePublished\":\"2018-04-09T03:29:05+02:00\",\"dateModified\":\"2018-04-09T03:29:05+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Viktor Orban gana las elecciones en Hungr\u00eda - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Viktor Orban gana las elecciones en Hungr\u00eda - El Digital de Asturias","description":"Budapest, 8 abr (dpa) - El conservador jefe de Gobierno Viktor Orban gan\u00f3 las elecciones parlamentarias en Hungr\u00eda con el 49,2 por ciento de los votos, inform\u00f3 hoy a oficina electoral en Budapest tras el recuento del 85 por ciento de los sufragios. Los analistas electorales estiman que su partido Fidesz obtendr\u00e1 hasta 134 de","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/#blogposting","name":"Viktor Orban gana las elecciones en Hungr\u00eda - El Digital de Asturias","headline":"Viktor Orban gana las elecciones en Hungr\u00eda","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":583110},"datePublished":"2018-04-09T03:29:05+02:00","dateModified":"2018-04-09T03:29:05+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/#webpage"},"articleSection":"Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/#listItem","name":"Viktor Orban gana las elecciones en Hungr\u00eda"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/#listItem","position":3,"name":"Viktor Orban gana las elecciones en Hungr\u00eda","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/","name":"Viktor Orban gana las elecciones en Hungr\u00eda - El Digital de Asturias","description":"Budapest, 8 abr (dpa) - El conservador jefe de Gobierno Viktor Orban gan\u00f3 las elecciones parlamentarias en Hungr\u00eda con el 49,2 por ciento de los votos, inform\u00f3 hoy a oficina electoral en Budapest tras el recuento del 85 por ciento de los sufragios. Los analistas electorales estiman que su partido Fidesz obtendr\u00e1 hasta 134 de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":583110,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/#mainImage"},"datePublished":"2018-04-09T03:29:05+02:00","dateModified":"2018-04-09T03:29:05+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Viktor Orban gana las elecciones en Hungr\u00eda - El Digital de Asturias","og:description":"Budapest, 8 abr (dpa) - El conservador jefe de Gobierno Viktor Orban gan\u00f3 las elecciones parlamentarias en Hungr\u00eda con el 49,2 por ciento de los votos, inform\u00f3 hoy a oficina electoral en Budapest tras el recuento del 85 por ciento de los sufragios. Los analistas electorales estiman que su partido Fidesz obtendr\u00e1 hasta 134 de","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/","article:tag":["actualidad"],"article:published_time":"2018-04-09T03:29:05+00:00","article:modified_time":"2018-04-09T03:29:05+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Viktor Orban gana las elecciones en Hungr\u00eda - El Digital de Asturias","twitter:description":"Budapest, 8 abr (dpa) - El conservador jefe de Gobierno Viktor Orban gan\u00f3 las elecciones parlamentarias en Hungr\u00eda con el 49,2 por ciento de los votos, inform\u00f3 hoy a oficina electoral en Budapest tras el recuento del 85 por ciento de los sufragios. Los analistas electorales estiman que su partido Fidesz obtendr\u00e1 hasta 134 de","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"975345","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-10-07 23:34:04","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 12:11:38","updated":"2025-10-07 23:34:04","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/\" title=\"Viktor Orban gana las elecciones en Hungr\u00eda\">Viktor Orban gana las elecciones en Hungr\u00eda<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Actualidad","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/"},{"label":"Viktor Orban gana las elecciones en Hungr\u00eda","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/viktor-orban-gana-las-elecciones-en-hungria\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/975345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=975345"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/975345\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=975345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=975345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=975345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}