{"id":962222,"date":"2017-12-03T18:04:30","date_gmt":"2017-12-03T18:04:30","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=962222"},"modified":"2017-12-03T18:04:30","modified_gmt":"2017-12-03T18:04:30","slug":"desventajas-que-pueden-tener-los-depositos-bancarios","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/","title":{"rendered":"Desventajas que pueden tener los dep\u00f3sitos bancarios"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-962223\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2017\/12\/depositos-bancarios-360x240.jpg\" alt=\"\" width=\"360\" height=\"240\" \/>Habitualmente, han sido santo de la devoci\u00f3n de la mayor parte de ahorradores de nuestro pa\u00eds. Desgraciadamente, los continuos recortes en los tipos de inter\u00e9s, as\u00ed como el recrudecimiento de las condiciones interpuestas por los bancos no han hecho sino mermar el atractivo de este producto financiero que anta\u00f1o disfrut\u00f3 de una \u00e9poca gloriosa.<\/p>\n<p>No nos malinterpretes. <strong>A\u00fan es posible encontrar y <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/www.busconomico.com\/depositos\/mejores-depositos.aspx\" target=\"_blank\" rel=\"noopener\">contratar dep\u00f3sitos bancarios<\/a> <\/span>cuyas caracter\u00edsticas resulten atractivas<\/strong>. Sin embargo, buena parte de la oferta del mercado es tan s\u00f3lo una sombra de lo que era.<\/p>\n<p>Nuestro consejo es que tengas en cuenta todas las desventajas de los dep\u00f3sitos bancarios antes de proceder a su contrataci\u00f3n. Es posible que prefieras optar por otra soluci\u00f3n m\u00e1s beneficiosa.<\/p>\n<p><strong>Escasa rentabilidad debida a las limitaciones del BCE<\/strong><\/p>\n<p>La pol\u00edtica del Banco Central Europeo desde hace ya varios a\u00f1os ha sido la de reducir los tipos de inter\u00e9s del dinero a l\u00edmites irrisorios. Por su parte, el Banco de Espa\u00f1a ha establecido prerrogativas semejantes, cuyo incumplimiento puede suponer sanciones para las entidades bancarias.<\/p>\n<p>El resultado es, cuanto menos, rid\u00edculo. En la fecha de redacci\u00f3n de este art\u00edculo, <strong>el Euribor se sit\u00faa en el -0,188%<\/strong>, o lo que es lo mismo, en terreno negativo.<\/p>\n<p>Dadas las circunstancias, <strong>los bancos han ido bajando m\u00e1s y m\u00e1s los tipos de inter\u00e9s<\/strong> a los que remuneran las imposiciones a plazo fijo hasta dejarlas en cifras insignificantes.<\/p>\n<p>Tradicionalmente, los dep\u00f3sitos se utilizaban como un mecanismo de ahorro para reducir la merma econ\u00f3mica ocasionada por la inflaci\u00f3n. En los tiempos que corren, combatir la subida del coste de la vida mediante la contrataci\u00f3n de dep\u00f3sitos se ha vuelto una tarea bastante complicada.<\/p>\n<p><strong>Renuncia a la liquidez durante el plazo del dep\u00f3sito<\/strong><\/p>\n<p>El gran inconveniente de los dep\u00f3sitos siempre ha sido el hecho de que es necesario renunciar a una suma de dinero durante determinado tiempo.<\/p>\n<p>Eso significa que, si a lo largo del plazo de duraci\u00f3n del dep\u00f3sito, surgiera una oportunidad de obtener un mayor rendimiento de tu capital, no te ser\u00eda posible hacerlo, debido a que \u00e9ste permanecer\u00eda <strong>inmovilizado hasta el vencimiento del contrato<\/strong>.<\/p>\n<p>Por supuesto, existe la posibilidad de cancelar anticipadamente el dep\u00f3sito, pero habr\u00eda que hacer frente a las comisiones de penalizaci\u00f3n de las que hablaremos en seguida.<\/p>\n<p>\u00a1Pero eso no es lo peor!<\/p>\n<p><strong>Determinados dep\u00f3sitos ni siquiera permiten la cancelaci\u00f3n anticipada<\/strong>. Se trata de una condici\u00f3n contractual cuanto menos cuestionable, que no hace sino empeorar a\u00fan m\u00e1s el poco atractivo actual de las imposiciones a plazo.<\/p>\n<p><strong>Penalizaci\u00f3n por cancelaci\u00f3n anticipada<\/strong><\/p>\n<p>Tal y como indic\u00e1bamos hace un momento, la cancelaci\u00f3n del dep\u00f3sito antes del plazo acordado acarrea la imposici\u00f3n de una penalizaci\u00f3n por parte del banco emisor.<\/p>\n<p>En el pasado, era posible encontrar dep\u00f3sitos con distintos tipos de penalizaciones, m\u00e1s o menos proporcionales; es decir, o bien se reduc\u00eda el tipo de inter\u00e9s o bien se reduc\u00eda parte de los intereses generados. El objetivo no era otro que intentar ajustar el beneficio obtenido al plazo durante el cual se ha mantenido el dinero en el dep\u00f3sito.<\/p>\n<p>En la actualidad, sin embargo, <strong>la gran mayor\u00eda de las entidades bancarias optan por el criterio de eliminar la totalidad de los intereses generados<\/strong> hasta el momento de la cancelaci\u00f3n anticipada. \u00c9ste es el l\u00edmite m\u00e1ximo permitido por el Banco de Espa\u00f1a. Es m\u00e1s, algunas entidades ni siquiera indican en sus contratos la penalizaci\u00f3n espec\u00edfica que se aplicar\u00e1 en caso de cancelaci\u00f3n anticipada. En su lugar, se limitan a indicar que \u00e9sta no superar\u00e1 los intereses generados.<\/p>\n<p>Esta pr\u00e1ctica cada vez m\u00e1s frecuente es totalmente inadmisible, dado que deja en una situaci\u00f3n muy vulnerable al cliente. No obstante, no parecer que las autoridades reguladoras est\u00e9n por la labor de controlarlo de forma m\u00e1s en\u00e9rgica.<\/p>\n<p><strong>Tributaci\u00f3n menos favorable que productos de inversi\u00f3n<\/strong><\/p>\n<p>La tributaci\u00f3n de los dep\u00f3sitos es bastante sencilla. Sencillamente, <strong>se aplica una retenci\u00f3n y se tributa como rendimiento del capital sobre la base del ahorro<\/strong> al tipo establecido en cada ejercicio. Hasta ah\u00ed, no hay nada que objetar.<\/p>\n<p>La cuesti\u00f3n es que existen otros productos \u2013tanto de ahorro, como de inversi\u00f3n- cuya rentabilidad es considerablemente m\u00e1s favorable que la de los dep\u00f3sitos.<\/p>\n<p>Un ejemplo de ello son los planes de pensiones, los cuales permiten obtener beneficios fiscales muy interesantes, como desgravaciones en el IRPF, o el hecho de diferir la tributaci\u00f3n. Precisamente, esto \u00faltimo es lo que permiten tambi\u00e9n los fondos de inversi\u00f3n, por ejemplo.<\/p>\n<p><strong>Limitaciones del capital a aportar<\/strong><\/p>\n<p>Tampoco debemos olvidar que la mayor\u00eda de los dep\u00f3sitos establecen l\u00edmites m\u00e1ximos y m\u00ednimos respecto al capital que se puede imponer a plazo.<\/p>\n<p>Los dep\u00f3sitos promocionales que ofrecen elevados tipos de inter\u00e9s suelen imponer l\u00edmites m\u00e1ximos relativamente reducidos, por lo que el margen de beneficio que se puede obtener en t\u00e9rminos absolutos es reducido.<\/p>\n<p>Fuera del \u00e1mbito de las promociones y campa\u00f1as de captaci\u00f3n, <strong>los \u00fanicos dep\u00f3sitos que ofrecen una alta remuneraci\u00f3n son aquellos destinados a grandes cuentas<\/strong>; o lo que es lo mismo, es necesario disponer de enormes sumas de dinero para proceder a su contrataci\u00f3n.<\/p>\n<p><strong>Renovaci\u00f3n autom\u00e1tica al tipo de inter\u00e9s vigente<\/strong><\/p>\n<p>Finalmente, no debemos olvidar que muchos dep\u00f3sitos se renuevan de forma autom\u00e1tica al tipo de inter\u00e9s que est\u00e9 vigente en el momento de la renovaci\u00f3n.<\/p>\n<p>Teniendo en cuenta que los tipos de inter\u00e9s no han hecho otra cosa que bajar a lo largo de estos \u00faltimos a\u00f1os, m\u00e1s vale estar pendiente de la fecha de vencimiento del dep\u00f3sito contratado. Si se detecta una alternativa m\u00e1s favorable, entonces m\u00e1s vale solicitar que no se proceda a la renovaci\u00f3n autom\u00e1tica y recuperar el capital tan pronto como llegue la fecha de vencimiento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Habitualmente, han sido santo de la devoci\u00f3n de la mayor parte de ahorradores de nuestro pa\u00eds. Desgraciadamente, los continuos recortes en los tipos de inter\u00e9s, as\u00ed como el recrudecimiento de las condiciones interpuestas por los bancos no han hecho sino mermar el atractivo de este producto financiero que anta\u00f1o disfrut\u00f3 de una \u00e9poca gloriosa. No [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":962223,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[187],"tags":[],"class_list":["post-962222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Habitualmente, han sido santo de la devoci\u00f3n de la mayor parte de ahorradores de nuestro pa\u00eds. Desgraciadamente, los continuos recortes en los tipos de inter\u00e9s, as\u00ed como el recrudecimiento de las condiciones interpuestas por los bancos no han hecho sino mermar el atractivo de este producto financiero que anta\u00f1o disfrut\u00f3 de una \u00e9poca gloriosa. No\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"econom\u00eda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Desventajas que pueden tener los dep\u00f3sitos bancarios - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Habitualmente, han sido santo de la devoci\u00f3n de la mayor parte de ahorradores de nuestro pa\u00eds. Desgraciadamente, los continuos recortes en los tipos de inter\u00e9s, as\u00ed como el recrudecimiento de las condiciones interpuestas por los bancos no han hecho sino mermar el atractivo de este producto financiero que anta\u00f1o disfrut\u00f3 de una \u00e9poca gloriosa. No\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"econom\u00eda\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-12-03T18:04:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-12-03T18:04:30+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Desventajas que pueden tener los dep\u00f3sitos bancarios - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Habitualmente, han sido santo de la devoci\u00f3n de la mayor parte de ahorradores de nuestro pa\u00eds. Desgraciadamente, los continuos recortes en los tipos de inter\u00e9s, as\u00ed como el recrudecimiento de las condiciones interpuestas por los bancos no han hecho sino mermar el atractivo de este producto financiero que anta\u00f1o disfrut\u00f3 de una \u00e9poca gloriosa. No\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/desventajas-que-pueden-tener-los-depositos-bancarios\\\/#blogposting\",\"name\":\"Desventajas que pueden tener los dep\\u00f3sitos bancarios - El Digital de Asturias\",\"headline\":\"Desventajas que pueden tener los dep\\u00f3sitos bancarios\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":962223},\"datePublished\":\"2017-12-03T18:04:30+01:00\",\"dateModified\":\"2017-12-03T18:04:30+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/desventajas-que-pueden-tener-los-depositos-bancarios\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/desventajas-que-pueden-tener-los-depositos-bancarios\\\/#webpage\"},\"articleSection\":\"Econom\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/desventajas-que-pueden-tener-los-depositos-bancarios\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"name\":\"Econom\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"position\":2,\"name\":\"Econom\\u00eda\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/desventajas-que-pueden-tener-los-depositos-bancarios\\\/#listItem\",\"name\":\"Desventajas que pueden tener los dep\\u00f3sitos bancarios\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/desventajas-que-pueden-tener-los-depositos-bancarios\\\/#listItem\",\"position\":3,\"name\":\"Desventajas que pueden tener los dep\\u00f3sitos bancarios\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"name\":\"Econom\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/desventajas-que-pueden-tener-los-depositos-bancarios\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/desventajas-que-pueden-tener-los-depositos-bancarios\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/desventajas-que-pueden-tener-los-depositos-bancarios\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/desventajas-que-pueden-tener-los-depositos-bancarios\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/desventajas-que-pueden-tener-los-depositos-bancarios\\\/\",\"name\":\"Desventajas que pueden tener los dep\\u00f3sitos bancarios - El Digital de Asturias\",\"description\":\"Habitualmente, han sido santo de la devoci\\u00f3n de la mayor parte de ahorradores de nuestro pa\\u00eds. Desgraciadamente, los continuos recortes en los tipos de inter\\u00e9s, as\\u00ed como el recrudecimiento de las condiciones interpuestas por los bancos no han hecho sino mermar el atractivo de este producto financiero que anta\\u00f1o disfrut\\u00f3 de una \\u00e9poca gloriosa. No\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/desventajas-que-pueden-tener-los-depositos-bancarios\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":962223,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/desventajas-que-pueden-tener-los-depositos-bancarios\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/desventajas-que-pueden-tener-los-depositos-bancarios\\\/#mainImage\"},\"datePublished\":\"2017-12-03T18:04:30+01:00\",\"dateModified\":\"2017-12-03T18:04:30+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Desventajas que pueden tener los dep\u00f3sitos bancarios - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Desventajas que pueden tener los dep\u00f3sitos bancarios - El Digital de Asturias","description":"Habitualmente, han sido santo de la devoci\u00f3n de la mayor parte de ahorradores de nuestro pa\u00eds. Desgraciadamente, los continuos recortes en los tipos de inter\u00e9s, as\u00ed como el recrudecimiento de las condiciones interpuestas por los bancos no han hecho sino mermar el atractivo de este producto financiero que anta\u00f1o disfrut\u00f3 de una \u00e9poca gloriosa. No","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/","robots":"max-image-preview:large","keywords":"econom\u00eda","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/#blogposting","name":"Desventajas que pueden tener los dep\u00f3sitos bancarios - El Digital de Asturias","headline":"Desventajas que pueden tener los dep\u00f3sitos bancarios","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":962223},"datePublished":"2017-12-03T18:04:30+01:00","dateModified":"2017-12-03T18:04:30+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/#webpage"},"articleSection":"Econom\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","name":"Econom\u00eda"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","position":2,"name":"Econom\u00eda","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/#listItem","name":"Desventajas que pueden tener los dep\u00f3sitos bancarios"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/#listItem","position":3,"name":"Desventajas que pueden tener los dep\u00f3sitos bancarios","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","name":"Econom\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/","name":"Desventajas que pueden tener los dep\u00f3sitos bancarios - El Digital de Asturias","description":"Habitualmente, han sido santo de la devoci\u00f3n de la mayor parte de ahorradores de nuestro pa\u00eds. Desgraciadamente, los continuos recortes en los tipos de inter\u00e9s, as\u00ed como el recrudecimiento de las condiciones interpuestas por los bancos no han hecho sino mermar el atractivo de este producto financiero que anta\u00f1o disfrut\u00f3 de una \u00e9poca gloriosa. No","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":962223,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/#mainImage"},"datePublished":"2017-12-03T18:04:30+01:00","dateModified":"2017-12-03T18:04:30+01:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Desventajas que pueden tener los dep\u00f3sitos bancarios - El Digital de Asturias","og:description":"Habitualmente, han sido santo de la devoci\u00f3n de la mayor parte de ahorradores de nuestro pa\u00eds. Desgraciadamente, los continuos recortes en los tipos de inter\u00e9s, as\u00ed como el recrudecimiento de las condiciones interpuestas por los bancos no han hecho sino mermar el atractivo de este producto financiero que anta\u00f1o disfrut\u00f3 de una \u00e9poca gloriosa. No","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/","article:tag":["econom\u00eda"],"article:published_time":"2017-12-03T18:04:30+00:00","article:modified_time":"2017-12-03T18:04:30+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Desventajas que pueden tener los dep\u00f3sitos bancarios - El Digital de Asturias","twitter:description":"Habitualmente, han sido santo de la devoci\u00f3n de la mayor parte de ahorradores de nuestro pa\u00eds. Desgraciadamente, los continuos recortes en los tipos de inter\u00e9s, as\u00ed como el recrudecimiento de las condiciones interpuestas por los bancos no han hecho sino mermar el atractivo de este producto financiero que anta\u00f1o disfrut\u00f3 de una \u00e9poca gloriosa. No","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"5 minutos"},"aioseo_meta_data":{"post_id":"962222","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-12-07 11:41:17","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 12:46:39","updated":"2025-12-07 11:41:17","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/\" title=\"Econom\u00eda\">Econom\u00eda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/\" title=\"Desventajas que pueden tener los dep\u00f3sitos bancarios\">Desventajas que pueden tener los dep\u00f3sitos bancarios<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Econom\u00eda","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/"},{"label":"Desventajas que pueden tener los dep\u00f3sitos bancarios","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/desventajas-que-pueden-tener-los-depositos-bancarios\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/962222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=962222"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/962222\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=962222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=962222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=962222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}