{"id":958548,"date":"2017-11-03T17:43:25","date_gmt":"2017-11-03T17:43:25","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=958548"},"modified":"2017-11-03T17:43:25","modified_gmt":"2017-11-03T17:43:25","slug":"la-seguridad-social-cuenta-con-18-430-529-afiliados","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/","title":{"rendered":"La Seguridad Social cuenta con 18.430.529 afiliados"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-958549\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2017\/11\/040917trabajador-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" \/>La afiliaci\u00f3n media a la Seguridad Social alcanza 18.430.529 ocupados en octubre, tras registrar el mayor incremento interanual de la serie hist\u00f3rica en ese mes, a excepci\u00f3n de 2005 (a\u00f1o condicionado por la regularizaci\u00f3n extraordinaria de inmigrantes) con 617.173 afiliados m\u00e1s respecto a 2016.<\/p>\n<p>\u200bEl mes de octubre, la Seguridad Social sum\u00f3 94.368 ocupados, el ascenso m\u00e1s alto de los \u00faltimos doce a\u00f1os en ese mes junto al de 2016.<\/p>\n<p>Para el secretario de Estado de la seguridad Social, Tomas Burgos: \u00abEste resultado positivo es consecuencia de la buena evoluci\u00f3n del R\u00e9gimen General -sin agrario y hogar- que aumenta en 89.515 personas (0,64%). Se trata del mejor resultado de la serie hist\u00f3rica y es una expresi\u00f3n clara del buen comportamiento del coraz\u00f3n del Sistema\u00bb.<\/p>\n<p>Destaca de nuevo el n\u00famero de mujeres afiliadas a la Seguridad Social que vuelve a marcar un r\u00e9cord y totaliza 8.533.274 trabajadoras. Representan el 46,30% del total de ocupados.<\/p>\n<blockquote><p><strong><em>Hay que se\u00f1alar que en estos diez meses se han creado 581.475 empleos, un 15,1% m\u00e1s que en 2016.<\/em><\/strong><\/p><\/blockquote>\n<p>El dato desestacionalizado, que sirve para hacer un seguimiento de la tendencia de fondo que subyace en la evoluci\u00f3n del n\u00famero de afiliados, crece en el mes en 101.479 ocupados, el mayor aumento registrado en lo que va de a\u00f1o. Este dato junto al registrado el pasado a\u00f1o son los mejores de toda la serie hist\u00f3rica de los meses de octubre, que arranca en 2001.<\/p>\n<p><strong>Respecto a septiembre<\/strong><\/p>\n<p>El R\u00e9gimen General registr\u00f3 un ascenso de 94.979 personas (0,63%), hasta situarse en 15.144.839 ocupados. En octubre, la afiliaci\u00f3n creci\u00f3 en t\u00e9rminos absolutos principalmente en Educaci\u00f3n (137.152), Administraci\u00f3n P\u00fablica y Defensa; S. Social obligatoria (26.711), Construcci\u00f3n (17.779), Actividades Art\u00edsticas, Recreativas y Entretenimiento (13.901) y en menor medida en Industria Manufacturera (6.137). Disminuy\u00f3 especialmente en Hosteler\u00eda (-60.030), Actividades Sanitarias y Servicios Sociales (-33.888) y Actividades Administrativas y Servicios Auxiliares (-16.088).<\/p>\n<p>En cuanto al Sistema Especial Agrario, incorpor\u00f3 4.834 afiliados medios m\u00e1s (0,64%), hasta situarse ahora en 755.833 personas. Por su parte, el Sistema Especial del Empleados del Hogar gan\u00f3 630 (0,15%) y ahora alcanza los 420.067 ocupados.<\/p>\n<p>El R\u00e9gimen de Aut\u00f3nomos cuenta con 3.217.902 personas, tras crecer en 1.630 (0,05%) en el \u00faltimo mes. Respecto al R\u00e9gimen Especial del Mar, desciende en 2.195 ocupados (-3,25%) hasta situarse en 65.309 ocupados. Finalmente, el Carb\u00f3n est\u00e1 constituido por 2.479 afiliados medios tras descender en 46 personas (-1,83%).<\/p>\n<p>Por comunidades aut\u00f3nomas, el n\u00famero de afiliados avanz\u00f3 en octubre en Madrid, con 39.219 ocupados (1,31%); Comunidad Valenciana, con 38.607 (2,18%), Andaluc\u00eda, 36.509 (1,25%); Pa\u00eds Vasco, 12.378 afiliados m\u00e1s (1,34%); Canarias, 7.892 (1,02%); Regi\u00f3n de Murcia, 5.211 (0,96%); Navarra, 2.033 (0,74%); Castilla Le\u00f3n, 1.820 (0,20%); Catalu\u00f1a, 1.702 (0,05%); Extremadura, 825 (0,21%) y Asturias, 451 (0,13%). Tambi\u00e9n aument\u00f3 en las ciudades aut\u00f3nomas de Ceuta (748) y Melilla (365).<\/p>\n<p>Por el contrario, octubre registr\u00f3 descensos en Islas Baleares, con 36.139 ocupados menos, Castilla-La Mancha (-10.869), Galicia (-2.356), La Rioja (-1.846), Cantabria (-1.716) y Arag\u00f3n (-466).<\/p>\n<p><strong>Respecto a 2016<\/strong><\/p>\n<p>En relaci\u00f3n al a\u00f1o pasado, el Sistema ha ganado 617.173 ocupados, el 3,46%, junto con octubre del a\u00f1o pasado, el mejor resultado desde 2005. En concreto, destaca el buen comportamiento del R\u00e9gimen General, que incorpora 593.690 trabajadores (4,08%). El crecimiento alcanza el 4,63% si hablamos del R\u00e9gimen General propiamente dicho (sin Agrario ni Hogar).<\/p>\n<p>En el R\u00e9gimen Especial de Trabajadores Aut\u00f3nomos hay que se\u00f1alar que la tasa aument\u00f3 un 0,74%, lo que se traduce en un crecimiento de 23.642 personas. El R\u00e9gimen del Mar creci\u00f3 un 0,24% (154) y el Carb\u00f3n registr\u00f3 un descenso de 313 (-11,21%).<\/p>\n<p>En t\u00e9rminos anuales, la afiliaci\u00f3n creci\u00f3 en todas las Comunidades Aut\u00f3nomas, excepto en Melilla (-338) y la Rioja (-1.025), destacando en cifras absolutas los incrementos de Catalu\u00f1a (119.638), Comunidad de Madrid (115.377), Andaluc\u00eda (109.577) y la Comunidad Valenciana (78.943).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La afiliaci\u00f3n media a la Seguridad Social alcanza 18.430.529 ocupados en octubre, tras registrar el mayor incremento interanual de la serie hist\u00f3rica en ese mes, a excepci\u00f3n de 2005 (a\u00f1o condicionado por la regularizaci\u00f3n extraordinaria de inmigrantes) con 617.173 afiliados m\u00e1s respecto a 2016. \u200bEl mes de octubre, la Seguridad Social sum\u00f3 94.368 ocupados, el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":958549,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[187],"tags":[],"class_list":["post-958548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"La afiliaci\u00f3n media a la Seguridad Social alcanza 18.430.529 ocupados en octubre, tras registrar el mayor incremento interanual de la serie hist\u00f3rica en ese mes, a excepci\u00f3n de 2005 (a\u00f1o condicionado por la regularizaci\u00f3n extraordinaria de inmigrantes) con 617.173 afiliados m\u00e1s respecto a 2016. \u200bEl mes de octubre, la Seguridad Social sum\u00f3 94.368 ocupados, el\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"econom\u00eda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Seguridad Social cuenta con 18.430.529 afiliados - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La afiliaci\u00f3n media a la Seguridad Social alcanza 18.430.529 ocupados en octubre, tras registrar el mayor incremento interanual de la serie hist\u00f3rica en ese mes, a excepci\u00f3n de 2005 (a\u00f1o condicionado por la regularizaci\u00f3n extraordinaria de inmigrantes) con 617.173 afiliados m\u00e1s respecto a 2016. \u200bEl mes de octubre, la Seguridad Social sum\u00f3 94.368 ocupados, el\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"econom\u00eda\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-11-03T17:43:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-11-03T17:43:25+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Seguridad Social cuenta con 18.430.529 afiliados - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La afiliaci\u00f3n media a la Seguridad Social alcanza 18.430.529 ocupados en octubre, tras registrar el mayor incremento interanual de la serie hist\u00f3rica en ese mes, a excepci\u00f3n de 2005 (a\u00f1o condicionado por la regularizaci\u00f3n extraordinaria de inmigrantes) con 617.173 afiliados m\u00e1s respecto a 2016. \u200bEl mes de octubre, la Seguridad Social sum\u00f3 94.368 ocupados, el\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-seguridad-social-cuenta-con-18-430-529-afiliados\\\/#blogposting\",\"name\":\"La Seguridad Social cuenta con 18.430.529 afiliados - El Digital de Asturias\",\"headline\":\"La Seguridad Social cuenta con 18.430.529 afiliados\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":958549},\"datePublished\":\"2017-11-03T17:43:25+01:00\",\"dateModified\":\"2017-11-03T17:43:25+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-seguridad-social-cuenta-con-18-430-529-afiliados\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-seguridad-social-cuenta-con-18-430-529-afiliados\\\/#webpage\"},\"articleSection\":\"Econom\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-seguridad-social-cuenta-con-18-430-529-afiliados\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"name\":\"Econom\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"position\":2,\"name\":\"Econom\\u00eda\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-seguridad-social-cuenta-con-18-430-529-afiliados\\\/#listItem\",\"name\":\"La Seguridad Social cuenta con 18.430.529 afiliados\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-seguridad-social-cuenta-con-18-430-529-afiliados\\\/#listItem\",\"position\":3,\"name\":\"La Seguridad Social cuenta con 18.430.529 afiliados\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"name\":\"Econom\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-seguridad-social-cuenta-con-18-430-529-afiliados\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-seguridad-social-cuenta-con-18-430-529-afiliados\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-seguridad-social-cuenta-con-18-430-529-afiliados\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-seguridad-social-cuenta-con-18-430-529-afiliados\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-seguridad-social-cuenta-con-18-430-529-afiliados\\\/\",\"name\":\"La Seguridad Social cuenta con 18.430.529 afiliados - El Digital de Asturias\",\"description\":\"La afiliaci\\u00f3n media a la Seguridad Social alcanza 18.430.529 ocupados en octubre, tras registrar el mayor incremento interanual de la serie hist\\u00f3rica en ese mes, a excepci\\u00f3n de 2005 (a\\u00f1o condicionado por la regularizaci\\u00f3n extraordinaria de inmigrantes) con 617.173 afiliados m\\u00e1s respecto a 2016. \\u200bEl mes de octubre, la Seguridad Social sum\\u00f3 94.368 ocupados, el\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-seguridad-social-cuenta-con-18-430-529-afiliados\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":958549,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-seguridad-social-cuenta-con-18-430-529-afiliados\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-seguridad-social-cuenta-con-18-430-529-afiliados\\\/#mainImage\"},\"datePublished\":\"2017-11-03T17:43:25+01:00\",\"dateModified\":\"2017-11-03T17:43:25+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La Seguridad Social cuenta con 18.430.529 afiliados - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"La Seguridad Social cuenta con 18.430.529 afiliados - El Digital de Asturias","description":"La afiliaci\u00f3n media a la Seguridad Social alcanza 18.430.529 ocupados en octubre, tras registrar el mayor incremento interanual de la serie hist\u00f3rica en ese mes, a excepci\u00f3n de 2005 (a\u00f1o condicionado por la regularizaci\u00f3n extraordinaria de inmigrantes) con 617.173 afiliados m\u00e1s respecto a 2016. \u200bEl mes de octubre, la Seguridad Social sum\u00f3 94.368 ocupados, el","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/","robots":"max-image-preview:large","keywords":"econom\u00eda","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/#blogposting","name":"La Seguridad Social cuenta con 18.430.529 afiliados - El Digital de Asturias","headline":"La Seguridad Social cuenta con 18.430.529 afiliados","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":958549},"datePublished":"2017-11-03T17:43:25+01:00","dateModified":"2017-11-03T17:43:25+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/#webpage"},"articleSection":"Econom\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","name":"Econom\u00eda"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","position":2,"name":"Econom\u00eda","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/#listItem","name":"La Seguridad Social cuenta con 18.430.529 afiliados"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/#listItem","position":3,"name":"La Seguridad Social cuenta con 18.430.529 afiliados","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","name":"Econom\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/","name":"La Seguridad Social cuenta con 18.430.529 afiliados - El Digital de Asturias","description":"La afiliaci\u00f3n media a la Seguridad Social alcanza 18.430.529 ocupados en octubre, tras registrar el mayor incremento interanual de la serie hist\u00f3rica en ese mes, a excepci\u00f3n de 2005 (a\u00f1o condicionado por la regularizaci\u00f3n extraordinaria de inmigrantes) con 617.173 afiliados m\u00e1s respecto a 2016. \u200bEl mes de octubre, la Seguridad Social sum\u00f3 94.368 ocupados, el","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":958549,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/#mainImage"},"datePublished":"2017-11-03T17:43:25+01:00","dateModified":"2017-11-03T17:43:25+01:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"La Seguridad Social cuenta con 18.430.529 afiliados - El Digital de Asturias","og:description":"La afiliaci\u00f3n media a la Seguridad Social alcanza 18.430.529 ocupados en octubre, tras registrar el mayor incremento interanual de la serie hist\u00f3rica en ese mes, a excepci\u00f3n de 2005 (a\u00f1o condicionado por la regularizaci\u00f3n extraordinaria de inmigrantes) con 617.173 afiliados m\u00e1s respecto a 2016. \u200bEl mes de octubre, la Seguridad Social sum\u00f3 94.368 ocupados, el","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/","article:tag":["econom\u00eda"],"article:published_time":"2017-11-03T17:43:25+00:00","article:modified_time":"2017-11-03T17:43:25+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"La Seguridad Social cuenta con 18.430.529 afiliados - El Digital de Asturias","twitter:description":"La afiliaci\u00f3n media a la Seguridad Social alcanza 18.430.529 ocupados en octubre, tras registrar el mayor incremento interanual de la serie hist\u00f3rica en ese mes, a excepci\u00f3n de 2005 (a\u00f1o condicionado por la regularizaci\u00f3n extraordinaria de inmigrantes) con 617.173 afiliados m\u00e1s respecto a 2016. \u200bEl mes de octubre, la Seguridad Social sum\u00f3 94.368 ocupados, el","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"958548","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-12-06 21:37:13","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 12:54:07","updated":"2025-12-06 21:37:13","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/\" title=\"Econom\u00eda\">Econom\u00eda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/\" title=\"La Seguridad Social cuenta con 18.430.529 afiliados\">La Seguridad Social cuenta con 18.430.529 afiliados<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Econom\u00eda","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/"},{"label":"La Seguridad Social cuenta con 18.430.529 afiliados","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-seguridad-social-cuenta-con-18-430-529-afiliados\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/958548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=958548"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/958548\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=958548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=958548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=958548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}