{"id":879016,"date":"2016-04-30T08:31:12","date_gmt":"2016-04-30T08:31:12","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=879016"},"modified":"2016-04-30T08:31:12","modified_gmt":"2016-04-30T08:31:12","slug":"parques-reunidos-cae-un-483-en-su-vuelta-al-mercado","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/","title":{"rendered":"Parques Reunidos cae un 4,83% en su vuelta al mercado"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-879017\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2016\/04\/fotonoticia_20160429182315_800-360x259.jpg\" alt=\"fotonoticia_20160429182315_800\" width=\"360\" height=\"259\" \/>Parques Reunidos ha culminado su regreso a la Bolsa con una ca\u00edda del 4,83%, tras doce a\u00f1os alejada del mercado burs\u00e1til, al cerrar la jornada a un precio de 14,75 euros, frente al precio de 15,50 euros que la compa\u00f1\u00eda fij\u00f3 para su vuelta al parqu\u00e9 madrile\u00f1o.<\/p>\n<p>El grupo de parques tem\u00e1ticos y de ocio inici\u00f3 su vuelta a la cotizaci\u00f3n con un desplome de m\u00e1s de un 5% como una monta\u00f1a rusa y marcar el mismo precio de su retorno en el primer intercambio de t\u00edtulos, realizado a las 12.00 horas, despu\u00e9s del tradicional toque de campana, para mitigar levemente su ca\u00edda al cierre de la sesi\u00f3n.<\/p>\n<p>La compa\u00f1\u00eda, que ha protagoniza la tercera salida a Bolsa esta semana, ha retornado al mercado con una capitalizaci\u00f3n burs\u00e1til inicial de 1.250 millones de euros, despu\u00e9s de su exclusi\u00f3n en mayo de 1999 (a 9,5 euros) y en el que dej\u00f3 de cotizar en marzo de 2004.<\/p>\n<p>Como en los dos casos anteriores, ni siquiera el haber fijado el precio de salida en el rango bajo de la horquilla indicativa de precios le ha garantizado una buena acogida, en una jornada con la mayor\u00eda de los valores te\u00f1idos de rojo, tambi\u00e9n en el selectivo, y la presentaci\u00f3n de muchos resultados.<\/p>\n<p>El Ibex 35 ha cerrado la sesi\u00f3n de este viernes con una ca\u00edda del 2,62%, lo que ha llevado al selectivo a situarse levemente por encima de los 9.000 enteros (9.025,7) y a acumular un retroceso del 2,24% en la semana. Por el contrario, el \u00edndice ha conseguido sumar un avance del 3,46% en el mes de abril.<\/p>\n<p>DESTACA LA \u00abCALIDAD Y CONFIANZA\u00bb DE LOS INVERSORES.<\/p>\n<p>Pese a la fr\u00eda acogida, Parques Reunidos asegura que afronta con \u00aboptimismo\u00bb y ha mostrando su satisfacci\u00f3n por la \u00abcalidad\u00bb y \u00abconfianza\u00bb de los inversores en la colocaci\u00f3n.<\/p>\n<p>El consejero delegado del grupo, Fernando Eiroa, rest\u00f3 importancia a su salida en el rango m\u00e1s bajo y asegur\u00f3 que se ha cubierto \u00abmuy bien\u00bb la colocaci\u00f3n, lo que en su opini\u00f3n es \u00abuna excelente prueba de la confianza de los inversores en la fortaleza financiera, la capacidad de generaci\u00f3n de ingresos y la evoluci\u00f3n del negocio de la compa\u00f1\u00eda\u00bb.<\/p>\n<p>Como ejemplo de ello se refiri\u00f3 a la adquisici\u00f3n del 8% del capital por Corporaci\u00f3n Financiera Alba, que ha invertido m\u00e1s de 100 millones, en la compra de un paquete de 6,4 millones de t\u00edtulos de la sociedad. Asimismo, destac\u00f3 que la demanda ha sido mayor por parte de inversores internacionales sobre todo Reino Unido y Estados Unidos.<\/p>\n<p>\u00abSon accionistas a largo plazo que es lo que nos gusta a nosotros, no vamos a correr los cien metros, vamos a correr un marat\u00f3n, y en ese marat\u00f3n Parques Reunidos va a tener unos resultados excelentes porque tenemos una empresa con presencia mundial, superdiversificada y con un crecimiento impresionante\u00bb, defendi\u00f3.<\/p>\n<p>Eiroa confirm\u00f3 que tiene la intenci\u00f3n de retribuir al accionista con una pol\u00edtica de dividendos de entre un 20% y un 30% de los beneficios netos del grupo, y repartir\u00e1 un dividendo en 2017 con cargo a los resultados de 2016.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parques Reunidos ha culminado su regreso a la Bolsa con una ca\u00edda del 4,83%, tras doce a\u00f1os alejada del mercado burs\u00e1til, al cerrar la jornada a un precio de 14,75 euros, frente al precio de 15,50 euros que la compa\u00f1\u00eda fij\u00f3 para su vuelta al parqu\u00e9 madrile\u00f1o. El grupo de parques tem\u00e1ticos y de ocio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":879017,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[187],"tags":[],"class_list":["post-879016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Parques Reunidos ha culminado su regreso a la Bolsa con una ca\u00edda del 4,83%, tras doce a\u00f1os alejada del mercado burs\u00e1til, al cerrar la jornada a un precio de 14,75 euros, frente al precio de 15,50 euros que la compa\u00f1\u00eda fij\u00f3 para su vuelta al parqu\u00e9 madrile\u00f1o. El grupo de parques tem\u00e1ticos y de ocio\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"econom\u00eda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Parques Reunidos cae un 4,83% en su vuelta al mercado - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Parques Reunidos ha culminado su regreso a la Bolsa con una ca\u00edda del 4,83%, tras doce a\u00f1os alejada del mercado burs\u00e1til, al cerrar la jornada a un precio de 14,75 euros, frente al precio de 15,50 euros que la compa\u00f1\u00eda fij\u00f3 para su vuelta al parqu\u00e9 madrile\u00f1o. El grupo de parques tem\u00e1ticos y de ocio\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"econom\u00eda\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-04-30T08:31:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-04-30T08:31:12+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Parques Reunidos cae un 4,83% en su vuelta al mercado - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Parques Reunidos ha culminado su regreso a la Bolsa con una ca\u00edda del 4,83%, tras doce a\u00f1os alejada del mercado burs\u00e1til, al cerrar la jornada a un precio de 14,75 euros, frente al precio de 15,50 euros que la compa\u00f1\u00eda fij\u00f3 para su vuelta al parqu\u00e9 madrile\u00f1o. El grupo de parques tem\u00e1ticos y de ocio\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\\\/#blogposting\",\"name\":\"Parques Reunidos cae un 4,83% en su vuelta al mercado - El Digital de Asturias\",\"headline\":\"Parques Reunidos cae un 4,83% en su vuelta al mercado\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":879017},\"datePublished\":\"2016-04-30T08:31:12+02:00\",\"dateModified\":\"2016-04-30T08:31:12+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\\\/#webpage\"},\"articleSection\":\"Econom\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"name\":\"Econom\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"position\":2,\"name\":\"Econom\\u00eda\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\\\/#listItem\",\"name\":\"Parques Reunidos cae un 4,83% en su vuelta al mercado\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\\\/#listItem\",\"position\":3,\"name\":\"Parques Reunidos cae un 4,83% en su vuelta al mercado\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"name\":\"Econom\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\\\/\",\"name\":\"Parques Reunidos cae un 4,83% en su vuelta al mercado - El Digital de Asturias\",\"description\":\"Parques Reunidos ha culminado su regreso a la Bolsa con una ca\\u00edda del 4,83%, tras doce a\\u00f1os alejada del mercado burs\\u00e1til, al cerrar la jornada a un precio de 14,75 euros, frente al precio de 15,50 euros que la compa\\u00f1\\u00eda fij\\u00f3 para su vuelta al parqu\\u00e9 madrile\\u00f1o. El grupo de parques tem\\u00e1ticos y de ocio\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":879017,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\\\/#mainImage\"},\"datePublished\":\"2016-04-30T08:31:12+02:00\",\"dateModified\":\"2016-04-30T08:31:12+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Parques Reunidos cae un 4,83% en su vuelta al mercado - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Parques Reunidos cae un 4,83% en su vuelta al mercado - El Digital de Asturias","description":"Parques Reunidos ha culminado su regreso a la Bolsa con una ca\u00edda del 4,83%, tras doce a\u00f1os alejada del mercado burs\u00e1til, al cerrar la jornada a un precio de 14,75 euros, frente al precio de 15,50 euros que la compa\u00f1\u00eda fij\u00f3 para su vuelta al parqu\u00e9 madrile\u00f1o. El grupo de parques tem\u00e1ticos y de ocio","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/","robots":"max-image-preview:large","keywords":"econom\u00eda","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/#blogposting","name":"Parques Reunidos cae un 4,83% en su vuelta al mercado - El Digital de Asturias","headline":"Parques Reunidos cae un 4,83% en su vuelta al mercado","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":879017},"datePublished":"2016-04-30T08:31:12+02:00","dateModified":"2016-04-30T08:31:12+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/#webpage"},"articleSection":"Econom\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","name":"Econom\u00eda"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","position":2,"name":"Econom\u00eda","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/#listItem","name":"Parques Reunidos cae un 4,83% en su vuelta al mercado"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/#listItem","position":3,"name":"Parques Reunidos cae un 4,83% en su vuelta al mercado","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","name":"Econom\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/","name":"Parques Reunidos cae un 4,83% en su vuelta al mercado - El Digital de Asturias","description":"Parques Reunidos ha culminado su regreso a la Bolsa con una ca\u00edda del 4,83%, tras doce a\u00f1os alejada del mercado burs\u00e1til, al cerrar la jornada a un precio de 14,75 euros, frente al precio de 15,50 euros que la compa\u00f1\u00eda fij\u00f3 para su vuelta al parqu\u00e9 madrile\u00f1o. El grupo de parques tem\u00e1ticos y de ocio","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":879017,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/#mainImage"},"datePublished":"2016-04-30T08:31:12+02:00","dateModified":"2016-04-30T08:31:12+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Parques Reunidos cae un 4,83% en su vuelta al mercado - El Digital de Asturias","og:description":"Parques Reunidos ha culminado su regreso a la Bolsa con una ca\u00edda del 4,83%, tras doce a\u00f1os alejada del mercado burs\u00e1til, al cerrar la jornada a un precio de 14,75 euros, frente al precio de 15,50 euros que la compa\u00f1\u00eda fij\u00f3 para su vuelta al parqu\u00e9 madrile\u00f1o. El grupo de parques tem\u00e1ticos y de ocio","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/","article:tag":["econom\u00eda"],"article:published_time":"2016-04-30T08:31:12+00:00","article:modified_time":"2016-04-30T08:31:12+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Parques Reunidos cae un 4,83% en su vuelta al mercado - El Digital de Asturias","twitter:description":"Parques Reunidos ha culminado su regreso a la Bolsa con una ca\u00edda del 4,83%, tras doce a\u00f1os alejada del mercado burs\u00e1til, al cerrar la jornada a un precio de 14,75 euros, frente al precio de 15,50 euros que la compa\u00f1\u00eda fij\u00f3 para su vuelta al parqu\u00e9 madrile\u00f1o. El grupo de parques tem\u00e1ticos y de ocio","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"879016","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-11-09 16:44:20","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-01-23 04:41:39","updated":"2025-11-09 16:44:20","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/\" title=\"Econom\u00eda\">Econom\u00eda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/\" title=\"Parques Reunidos cae un 4,83% en su vuelta al mercado\">Parques Reunidos cae un 4,83% en su vuelta al mercado<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Econom\u00eda","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/"},{"label":"Parques Reunidos cae un 4,83% en su vuelta al mercado","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/parques-reunidos-cae-un-483-en-su-vuelta-al-mercado\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/879016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=879016"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/879016\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=879016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=879016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=879016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}