{"id":877244,"date":"2016-04-25T21:37:19","date_gmt":"2016-04-25T21:37:19","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=877244"},"modified":"2016-04-25T21:37:19","modified_gmt":"2016-04-25T21:37:19","slug":"el-ibex-35-comienza-la-semana-perdiendo-un-101","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/","title":{"rendered":"El Ibex 35 comienza la semana perdiendo un 1,01%"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-820604\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2015\/11\/bolsa-360x217.jpg\" alt=\"bolsa\" width=\"360\" height=\"217\" \/>El Ibex 35 ha cerrado la sesi\u00f3n de este lunes con una ca\u00edda del 1,01%, lo que ha llevado al selectivo a situarse por debajo de la cota psicol\u00f3gica de los 9.200 enteros (9.140) y a romper con cinco jornadas al alza debido a la ca\u00edda de las materias primas y los precios del petr\u00f3leo.<\/p>\n<p>En el mercado de deuda, la prima de riesgo se ha colocado en 137,9 puntos b\u00e1sicos, con la rentabilidad del bono a diez a\u00f1os en el 1,64%. Mientras, en el mercado de divisas, el euro se intercambiaba a 1,1274 d\u00f3lares.<\/p>\n<p>ArcelorMittal ha liderado los recortes con un retroceso del 4,94%, seguido de Mapfre (-4,03%), OHL (-3,71%), Sacyr (-3,54%) y Sabadell (-3,22%).<\/p>\n<p>Por el contrario, Merlin se ha erigido como el mejor valor de la jornada con un avance del 1,24%, seguido de Ferrovial (+1,1%), Aena (+1,08%), IAG (+0,93%) y Abertis (+0,59%).<\/p>\n<p>Salvo Endesa, que ha conseguido mantener el tipo y anotarse una leve subida del 0,16%, el resto de los grandes valores se han adentrado en p\u00e9rdidas con Repsol (-2,1%), BBVA (-2,03%) y Santander (-2,01%) a la cabeza. Inditex ha recortado un 0,94%, Telef\u00f3nica un 0,75% e Iberdrola un 0,5%.<\/p>\n<p>El selectivo espa\u00f1ol ha liderado, junto con Mil\u00e1n (-1,5%), las ca\u00eddas en las plazas del Viejo Continente, poco optimistas en la jornada de este lunes: Londres y Francfort se han dejado un 0,8% y Par\u00eds un 0,5%.<\/p>\n<p>El estratega de mercados de IG Daniel Pingarr\u00f3n ha se\u00f1alado que las ca\u00eddas que se han visto en las principales plazas del Viejo Continente se deben a \u00abun c\u00famulo de factores parciales adversos\u00bb que han coincidido en la sesi\u00f3n de hoy, \u00abpero sin que la estructura alcista se vea demasiado amenazada\u00bb.<\/p>\n<p>Entre esos factores se encuentran la ca\u00edda de los precios de las materias primas y del petr\u00f3leo.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ibex 35 ha cerrado la sesi\u00f3n de este lunes con una ca\u00edda del 1,01%, lo que ha llevado al selectivo a situarse por debajo de la cota psicol\u00f3gica de los 9.200 enteros (9.140) y a romper con cinco jornadas al alza debido a la ca\u00edda de las materias primas y los precios del petr\u00f3leo. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":764750,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[187],"tags":[],"class_list":["post-877244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Ibex 35 ha cerrado la sesi\u00f3n de este lunes con una ca\u00edda del 1,01%, lo que ha llevado al selectivo a situarse por debajo de la cota psicol\u00f3gica de los 9.200 enteros (9.140) y a romper con cinco jornadas al alza debido a la ca\u00edda de las materias primas y los precios del petr\u00f3leo.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"econom\u00eda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Ibex 35 comienza la semana perdiendo un 1,01% - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"El Ibex 35 ha cerrado la sesi\u00f3n de este lunes con una ca\u00edda del 1,01%, lo que ha llevado al selectivo a situarse por debajo de la cota psicol\u00f3gica de los 9.200 enteros (9.140) y a romper con cinco jornadas al alza debido a la ca\u00edda de las materias primas y los precios del petr\u00f3leo.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"econom\u00eda\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-04-25T21:37:19+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-04-25T21:37:19+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Ibex 35 comienza la semana perdiendo un 1,01% - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Ibex 35 ha cerrado la sesi\u00f3n de este lunes con una ca\u00edda del 1,01%, lo que ha llevado al selectivo a situarse por debajo de la cota psicol\u00f3gica de los 9.200 enteros (9.140) y a romper con cinco jornadas al alza debido a la ca\u00edda de las materias primas y los precios del petr\u00f3leo.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-comienza-la-semana-perdiendo-un-101\\\/#blogposting\",\"name\":\"El Ibex 35 comienza la semana perdiendo un 1,01% - El Digital de Asturias\",\"headline\":\"El Ibex 35 comienza la semana perdiendo un 1,01%\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":764750},\"datePublished\":\"2016-04-25T21:37:19+02:00\",\"dateModified\":\"2016-04-25T21:37:19+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-comienza-la-semana-perdiendo-un-101\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-comienza-la-semana-perdiendo-un-101\\\/#webpage\"},\"articleSection\":\"Econom\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-comienza-la-semana-perdiendo-un-101\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"name\":\"Econom\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"position\":2,\"name\":\"Econom\\u00eda\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-comienza-la-semana-perdiendo-un-101\\\/#listItem\",\"name\":\"El Ibex 35 comienza la semana perdiendo un 1,01%\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-comienza-la-semana-perdiendo-un-101\\\/#listItem\",\"position\":3,\"name\":\"El Ibex 35 comienza la semana perdiendo un 1,01%\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"name\":\"Econom\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-comienza-la-semana-perdiendo-un-101\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-comienza-la-semana-perdiendo-un-101\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-comienza-la-semana-perdiendo-un-101\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-comienza-la-semana-perdiendo-un-101\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-comienza-la-semana-perdiendo-un-101\\\/\",\"name\":\"El Ibex 35 comienza la semana perdiendo un 1,01% - El Digital de Asturias\",\"description\":\"El Ibex 35 ha cerrado la sesi\\u00f3n de este lunes con una ca\\u00edda del 1,01%, lo que ha llevado al selectivo a situarse por debajo de la cota psicol\\u00f3gica de los 9.200 enteros (9.140) y a romper con cinco jornadas al alza debido a la ca\\u00edda de las materias primas y los precios del petr\\u00f3leo.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-comienza-la-semana-perdiendo-un-101\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":764750,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-comienza-la-semana-perdiendo-un-101\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-comienza-la-semana-perdiendo-un-101\\\/#mainImage\"},\"datePublished\":\"2016-04-25T21:37:19+02:00\",\"dateModified\":\"2016-04-25T21:37:19+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Ibex 35 comienza la semana perdiendo un 1,01% - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El Ibex 35 comienza la semana perdiendo un 1,01% - El Digital de Asturias","description":"El Ibex 35 ha cerrado la sesi\u00f3n de este lunes con una ca\u00edda del 1,01%, lo que ha llevado al selectivo a situarse por debajo de la cota psicol\u00f3gica de los 9.200 enteros (9.140) y a romper con cinco jornadas al alza debido a la ca\u00edda de las materias primas y los precios del petr\u00f3leo.","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/","robots":"max-image-preview:large","keywords":"econom\u00eda","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/#blogposting","name":"El Ibex 35 comienza la semana perdiendo un 1,01% - El Digital de Asturias","headline":"El Ibex 35 comienza la semana perdiendo un 1,01%","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":764750},"datePublished":"2016-04-25T21:37:19+02:00","dateModified":"2016-04-25T21:37:19+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/#webpage"},"articleSection":"Econom\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","name":"Econom\u00eda"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","position":2,"name":"Econom\u00eda","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/#listItem","name":"El Ibex 35 comienza la semana perdiendo un 1,01%"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/#listItem","position":3,"name":"El Ibex 35 comienza la semana perdiendo un 1,01%","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","name":"Econom\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/","name":"El Ibex 35 comienza la semana perdiendo un 1,01% - El Digital de Asturias","description":"El Ibex 35 ha cerrado la sesi\u00f3n de este lunes con una ca\u00edda del 1,01%, lo que ha llevado al selectivo a situarse por debajo de la cota psicol\u00f3gica de los 9.200 enteros (9.140) y a romper con cinco jornadas al alza debido a la ca\u00edda de las materias primas y los precios del petr\u00f3leo.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":764750,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/#mainImage"},"datePublished":"2016-04-25T21:37:19+02:00","dateModified":"2016-04-25T21:37:19+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"El Ibex 35 comienza la semana perdiendo un 1,01% - El Digital de Asturias","og:description":"El Ibex 35 ha cerrado la sesi\u00f3n de este lunes con una ca\u00edda del 1,01%, lo que ha llevado al selectivo a situarse por debajo de la cota psicol\u00f3gica de los 9.200 enteros (9.140) y a romper con cinco jornadas al alza debido a la ca\u00edda de las materias primas y los precios del petr\u00f3leo.","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/","article:tag":["econom\u00eda"],"article:published_time":"2016-04-25T21:37:19+00:00","article:modified_time":"2016-04-25T21:37:19+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"El Ibex 35 comienza la semana perdiendo un 1,01% - El Digital de Asturias","twitter:description":"El Ibex 35 ha cerrado la sesi\u00f3n de este lunes con una ca\u00edda del 1,01%, lo que ha llevado al selectivo a situarse por debajo de la cota psicol\u00f3gica de los 9.200 enteros (9.140) y a romper con cinco jornadas al alza debido a la ca\u00edda de las materias primas y los precios del petr\u00f3leo.","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"877244","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-11-09 10:56:05","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-01-22 16:28:53","updated":"2025-11-09 10:56:05","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/\" title=\"Econom\u00eda\">Econom\u00eda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/\" title=\"El Ibex 35 comienza la semana perdiendo un 1,01%\">El Ibex 35 comienza la semana perdiendo un 1,01%<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Econom\u00eda","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/"},{"label":"El Ibex 35 comienza la semana perdiendo un 1,01%","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-comienza-la-semana-perdiendo-un-101\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/877244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=877244"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/877244\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=877244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=877244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=877244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}