{"id":872058,"date":"2016-04-08T18:57:34","date_gmt":"2016-04-08T18:57:34","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=872058"},"modified":"2016-04-08T18:57:34","modified_gmt":"2016-04-08T18:57:34","slug":"el-ibex-35-cierra-la-semana-en-los-8-4276-puntos","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/","title":{"rendered":"El Ibex 35 cierra la semana en los 8.427,6 puntos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-872059\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2016\/04\/fotonoticia_20160408181258_800-360x248.jpg\" alt=\"fotonoticia_20160408181258_800\" width=\"360\" height=\"248\" \/>El Ibex 35 ha cerrado la sesi\u00f3n de este viernes con un repunte del 1,62%, lo que ha llevado al selectivo a situarse por encima de los 8.400 enteros (8.427,6) con las constructoras y la banca tirando del selectivo, impulso que ha permitido al \u00edndice reducir sus p\u00e9rdidas semanales al 2%.<\/p>\n<p>En el mercado de deuda, la prima de riesgo se ha situado en 143,1 puntos b\u00e1sicos, con la rentabilidad del bono a diez a\u00f1os en el 1,523%. Mientras, en el mercado de divisas, el euro se intercambiaba en 1,1414 d\u00f3lares.<\/p>\n<p>OHL se ha erigido como el valor l\u00edder de la jornada tras dispararse un 5,79%, seguido de Sacyr (+4,97%), Acerinox (+4,04%) y ACS (+3,85%). La banca tambi\u00e9n ha celebrado una buena sesi\u00f3n y ha colocado a Popular (+3%), Caixabank (+2,85%) y Bankia (+2,61%) entre los valores que m\u00e1s han subido. Tan solo Grifols, que ha cedido un 0,24%, ha cerrado en &#8216;n\u00fameros rojos&#8217;.<\/p>\n<p>El positivo se ha extendido entre los grandes valores, cuyas ganancias han oscilado entre el 2,8% de Repsol y el 0,54% de Inditex. Santander ha subido un 2,43%, Telef\u00f3nica un 2,22%, Endesa un 1,85%, BBVA un 1,5% e Iberdrola un 0,99%.<\/p>\n<p>De este modo, el selectivo espa\u00f1ol se ha colocado, junto con Mil\u00e1n (+3,97%) entre las mejores plazas de Europa, por delante de Par\u00eds (+1,21%), Londres (+1,08%) y Francfort (+0,96%). La Bolsa italiana se ha disparado gracias a la banca, que ha anticipado las medidas del banco malo que se aplicar\u00e1n a partir de la semana que viene.<\/p>\n<p><strong>BALANCE SEMANAL NEGATIVO<\/strong><\/p>\n<p>El analista de XTB Rodrigo Garc\u00eda ha explicado a Europa Press que, a la vista de la evoluci\u00f3n del selectivo en los \u00faltimos cinco d\u00edas, \u00ablos altos niveles de volatilidad, propios de escenarios bajistas, dejan claro que el escenario m\u00e1s probable no pasa por un repunte sostenido y sostenible de la renta variable\u00bb.<\/p>\n<p>Los valores financieros han sido los que peor comportamiento han mostrado a lo largo de la semana, castigados, de manera general, por la reducci\u00f3n de m\u00e1rgenes y la sentencia de un Juzgado de Madrid que declara nulas las cl\u00e1usulas suelo de los contratos hipotecarios de 40 bancos y cajas de ahorros.<\/p>\n<p>No obstante, el experto, que no augura un comportamiento especialmente bueno del sector financiero, ve dif\u00edcil encontrar en esta resoluci\u00f3n la excusa para esos comportamientos burs\u00e1tiles.<\/p>\n<p>BBVA, Caixabank, Bankia y el Banco Popular se han dejado alrededor de un 5%, mientras que Banco Sabadell se ha convertido en el peor valor del selectivo, con recortes del 10%. Por otra parte, las &#8216;utilities&#8217; han ocupado los primeros puestos, s\u00f3lo por detr\u00e1s de Aena y Grifols, que se han anotado repuntes pr\u00f3ximos al 4% y al 3%, respectivamente.<\/p>\n<p>Para la semana que viene, Garc\u00eda adelanta un escenario en el que contin\u00fae la incertidumbre \u00abque tanto est\u00e1 lastrando la cotizaci\u00f3n de las grandes compa\u00f1\u00edas\u00bb espa\u00f1olas. En ese sentido, ha advertido de que la presi\u00f3n vendedora podr\u00eda llevar al selectivo a una banda de fluctuaci\u00f3n que oscile entre los 8.600 puntos y los 8.000 enteros.<\/p>\n<p>\u00abCon el escenario de pol\u00edticas monetarias pr\u00e1cticamente definido, prestaremos atenci\u00f3n al conjunto de indicadores macroecon\u00f3micos, en los que un deterioro mayor al esperado puede hacer que los inversores m\u00e1s optimistas tiren tambi\u00e9n la toalla\u00bb, ha destacado.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ibex 35 ha cerrado la sesi\u00f3n de este viernes con un repunte del 1,62%, lo que ha llevado al selectivo a situarse por encima de los 8.400 enteros (8.427,6) con las constructoras y la banca tirando del selectivo, impulso que ha permitido al \u00edndice reducir sus p\u00e9rdidas semanales al 2%. En el mercado de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":872059,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[187],"tags":[],"class_list":["post-872058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Ibex 35 ha cerrado la sesi\u00f3n de este viernes con un repunte del 1,62%, lo que ha llevado al selectivo a situarse por encima de los 8.400 enteros (8.427,6) con las constructoras y la banca tirando del selectivo, impulso que ha permitido al \u00edndice reducir sus p\u00e9rdidas semanales al 2%. En el mercado de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"econom\u00eda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Ibex 35 cierra la semana en los 8.427,6 puntos - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"El Ibex 35 ha cerrado la sesi\u00f3n de este viernes con un repunte del 1,62%, lo que ha llevado al selectivo a situarse por encima de los 8.400 enteros (8.427,6) con las constructoras y la banca tirando del selectivo, impulso que ha permitido al \u00edndice reducir sus p\u00e9rdidas semanales al 2%. En el mercado de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"econom\u00eda\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-04-08T18:57:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-04-08T18:57:34+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Ibex 35 cierra la semana en los 8.427,6 puntos - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Ibex 35 ha cerrado la sesi\u00f3n de este viernes con un repunte del 1,62%, lo que ha llevado al selectivo a situarse por encima de los 8.400 enteros (8.427,6) con las constructoras y la banca tirando del selectivo, impulso que ha permitido al \u00edndice reducir sus p\u00e9rdidas semanales al 2%. En el mercado de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\\\/#blogposting\",\"name\":\"El Ibex 35 cierra la semana en los 8.427,6 puntos - El Digital de Asturias\",\"headline\":\"El Ibex 35 cierra la semana en los 8.427,6 puntos\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":872059},\"datePublished\":\"2016-04-08T18:57:34+02:00\",\"dateModified\":\"2016-04-08T18:57:34+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\\\/#webpage\"},\"articleSection\":\"Econom\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"name\":\"Econom\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"position\":2,\"name\":\"Econom\\u00eda\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\\\/#listItem\",\"name\":\"El Ibex 35 cierra la semana en los 8.427,6 puntos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\\\/#listItem\",\"position\":3,\"name\":\"El Ibex 35 cierra la semana en los 8.427,6 puntos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"name\":\"Econom\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\\\/\",\"name\":\"El Ibex 35 cierra la semana en los 8.427,6 puntos - El Digital de Asturias\",\"description\":\"El Ibex 35 ha cerrado la sesi\\u00f3n de este viernes con un repunte del 1,62%, lo que ha llevado al selectivo a situarse por encima de los 8.400 enteros (8.427,6) con las constructoras y la banca tirando del selectivo, impulso que ha permitido al \\u00edndice reducir sus p\\u00e9rdidas semanales al 2%. En el mercado de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":872059,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\\\/#mainImage\"},\"datePublished\":\"2016-04-08T18:57:34+02:00\",\"dateModified\":\"2016-04-08T18:57:34+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Ibex 35 cierra la semana en los 8.427,6 puntos - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El Ibex 35 cierra la semana en los 8.427,6 puntos - El Digital de Asturias","description":"El Ibex 35 ha cerrado la sesi\u00f3n de este viernes con un repunte del 1,62%, lo que ha llevado al selectivo a situarse por encima de los 8.400 enteros (8.427,6) con las constructoras y la banca tirando del selectivo, impulso que ha permitido al \u00edndice reducir sus p\u00e9rdidas semanales al 2%. En el mercado de","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/","robots":"max-image-preview:large","keywords":"econom\u00eda","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/#blogposting","name":"El Ibex 35 cierra la semana en los 8.427,6 puntos - El Digital de Asturias","headline":"El Ibex 35 cierra la semana en los 8.427,6 puntos","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":872059},"datePublished":"2016-04-08T18:57:34+02:00","dateModified":"2016-04-08T18:57:34+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/#webpage"},"articleSection":"Econom\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","name":"Econom\u00eda"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","position":2,"name":"Econom\u00eda","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/#listItem","name":"El Ibex 35 cierra la semana en los 8.427,6 puntos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/#listItem","position":3,"name":"El Ibex 35 cierra la semana en los 8.427,6 puntos","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","name":"Econom\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/","name":"El Ibex 35 cierra la semana en los 8.427,6 puntos - El Digital de Asturias","description":"El Ibex 35 ha cerrado la sesi\u00f3n de este viernes con un repunte del 1,62%, lo que ha llevado al selectivo a situarse por encima de los 8.400 enteros (8.427,6) con las constructoras y la banca tirando del selectivo, impulso que ha permitido al \u00edndice reducir sus p\u00e9rdidas semanales al 2%. En el mercado de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":872059,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/#mainImage"},"datePublished":"2016-04-08T18:57:34+02:00","dateModified":"2016-04-08T18:57:34+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"El Ibex 35 cierra la semana en los 8.427,6 puntos - El Digital de Asturias","og:description":"El Ibex 35 ha cerrado la sesi\u00f3n de este viernes con un repunte del 1,62%, lo que ha llevado al selectivo a situarse por encima de los 8.400 enteros (8.427,6) con las constructoras y la banca tirando del selectivo, impulso que ha permitido al \u00edndice reducir sus p\u00e9rdidas semanales al 2%. En el mercado de","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/","article:tag":["econom\u00eda"],"article:published_time":"2016-04-08T18:57:34+00:00","article:modified_time":"2016-04-08T18:57:34+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"El Ibex 35 cierra la semana en los 8.427,6 puntos - El Digital de Asturias","twitter:description":"El Ibex 35 ha cerrado la sesi\u00f3n de este viernes con un repunte del 1,62%, lo que ha llevado al selectivo a situarse por encima de los 8.400 enteros (8.427,6) con las constructoras y la banca tirando del selectivo, impulso que ha permitido al \u00edndice reducir sus p\u00e9rdidas semanales al 2%. En el mercado de","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"872058","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-11-08 17:42:05","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-01-23 16:13:18","updated":"2025-11-08 17:42:05","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/\" title=\"Econom\u00eda\">Econom\u00eda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/\" title=\"El Ibex 35 cierra la semana en los 8.427,6 puntos\">El Ibex 35 cierra la semana en los 8.427,6 puntos<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Econom\u00eda","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/"},{"label":"El Ibex 35 cierra la semana en los 8.427,6 puntos","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-ibex-35-cierra-la-semana-en-los-8-4276-puntos\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/872058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=872058"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/872058\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=872058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=872058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=872058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}