{"id":858626,"date":"2016-02-16T08:25:19","date_gmt":"2016-02-16T08:25:19","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=858626"},"modified":"2016-02-16T08:25:19","modified_gmt":"2016-02-16T08:25:19","slug":"el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/","title":{"rendered":"El perfil del consumidor medio de minicr\u00e9ditos online es el de un var\u00f3n de 41 a\u00f1os"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-858627\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2016\/02\/1455527925_euro_447209_640-360x240.jpg\" alt=\"1455527925_euro_447209_640\" width=\"360\" height=\"240\" \/>El perfil m\u00e1s habitual entre las personas que solicitan minicr\u00e9ditos por Internet es el de un hombre de unos 41 a\u00f1os de edad, asalariado, soltero y con unos ingresos medios de m\u00e1s de 1.300 euros. Es lo que revela un estudio realizado por la entidad prestamista Cashper en el que se recopilan los datos de sus clientes entre los a\u00f1os 2011 y 2014.<\/p>\n<p>Adem\u00e1s, el an\u00e1lisis tambi\u00e9n muestra que la cantidad media solicitada es de unos 214 euros, algo bastante normal si consideramos que la mayor\u00eda de estos pr\u00e9stamos r\u00e1pidos no superan los 600 euros y, en la primera solicitud, no suelen permitir obtener m\u00e1s de 300 euros. Una de las formas m\u00e1s habituales para solicitar este dinero r\u00e1pido es a trav\u00e9s de herramientas online como el comparador de minicr\u00e9ditos de dinerorapidonline.com.<\/p>\n<p><strong>No predominan los perfiles afectados por la crisis<\/strong><\/p>\n<p>Es de destacar que, a pesar de lo que se podr\u00eda esperar, el perfil predominante no es el de una persona con bajos ingresos que no puede recurrir a los medios tradicionales para conseguir dinero. El estudio indica que el 82% de los usuarios tiene un empleo por cuenta ajena, siendo el resto jubilados, perceptores de distintos tipos de prestaciones y aut\u00f3nomos.<\/p>\n<p>De forma global, el importe medio de ingresos que obtienen los clientes son de 1.310 euros, un salario que actualmente puede considerarse incluso elevado, en el entorno de dificultad econ\u00f3mica y de alto paro en el que nos encontramos. Esto nos demuestra que no s\u00f3lo las personas con dificultades econ\u00f3micas son las que recurren a los minicr\u00e9ditos para obtener una peque\u00f1a cantidad de dinero r\u00e1pido.<\/p>\n<p><strong>Las comunidades con m\u00e1s solicitudes de cr\u00e9ditos r\u00e1pidos<\/strong><\/p>\n<p>Catalu\u00f1a y la Comunidad de Madrid son las comunidades aut\u00f3nomas que concentran mayor n\u00famero de peticiones, sumando entre las dos el 41,7% del total. Por ciudades, Madrid es la primera con un 10% y Barcelona la segunda con m\u00e1s del 5% de las solicitudes de minipr\u00e9stamos.<\/p>\n<p>Entre las comunidades destaca el dato de Andaluc\u00eda que, siendo la regi\u00f3n m\u00e1s poblada y una de las que m\u00e1s paro registra, s\u00f3lo concentra el 13% de las peticiones, desmintiendo una vez m\u00e1s el mito de que las personas con menos recursos son las que m\u00e1s recurren a los cr\u00e9ditos r\u00e1pidos.<\/p>\n<p>Las siguientes comunidades en las que m\u00e1s se solicitan estos productos financieros son la Comunidad Valenciana con m\u00e1s del 11%, Galicia que llega casi al 6% y Castilla y Le\u00f3n, que se queda en el 4,7%. El resto no llega a superar el 4%, aunque tambi\u00e9n se trata de comunidades con menor poblaci\u00f3n que las anteriores.<\/p>\n<p><strong>Los hombres recurren m\u00e1s a los minicr\u00e9ditos<\/strong><\/p>\n<p>Otro dato que revela el estudio es que son los varones los que m\u00e1s predominan entre los solicitantes de pr\u00e9stamos r\u00e1pidos, siendo casi dos tercios del total, y la edad media se encuentra entorno a los 41 a\u00f1os de edad. La situaci\u00f3n familiar m\u00e1s com\u00fan es la de los solteros, con un 45%, luego vienen los casados, con un 35% y los divorciados con un 15%. El otro 5% se corresponde con viudos y con los que a\u00fan viven con sus padres.<\/p>\n<p>El an\u00e1lisis tambi\u00e9n muestra que la cantidad media que se solicita en los microcr\u00e9ditos es de 214 euros. Son, por tanto, peque\u00f1os importes que se utilizan para situaciones puntuales de necesidad en las que se requiere un dinero r\u00e1pido para alg\u00fan imprevisto o para pagar gastos extraordinarios que llegan en momentos en los que no se dispone de liquidez para hacerles frente.<\/p>\n<p>Los minicr\u00e9ditos r\u00e1pidos online son un producto que se ha popularizado en nuestro pa\u00eds a ra\u00edz del inicio de la crisis econ\u00f3mica y financiera. Los altos requisitos impuestos por los bancos para conseguir financiaci\u00f3n han obligado a muchas personas a tener que recurrir a estos medios para obtener peque\u00f1as cantidades de dinero r\u00e1pido. La f\u00e1cil y r\u00e1pida gesti\u00f3n para conceder minipr\u00e9stamos ha hecho que cada vez m\u00e1s usuarios los utilicen y que las entidades que los conceden se hayan multiplicado en los \u00faltimos a\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El perfil m\u00e1s habitual entre las personas que solicitan minicr\u00e9ditos por Internet es el de un hombre de unos 41 a\u00f1os de edad, asalariado, soltero y con unos ingresos medios de m\u00e1s de 1.300 euros. Es lo que revela un estudio realizado por la entidad prestamista Cashper en el que se recopilan los datos de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":858627,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-858626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"El perfil m\u00e1s habitual entre las personas que solicitan minicr\u00e9ditos por Internet es el de un hombre de unos 41 a\u00f1os de edad, asalariado, soltero y con unos ingresos medios de m\u00e1s de 1.300 euros. Es lo que revela un estudio realizado por la entidad prestamista Cashper en el que se recopilan los datos de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El perfil del consumidor medio de minicr\u00e9ditos online es el de un var\u00f3n de 41 a\u00f1os - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"El perfil m\u00e1s habitual entre las personas que solicitan minicr\u00e9ditos por Internet es el de un hombre de unos 41 a\u00f1os de edad, asalariado, soltero y con unos ingresos medios de m\u00e1s de 1.300 euros. Es lo que revela un estudio realizado por la entidad prestamista Cashper en el que se recopilan los datos de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"actualidad\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-16T08:25:19+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-16T08:25:19+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El perfil del consumidor medio de minicr\u00e9ditos online es el de un var\u00f3n de 41 a\u00f1os - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El perfil m\u00e1s habitual entre las personas que solicitan minicr\u00e9ditos por Internet es el de un hombre de unos 41 a\u00f1os de edad, asalariado, soltero y con unos ingresos medios de m\u00e1s de 1.300 euros. Es lo que revela un estudio realizado por la entidad prestamista Cashper en el que se recopilan los datos de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\\\/#blogposting\",\"name\":\"El perfil del consumidor medio de minicr\\u00e9ditos online es el de un var\\u00f3n de 41 a\\u00f1os - El Digital de Asturias\",\"headline\":\"El perfil del consumidor medio de minicr\\u00e9ditos online es el de un var\\u00f3n de 41 a\\u00f1os\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":858627},\"datePublished\":\"2016-02-16T08:25:19+01:00\",\"dateModified\":\"2016-02-16T08:25:19+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\\\/#webpage\"},\"articleSection\":\"Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\\\/#listItem\",\"name\":\"El perfil del consumidor medio de minicr\\u00e9ditos online es el de un var\\u00f3n de 41 a\\u00f1os\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\\\/#listItem\",\"position\":3,\"name\":\"El perfil del consumidor medio de minicr\\u00e9ditos online es el de un var\\u00f3n de 41 a\\u00f1os\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\\\/\",\"name\":\"El perfil del consumidor medio de minicr\\u00e9ditos online es el de un var\\u00f3n de 41 a\\u00f1os - El Digital de Asturias\",\"description\":\"El perfil m\\u00e1s habitual entre las personas que solicitan minicr\\u00e9ditos por Internet es el de un hombre de unos 41 a\\u00f1os de edad, asalariado, soltero y con unos ingresos medios de m\\u00e1s de 1.300 euros. Es lo que revela un estudio realizado por la entidad prestamista Cashper en el que se recopilan los datos de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":858627,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\\\/#mainImage\"},\"datePublished\":\"2016-02-16T08:25:19+01:00\",\"dateModified\":\"2016-02-16T08:25:19+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El perfil del consumidor medio de minicr\u00e9ditos online es el de un var\u00f3n de 41 a\u00f1os - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El perfil del consumidor medio de minicr\u00e9ditos online es el de un var\u00f3n de 41 a\u00f1os - El Digital de Asturias","description":"El perfil m\u00e1s habitual entre las personas que solicitan minicr\u00e9ditos por Internet es el de un hombre de unos 41 a\u00f1os de edad, asalariado, soltero y con unos ingresos medios de m\u00e1s de 1.300 euros. Es lo que revela un estudio realizado por la entidad prestamista Cashper en el que se recopilan los datos de","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/#blogposting","name":"El perfil del consumidor medio de minicr\u00e9ditos online es el de un var\u00f3n de 41 a\u00f1os - El Digital de Asturias","headline":"El perfil del consumidor medio de minicr\u00e9ditos online es el de un var\u00f3n de 41 a\u00f1os","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":858627},"datePublished":"2016-02-16T08:25:19+01:00","dateModified":"2016-02-16T08:25:19+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/#webpage"},"articleSection":"Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/#listItem","name":"El perfil del consumidor medio de minicr\u00e9ditos online es el de un var\u00f3n de 41 a\u00f1os"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/#listItem","position":3,"name":"El perfil del consumidor medio de minicr\u00e9ditos online es el de un var\u00f3n de 41 a\u00f1os","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/","name":"El perfil del consumidor medio de minicr\u00e9ditos online es el de un var\u00f3n de 41 a\u00f1os - El Digital de Asturias","description":"El perfil m\u00e1s habitual entre las personas que solicitan minicr\u00e9ditos por Internet es el de un hombre de unos 41 a\u00f1os de edad, asalariado, soltero y con unos ingresos medios de m\u00e1s de 1.300 euros. Es lo que revela un estudio realizado por la entidad prestamista Cashper en el que se recopilan los datos de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":858627,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/#mainImage"},"datePublished":"2016-02-16T08:25:19+01:00","dateModified":"2016-02-16T08:25:19+01:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"El perfil del consumidor medio de minicr\u00e9ditos online es el de un var\u00f3n de 41 a\u00f1os - El Digital de Asturias","og:description":"El perfil m\u00e1s habitual entre las personas que solicitan minicr\u00e9ditos por Internet es el de un hombre de unos 41 a\u00f1os de edad, asalariado, soltero y con unos ingresos medios de m\u00e1s de 1.300 euros. Es lo que revela un estudio realizado por la entidad prestamista Cashper en el que se recopilan los datos de","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/","article:tag":["actualidad"],"article:published_time":"2016-02-16T08:25:19+00:00","article:modified_time":"2016-02-16T08:25:19+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"El perfil del consumidor medio de minicr\u00e9ditos online es el de un var\u00f3n de 41 a\u00f1os - El Digital de Asturias","twitter:description":"El perfil m\u00e1s habitual entre las personas que solicitan minicr\u00e9ditos por Internet es el de un hombre de unos 41 a\u00f1os de edad, asalariado, soltero y con unos ingresos medios de m\u00e1s de 1.300 euros. Es lo que revela un estudio realizado por la entidad prestamista Cashper en el que se recopilan los datos de","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"4 minutos"},"aioseo_meta_data":{"post_id":"858626","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-12-10 12:01:02","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-01-22 12:37:49","updated":"2025-12-10 12:01:02","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/\" title=\"El perfil del consumidor medio de minicr\u00e9ditos online es el de un var\u00f3n de 41 a\u00f1os\">El perfil del consumidor medio de minicr\u00e9ditos online es el de un var\u00f3n de 41 a\u00f1os<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Actualidad","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/"},{"label":"El perfil del consumidor medio de minicr\u00e9ditos online es el de un var\u00f3n de 41 a\u00f1os","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-perfil-del-consumidor-medio-de-minicreditos-online-es-el-de-un-varon-de-41-anos\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/858626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=858626"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/858626\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=858626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=858626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=858626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}