{"id":840605,"date":"2015-12-29T02:35:55","date_gmt":"2015-12-29T02:35:55","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=840605"},"modified":"2015-12-29T02:35:55","modified_gmt":"2015-12-29T02:35:55","slug":"faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/","title":{"rendered":"Faunia organiza un taller para ni\u00f1os sobre la tenencia responsable de mascotas ex\u00f3ticas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-840606\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2015\/12\/fotonoticia_20151228145142_800-360x239.jpg\" alt=\"fotonoticia_20151228145142_800\" width=\"360\" height=\"239\" \/>Faunia ofrecer\u00e1 un taller para los m\u00e1s peque\u00f1os con el fin de evitar que las especies ex\u00f3ticas como tit\u00eds, reptiles o guacamayos se conviertan en mascotas y regalos pasajeros de estas navidades.<\/p>\n<p>El pr\u00f3ximo 30 de diciembre, el territorio de los monos ardilla acoger\u00e1 una clase pr\u00e1ctica de sus cuidadores para sensibilizar frente a la adquisici\u00f3n de especies ex\u00f3ticas en estas fechas, seg\u00fan un comunicado.<\/p>\n<p>Se trata de uno de los campamentos de Navidad de Faunia que, a partir de este lunes y hasta el pr\u00f3ximo 7 de enero, acercar\u00e1n a los peque\u00f1os de la casa divertidos talleres relacionados con la conservaci\u00f3n y la naturaleza en los que cobrar\u00e1 especial protagonismo la alimentaci\u00f3n, cuidado y condiciones necesarias para una tenencia responsable de especies ex\u00f3ticas.<\/p>\n<p>La necesidad de habitar en compa\u00f1\u00eda junto a otros miembros de su misma especie bajo una temperatura tropical adecuada y una equilibrada dieta a base de frutas y verduras ser\u00e1n algunas de las curiosidades del taller sobre los monos ardilla, en el que sus cuidadores mostrar\u00e1n las habilidades de estos peque\u00f1os primates que conviven en s\u00f3lidos y numerosos grupos familiares.<\/p>\n<p>En este escenario educativo, Faunia da cinco recomendaciones b\u00e1sicas sobre la tenencia responsable de mascotas y especies ex\u00f3ticas: informarse sobre la especie y los requerimientos del animal que se pretende adquirir; valorar si la vivienda dispone de las instalaciones id\u00f3neas y las condiciones ambientales necesarias; evaluar si hay disposici\u00f3n y proximidad de servicios veterinarios especializados para esa especie; evaluar la alimentaci\u00f3n que requiere, y tener en cuenta la esperanza de vida.<\/p>\n<p>CAMPAMENTOS DE NAVIDAD<\/p>\n<p>Los campamentos de Navidad de Faunia ofrecen un amplio programa de actividades en torno a 15 \u00e1reas tem\u00e1ticas y 4 ecosistemas del parque en los que habitan m\u00e1s de 3.000 animales de 300 especies en dos semanas tem\u00e1ticas repletas de magia, aventura y diversi\u00f3n, del 28 al 31 de diciembre y del 4 al 7 de enero.<\/p>\n<p>Podr\u00e1n participar los ni\u00f1os de 3 a 13 a\u00f1os, en horario de 9 a 16 horas, por 38 euros al d\u00eda, incluyendo desayuno y comida. Habr\u00e1 un servicio de autob\u00fas y de guarder\u00eda por 7 euros por ni\u00f1o y d\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faunia ofrecer\u00e1 un taller para los m\u00e1s peque\u00f1os con el fin de evitar que las especies ex\u00f3ticas como tit\u00eds, reptiles o guacamayos se conviertan en mascotas y regalos pasajeros de estas navidades. El pr\u00f3ximo 30 de diciembre, el territorio de los monos ardilla acoger\u00e1 una clase pr\u00e1ctica de sus cuidadores para sensibilizar frente a la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":840606,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[598],"tags":[],"class_list":["post-840605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mascotas"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Faunia ofrecer\u00e1 un taller para los m\u00e1s peque\u00f1os con el fin de evitar que las especies ex\u00f3ticas como tit\u00eds, reptiles o guacamayos se conviertan en mascotas y regalos pasajeros de estas navidades. El pr\u00f3ximo 30 de diciembre, el territorio de los monos ardilla acoger\u00e1 una clase pr\u00e1ctica de sus cuidadores para sensibilizar frente a la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"mascotas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Faunia organiza un taller para ni\u00f1os sobre la tenencia responsable de mascotas ex\u00f3ticas - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Faunia ofrecer\u00e1 un taller para los m\u00e1s peque\u00f1os con el fin de evitar que las especies ex\u00f3ticas como tit\u00eds, reptiles o guacamayos se conviertan en mascotas y regalos pasajeros de estas navidades. El pr\u00f3ximo 30 de diciembre, el territorio de los monos ardilla acoger\u00e1 una clase pr\u00e1ctica de sus cuidadores para sensibilizar frente a la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"mascotas\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-12-29T02:35:55+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-12-29T02:35:55+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Faunia organiza un taller para ni\u00f1os sobre la tenencia responsable de mascotas ex\u00f3ticas - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Faunia ofrecer\u00e1 un taller para los m\u00e1s peque\u00f1os con el fin de evitar que las especies ex\u00f3ticas como tit\u00eds, reptiles o guacamayos se conviertan en mascotas y regalos pasajeros de estas navidades. El pr\u00f3ximo 30 de diciembre, el territorio de los monos ardilla acoger\u00e1 una clase pr\u00e1ctica de sus cuidadores para sensibilizar frente a la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\\\/#blogposting\",\"name\":\"Faunia organiza un taller para ni\\u00f1os sobre la tenencia responsable de mascotas ex\\u00f3ticas - El Digital de Asturias\",\"headline\":\"Faunia organiza un taller para ni\\u00f1os sobre la tenencia responsable de mascotas ex\\u00f3ticas\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":840606},\"datePublished\":\"2015-12-29T02:35:55+01:00\",\"dateModified\":\"2015-12-29T02:35:55+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\\\/#webpage\"},\"articleSection\":\"Mascotas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/#listItem\",\"name\":\"Mascotas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/#listItem\",\"position\":2,\"name\":\"Mascotas\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\\\/#listItem\",\"name\":\"Faunia organiza un taller para ni\\u00f1os sobre la tenencia responsable de mascotas ex\\u00f3ticas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\\\/#listItem\",\"position\":3,\"name\":\"Faunia organiza un taller para ni\\u00f1os sobre la tenencia responsable de mascotas ex\\u00f3ticas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/#listItem\",\"name\":\"Mascotas\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\\\/\",\"name\":\"Faunia organiza un taller para ni\\u00f1os sobre la tenencia responsable de mascotas ex\\u00f3ticas - El Digital de Asturias\",\"description\":\"Faunia ofrecer\\u00e1 un taller para los m\\u00e1s peque\\u00f1os con el fin de evitar que las especies ex\\u00f3ticas como tit\\u00eds, reptiles o guacamayos se conviertan en mascotas y regalos pasajeros de estas navidades. El pr\\u00f3ximo 30 de diciembre, el territorio de los monos ardilla acoger\\u00e1 una clase pr\\u00e1ctica de sus cuidadores para sensibilizar frente a la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":840606,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\\\/#mainImage\"},\"datePublished\":\"2015-12-29T02:35:55+01:00\",\"dateModified\":\"2015-12-29T02:35:55+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Faunia organiza un taller para ni\u00f1os sobre la tenencia responsable de mascotas ex\u00f3ticas - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Faunia organiza un taller para ni\u00f1os sobre la tenencia responsable de mascotas ex\u00f3ticas - El Digital de Asturias","description":"Faunia ofrecer\u00e1 un taller para los m\u00e1s peque\u00f1os con el fin de evitar que las especies ex\u00f3ticas como tit\u00eds, reptiles o guacamayos se conviertan en mascotas y regalos pasajeros de estas navidades. El pr\u00f3ximo 30 de diciembre, el territorio de los monos ardilla acoger\u00e1 una clase pr\u00e1ctica de sus cuidadores para sensibilizar frente a la","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/","robots":"max-image-preview:large","keywords":"mascotas","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/#blogposting","name":"Faunia organiza un taller para ni\u00f1os sobre la tenencia responsable de mascotas ex\u00f3ticas - El Digital de Asturias","headline":"Faunia organiza un taller para ni\u00f1os sobre la tenencia responsable de mascotas ex\u00f3ticas","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":840606},"datePublished":"2015-12-29T02:35:55+01:00","dateModified":"2015-12-29T02:35:55+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/#webpage"},"articleSection":"Mascotas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/#listItem","name":"Mascotas"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/#listItem","position":2,"name":"Mascotas","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/#listItem","name":"Faunia organiza un taller para ni\u00f1os sobre la tenencia responsable de mascotas ex\u00f3ticas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/#listItem","position":3,"name":"Faunia organiza un taller para ni\u00f1os sobre la tenencia responsable de mascotas ex\u00f3ticas","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/#listItem","name":"Mascotas"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/","name":"Faunia organiza un taller para ni\u00f1os sobre la tenencia responsable de mascotas ex\u00f3ticas - El Digital de Asturias","description":"Faunia ofrecer\u00e1 un taller para los m\u00e1s peque\u00f1os con el fin de evitar que las especies ex\u00f3ticas como tit\u00eds, reptiles o guacamayos se conviertan en mascotas y regalos pasajeros de estas navidades. El pr\u00f3ximo 30 de diciembre, el territorio de los monos ardilla acoger\u00e1 una clase pr\u00e1ctica de sus cuidadores para sensibilizar frente a la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":840606,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/#mainImage"},"datePublished":"2015-12-29T02:35:55+01:00","dateModified":"2015-12-29T02:35:55+01:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Faunia organiza un taller para ni\u00f1os sobre la tenencia responsable de mascotas ex\u00f3ticas - El Digital de Asturias","og:description":"Faunia ofrecer\u00e1 un taller para los m\u00e1s peque\u00f1os con el fin de evitar que las especies ex\u00f3ticas como tit\u00eds, reptiles o guacamayos se conviertan en mascotas y regalos pasajeros de estas navidades. El pr\u00f3ximo 30 de diciembre, el territorio de los monos ardilla acoger\u00e1 una clase pr\u00e1ctica de sus cuidadores para sensibilizar frente a la","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/","article:tag":["mascotas"],"article:published_time":"2015-12-29T02:35:55+00:00","article:modified_time":"2015-12-29T02:35:55+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Faunia organiza un taller para ni\u00f1os sobre la tenencia responsable de mascotas ex\u00f3ticas - El Digital de Asturias","twitter:description":"Faunia ofrecer\u00e1 un taller para los m\u00e1s peque\u00f1os con el fin de evitar que las especies ex\u00f3ticas como tit\u00eds, reptiles o guacamayos se conviertan en mascotas y regalos pasajeros de estas navidades. El pr\u00f3ximo 30 de diciembre, el territorio de los monos ardilla acoger\u00e1 una clase pr\u00e1ctica de sus cuidadores para sensibilizar frente a la","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"840605","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-12-27 18:42:30","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-01-23 03:32:11","updated":"2025-12-27 18:42:30"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/\" title=\"Mascotas\">Mascotas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/\" title=\"Faunia organiza un taller para ni\u00f1os sobre la tenencia responsable de mascotas ex\u00f3ticas\">Faunia organiza un taller para ni\u00f1os sobre la tenencia responsable de mascotas ex\u00f3ticas<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Mascotas","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/"},{"label":"Faunia organiza un taller para ni\u00f1os sobre la tenencia responsable de mascotas ex\u00f3ticas","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/faunia-organiza-un-taller-para-ninos-sobre-la-tenencia-responsable-de-mascotas-exoticas\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/840605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=840605"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/840605\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=840605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=840605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=840605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}