{"id":634759,"date":"2014-10-03T19:17:13","date_gmt":"2014-10-03T17:17:13","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=634759"},"modified":"2014-10-03T19:17:13","modified_gmt":"2014-10-03T17:17:13","slug":"valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/","title":{"rendered":"Valencia y Atl\u00e9tico compiten por el segundo puesto con el liderato a la vista"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-634760\" alt=\"6703195w\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2014\/10\/6703195w-360x234.jpg\" width=\"360\" height=\"234\" \/>Valencia\/Madrid, 3 oct (EFE).- Mestalla enfrentar\u00e1 este s\u00e1bado a Valencia y Atl\u00e9tico de Madrid por la segunda posici\u00f3n, con el liderato al alcance para el ganador, pendiente del resultado del Barcelona, en un duelo potente entre dos equipos invictos y dise\u00f1ados para luchar por los cuatro primeros puestos de la tabla.<\/p>\n<p>Es una prueba de fuego para ambos conjuntos y sus prometedoras sensaciones de este comienzo de temporada, que ha demostrado la capacidad de dos bloques de una competitividad m\u00e1xima y que siguen la estela del Bar\u00e7a a s\u00f3lo dos puntos de distancia con la convicci\u00f3n que transmiten sus buenos n\u00fameros en el inicio de la actual Liga.<\/p>\n<p>No ha perdido ninguno de los dos en esa competici\u00f3n este curso. S\u00f3lo dos empates interrumpen la din\u00e1mica triunfal de Valencia y Atl\u00e9tico, protagonistas del campeonato tras las primeras seis citas de la temporada y enfrentados este s\u00e1bado por el segundo lugar del podio con ambici\u00f3n y sin renunciar a nada en la actual campa\u00f1a.<\/p>\n<p>Ma\u00f1ana es el primer examen ante un grande para la solidez del Valencia en el arranque liguero, en el que demostr\u00f3 capacidad de reacci\u00f3n ante el Sevilla, de pegada ante el M\u00e1laga, el Espanyol y el Getafe y de sufrimiento ante la Real Sociedad. Ahora deber\u00e1 combinar esas virtudes para plantar cara al actual campe\u00f3n.<\/p>\n<p>Pese a estar invicto y encaramado a la segunda posici\u00f3n de la clasificaci\u00f3n, en el Valencia todos ven como favorito para este encuentro al Atl\u00e9tico y Nuno Esp\u00edrito Santo, sin renunciar en ning\u00fan momento a la victoria, ha remarcado que a\u00fan no est\u00e1n a la altura del equipo de Diego Simeone, del Barcelona o del Real Madrid.<\/p>\n<p>El entrenador portugu\u00e9s admiti\u00f3 que una de sus armas para este s\u00e1bado ser\u00e1 tratar de aprovechar el desgaste que le ha supuesto al Atl\u00e9tico su partido de Liga de Campeones ante el Juventus y, aunque dijo que tienen un plan para hacerlo, no lo desvel\u00f3.<\/p>\n<p>Otro de los aspectos que deber\u00e1 cuidar el Valencia ser\u00e1 la defensa de las jugadas a bal\u00f3n parado de su rival, para lo que exigi\u00f3 \u00abconcentraci\u00f3n y rigor\u00bb a sus jugadores pero en las que tambi\u00e9n pidi\u00f3 al \u00e1rbitro que sancione como falta los \u00abbloqueos\u00bb de los que dice se beneficia el equipo madrile\u00f1o.<\/p>\n<p>Para tratar de compensar la capacidad de remate de cabeza de su rival, el t\u00e9cnico luso podr\u00eda dar continuidad en el eje de la defensa junto a Nico Otamendi al alem\u00e1n Mustafi, que ya fue titular en el partido ante la Real Sociedad en detrimento de Rub\u00e9n Vezo.<\/p>\n<p>De hecho, la \u00fanica novedad que se espera en el once titular es el regreso de Pablo Piatti, al que reserv\u00f3 en el duelo de Anoeta para poderlo tener en este encuentro y que volver\u00eda a ocupar la banda en la que jug\u00f3 Carles Gil ante el equipo donostiarra.<\/p>\n<p>Enfrente estar\u00e1 el Atl\u00e9tico, cuya semana es imponente. En siete d\u00edas clave, que concluyen con la visita al Valencia, calificado por el argentino Diego Simeone como un rival directo por la &#8216;Champions&#8217; y al que elogi\u00f3 este viernes en conferencia de prensa, ya ha derribado a Sevilla (4-0) y Juventus (1-0) del s\u00e1bado al mi\u00e9rcoles.<\/p>\n<p>Dos resultados reafirmantes para el actual campe\u00f3n de Liga, a\u00fan en busca de su \u00abmejor funcionamiento\u00bb, seg\u00fan dijo hoy su t\u00e9cnico, pero ya en un nivel alto este curso, el que ofreci\u00f3 para golear de forma incontestable el s\u00e1bado al conjunto andaluz y el que demostr\u00f3 el mi\u00e9rcoles para ganar a un Juventus que parec\u00eda casi inabordable.<\/p>\n<p>Sin tiempo para el descanso, apenas 64 horas despu\u00e9s del final del intenso choque ante el equipo italiano, el Atl\u00e9tico regresa a la competici\u00f3n con la vuelta de Gabi Fern\u00e1ndez a la alineaci\u00f3n titular, ya recuperado de un golpe en el tobillo derecho, y con tres cambios m\u00e1s en el once que planea el t\u00e9cnico para jugar en Mestalla.<\/p>\n<p>Entre las novedades, Jes\u00fas G\u00e1mez apunta al equipo inicial del conjunto rojiblanco, en sus primeros minutos en encuentro oficial desde su fichaje de este verano, para dar descanso a Juanfran Torres. Tambi\u00e9n Guilherme Siqueira, en el lateral izquierdo, y Antoine Griezmann, en la delantera, entrar\u00e1n en la alineaci\u00f3n.<\/p>\n<p>Miguel \u00c1ngel Moy\u00e1, ya indiscutible portero titular del Atl\u00e9tico en estos primeros meses de la campa\u00f1a; Joao Miranda y Diego God\u00edn, en el centro de la defensa; Tiago Mendes, en el medio con Gabi; Arda Turan, que cumple cien partidos en la Liga espa\u00f1ola, y Koke Resurrecci\u00f3n, en las bandas; y Mario Mandzukic, en punta, completan el probable once, del que salen Sa\u00fal \u00d1\u00edguez, Juanfran Torres, Cristian Ansaldi y Ra\u00fal Garc\u00eda respecto al duelo con el Juventus.<\/p>\n<p>Alineaciones probables.<\/p>\n<p>Valencia: Alves; Barrag\u00e1n, Mustafi, Otamendi, Gay\u00e0; Javi Fuego, Andr\u00e9 Gomes, Parejo; Piatti, Rodrigo y Alc\u00e1cer.<\/p>\n<p>Atl\u00e9tico de Madrid: Moy\u00e1; G\u00e1mez, Miranda, God\u00edn, Siqueira; Arda, Gabi, Tiago, Koke; Griezmann y Mandzukic.<\/p>\n<p>\u00c1rbitro: Fernando Teixeira Vitienes (C. C\u00e1ntabro).<\/p>\n<p>Estadio: Mestalla.<\/p>\n<p>Hora: 16.00.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Valencia\/Madrid, 3 oct (EFE).- Mestalla enfrentar\u00e1 este s\u00e1bado a Valencia y Atl\u00e9tico de Madrid por la segunda posici\u00f3n, con el liderato al alcance para el ganador, pendiente del resultado del Barcelona, en un duelo potente entre dos equipos invictos y dise\u00f1ados para luchar por los cuatro primeros puestos de la tabla. Es una prueba de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":634760,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[190],"tags":[],"class_list":["post-634759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Valencia\/Madrid, 3 oct (EFE).- Mestalla enfrentar\u00e1 este s\u00e1bado a Valencia y Atl\u00e9tico de Madrid por la segunda posici\u00f3n, con el liderato al alcance para el ganador, pendiente del resultado del Barcelona, en un duelo potente entre dos equipos invictos y dise\u00f1ados para luchar por los cuatro primeros puestos de la tabla. Es una prueba de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"deportes\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Valencia y Atl\u00e9tico compiten por el segundo puesto con el liderato a la vista - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Valencia\/Madrid, 3 oct (EFE).- Mestalla enfrentar\u00e1 este s\u00e1bado a Valencia y Atl\u00e9tico de Madrid por la segunda posici\u00f3n, con el liderato al alcance para el ganador, pendiente del resultado del Barcelona, en un duelo potente entre dos equipos invictos y dise\u00f1ados para luchar por los cuatro primeros puestos de la tabla. Es una prueba de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"deportes\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-10-03T17:17:13+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-10-03T17:17:13+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Valencia y Atl\u00e9tico compiten por el segundo puesto con el liderato a la vista - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Valencia\/Madrid, 3 oct (EFE).- Mestalla enfrentar\u00e1 este s\u00e1bado a Valencia y Atl\u00e9tico de Madrid por la segunda posici\u00f3n, con el liderato al alcance para el ganador, pendiente del resultado del Barcelona, en un duelo potente entre dos equipos invictos y dise\u00f1ados para luchar por los cuatro primeros puestos de la tabla. Es una prueba de\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\\\/#blogposting\",\"name\":\"Valencia y Atl\\u00e9tico compiten por el segundo puesto con el liderato a la vista - El Digital de Asturias\",\"headline\":\"Valencia y Atl\\u00e9tico compiten por el segundo puesto con el liderato a la vista\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":634760},\"datePublished\":\"2014-10-03T19:17:13+02:00\",\"dateModified\":\"2014-10-03T19:17:13+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\\\/#webpage\"},\"articleSection\":\"Deportes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"position\":2,\"name\":\"Deportes\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\\\/#listItem\",\"name\":\"Valencia y Atl\\u00e9tico compiten por el segundo puesto con el liderato a la vista\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\\\/#listItem\",\"position\":3,\"name\":\"Valencia y Atl\\u00e9tico compiten por el segundo puesto con el liderato a la vista\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\\\/\",\"name\":\"Valencia y Atl\\u00e9tico compiten por el segundo puesto con el liderato a la vista - El Digital de Asturias\",\"description\":\"Valencia\\\/Madrid, 3 oct (EFE).- Mestalla enfrentar\\u00e1 este s\\u00e1bado a Valencia y Atl\\u00e9tico de Madrid por la segunda posici\\u00f3n, con el liderato al alcance para el ganador, pendiente del resultado del Barcelona, en un duelo potente entre dos equipos invictos y dise\\u00f1ados para luchar por los cuatro primeros puestos de la tabla. Es una prueba de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":634760,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\\\/#mainImage\"},\"datePublished\":\"2014-10-03T19:17:13+02:00\",\"dateModified\":\"2014-10-03T19:17:13+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Valencia y Atl\u00e9tico compiten por el segundo puesto con el liderato a la vista - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Valencia y Atl\u00e9tico compiten por el segundo puesto con el liderato a la vista - El Digital de Asturias","description":"Valencia\/Madrid, 3 oct (EFE).- Mestalla enfrentar\u00e1 este s\u00e1bado a Valencia y Atl\u00e9tico de Madrid por la segunda posici\u00f3n, con el liderato al alcance para el ganador, pendiente del resultado del Barcelona, en un duelo potente entre dos equipos invictos y dise\u00f1ados para luchar por los cuatro primeros puestos de la tabla. Es una prueba de","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/","robots":"max-image-preview:large","keywords":"deportes","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/#blogposting","name":"Valencia y Atl\u00e9tico compiten por el segundo puesto con el liderato a la vista - El Digital de Asturias","headline":"Valencia y Atl\u00e9tico compiten por el segundo puesto con el liderato a la vista","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":634760},"datePublished":"2014-10-03T19:17:13+02:00","dateModified":"2014-10-03T19:17:13+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/#webpage"},"articleSection":"Deportes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","position":2,"name":"Deportes","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/#listItem","name":"Valencia y Atl\u00e9tico compiten por el segundo puesto con el liderato a la vista"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/#listItem","position":3,"name":"Valencia y Atl\u00e9tico compiten por el segundo puesto con el liderato a la vista","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/","name":"Valencia y Atl\u00e9tico compiten por el segundo puesto con el liderato a la vista - El Digital de Asturias","description":"Valencia\/Madrid, 3 oct (EFE).- Mestalla enfrentar\u00e1 este s\u00e1bado a Valencia y Atl\u00e9tico de Madrid por la segunda posici\u00f3n, con el liderato al alcance para el ganador, pendiente del resultado del Barcelona, en un duelo potente entre dos equipos invictos y dise\u00f1ados para luchar por los cuatro primeros puestos de la tabla. Es una prueba de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":634760,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/#mainImage"},"datePublished":"2014-10-03T19:17:13+02:00","dateModified":"2014-10-03T19:17:13+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Valencia y Atl\u00e9tico compiten por el segundo puesto con el liderato a la vista - El Digital de Asturias","og:description":"Valencia\/Madrid, 3 oct (EFE).- Mestalla enfrentar\u00e1 este s\u00e1bado a Valencia y Atl\u00e9tico de Madrid por la segunda posici\u00f3n, con el liderato al alcance para el ganador, pendiente del resultado del Barcelona, en un duelo potente entre dos equipos invictos y dise\u00f1ados para luchar por los cuatro primeros puestos de la tabla. Es una prueba de","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/","article:tag":["deportes"],"article:published_time":"2014-10-03T17:17:13+00:00","article:modified_time":"2014-10-03T17:17:13+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Valencia y Atl\u00e9tico compiten por el segundo puesto con el liderato a la vista - El Digital de Asturias","twitter:description":"Valencia\/Madrid, 3 oct (EFE).- Mestalla enfrentar\u00e1 este s\u00e1bado a Valencia y Atl\u00e9tico de Madrid por la segunda posici\u00f3n, con el liderato al alcance para el ganador, pendiente del resultado del Barcelona, en un duelo potente entre dos equipos invictos y dise\u00f1ados para luchar por los cuatro primeros puestos de la tabla. Es una prueba de","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"4 minutos"},"aioseo_meta_data":{"post_id":"634759","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-07-07 19:11:39","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-11-14 23:44:34","updated":"2026-07-07 19:11:39"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/\" title=\"Deportes\">Deportes<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/\" title=\"Valencia y Atl\u00e9tico compiten por el segundo puesto con el liderato a la vista\">Valencia y Atl\u00e9tico compiten por el segundo puesto con el liderato a la vista<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Deportes","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/"},{"label":"Valencia y Atl\u00e9tico compiten por el segundo puesto con el liderato a la vista","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/valencia-y-atletico-compiten-por-el-segundo-puesto-con-el-liderato-a-la-vista\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/634759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=634759"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/634759\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=634759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=634759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=634759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}