{"id":598781,"date":"2014-09-02T01:29:02","date_gmt":"2014-09-02T03:29:02","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=598781"},"modified":"2014-09-02T01:31:41","modified_gmt":"2014-09-02T03:31:41","slug":"cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/","title":{"rendered":"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-598782\" alt=\"6607119w\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2014\/09\/6607119w-213x320.jpg\" width=\"213\" height=\"320\" \/>Madrid, 1 sep (EFE).- La firma del contrato de Alessio Cerci y las salidas como cedidos de Emiliano Insua, Toby Alderweireld y Yassine Bono completaron hoy los movimientos en la plantilla del Atl\u00e9tico de Madrid para esta temporada, con 21 efectivos y con diez fichajes respecto al conjunto que fue campe\u00f3n de Liga el 18 de mayo.<\/p>\n<p>Cerci, cuya incorporaci\u00f3n estaba ultimada desde el domingo con el acuerdo entre el club rojiblanco, el Torino y el futbolista para su traspaso, formaliz\u00f3 este lunes su fichaje por el Atl\u00e9tico con el pertinente reconocimiento m\u00e9dico, la firma por tres temporadas y su inscripci\u00f3n en la Liga de F\u00fatbol Profesional (LFP) para este curso.<\/p>\n<p>Al mismo tiempo, sujeto al control econ\u00f3mico-financiero de la LFP, el Atl\u00e9tico culmin\u00f3 hoy su operaci\u00f3n salida con las cesiones del belga Toby Alderweireld al Southampton ingl\u00e9s -oficializada ya pasada la medianoche-, del argentino Emiliano Insua al Rayo Vallecano y del marroqu\u00ed Bono al Zaragoza. El uruguayo Cristian &#8216;Cebolla&#8217; Rodr\u00edguez, finalmente, seguir\u00e1 en el equipo rojiblanco.<\/p>\n<p>El Atl\u00e9tico ha cambiado m\u00e1s de la mitad de su plantilla. Siguen once jugadores de los 23 que terminaron la pasada Liga, ha habido 12 salidas respecto al curso 2013-14 y ha hecho diez incorporaciones, incluida la vuelta de Sa\u00fal \u00d1\u00edguez tras su cesi\u00f3n al Rayo Vallecano, para suplir esas bajas y potenciar los recursos del equipo.<\/p>\n<p>En el primer caso, los defensas Juanfran Torres, Joao Miranda, Diego God\u00edn y Jos\u00e9 Mar\u00eda Gim\u00e9nez y los centrocampistas Arda Turan, Mario Su\u00e1rez, Gabi Fern\u00e1ndez, Tiago Mendes, Koke Resurrecci\u00f3n, Ra\u00fal Garc\u00eda y Cristian Rodr\u00edguez, campeones de Liga y finalistas de Liga de Campeones hace cuatro meses, contin\u00faan en el conjunto rojiblanco.<\/p>\n<p>El resto de nombres han cambiado en la plantilla, con m\u00e1s de 100 millones de euros de inversi\u00f3n en fichajes, y con novedades en todas las l\u00edneas, empezando por la porter\u00eda, con la vuelta de Thibaut Courtois al Chelsea despu\u00e9s de tres a\u00f1os seguidos de cesi\u00f3n en el Vicente Calder\u00f3n y la finalizaci\u00f3n de contrato de Dani Aranzubia, adem\u00e1s de la marcha de Yassine Bono, tercer guardameta, al Zaragoza.<\/p>\n<p>La respuesta fue las contrataciones de Miguel \u00c1ngel Moy\u00e1 (Getafe), el titular en los primeros cuatro encuentros oficiales de esta temporada, y el esloveno Jan Oblak, guardameta procedente del Benfica, por el que el club rojiblanco ha pagado 16 millones de euros y ya recuperado de una microrrotura en el psoas-iliaco.<\/p>\n<p>En defensa, el Atl\u00e9tico ha cubierto el traspaso al Chelsea del lateral izquierdo Filipe Luis, que expres\u00f3 su deseo de marcharse al club brit\u00e1nico, con las incorporaciones de Guilherme Siqueira (Granada) y Cristian Ansaldi (Zenit), este \u00faltimo como cedido. Ah\u00ed, no contaba Emiliano Insua, cedido este lunes al Rayo Vallecano.<\/p>\n<p>En la otra banda, Javi Manquillo, que s\u00f3lo jug\u00f3 siete partidos, tres de Liga, durante el anterior ejercicio, ha sido cedido por dos a\u00f1os al Liverpool, mientras que Toby Alderweireld, un futbolista muy valorado en el Atl\u00e9tico, pero que quer\u00eda disputar m\u00e1s minutos, jugar\u00e1 a pr\u00e9stamo esta temporada en el Southampton ingl\u00e9s.<\/p>\n<p>Para cumplir el rol de cuarto central, con Joao Miranda, Diego God\u00edn y Jos\u00e9 Mar\u00eda Gim\u00e9nez por delante en esa posici\u00f3n, y de opci\u00f3n en el lateral derecho, en competencia con Juanfran Torres, fijo en el once, el Atl\u00e9tico ha fichado a Jes\u00fas G\u00e1mez desde el M\u00e1laga.<\/p>\n<p>En medio campo, el argentino Jos\u00e9 Sosa y el brasile\u00f1o Diego Ribas han sido las bajas del Atl\u00e9tico. El primero termin\u00f3 su cesi\u00f3n de un a\u00f1o desde el Metalist Kharkiv ucraniano y el segundo fich\u00f3 por el Fenerbahce tras su vuelta al Calder\u00f3n en el mercado invernal.<\/p>\n<p>Desde el Rayo ha regresado, en cambio, Sa\u00fal \u00d1\u00edguez, que ha ocupado el costado derecho en los encuentros que ha disputado este verano, pero que tambi\u00e9n puede jugar como medio centro, y desde el Torino se ha fichado a Alessio Cerci, centrocampista zurdo e internacional italiano polivalente en las posiciones ofensivas.<\/p>\n<p>En la banda o en la delantera tambi\u00e9n desarrolla su talento el franc\u00e9s Antoine Griezmann, uno de los refuerzos del ataque junto al goleador croata Mario Mandzukic y al mexicano Ra\u00fal Jim\u00e9nez. Los tres reemplazan al hispano-brasile\u00f1o Diego Costa (Chelsea), David Villa (Nueva York City) y Adri\u00e1n L\u00f3pez, traspasado al Oporto.<\/p>\n<p>Con todos esos movimientos y uno m\u00e1s pendiente, el fichaje del argentino \u00c1ngel Correa en cuanto est\u00e9 totalmente recuperado de la microcirug\u00eda cardiaca a la que fue sometido el pasado 18 de junio, el argentino Diego Simeone dispone ahora de 21 jugadores y una plantilla m\u00e1s potente para los nuevos desaf\u00edos de esta temporada.<\/p>\n<p>&#8211; LOS MOVIMIENTOS EN LA PLANTILLA DEL ATL\u00c9TICO DE MADRID:<\/p>\n<p>. 11 jugadores contin\u00faan en la plantilla: Juanfran Torres, Joao Miranda, Diego God\u00edn, Jos\u00e9 Mar\u00eda Gim\u00e9nez, Arda Turan, Mario Su\u00e1rez, Gabi Fern\u00e1ndez, Tiago Mendes, Koke Resurrecci\u00f3n, Ra\u00fal Garc\u00eda y Cristian &#8216;Cebolla&#8217; Rodr\u00edguez.<\/p>\n<p>&#8211; Entradas (10):<\/p>\n<p>. 1 futbolista vuelve de cesi\u00f3n: Sa\u00fal \u00d1\u00edguez (Rayo Vallecano).<\/p>\n<p>. 9 fichajes: Miguel \u00c1ngel Moy\u00e1 (Getafe), Jan Oblak (Benfica), Guilherme Siqueira (Granada), Cristian Ansaldi (cedido por el Zeni), Jes\u00fas G\u00e1mez (M\u00e1laga), Antoine Griezmann (Real Sociedad), Mario Mandzukic (Bayern M\u00fanich), Ra\u00fal Jim\u00e9nez (Am\u00e9rica) y Alessio Cerci (Torino).<\/p>\n<p>&#8211; Salidas (12):<\/p>\n<p>. 2 jugadores terminaron su cesi\u00f3n el pasado 30 de junio: Thibaut Courtois (Chelsea) y Jos\u00e9 Sosa (Metalist Kharkiv).<\/p>\n<p>. 3 jugadores concluyeron contrato el pasado 30 de junio: David Villa, Diego Ribas y Dani Aranzubia.<\/p>\n<p>. 4 jugadores han sido cedidos a otros clubes: Emiliano Insua (Rayo Vallecano), Javi Manquillo (Liverpool), Toby Alderweireld (Southampton) y Yassine Bounou, &#8216;Bono&#8217; (Zaragoza).<\/p>\n<p>. 3 jugadores han sido traspasados: Diego Costa (Chelsea), Filipe Luis (Chelsea) y Adri\u00e1n L\u00f3pez (Oporto).<\/p>\n<p>I\u00f1aki Dufour<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 1 sep (EFE).- La firma del contrato de Alessio Cerci y las salidas como cedidos de Emiliano Insua, Toby Alderweireld y Yassine Bono completaron hoy los movimientos en la plantilla del Atl\u00e9tico de Madrid para esta temporada, con 21 efectivos y con diez fichajes respecto al conjunto que fue campe\u00f3n de Liga el 18 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":598782,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[190],"tags":[],"class_list":["post-598781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 1 sep (EFE).- La firma del contrato de Alessio Cerci y las salidas como cedidos de Emiliano Insua, Toby Alderweireld y Yassine Bono completaron hoy los movimientos en la plantilla del Atl\u00e9tico de Madrid para esta temporada, con 21 efectivos y con diez fichajes respecto al conjunto que fue campe\u00f3n de Liga el 18\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"deportes\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 1 sep (EFE).- La firma del contrato de Alessio Cerci y las salidas como cedidos de Emiliano Insua, Toby Alderweireld y Yassine Bono completaron hoy los movimientos en la plantilla del Atl\u00e9tico de Madrid para esta temporada, con 21 efectivos y con diez fichajes respecto al conjunto que fue campe\u00f3n de Liga el 18\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"deportes\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-09-02T03:29:02+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-09-02T03:31:41+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 1 sep (EFE).- La firma del contrato de Alessio Cerci y las salidas como cedidos de Emiliano Insua, Toby Alderweireld y Yassine Bono completaron hoy los movimientos en la plantilla del Atl\u00e9tico de Madrid para esta temporada, con 21 efectivos y con diez fichajes respecto al conjunto que fue campe\u00f3n de Liga el 18\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\\\/#blogposting\",\"name\":\"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores - El Digital de Asturias\",\"headline\":\"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":598782},\"datePublished\":\"2014-09-02T01:29:02+02:00\",\"dateModified\":\"2014-09-02T01:31:41+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\\\/#webpage\"},\"articleSection\":\"Deportes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"position\":2,\"name\":\"Deportes\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\\\/#listItem\",\"name\":\"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\\\/#listItem\",\"position\":3,\"name\":\"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\\\/\",\"name\":\"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores - El Digital de Asturias\",\"description\":\"Madrid, 1 sep (EFE).- La firma del contrato de Alessio Cerci y las salidas como cedidos de Emiliano Insua, Toby Alderweireld y Yassine Bono completaron hoy los movimientos en la plantilla del Atl\\u00e9tico de Madrid para esta temporada, con 21 efectivos y con diez fichajes respecto al conjunto que fue campe\\u00f3n de Liga el 18\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":598782,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\\\/#mainImage\"},\"datePublished\":\"2014-09-02T01:29:02+02:00\",\"dateModified\":\"2014-09-02T01:31:41+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores - El Digital de Asturias","description":"Madrid, 1 sep (EFE).- La firma del contrato de Alessio Cerci y las salidas como cedidos de Emiliano Insua, Toby Alderweireld y Yassine Bono completaron hoy los movimientos en la plantilla del Atl\u00e9tico de Madrid para esta temporada, con 21 efectivos y con diez fichajes respecto al conjunto que fue campe\u00f3n de Liga el 18","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/","robots":"max-image-preview:large","keywords":"deportes","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/#blogposting","name":"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores - El Digital de Asturias","headline":"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":598782},"datePublished":"2014-09-02T01:29:02+02:00","dateModified":"2014-09-02T01:31:41+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/#webpage"},"articleSection":"Deportes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","position":2,"name":"Deportes","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/#listItem","name":"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/#listItem","position":3,"name":"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/","name":"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores - El Digital de Asturias","description":"Madrid, 1 sep (EFE).- La firma del contrato de Alessio Cerci y las salidas como cedidos de Emiliano Insua, Toby Alderweireld y Yassine Bono completaron hoy los movimientos en la plantilla del Atl\u00e9tico de Madrid para esta temporada, con 21 efectivos y con diez fichajes respecto al conjunto que fue campe\u00f3n de Liga el 18","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":598782,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/#mainImage"},"datePublished":"2014-09-02T01:29:02+02:00","dateModified":"2014-09-02T01:31:41+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores - El Digital de Asturias","og:description":"Madrid, 1 sep (EFE).- La firma del contrato de Alessio Cerci y las salidas como cedidos de Emiliano Insua, Toby Alderweireld y Yassine Bono completaron hoy los movimientos en la plantilla del Atl\u00e9tico de Madrid para esta temporada, con 21 efectivos y con diez fichajes respecto al conjunto que fue campe\u00f3n de Liga el 18","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/","article:tag":["deportes"],"article:published_time":"2014-09-02T03:29:02+00:00","article:modified_time":"2014-09-02T03:31:41+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores - El Digital de Asturias","twitter:description":"Madrid, 1 sep (EFE).- La firma del contrato de Alessio Cerci y las salidas como cedidos de Emiliano Insua, Toby Alderweireld y Yassine Bono completaron hoy los movimientos en la plantilla del Atl\u00e9tico de Madrid para esta temporada, con 21 efectivos y con diez fichajes respecto al conjunto que fue campe\u00f3n de Liga el 18","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"5 minutos"},"aioseo_meta_data":{"post_id":"598781","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-06-26 08:54:21","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-11-14 23:39:01","updated":"2026-06-26 08:54:21"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/\" title=\"Deportes\">Deportes<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/\" title=\"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores\">Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Deportes","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/"},{"label":"Cerci por Insua, Alderweireld y Bono para cerrar un plantel de 21 jugadores","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cerci-por-insua-alderweireld-y-bono-para-cerrar-un-plantel-de-21-jugadores\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/598781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=598781"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/598781\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=598781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=598781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=598781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}