{"id":590352,"date":"2014-08-24T13:56:14","date_gmt":"2014-08-24T15:56:14","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=590352"},"modified":"2014-08-24T13:56:14","modified_gmt":"2014-08-24T15:56:14","slug":"simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/","title":{"rendered":"Simeone dice que \u00abcuando uno se equivoca es justo pagarlo y estamos esperando\u00bb"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-590353\" alt=\"6582413w\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2014\/08\/6582413w-360x255.jpg\" width=\"360\" height=\"255\" \/>Majadahonda (Madrid), 24 ago (EFE).- El argentino Diego Simeone, entrenador del Atl\u00e9tico de Madrid, valor\u00f3 hoy sobre la sanci\u00f3n a la que se expone tras su expulsi\u00f3n en el partido de vuelta de la Supercopa ante el Real Madrid que \u00abcuando uno se equivoca es justo pagarlo y, en ese sentido\u00bb, est\u00e1 \u00abesperando lo que haya que pagar\u00bb.<\/p>\n<p>\u00abEs un tema terminado de parte de lo que pas\u00f3 el otro d\u00eda. Y reiterar y volver a hablar de lo mismo no es bueno. La gente que decide tendr\u00e1 que tomar la decisi\u00f3n que crea m\u00e1s justa y ojal\u00e1 que sea lo menor posible para el bien del equipo\u00bb, declar\u00f3 este domingo en conferencia de prensa tras el entrenamiento en Majadahonda.<\/p>\n<p>\u00abSabemos que cuando uno se equivoca es justo pagarlo y en ese sentido estamos esperando lo que haya que pagar\u00bb, prosigui\u00f3 Simeone, que tambi\u00e9n fue preguntado por la agresi\u00f3n de Cristiano Ronaldo a Diego God\u00edn en el duelo del pasado viernes: \u00abLa imagen en el partido no la vi. En la televisi\u00f3n se vio muy poquito\u00bb.<\/p>\n<p>\u00abPero son situaciones de juego que ustedes est\u00e1n para opinar lo que pasa. Nosotros siempre decimos que lo que pasa en el campo queda ah\u00ed dentro\u00bb, dijo el t\u00e9cnico, que, por otro lado, vio a Luka Modric \u00abque estaba en el t\u00fanel viendo el partido cuando hab\u00eda sido expulsado; eso lo vi en televisi\u00f3n y lo vieron ustedes tambi\u00e9n\u00bb.<\/p>\n<p>A la espera de la decisi\u00f3n del Juez de Competici\u00f3n sobre su expulsi\u00f3n en la Supercopa de Espa\u00f1a, Simeone cumplir\u00e1 ma\u00f1ana un encuentro de sanci\u00f3n por acumulaci\u00f3n de cinco tarjetas amarillas de la pasada temporada; un partido de suspensi\u00f3n que arrastraba desde la \u00faltima jornada de la anterior campa\u00f1a frente al Barcelona.<\/p>\n<p>\u00abLas cont\u00e9 (las amarillas de la pasada temporada). De las cinco amarillas del a\u00f1o pasado, me sacaron dos con el Real Madrid, dos con el Barcelona y una con el M\u00e1laga. Me echaron con el Madrid. Y me echaron en la Liga de Campeones con el Madrid. Debe ser que algo raro veo, porque siempre es con ellos\u00bb, valor\u00f3 en rueda de prensa.<\/p>\n<p>Ma\u00f1ana, por tanto, no se podr\u00e1 sentar en el banquillo de Vallecas. Lo har\u00e1 su segundo t\u00e9cnico, el argentino Germ\u00e1n &#8216;Mono&#8217; Burgos. \u00abTrataremos de buscar la mejor manera para comunicarnos, pero Germ\u00e1n tiene la capacidad, la confianza y me da la tranquilidad de que vemos el f\u00fatbol de la misma manera, as\u00ed que ning\u00fan problema\u00bb.<\/p>\n<p>El t\u00e9cnico, que confirm\u00f3 la titularidad de Miguel \u00c1ngel Moy\u00e1 en la porter\u00eda del conjunto rojiblanco para la visita de ma\u00f1ana a Vallecas, respondi\u00f3 con \u00absilencio, silencio, nada m\u00e1s que eso\u00bb, a las declaraciones de rivales que dan a su equipo como el m\u00e1ximo favorito al t\u00edtulo de Liga en esta campa\u00f1a, como afirm\u00f3 este s\u00e1bado Luis Enrique, su hom\u00f3logo en el banquillo del Barcelona.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Majadahonda (Madrid), 24 ago (EFE).- El argentino Diego Simeone, entrenador del Atl\u00e9tico de Madrid, valor\u00f3 hoy sobre la sanci\u00f3n a la que se expone tras su expulsi\u00f3n en el partido de vuelta de la Supercopa ante el Real Madrid que \u00abcuando uno se equivoca es justo pagarlo y, en ese sentido\u00bb, est\u00e1 \u00abesperando lo que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":590353,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[190],"tags":[],"class_list":["post-590352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Majadahonda (Madrid), 24 ago (EFE).- El argentino Diego Simeone, entrenador del Atl\u00e9tico de Madrid, valor\u00f3 hoy sobre la sanci\u00f3n a la que se expone tras su expulsi\u00f3n en el partido de vuelta de la Supercopa ante el Real Madrid que &quot;cuando uno se equivoca es justo pagarlo y, en ese sentido&quot;, est\u00e1 &quot;esperando lo que\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"deportes\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Simeone dice que \u00abcuando uno se equivoca es justo pagarlo y estamos esperando\u00bb - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Majadahonda (Madrid), 24 ago (EFE).- El argentino Diego Simeone, entrenador del Atl\u00e9tico de Madrid, valor\u00f3 hoy sobre la sanci\u00f3n a la que se expone tras su expulsi\u00f3n en el partido de vuelta de la Supercopa ante el Real Madrid que &quot;cuando uno se equivoca es justo pagarlo y, en ese sentido&quot;, est\u00e1 &quot;esperando lo que\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"deportes\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-08-24T15:56:14+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-08-24T15:56:14+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Simeone dice que \u00abcuando uno se equivoca es justo pagarlo y estamos esperando\u00bb - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Majadahonda (Madrid), 24 ago (EFE).- El argentino Diego Simeone, entrenador del Atl\u00e9tico de Madrid, valor\u00f3 hoy sobre la sanci\u00f3n a la que se expone tras su expulsi\u00f3n en el partido de vuelta de la Supercopa ante el Real Madrid que &quot;cuando uno se equivoca es justo pagarlo y, en ese sentido&quot;, est\u00e1 &quot;esperando lo que\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\\\/#blogposting\",\"name\":\"Simeone dice que \\u00abcuando uno se equivoca es justo pagarlo y estamos esperando\\u00bb - El Digital de Asturias\",\"headline\":\"Simeone dice que \\u00abcuando uno se equivoca es justo pagarlo y estamos esperando\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":590353},\"datePublished\":\"2014-08-24T13:56:14+02:00\",\"dateModified\":\"2014-08-24T13:56:14+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\\\/#webpage\"},\"articleSection\":\"Deportes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"position\":2,\"name\":\"Deportes\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\\\/#listItem\",\"name\":\"Simeone dice que \\u00abcuando uno se equivoca es justo pagarlo y estamos esperando\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\\\/#listItem\",\"position\":3,\"name\":\"Simeone dice que \\u00abcuando uno se equivoca es justo pagarlo y estamos esperando\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\\\/\",\"name\":\"Simeone dice que \\u00abcuando uno se equivoca es justo pagarlo y estamos esperando\\u00bb - El Digital de Asturias\",\"description\":\"Majadahonda (Madrid), 24 ago (EFE).- El argentino Diego Simeone, entrenador del Atl\\u00e9tico de Madrid, valor\\u00f3 hoy sobre la sanci\\u00f3n a la que se expone tras su expulsi\\u00f3n en el partido de vuelta de la Supercopa ante el Real Madrid que \\\"cuando uno se equivoca es justo pagarlo y, en ese sentido\\\", est\\u00e1 \\\"esperando lo que\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":590353,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\\\/#mainImage\"},\"datePublished\":\"2014-08-24T13:56:14+02:00\",\"dateModified\":\"2014-08-24T13:56:14+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Simeone dice que \u00abcuando uno se equivoca es justo pagarlo y estamos esperando\u00bb - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Simeone dice que \u00abcuando uno se equivoca es justo pagarlo y estamos esperando\u00bb - El Digital de Asturias","description":"Majadahonda (Madrid), 24 ago (EFE).- El argentino Diego Simeone, entrenador del Atl\u00e9tico de Madrid, valor\u00f3 hoy sobre la sanci\u00f3n a la que se expone tras su expulsi\u00f3n en el partido de vuelta de la Supercopa ante el Real Madrid que \"cuando uno se equivoca es justo pagarlo y, en ese sentido\", est\u00e1 \"esperando lo que","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/","robots":"max-image-preview:large","keywords":"deportes","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/#blogposting","name":"Simeone dice que \u00abcuando uno se equivoca es justo pagarlo y estamos esperando\u00bb - El Digital de Asturias","headline":"Simeone dice que \u00abcuando uno se equivoca es justo pagarlo y estamos esperando\u00bb","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":590353},"datePublished":"2014-08-24T13:56:14+02:00","dateModified":"2014-08-24T13:56:14+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/#webpage"},"articleSection":"Deportes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","position":2,"name":"Deportes","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/#listItem","name":"Simeone dice que \u00abcuando uno se equivoca es justo pagarlo y estamos esperando\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/#listItem","position":3,"name":"Simeone dice que \u00abcuando uno se equivoca es justo pagarlo y estamos esperando\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/","name":"Simeone dice que \u00abcuando uno se equivoca es justo pagarlo y estamos esperando\u00bb - El Digital de Asturias","description":"Majadahonda (Madrid), 24 ago (EFE).- El argentino Diego Simeone, entrenador del Atl\u00e9tico de Madrid, valor\u00f3 hoy sobre la sanci\u00f3n a la que se expone tras su expulsi\u00f3n en el partido de vuelta de la Supercopa ante el Real Madrid que \"cuando uno se equivoca es justo pagarlo y, en ese sentido\", est\u00e1 \"esperando lo que","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":590353,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/#mainImage"},"datePublished":"2014-08-24T13:56:14+02:00","dateModified":"2014-08-24T13:56:14+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Simeone dice que \u00abcuando uno se equivoca es justo pagarlo y estamos esperando\u00bb - El Digital de Asturias","og:description":"Majadahonda (Madrid), 24 ago (EFE).- El argentino Diego Simeone, entrenador del Atl\u00e9tico de Madrid, valor\u00f3 hoy sobre la sanci\u00f3n a la que se expone tras su expulsi\u00f3n en el partido de vuelta de la Supercopa ante el Real Madrid que &quot;cuando uno se equivoca es justo pagarlo y, en ese sentido&quot;, est\u00e1 &quot;esperando lo que","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/","article:tag":["deportes"],"article:published_time":"2014-08-24T15:56:14+00:00","article:modified_time":"2014-08-24T15:56:14+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Simeone dice que \u00abcuando uno se equivoca es justo pagarlo y estamos esperando\u00bb - El Digital de Asturias","twitter:description":"Majadahonda (Madrid), 24 ago (EFE).- El argentino Diego Simeone, entrenador del Atl\u00e9tico de Madrid, valor\u00f3 hoy sobre la sanci\u00f3n a la que se expone tras su expulsi\u00f3n en el partido de vuelta de la Supercopa ante el Real Madrid que &quot;cuando uno se equivoca es justo pagarlo y, en ese sentido&quot;, est\u00e1 &quot;esperando lo que","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"590352","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-06-24 19:27:03","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-11-14 23:36:21","updated":"2026-06-24 19:27:03"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/\" title=\"Deportes\">Deportes<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/\" title=\"Simeone dice que \u00abcuando uno se equivoca es justo pagarlo y estamos esperando\u00bb\">Simeone dice que \u00abcuando uno se equivoca es justo pagarlo y estamos esperando\u00bb<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Deportes","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/"},{"label":"Simeone dice que \u00abcuando uno se equivoca es justo pagarlo y estamos esperando\u00bb","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/simeone-dice-que-cuando-uno-se-equivoca-es-justo-pagarlo-y-estamos-esperando\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/590352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=590352"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/590352\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=590352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=590352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=590352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}