{"id":557999,"date":"2014-07-07T16:00:40","date_gmt":"2014-07-07T17:00:40","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=557999"},"modified":"2014-07-07T16:00:40","modified_gmt":"2014-07-07T17:00:40","slug":"el-atletico-de-madrid-arranca-la-pretemporada-con-dudas","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/","title":{"rendered":"El Atl\u00e9tico de Madrid arranca la pretemporada con dudas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-557986\" alt=\"6443253w\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2014\/07\/6443253w-360x239.jpg\" width=\"360\" height=\"239\" \/>Madrid, 7 jul (dpa) &#8211; El Atl\u00e9tico de Madrid, actual campe\u00f3n de la Liga espa\u00f1ola, comenz\u00f3 hoy sus entrenamientos de pretemporada con 24 jugadores, entre ellos los brasile\u00f1os Filipe Luis y Joao Miranda, y con un saco de dudas sobre el futuro de estos y otros jugadores.<\/p>\n<p>A la primera cita con el trabajo faltaron los futbolistas que estuvieron en el \u00faltimo Mundial, como son los espa\u00f1oles Koke Resurrecci\u00f3n y Juanfran Torres, los uruguayos Diego God\u00edn, Jos\u00e9 Mar\u00eda Gim\u00e9nez y Cristian Rodr\u00edguez y los belgas Toby Alderweireld y Thibaut Courtois. Por este motivo, el t\u00e9cnico argentino Diego Simeone recurri\u00f3 a siete futbolistas de las categor\u00edas inferiores para completar la sesi\u00f3n inicial, que dur\u00f3 75 minutos.<\/p>\n<p>Fue la primera toma de contacto de los rojiblancos tras finalizar la temporada anterior el 24 de mayo, cuando jugaron la final de la Liga de Campeones ante el Real Madrid, finalizada con triunfo de los blancos por 4-1. Una semana antes conquistaron la Liga espa\u00f1ola, su primera desde 1996.<\/p>\n<p>El magn\u00edfico e inesperado \u00e9xito de la temporada del Atl\u00e9tico proyect\u00f3 un problema a corto plazo: ser\u00eda dif\u00edcil mantener el bloque campe\u00f3n. Y as\u00ed est\u00e1 sucediendo.<\/p>\n<p>Tres fueron los primeros futbolistas en bajarse del campe\u00f3n: el delantero hispano-brasile\u00f1o Diego Costa, su gran estrella, se fue al Chelsea, donde tambi\u00e9n se reencontrar\u00e1 con el portugu\u00e9s Tiago. Y David Villa acept\u00f3 una oferta millonaria del New York City estadounidense.<\/p>\n<p>El siguiente en marcharse ser\u00e1 Courtois, salvo sorpresa inesperada. Sus derechos pertenecen al Chelsea, cuyo t\u00e9cnico, Jos\u00e9 Mourinho, ya anunci\u00f3 hace semanas que exist\u00eda \u00abcero posibilidad\u00bb de que el arquero belga siguiese cedido en el Atl\u00e9tico.<\/p>\n<p>Adem\u00e1s, tambi\u00e9n se da por segura la salida de Cristian \u00abCebolla\u00bb Rodr\u00edguez, quien a finales de temporada asegur\u00f3 que iba a buscar equipo ante la falta de minutos.<\/p>\n<p>Las grandes inc\u00f3gnitas en estos d\u00edas son Filipe Luis y Miranda, quienes no aceptaron las propuestas de renovaci\u00f3n, cosa que s\u00ed hicieron los espa\u00f1oles Koke y Gabi.<\/p>\n<p>Es un problema mayor para el Atl\u00e9tico, pues la pasada temporada los dos brasile\u00f1os fueron dos de los futbolistas b\u00e1sicos en el esquema de Simeone, tan fiado a su f\u00e9rrea defensa.<\/p>\n<p>\u00abEl Atl\u00e9tico no vende. El que quiera irse, que pague la cl\u00e1usula\u00bb, asegur\u00f3 recientemente su presidente, Enrique Cerezo. Es lo que hizo Costa.<\/p>\n<p>Y ahora el club rojiblanco teme que ocurra lo mismo con Filipe Luis, quien ya manifest\u00f3 p\u00fablicamente durante sus vacaciones que desea abandonar la nave rojiblanca al existir ofertas. Y con Miranda ocurre algo similar.<\/p>\n<p>El Atl\u00e9tico de Madrid, inmerso en una gran deuda que debe ir amortizando a\u00f1o a a\u00f1o, no puede competir con los clubes m\u00e1s millonarios de Europa, que ofrecen grandes sueldos a los jugadores, cifras a las que no puede llegar el campe\u00f3n de Espa\u00f1a.<\/p>\n<p>Lo siguiente que deber\u00e1 hacer el Atl\u00e9tico es acertar con los recambios. Busca dos delanteros y un arquero como prioridades. Pero su lista se extender\u00e1 si Miranda y Filipe Luis abren la puerta de salida.<\/p>\n<p>Sin embargo, Simeone parece bastante menos inquieto que sus hinchas y conf\u00eda en el buen ojo que el Atl\u00e9tico mostr\u00f3 la \u00faltima d\u00e9cada para fichar.<\/p>\n<p>\u00abSe fue (Sergio) Ag\u00fcero y muchos se asustaron, pero lleg\u00f3 (Radamel) Falcao y el equipo gan\u00f3 lo que gan\u00f3. Luego se fue Falcao y parec\u00eda que no se pod\u00eda mejorar. Lleg\u00f3 Costa y sigui\u00f3 creciendo. El Atl\u00e9tico siempre se ha manejado muy bien con los recambios que han tenido y esperemos que en esta oportunidad suceda lo mismo\u00bb, afirm\u00f3 en \u00abgoal.com\u00bb.<\/p>\n<p>El plantel permanecer\u00e1 hasta el jueves en Madrid antes de viajar a la tradicional concentraci\u00f3n de pretemporada en la localidad segoviana de Los \u00c1ngeles de San Rafael, donde se entrenar\u00e1 hasta el 23 de julio. Ese d\u00eda disputar\u00e1 su primer amistoso frente al Numancia en El Burgo de Osma, en la provincia de Soria.<\/p>\n<p>Despu\u00e9s, jugar\u00e1 otros seis encuentros de preparaci\u00f3n: el 27 de julio frente al San Jos\u00e9 Earthquakes en San Francisco; el 30 de ese mes contra el Am\u00e9rica de M\u00e9xico en el estadio Azteca; el 6 de agosto ante el Galatasaray en Esmirna; el 10 contra el Wolfsburgo en Alemania; y el 15 y 16 en el Trofeo Carranza de C\u00e1diz.<\/p>\n<p>Por Alberto Bravo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 7 jul (dpa) &#8211; El Atl\u00e9tico de Madrid, actual campe\u00f3n de la Liga espa\u00f1ola, comenz\u00f3 hoy sus entrenamientos de pretemporada con 24 jugadores, entre ellos los brasile\u00f1os Filipe Luis y Joao Miranda, y con un saco de dudas sobre el futuro de estos y otros jugadores. A la primera cita con el trabajo faltaron [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":557986,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[190],"tags":[],"class_list":["post-557999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 7 jul (dpa) - El Atl\u00e9tico de Madrid, actual campe\u00f3n de la Liga espa\u00f1ola, comenz\u00f3 hoy sus entrenamientos de pretemporada con 24 jugadores, entre ellos los brasile\u00f1os Filipe Luis y Joao Miranda, y con un saco de dudas sobre el futuro de estos y otros jugadores. A la primera cita con el trabajo faltaron\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"deportes\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Atl\u00e9tico de Madrid arranca la pretemporada con dudas - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 7 jul (dpa) - El Atl\u00e9tico de Madrid, actual campe\u00f3n de la Liga espa\u00f1ola, comenz\u00f3 hoy sus entrenamientos de pretemporada con 24 jugadores, entre ellos los brasile\u00f1os Filipe Luis y Joao Miranda, y con un saco de dudas sobre el futuro de estos y otros jugadores. A la primera cita con el trabajo faltaron\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"deportes\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-07-07T17:00:40+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-07-07T17:00:40+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Atl\u00e9tico de Madrid arranca la pretemporada con dudas - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 7 jul (dpa) - El Atl\u00e9tico de Madrid, actual campe\u00f3n de la Liga espa\u00f1ola, comenz\u00f3 hoy sus entrenamientos de pretemporada con 24 jugadores, entre ellos los brasile\u00f1os Filipe Luis y Joao Miranda, y con un saco de dudas sobre el futuro de estos y otros jugadores. A la primera cita con el trabajo faltaron\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\\\/#blogposting\",\"name\":\"El Atl\\u00e9tico de Madrid arranca la pretemporada con dudas - El Digital de Asturias\",\"headline\":\"El Atl\\u00e9tico de Madrid arranca la pretemporada con dudas\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":557986},\"datePublished\":\"2014-07-07T16:00:40+02:00\",\"dateModified\":\"2014-07-07T16:00:40+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\\\/#webpage\"},\"articleSection\":\"Deportes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"position\":2,\"name\":\"Deportes\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\\\/#listItem\",\"name\":\"El Atl\\u00e9tico de Madrid arranca la pretemporada con dudas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\\\/#listItem\",\"position\":3,\"name\":\"El Atl\\u00e9tico de Madrid arranca la pretemporada con dudas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\\\/\",\"name\":\"El Atl\\u00e9tico de Madrid arranca la pretemporada con dudas - El Digital de Asturias\",\"description\":\"Madrid, 7 jul (dpa) - El Atl\\u00e9tico de Madrid, actual campe\\u00f3n de la Liga espa\\u00f1ola, comenz\\u00f3 hoy sus entrenamientos de pretemporada con 24 jugadores, entre ellos los brasile\\u00f1os Filipe Luis y Joao Miranda, y con un saco de dudas sobre el futuro de estos y otros jugadores. A la primera cita con el trabajo faltaron\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":557986,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\\\/#mainImage\"},\"datePublished\":\"2014-07-07T16:00:40+02:00\",\"dateModified\":\"2014-07-07T16:00:40+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Atl\u00e9tico de Madrid arranca la pretemporada con dudas - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El Atl\u00e9tico de Madrid arranca la pretemporada con dudas - El Digital de Asturias","description":"Madrid, 7 jul (dpa) - El Atl\u00e9tico de Madrid, actual campe\u00f3n de la Liga espa\u00f1ola, comenz\u00f3 hoy sus entrenamientos de pretemporada con 24 jugadores, entre ellos los brasile\u00f1os Filipe Luis y Joao Miranda, y con un saco de dudas sobre el futuro de estos y otros jugadores. A la primera cita con el trabajo faltaron","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/","robots":"max-image-preview:large","keywords":"deportes","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/#blogposting","name":"El Atl\u00e9tico de Madrid arranca la pretemporada con dudas - El Digital de Asturias","headline":"El Atl\u00e9tico de Madrid arranca la pretemporada con dudas","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":557986},"datePublished":"2014-07-07T16:00:40+02:00","dateModified":"2014-07-07T16:00:40+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/#webpage"},"articleSection":"Deportes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","position":2,"name":"Deportes","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/#listItem","name":"El Atl\u00e9tico de Madrid arranca la pretemporada con dudas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/#listItem","position":3,"name":"El Atl\u00e9tico de Madrid arranca la pretemporada con dudas","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/","name":"El Atl\u00e9tico de Madrid arranca la pretemporada con dudas - El Digital de Asturias","description":"Madrid, 7 jul (dpa) - El Atl\u00e9tico de Madrid, actual campe\u00f3n de la Liga espa\u00f1ola, comenz\u00f3 hoy sus entrenamientos de pretemporada con 24 jugadores, entre ellos los brasile\u00f1os Filipe Luis y Joao Miranda, y con un saco de dudas sobre el futuro de estos y otros jugadores. A la primera cita con el trabajo faltaron","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":557986,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/#mainImage"},"datePublished":"2014-07-07T16:00:40+02:00","dateModified":"2014-07-07T16:00:40+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"El Atl\u00e9tico de Madrid arranca la pretemporada con dudas - El Digital de Asturias","og:description":"Madrid, 7 jul (dpa) - El Atl\u00e9tico de Madrid, actual campe\u00f3n de la Liga espa\u00f1ola, comenz\u00f3 hoy sus entrenamientos de pretemporada con 24 jugadores, entre ellos los brasile\u00f1os Filipe Luis y Joao Miranda, y con un saco de dudas sobre el futuro de estos y otros jugadores. A la primera cita con el trabajo faltaron","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/","article:tag":["deportes"],"article:published_time":"2014-07-07T17:00:40+00:00","article:modified_time":"2014-07-07T17:00:40+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"El Atl\u00e9tico de Madrid arranca la pretemporada con dudas - El Digital de Asturias","twitter:description":"Madrid, 7 jul (dpa) - El Atl\u00e9tico de Madrid, actual campe\u00f3n de la Liga espa\u00f1ola, comenz\u00f3 hoy sus entrenamientos de pretemporada con 24 jugadores, entre ellos los brasile\u00f1os Filipe Luis y Joao Miranda, y con un saco de dudas sobre el futuro de estos y otros jugadores. A la primera cita con el trabajo faltaron","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"4 minutos"},"aioseo_meta_data":{"post_id":"557999","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-06-17 16:52:53","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-11-14 23:29:17","updated":"2026-06-17 16:52:53"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/\" title=\"Deportes\">Deportes<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/\" title=\"El Atl\u00e9tico de Madrid arranca la pretemporada con dudas\">El Atl\u00e9tico de Madrid arranca la pretemporada con dudas<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Deportes","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/"},{"label":"El Atl\u00e9tico de Madrid arranca la pretemporada con dudas","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-atletico-de-madrid-arranca-la-pretemporada-con-dudas\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/557999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=557999"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/557999\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=557999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=557999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=557999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}