{"id":535290,"date":"2014-05-25T00:13:50","date_gmt":"2014-05-25T01:13:50","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=535290"},"modified":"2014-05-25T00:13:50","modified_gmt":"2014-05-25T01:13:50","slug":"el-madrid-gana-la-decima-copa-de-europa","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/","title":{"rendered":"El Madrid gana la d\u00e9cima Copa de Europa"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-535291\" alt=\"6297544w\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2014\/05\/6297544w-360x239.jpg\" width=\"360\" height=\"239\" \/>Lisboa, 24 may (dpa) &#8211; El Real Madrid se consagr\u00f3 hoy como rey de Europa por d\u00e9cima vez en su historia gracias a una victoria por 4-1 sobre el Atl\u00e9tico de Madrid en la pr\u00f3rroga de la final de la Liga de Campeones.<\/p>\n<p>El equipo dirigido por el italiano Carlo Ancelotti recobr\u00f3 la vida en el tercer minuto de descuento del tiempo regular, gracias a un gol ag\u00f3nico de Sergio Ramos que le permiti\u00f3 disponer de media hora m\u00e1s para revertir el resultado en el estadio Da Luz.<\/p>\n<p>As\u00ed, el conjunto blanco se consolid\u00f3 como el equipo m\u00e1s ganador del m\u00e1ximo torneo continental y le puso fin a una sequ\u00eda de 12 a\u00f1os sin la gloria europea.<\/p>\n<p>Gareth Bale confirm\u00f3 la remontada en el minuto 110 y Marcelo, a los 117 minutos, y Cristiano Ronaldo, a los 119 minutos de penal, convirtieron el t\u00edtulo blanco en realidad.<\/p>\n<p>El Atl\u00e9tico, que hasta el minuto 93 era campe\u00f3n gracias al gol del uruguayo Diego God\u00edn a los 36 minutos, volvi\u00f3 a quedarse en las puertas de la gloria continental y revivi\u00f3 los fantasmas de 1974, cuando perdi\u00f3 su \u00fanica final anterior de la Copa de Europa.<\/p>\n<p>Hace 40 a\u00f1os, el Atl\u00e9tico vio c\u00f3mo se le escap\u00f3 el t\u00edtulo cuando, en el \u00faltimo minuto de la pr\u00f3rroga, el Bayern M\u00fanich empat\u00f3 la final 1-1 con un gol de Hans-Georg Schwarzenbeck y oblig\u00f3 a un duelo desempate en el que luego los b\u00e1varos ganar\u00edan con comodidad por 4-0.<\/p>\n<p>El partido de hoy en el estadio da Luz fue una fiesta desde cualquier punto de vista: el fervor constante en las gradas, la lesi\u00f3n de Diego Costa a los ocho minutos, un error grave de Iker Casillas que pudo significar la p\u00e9rdida del t\u00edtulo, y la remontada hist\u00f3rica de los blancos.<\/p>\n<p>La inclusi\u00f3n de Sami Khedira y de Diego Costa, quien apareci\u00f3 en el once inicial de milagro, representaron en el inicio el gran misterio del desarrollo del partido.<\/p>\n<p>Costa empez\u00f3 a esclarecer el enigma rojiblanco desde los primeros minutos. Su falta de intensidad evidenci\u00f3 sus problemas f\u00edsicos y la aventura del delantero en Lisboa dur\u00f3 apenas ocho minutos.<\/p>\n<p>El mejor atacante del Atl\u00e9tico no pudo contrarrestar su realidad f\u00edsica ni con la ayuda de la placenta de una yegua (recetado por una m\u00e9dica serbia) y abandon\u00f3 el partido por lesi\u00f3n a los ocho minutos.<\/p>\n<p>Reci\u00e9n despu\u00e9s de los diez minutos iniciales comenz\u00f3 la verdadera final de la Liga de Campeones. Ambos equipos afrontaron el primer tiempo con la idea de anular las armas de su rival antes que potenciar las ofensivas propias.<\/p>\n<p>El Atl\u00e9tico se empecin\u00f3 en evitar cualquier tipo de contraataque blanco y el Real Madrid se mantuvo conforme sin cometer faltas infantiles y regalarle balones parados a su rival cerca del \u00e1rea.<\/p>\n<p>Los dirigidos por Diego Simeone mostraron m\u00e1s actitud en el comienzo y expusieron mayor orden en el medio del campo, especialmente con el tridente formado por Gabi, Tiago y Ra\u00fal Garc\u00eda.<\/p>\n<p>Mientras tanto, el Real Madrid trataba de hacer pie con un mediocampo sin Xabi Alonso, suspendido, y con un Sami Khedira que hab\u00eda jugado menos de 90 minutos en los \u00faltimos cuatro meses.<\/p>\n<p>Las jugadas de peligro tardaron media hora en aparecer y, como era de esperar, surgieron por errores rivales.<\/p>\n<p>El Real Madrid desperdici\u00f3 su mejor oportunidad de la primera mitad a los 32 minutos, cuando Tiago le regal\u00f3 el bal\u00f3n a Bale en una salida y el gal\u00e9s tir\u00f3 el bal\u00f3n afuera dentro del \u00e1rea de un modo ins\u00f3lito.<\/p>\n<p>El gol del Atl\u00e9tico se produjo apenas cuatro minutos despu\u00e9s y tambi\u00e9n gracias a un error del rival. Juanfran lanz\u00f3 de cabeza el bal\u00f3n al coraz\u00f3n del \u00e1rea tras un despeje fallido de Raphael Varane y God\u00edn, el mismo que hab\u00eda dado el t\u00edtulo de Liga a su equipo en el Camp Nou, anotaba de cabeza.<\/p>\n<p>Gran parte de la responsabilidad repos\u00f3 nada menos que en Casillas, quien dud\u00f3 demasiado a la hora de salir a cortar el pase de Juanfr\u00e1n y qued\u00f3 a mitad de camino a la hora de atajar la pelota.<\/p>\n<p>El golpe dej\u00f3 al Real Madrid sin reacci\u00f3n reci\u00e9n hasta el segundo tiempo, cuando se vio obligado a plantar m\u00e1s jugadores en el campo rival y se mostr\u00f3 m\u00e1s incisivo en las bandas.<\/p>\n<p>Un tiro libre de Cristiano bien atajado por Courtois fue el primer s\u00edntoma de la nueva imagen del conjunto blanco.<\/p>\n<p>A falta de media hora, Ancelotti decidi\u00f3 los ingresos de Isco y Marcelo en lugar de Khedira y Coentrao. No qued\u00f3 claro si fue un cambio de estrategia obligado por el resultado en contra o la correcci\u00f3n de un planteo inicial fallido.<\/p>\n<p>Lo cierto es que el Real Madrid reaccion\u00f3 y amenaz\u00f3 con mucho peligro la porter\u00eda de Courtois, con un cabezazo desviado de Cristiano que Benzema no pudo empujar a la red y con un zurdazo de Bale apenas desviado desde la puerta del \u00e1rea.<\/p>\n<p>Los \u00faltimos 15 minutos fueron una tortura para ambos equipos: el Real Madrid se posicion\u00f3 definitivamente en los \u00faltimos 20 metros y fall\u00f3 goles de manera incre\u00edble y el Atl\u00e9tico se vio acorralado en su \u00e1rea sin poder respirar.<\/p>\n<p>La final parec\u00eda rojiblanca hasta el minuto 93, momento en que el Real Madrid sac\u00f3 a la luz su casta europea.<\/p>\n<p>Modric lanz\u00f3 un tiro de esquina al coraz\u00f3n del \u00e1rea y Ramos se elev\u00f3 entre todos para colocar la pelota de cabeza junto a un palo y hacer delirar a la mitad del estadio.<\/p>\n<p>Acorde al delirio de la afici\u00f3n blanca fue la desaz\u00f3n de los rojiblancos, que revivieron los fantasmas de 1974.<\/p>\n<p>La pr\u00f3rroga del \u00faltimo partido de la temporada para ambos equipos se convirti\u00f3 desde el primer minuto en un duelo de respuestas an\u00edmicas y resistencia f\u00edsica.<\/p>\n<p>Con los dos equipos agotados, el partido se defini\u00f3 en los \u00faltimos 10 minutos de la pr\u00f3rroga. Di Mar\u00eda volvi\u00f3 a hacer una de sus jugadas personales electrizantes sobre la derecha y provoc\u00f3 una atajada de Courtois, pero Bale se elev\u00f3 en el \u00e1rea peque\u00f1a para capturar el rebote anotar de cabeza el segundo tanto.<\/p>\n<p>Ya con el Atl\u00e9tico agotado f\u00edsica y mentalmente, el Real Madrid confirm\u00f3 su fiesta en los minutos finales con los dos goles de Marcelo y Cristiano Ronaldo, el m\u00e1ximo goleador de la edici\u00f3n actual de la Champions.<\/p>\n<p>FICHA DEL PARTIDO:<\/p>\n<p>REAL MADRID: Atl\u00e9tico; Carvajal, Varane, Ramos, Coentrao (59 m. Marcelo); Khedira (59 m. Isco), Modric, Di Mar\u00eda; Bale, Cristiano y Benzema'(79 m. Morata).<\/p>\n<p>ATL\u00c9TICO: Courtois; Juanfran, Miranda, God\u00edn, Filipe Luis (82 m. Alderweireld); Tiago, Gabi; R. Garc\u00eda (66 m. Sosa), Koke; Villa y Costa (8 m. Adri\u00e1n).<\/p>\n<p>GOLES: 0-1, 36 m. God\u00edn. 1-1 93 m. Ramos. 2-1 110 m. Bale. 3-1 117 m. Marcelo. 4-1 119 m. Cristiano Ronaldo, de penal.<\/p>\n<p>ARBITRO: Bjorn Kuipers (Holanda). Mostr\u00f3 tarjeta amarilla a R. Garc\u00eda, Ramos, Khedira, Miranda, Villa, Juanfran<\/p>\n<p>ESTADIO: Da Luz (Lisboa).<\/p>\n<p>Por Lars Reinefeld<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lisboa, 24 may (dpa) &#8211; El Real Madrid se consagr\u00f3 hoy como rey de Europa por d\u00e9cima vez en su historia gracias a una victoria por 4-1 sobre el Atl\u00e9tico de Madrid en la pr\u00f3rroga de la final de la Liga de Campeones. El equipo dirigido por el italiano Carlo Ancelotti recobr\u00f3 la vida en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1132184,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[190],"tags":[],"class_list":["post-535290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Lisboa, 24 may (dpa) - El Real Madrid se consagr\u00f3 hoy como rey de Europa por d\u00e9cima vez en su historia gracias a una victoria por 4-1 sobre el Atl\u00e9tico de Madrid en la pr\u00f3rroga de la final de la Liga de Campeones. El equipo dirigido por el italiano Carlo Ancelotti recobr\u00f3 la vida en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"deportes\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Madrid gana la d\u00e9cima Copa de Europa - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Lisboa, 24 may (dpa) - El Real Madrid se consagr\u00f3 hoy como rey de Europa por d\u00e9cima vez en su historia gracias a una victoria por 4-1 sobre el Atl\u00e9tico de Madrid en la pr\u00f3rroga de la final de la Liga de Campeones. El equipo dirigido por el italiano Carlo Ancelotti recobr\u00f3 la vida en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1265\" \/>\n\t\t<meta property=\"og:image:height\" content=\"697\" \/>\n\t\t<meta property=\"article:tag\" content=\"deportes\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-05-25T01:13:50+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-05-25T01:13:50+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Madrid gana la d\u00e9cima Copa de Europa - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Lisboa, 24 may (dpa) - El Real Madrid se consagr\u00f3 hoy como rey de Europa por d\u00e9cima vez en su historia gracias a una victoria por 4-1 sobre el Atl\u00e9tico de Madrid en la pr\u00f3rroga de la final de la Liga de Campeones. El equipo dirigido por el italiano Carlo Ancelotti recobr\u00f3 la vida en\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-madrid-gana-la-decima-copa-de-europa\\\/#blogposting\",\"name\":\"El Madrid gana la d\\u00e9cima Copa de Europa - El Digital de Asturias\",\"headline\":\"El Madrid gana la d\\u00e9cima Copa de Europa\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Contenidos.jpg\",\"width\":1265,\"height\":697,\"caption\":\"Contenidos\"},\"datePublished\":\"2014-05-25T00:13:50+02:00\",\"dateModified\":\"2014-05-25T00:13:50+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-madrid-gana-la-decima-copa-de-europa\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-madrid-gana-la-decima-copa-de-europa\\\/#webpage\"},\"articleSection\":\"Deportes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-madrid-gana-la-decima-copa-de-europa\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"position\":2,\"name\":\"Deportes\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-madrid-gana-la-decima-copa-de-europa\\\/#listItem\",\"name\":\"El Madrid gana la d\\u00e9cima Copa de Europa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-madrid-gana-la-decima-copa-de-europa\\\/#listItem\",\"position\":3,\"name\":\"El Madrid gana la d\\u00e9cima Copa de Europa\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-madrid-gana-la-decima-copa-de-europa\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-madrid-gana-la-decima-copa-de-europa\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-madrid-gana-la-decima-copa-de-europa\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-madrid-gana-la-decima-copa-de-europa\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-madrid-gana-la-decima-copa-de-europa\\\/\",\"name\":\"El Madrid gana la d\\u00e9cima Copa de Europa - El Digital de Asturias\",\"description\":\"Lisboa, 24 may (dpa) - El Real Madrid se consagr\\u00f3 hoy como rey de Europa por d\\u00e9cima vez en su historia gracias a una victoria por 4-1 sobre el Atl\\u00e9tico de Madrid en la pr\\u00f3rroga de la final de la Liga de Campeones. El equipo dirigido por el italiano Carlo Ancelotti recobr\\u00f3 la vida en\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-madrid-gana-la-decima-copa-de-europa\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Contenidos.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-madrid-gana-la-decima-copa-de-europa\\\/#mainImage\",\"width\":1265,\"height\":697,\"caption\":\"Contenidos\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-madrid-gana-la-decima-copa-de-europa\\\/#mainImage\"},\"datePublished\":\"2014-05-25T00:13:50+02:00\",\"dateModified\":\"2014-05-25T00:13:50+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Madrid gana la d\u00e9cima Copa de Europa - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El Madrid gana la d\u00e9cima Copa de Europa - El Digital de Asturias","description":"Lisboa, 24 may (dpa) - El Real Madrid se consagr\u00f3 hoy como rey de Europa por d\u00e9cima vez en su historia gracias a una victoria por 4-1 sobre el Atl\u00e9tico de Madrid en la pr\u00f3rroga de la final de la Liga de Campeones. El equipo dirigido por el italiano Carlo Ancelotti recobr\u00f3 la vida en","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/","robots":"max-image-preview:large","keywords":"deportes","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/#blogposting","name":"El Madrid gana la d\u00e9cima Copa de Europa - El Digital de Asturias","headline":"El Madrid gana la d\u00e9cima Copa de Europa","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","width":1265,"height":697,"caption":"Contenidos"},"datePublished":"2014-05-25T00:13:50+02:00","dateModified":"2014-05-25T00:13:50+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/#webpage"},"articleSection":"Deportes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","position":2,"name":"Deportes","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/#listItem","name":"El Madrid gana la d\u00e9cima Copa de Europa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/#listItem","position":3,"name":"El Madrid gana la d\u00e9cima Copa de Europa","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/","name":"El Madrid gana la d\u00e9cima Copa de Europa - El Digital de Asturias","description":"Lisboa, 24 may (dpa) - El Real Madrid se consagr\u00f3 hoy como rey de Europa por d\u00e9cima vez en su historia gracias a una victoria por 4-1 sobre el Atl\u00e9tico de Madrid en la pr\u00f3rroga de la final de la Liga de Campeones. El equipo dirigido por el italiano Carlo Ancelotti recobr\u00f3 la vida en","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/#mainImage","width":1265,"height":697,"caption":"Contenidos"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/#mainImage"},"datePublished":"2014-05-25T00:13:50+02:00","dateModified":"2014-05-25T00:13:50+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"El Madrid gana la d\u00e9cima Copa de Europa - El Digital de Asturias","og:description":"Lisboa, 24 may (dpa) - El Real Madrid se consagr\u00f3 hoy como rey de Europa por d\u00e9cima vez en su historia gracias a una victoria por 4-1 sobre el Atl\u00e9tico de Madrid en la pr\u00f3rroga de la final de la Liga de Campeones. El equipo dirigido por el italiano Carlo Ancelotti recobr\u00f3 la vida en","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/","og:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","og:image:secure_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","og:image:width":1265,"og:image:height":697,"article:tag":["deportes"],"article:published_time":"2014-05-25T01:13:50+00:00","article:modified_time":"2014-05-25T01:13:50+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"El Madrid gana la d\u00e9cima Copa de Europa - El Digital de Asturias","twitter:description":"Lisboa, 24 may (dpa) - El Real Madrid se consagr\u00f3 hoy como rey de Europa por d\u00e9cima vez en su historia gracias a una victoria por 4-1 sobre el Atl\u00e9tico de Madrid en la pr\u00f3rroga de la final de la Liga de Campeones. El equipo dirigido por el italiano Carlo Ancelotti recobr\u00f3 la vida en","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"6 minutos"},"aioseo_meta_data":{"post_id":"535290","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-06-13 05:17:48","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-11-14 23:19:11","updated":"2026-06-13 05:17:48"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/\" title=\"Deportes\">Deportes<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/\" title=\"El Madrid gana la d\u00e9cima Copa de Europa\">El Madrid gana la d\u00e9cima Copa de Europa<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Deportes","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/"},{"label":"El Madrid gana la d\u00e9cima Copa de Europa","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-madrid-gana-la-decima-copa-de-europa\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/535290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=535290"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/535290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media\/1132184"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=535290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=535290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=535290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}