{"id":481017,"date":"2014-01-31T13:11:32","date_gmt":"2014-01-31T14:11:32","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=481017"},"modified":"2014-01-31T13:11:32","modified_gmt":"2014-01-31T14:11:32","slug":"el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/","title":{"rendered":"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\u00e1s, pese a las p\u00e9rdidas por China"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-481018\" alt=\"5894381w\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2014\/01\/5894381w-360x239.jpg\" width=\"360\" height=\"239\" \/>Madrid, 31 ene (EFE).- El BBVA obtuvo un beneficio neto de 2.228 millones de euros en 2013, un 32,9 % m\u00e1s que el a\u00f1o anterior, ayudado por menores dotaciones a provisiones, plusval\u00edas por desinversiones y a pesar de las p\u00e9rdidas que se anot\u00f3 por la puesta en valor de mercado de su participaci\u00f3n en el banco chino CNCB.<\/p>\n<p>El banco llevaba ganados 3.077 millones hasta septiembre, pero en el \u00faltimo trimestre perdi\u00f3 849 millones porque, a pesar de que sum\u00f3 plusval\u00edas por 653 millones por la venta de su negocio en Panam\u00e1 y de la gestora de fondos en Chile, rest\u00f3 unos 2.600 millones antes de impuestos por su participaci\u00f3n en el chino CNCB.<\/p>\n<p>En la informaci\u00f3n remitida a la CNMV, el BBVA explica que tras la venta de un 5,1 % en el CNCB su participaci\u00f3n se redujo al 9,9 % y opt\u00f3 por considerarla como disponible para la venta, lo que requiere ponerla a precios de mercado y eso, por el momento, tiene un impacto contable negativo. Si bien, eso no quita para que en el futuro, si se revaloriza, el banco pueda anotarse plusval\u00edas.<\/p>\n<p>Al margen de esta singularidad, el BBVA cerr\u00f3 el pasado ejercicio con una tasa de morosidad del 6,8 %, frente al 5,1 % de 2012, incluyendo la actividad inmobiliaria en Espa\u00f1a.<\/p>\n<p>El cr\u00e9dito a la clientela se redujo el 4,7 %, hasta los 350.110 millones, mientras que los dep\u00f3sitos crecieron el 6 % y alcanzaron los 310.176 millones.<\/p>\n<p>En Espa\u00f1a, el BBVA vio caer su beneficio neto el 49,8 %, hasta los 583 millones, un resultado \u00abmuy influenciado\u00bb por la eliminaci\u00f3n de las \u00abcl\u00e1usulas suelo\u00bb y el incremento puntual de los saneamientos por la reclasificaci\u00f3n de cr\u00e9ditos refinanciados.<\/p>\n<p>En 2013, el BBVA continu\u00f3 invirtiendo en regiones emergentes, al tiempo que contuvo el gasto en los pa\u00edses desarrollados, una gesti\u00f3n que llev\u00f3 a un margen neto de 10.196 millones, un 8,2 % menos.<\/p>\n<p>En cuanto a la solvencia del grupo, el \u00abcore capital\u00bb o capital de m\u00e1xima calidad seg\u00fan Basilea II alcanz\u00f3 el 11,6 %, al tiempo que la ratio \u00abcore capital\u00bb \u00abfully loaded\u00bb, que asume todos los futuros impactos de la normativa, se situ\u00f3 en el 9,8 %.<\/p>\n<p>Sobre los principales m\u00e1rgenes de la cuenta, el de intereses se situ\u00f3 en 14.613 millones, un 3,4 % menos; el bruto, que refleja los ingresos m\u00e1s las comisiones, se redujo un 2,3 % y qued\u00f3 en 21.397 millones. El neto merm\u00f3 el 8,2 %, hasta 10.196 millones.<\/p>\n<p>Por \u00e1reas geogr\u00e1ficas, adem\u00e1s de los mencionados 583 millones ganados en Espa\u00f1a); en Eurasia -que incluye Turqu\u00eda y China- el beneficio neto del grupo se elev\u00f3 el 12,4 %, hasta los 454 millones, principalmente por el dinamismo del banco turco Garanti.<\/p>\n<p>En M\u00e9xico, principal motor de las cuentas del grupo, el beneficio neto creci\u00f3 el 6,8 % y sum\u00f3 1.805 millones, gracias a su acierto, tanto en inversi\u00f3n como en recursos.<\/p>\n<p>En Am\u00e9rica del Sur, por su parte, el beneficio avanz\u00f3 un 4,1 % y alcanz\u00f3 los 1.249 millones, mientras que en Estados Unidos, el BBVA gan\u00f3 390 millones, un 11,8 % menos.<\/p>\n<p>En el conjunto del a\u00f1o, la entidad obtuvo 823 millones gracias a \u00aboperaciones corporativas\u00bb, una nueva r\u00fabrica en la que incluye las plusval\u00edas por el acuerdo de reaseguro de la cartera de seguros de vida-riesgo individual en Espa\u00f1a, as\u00ed como los extraordinarios de inversiones y desinversiones en Unnim, BBVA Panam\u00e1 y BBVA Puerto Rico, as\u00ed como las p\u00e9rdidas por la puesta en valor de la participaci\u00f3n del 9,9 % en el chino CNCB.<\/p>\n<p>Para el BBVA, se trata de unos resultados globales \u00abmuy s\u00f3lidos, a pesar de la complejidad del entorno\u00bb, favorecidos por la diversificaci\u00f3n geogr\u00e1fica.<\/p>\n<p>\u00abLas perspectivas para 2014 han mejorado significativamente y en BBVA estamos en una posici\u00f3n inmejorable para responder al crecimiento de la demanda solvente de nuevo cr\u00e9dito\u00bb, ha destacado el presidente del banco, Francisco Gonz\u00e1lez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 31 ene (EFE).- El BBVA obtuvo un beneficio neto de 2.228 millones de euros en 2013, un 32,9 % m\u00e1s que el a\u00f1o anterior, ayudado por menores dotaciones a provisiones, plusval\u00edas por desinversiones y a pesar de las p\u00e9rdidas que se anot\u00f3 por la puesta en valor de mercado de su participaci\u00f3n en el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1132184,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-481017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 31 ene (EFE).- El BBVA obtuvo un beneficio neto de 2.228 millones de euros en 2013, un 32,9 % m\u00e1s que el a\u00f1o anterior, ayudado por menores dotaciones a provisiones, plusval\u00edas por desinversiones y a pesar de las p\u00e9rdidas que se anot\u00f3 por la puesta en valor de mercado de su participaci\u00f3n en el\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\u00e1s, pese a las p\u00e9rdidas por China - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 31 ene (EFE).- El BBVA obtuvo un beneficio neto de 2.228 millones de euros en 2013, un 32,9 % m\u00e1s que el a\u00f1o anterior, ayudado por menores dotaciones a provisiones, plusval\u00edas por desinversiones y a pesar de las p\u00e9rdidas que se anot\u00f3 por la puesta en valor de mercado de su participaci\u00f3n en el\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1265\" \/>\n\t\t<meta property=\"og:image:height\" content=\"697\" \/>\n\t\t<meta property=\"article:tag\" content=\"actualidad\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-01-31T14:11:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-01-31T14:11:32+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\u00e1s, pese a las p\u00e9rdidas por China - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 31 ene (EFE).- El BBVA obtuvo un beneficio neto de 2.228 millones de euros en 2013, un 32,9 % m\u00e1s que el a\u00f1o anterior, ayudado por menores dotaciones a provisiones, plusval\u00edas por desinversiones y a pesar de las p\u00e9rdidas que se anot\u00f3 por la puesta en valor de mercado de su participaci\u00f3n en el\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\\\/#blogposting\",\"name\":\"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\\u00e1s, pese a las p\\u00e9rdidas por China - El Digital de Asturias\",\"headline\":\"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\\u00e1s, pese a las p\\u00e9rdidas por China\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Contenidos.jpg\",\"width\":1265,\"height\":697,\"caption\":\"Contenidos\"},\"datePublished\":\"2014-01-31T13:11:32+01:00\",\"dateModified\":\"2014-01-31T13:11:32+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\\\/#webpage\"},\"articleSection\":\"Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\\\/#listItem\",\"name\":\"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\\u00e1s, pese a las p\\u00e9rdidas por China\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\\\/#listItem\",\"position\":3,\"name\":\"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\\u00e1s, pese a las p\\u00e9rdidas por China\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\\\/\",\"name\":\"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\\u00e1s, pese a las p\\u00e9rdidas por China - El Digital de Asturias\",\"description\":\"Madrid, 31 ene (EFE).- El BBVA obtuvo un beneficio neto de 2.228 millones de euros en 2013, un 32,9 % m\\u00e1s que el a\\u00f1o anterior, ayudado por menores dotaciones a provisiones, plusval\\u00edas por desinversiones y a pesar de las p\\u00e9rdidas que se anot\\u00f3 por la puesta en valor de mercado de su participaci\\u00f3n en el\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Contenidos.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\\\/#mainImage\",\"width\":1265,\"height\":697,\"caption\":\"Contenidos\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\\\/#mainImage\"},\"datePublished\":\"2014-01-31T13:11:32+01:00\",\"dateModified\":\"2014-01-31T13:11:32+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El BBVA gana 2.228 millones en 2013, un 33 por ciento m\u00e1s, pese a las p\u00e9rdidas por China - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\u00e1s, pese a las p\u00e9rdidas por China - El Digital de Asturias","description":"Madrid, 31 ene (EFE).- El BBVA obtuvo un beneficio neto de 2.228 millones de euros en 2013, un 32,9 % m\u00e1s que el a\u00f1o anterior, ayudado por menores dotaciones a provisiones, plusval\u00edas por desinversiones y a pesar de las p\u00e9rdidas que se anot\u00f3 por la puesta en valor de mercado de su participaci\u00f3n en el","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/#blogposting","name":"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\u00e1s, pese a las p\u00e9rdidas por China - El Digital de Asturias","headline":"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\u00e1s, pese a las p\u00e9rdidas por China","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","width":1265,"height":697,"caption":"Contenidos"},"datePublished":"2014-01-31T13:11:32+01:00","dateModified":"2014-01-31T13:11:32+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/#webpage"},"articleSection":"Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/#listItem","name":"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\u00e1s, pese a las p\u00e9rdidas por China"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/#listItem","position":3,"name":"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\u00e1s, pese a las p\u00e9rdidas por China","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/","name":"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\u00e1s, pese a las p\u00e9rdidas por China - El Digital de Asturias","description":"Madrid, 31 ene (EFE).- El BBVA obtuvo un beneficio neto de 2.228 millones de euros en 2013, un 32,9 % m\u00e1s que el a\u00f1o anterior, ayudado por menores dotaciones a provisiones, plusval\u00edas por desinversiones y a pesar de las p\u00e9rdidas que se anot\u00f3 por la puesta en valor de mercado de su participaci\u00f3n en el","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/#mainImage","width":1265,"height":697,"caption":"Contenidos"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/#mainImage"},"datePublished":"2014-01-31T13:11:32+01:00","dateModified":"2014-01-31T13:11:32+01:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\u00e1s, pese a las p\u00e9rdidas por China - El Digital de Asturias","og:description":"Madrid, 31 ene (EFE).- El BBVA obtuvo un beneficio neto de 2.228 millones de euros en 2013, un 32,9 % m\u00e1s que el a\u00f1o anterior, ayudado por menores dotaciones a provisiones, plusval\u00edas por desinversiones y a pesar de las p\u00e9rdidas que se anot\u00f3 por la puesta en valor de mercado de su participaci\u00f3n en el","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/","og:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","og:image:secure_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","og:image:width":1265,"og:image:height":697,"article:tag":["actualidad"],"article:published_time":"2014-01-31T14:11:32+00:00","article:modified_time":"2014-01-31T14:11:32+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\u00e1s, pese a las p\u00e9rdidas por China - El Digital de Asturias","twitter:description":"Madrid, 31 ene (EFE).- El BBVA obtuvo un beneficio neto de 2.228 millones de euros en 2013, un 32,9 % m\u00e1s que el a\u00f1o anterior, ayudado por menores dotaciones a provisiones, plusval\u00edas por desinversiones y a pesar de las p\u00e9rdidas que se anot\u00f3 por la puesta en valor de mercado de su participaci\u00f3n en el","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"481017","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-06-02 05:30:29","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-11-14 22:54:16","updated":"2026-06-02 05:30:29","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/\" title=\"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\u00e1s, pese a las p\u00e9rdidas por China\">El BBVA gana 2.228 millones en 2013, un 33 por ciento m\u00e1s, pese a las p\u00e9rdidas por China<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Actualidad","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/"},{"label":"El BBVA gana 2.228 millones en 2013, un 33 por ciento m\u00e1s, pese a las p\u00e9rdidas por China","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-bbva-gana-2-228-millones-en-2013-un-33-por-ciento-mas-pese-a-las-perdidas-por-china\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/481017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=481017"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/481017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media\/1132184"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=481017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=481017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=481017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}