{"id":480384,"date":"2014-01-30T01:54:52","date_gmt":"2014-01-30T02:54:52","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=480384"},"modified":"2014-01-30T01:54:52","modified_gmt":"2014-01-30T02:54:52","slug":"google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/","title":{"rendered":"Google vende Motorola a Lenovo por 2.910 millones de d\u00f3lares"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-480385\" alt=\"5889855w\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2014\/01\/5889855w-360x234.jpg\" width=\"360\" height=\"234\" \/>Los \u00c1ngeles (EE.UU.), 29 ene (EFE).- Google anunci\u00f3 hoy la venta de su filial de telefon\u00eda m\u00f3vil Motorola Mobility al gigante chino Lenovo por 2.910 millones de d\u00f3lares.<\/p>\n<p>La venta se produce apenas dos a\u00f1os y medio despu\u00e9s de que Google comprase la compa\u00f1\u00eda de telefon\u00eda m\u00f3vil por 12.500 millones de d\u00f3lares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los \u00c1ngeles (EE.UU.), 29 ene (EFE).- Google anunci\u00f3 hoy la venta de su filial de telefon\u00eda m\u00f3vil Motorola Mobility al gigante chino Lenovo por 2.910 millones de d\u00f3lares. La venta se produce apenas dos a\u00f1os y medio despu\u00e9s de que Google comprase la compa\u00f1\u00eda de telefon\u00eda m\u00f3vil por 12.500 millones de d\u00f3lares.<\/p>\n","protected":false},"author":1,"featured_media":1132184,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-480384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los \u00c1ngeles (EE.UU.), 29 ene (EFE).- Google anunci\u00f3 hoy la venta de su filial de telefon\u00eda m\u00f3vil Motorola Mobility al gigante chino Lenovo por 2.910 millones de d\u00f3lares. La venta se produce apenas dos a\u00f1os y medio despu\u00e9s de que Google comprase la compa\u00f1\u00eda de telefon\u00eda m\u00f3vil por 12.500 millones de d\u00f3lares.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Google vende Motorola a Lenovo por 2.910 millones de d\u00f3lares - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Los \u00c1ngeles (EE.UU.), 29 ene (EFE).- Google anunci\u00f3 hoy la venta de su filial de telefon\u00eda m\u00f3vil Motorola Mobility al gigante chino Lenovo por 2.910 millones de d\u00f3lares. La venta se produce apenas dos a\u00f1os y medio despu\u00e9s de que Google comprase la compa\u00f1\u00eda de telefon\u00eda m\u00f3vil por 12.500 millones de d\u00f3lares.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1265\" \/>\n\t\t<meta property=\"og:image:height\" content=\"697\" \/>\n\t\t<meta property=\"article:tag\" content=\"actualidad\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-01-30T02:54:52+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-01-30T02:54:52+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Google vende Motorola a Lenovo por 2.910 millones de d\u00f3lares - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los \u00c1ngeles (EE.UU.), 29 ene (EFE).- Google anunci\u00f3 hoy la venta de su filial de telefon\u00eda m\u00f3vil Motorola Mobility al gigante chino Lenovo por 2.910 millones de d\u00f3lares. La venta se produce apenas dos a\u00f1os y medio despu\u00e9s de que Google comprase la compa\u00f1\u00eda de telefon\u00eda m\u00f3vil por 12.500 millones de d\u00f3lares.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\\\/#blogposting\",\"name\":\"Google vende Motorola a Lenovo por 2.910 millones de d\\u00f3lares - El Digital de Asturias\",\"headline\":\"Google vende Motorola a Lenovo por 2.910 millones de d\\u00f3lares\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Contenidos.jpg\",\"width\":1265,\"height\":697,\"caption\":\"Contenidos\"},\"datePublished\":\"2014-01-30T01:54:52+01:00\",\"dateModified\":\"2014-01-30T01:54:52+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\\\/#webpage\"},\"articleSection\":\"Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\\\/#listItem\",\"name\":\"Google vende Motorola a Lenovo por 2.910 millones de d\\u00f3lares\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\\\/#listItem\",\"position\":3,\"name\":\"Google vende Motorola a Lenovo por 2.910 millones de d\\u00f3lares\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\\\/\",\"name\":\"Google vende Motorola a Lenovo por 2.910 millones de d\\u00f3lares - El Digital de Asturias\",\"description\":\"Los \\u00c1ngeles (EE.UU.), 29 ene (EFE).- Google anunci\\u00f3 hoy la venta de su filial de telefon\\u00eda m\\u00f3vil Motorola Mobility al gigante chino Lenovo por 2.910 millones de d\\u00f3lares. La venta se produce apenas dos a\\u00f1os y medio despu\\u00e9s de que Google comprase la compa\\u00f1\\u00eda de telefon\\u00eda m\\u00f3vil por 12.500 millones de d\\u00f3lares.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Contenidos.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\\\/#mainImage\",\"width\":1265,\"height\":697,\"caption\":\"Contenidos\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\\\/#mainImage\"},\"datePublished\":\"2014-01-30T01:54:52+01:00\",\"dateModified\":\"2014-01-30T01:54:52+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Google vende Motorola a Lenovo por 2.910 millones de d\u00f3lares - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Google vende Motorola a Lenovo por 2.910 millones de d\u00f3lares - El Digital de Asturias","description":"Los \u00c1ngeles (EE.UU.), 29 ene (EFE).- Google anunci\u00f3 hoy la venta de su filial de telefon\u00eda m\u00f3vil Motorola Mobility al gigante chino Lenovo por 2.910 millones de d\u00f3lares. La venta se produce apenas dos a\u00f1os y medio despu\u00e9s de que Google comprase la compa\u00f1\u00eda de telefon\u00eda m\u00f3vil por 12.500 millones de d\u00f3lares.","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/#blogposting","name":"Google vende Motorola a Lenovo por 2.910 millones de d\u00f3lares - El Digital de Asturias","headline":"Google vende Motorola a Lenovo por 2.910 millones de d\u00f3lares","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","width":1265,"height":697,"caption":"Contenidos"},"datePublished":"2014-01-30T01:54:52+01:00","dateModified":"2014-01-30T01:54:52+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/#webpage"},"articleSection":"Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/#listItem","name":"Google vende Motorola a Lenovo por 2.910 millones de d\u00f3lares"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/#listItem","position":3,"name":"Google vende Motorola a Lenovo por 2.910 millones de d\u00f3lares","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/","name":"Google vende Motorola a Lenovo por 2.910 millones de d\u00f3lares - El Digital de Asturias","description":"Los \u00c1ngeles (EE.UU.), 29 ene (EFE).- Google anunci\u00f3 hoy la venta de su filial de telefon\u00eda m\u00f3vil Motorola Mobility al gigante chino Lenovo por 2.910 millones de d\u00f3lares. La venta se produce apenas dos a\u00f1os y medio despu\u00e9s de que Google comprase la compa\u00f1\u00eda de telefon\u00eda m\u00f3vil por 12.500 millones de d\u00f3lares.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/#mainImage","width":1265,"height":697,"caption":"Contenidos"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/#mainImage"},"datePublished":"2014-01-30T01:54:52+01:00","dateModified":"2014-01-30T01:54:52+01:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Google vende Motorola a Lenovo por 2.910 millones de d\u00f3lares - El Digital de Asturias","og:description":"Los \u00c1ngeles (EE.UU.), 29 ene (EFE).- Google anunci\u00f3 hoy la venta de su filial de telefon\u00eda m\u00f3vil Motorola Mobility al gigante chino Lenovo por 2.910 millones de d\u00f3lares. La venta se produce apenas dos a\u00f1os y medio despu\u00e9s de que Google comprase la compa\u00f1\u00eda de telefon\u00eda m\u00f3vil por 12.500 millones de d\u00f3lares.","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/","og:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","og:image:secure_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","og:image:width":1265,"og:image:height":697,"article:tag":["actualidad"],"article:published_time":"2014-01-30T02:54:52+00:00","article:modified_time":"2014-01-30T02:54:52+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Google vende Motorola a Lenovo por 2.910 millones de d\u00f3lares - El Digital de Asturias","twitter:description":"Los \u00c1ngeles (EE.UU.), 29 ene (EFE).- Google anunci\u00f3 hoy la venta de su filial de telefon\u00eda m\u00f3vil Motorola Mobility al gigante chino Lenovo por 2.910 millones de d\u00f3lares. La venta se produce apenas dos a\u00f1os y medio despu\u00e9s de que Google comprase la compa\u00f1\u00eda de telefon\u00eda m\u00f3vil por 12.500 millones de d\u00f3lares.","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias"},"aioseo_meta_data":{"post_id":"480384","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-06-02 03:33:57","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-11-14 22:54:10","updated":"2026-06-02 03:33:57","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/\" title=\"Google vende Motorola a Lenovo por 2.910 millones de d\u00f3lares\">Google vende Motorola a Lenovo por 2.910 millones de d\u00f3lares<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Actualidad","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/"},{"label":"Google vende Motorola a Lenovo por 2.910 millones de d\u00f3lares","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/google-vende-motorola-a-lenovo-por-2-910-millones-de-dolares\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/480384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=480384"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/480384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media\/1132184"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=480384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=480384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=480384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}