{"id":480333,"date":"2014-01-30T00:38:45","date_gmt":"2014-01-30T01:38:45","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=480333"},"modified":"2014-01-30T00:38:45","modified_gmt":"2014-01-30T01:38:45","slug":"occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/","title":{"rendered":"Occidente dobla el suministro de armas a los rebeldes Sirios"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-453154\" alt=\"5749312wsiria\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2013\/11\/5749312w-360x239.jpg\" width=\"360\" height=\"239\" \/>Amm\u00e1n, 29 ene (dpa) &#8211; Las naciones occidentales est\u00e1n pr\u00e1cticamente doblando sus suministros de armas a los rebeldes sirios, informaron oficiales rebeldes y fuentes diplom\u00e1ticos, lo que podr\u00eda poner en peligro las negociaciones de paz entre el gobierno y la oposici\u00f3n que se llevan a cabo en Ginebra.<\/p>\n<p>La informaci\u00f3n provoc\u00f3 el enfado del viceministro de Exteriores sirio, Feisal al Meqdad, que acus\u00f3 desde Ginebra el martes a Washington de suministrar armas a \u00abgrupos terroristas\u00bb. Damasco emiti\u00f3 un comunicado separado acusando a Estados Unidos de minar las conversaciones de Ginebra 2.<\/p>\n<p>Seg\u00fan informaci\u00f3n de los rebeldes, Estados Unidos ha duplicado sus suministros de armas ligeras y municiones a los rebeldes vinculados con el Comando Militar Supremo del Ej\u00e9rcito Libre de Siria (ELS) en enero, entregando m\u00e1s de 600 toneladas de ayuda miltiar a los rebeldes desde el lanzamiento de las conversacionse de paz el 22 de enero.<\/p>\n<p>\u00abHemos visto el doble de la cantidad de armas entregadas desde Estados Unidos, Francia, Arabia Saud\u00ed y Qatar\u00bb, dijo Abu Mohamed al Quneitri, l\u00edder de la inteligencia del ELS en el sur del pa\u00eds, donde se hicieron la mayor\u00eda de las entregas. \u00abNo han hecho que logremos a\u00fan avances militares, pero nos mantienen con vida\u00bb.<\/p>\n<p>Ello formar\u00eda parte de un aumento del apoyo occidental a los rebeldes moderados, que sufrieron una serie de derrotas por parte de las fuerzas del gobierno de Bashar al Assad, pero tambi\u00e9n por ataques de grupos yihadistas.<\/p>\n<p>El Comando Militar supremo del ELS, alineado con la Coalici\u00f3n Nacional Siria y respaldado por el Golfo y por Occidente, se ha visto eclipsado por el Frente Isl\u00e1mico formado en noviembre que a\u00fana algunas de las mayores fuerzas rebeldes.<\/p>\n<p>Un diplom\u00e1tico estadounidense en Amm\u00e1n confirm\u00f3 el aumento de los env\u00edos, que supuestamente se aprob\u00f3 en una votaci\u00f3n del Congreso a puerta cerrada sobre el presupuesto anual de defensa y que prev\u00e9 apoyar al ELS en su defensa contra las fuerzas de Al Qaeda.<\/p>\n<p>Oficialmente Estados Unidos hab\u00eda dicho que congel\u00f3 su ayuda militar a los grupos rebeldes, pero el funcionario se\u00f1al\u00f3 que las condiciones sobre el terreno han cambiado ahora.<\/p>\n<p>Seg\u00fan el estadounidense, Washington estar\u00eda considerando incluso extender parte de los suministros a grupos fuera del ELS, incluso al Frente Isl\u00e1mico, para ayudarlos en su lucha contra el Estado Isl\u00e1mico de Irak y Siria (ISIS), cercano a Al Qaeda.<\/p>\n<p>Sin embargo hasta ahora, todas las armas entregadas siguen en manos de las fuerzas moderadas del ELS, se\u00f1alaron fuentes rebeldes y diplom\u00e1ticas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amm\u00e1n, 29 ene (dpa) &#8211; Las naciones occidentales est\u00e1n pr\u00e1cticamente doblando sus suministros de armas a los rebeldes sirios, informaron oficiales rebeldes y fuentes diplom\u00e1ticos, lo que podr\u00eda poner en peligro las negociaciones de paz entre el gobierno y la oposici\u00f3n que se llevan a cabo en Ginebra. La informaci\u00f3n provoc\u00f3 el enfado del viceministro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":453154,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-480333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Amm\u00e1n, 29 ene (dpa) - Las naciones occidentales est\u00e1n pr\u00e1cticamente doblando sus suministros de armas a los rebeldes sirios, informaron oficiales rebeldes y fuentes diplom\u00e1ticos, lo que podr\u00eda poner en peligro las negociaciones de paz entre el gobierno y la oposici\u00f3n que se llevan a cabo en Ginebra. La informaci\u00f3n provoc\u00f3 el enfado del viceministro\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Occidente dobla el suministro de armas a los rebeldes Sirios - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Amm\u00e1n, 29 ene (dpa) - Las naciones occidentales est\u00e1n pr\u00e1cticamente doblando sus suministros de armas a los rebeldes sirios, informaron oficiales rebeldes y fuentes diplom\u00e1ticos, lo que podr\u00eda poner en peligro las negociaciones de paz entre el gobierno y la oposici\u00f3n que se llevan a cabo en Ginebra. La informaci\u00f3n provoc\u00f3 el enfado del viceministro\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"actualidad\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-01-30T01:38:45+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-01-30T01:38:45+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Occidente dobla el suministro de armas a los rebeldes Sirios - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Amm\u00e1n, 29 ene (dpa) - Las naciones occidentales est\u00e1n pr\u00e1cticamente doblando sus suministros de armas a los rebeldes sirios, informaron oficiales rebeldes y fuentes diplom\u00e1ticos, lo que podr\u00eda poner en peligro las negociaciones de paz entre el gobierno y la oposici\u00f3n que se llevan a cabo en Ginebra. La informaci\u00f3n provoc\u00f3 el enfado del viceministro\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\\\/#blogposting\",\"name\":\"Occidente dobla el suministro de armas a los rebeldes Sirios - El Digital de Asturias\",\"headline\":\"Occidente dobla el suministro de armas a los rebeldes Sirios\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":453154},\"datePublished\":\"2014-01-30T00:38:45+01:00\",\"dateModified\":\"2014-01-30T00:38:45+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\\\/#webpage\"},\"articleSection\":\"Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\\\/#listItem\",\"name\":\"Occidente dobla el suministro de armas a los rebeldes Sirios\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\\\/#listItem\",\"position\":3,\"name\":\"Occidente dobla el suministro de armas a los rebeldes Sirios\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\\\/\",\"name\":\"Occidente dobla el suministro de armas a los rebeldes Sirios - El Digital de Asturias\",\"description\":\"Amm\\u00e1n, 29 ene (dpa) - Las naciones occidentales est\\u00e1n pr\\u00e1cticamente doblando sus suministros de armas a los rebeldes sirios, informaron oficiales rebeldes y fuentes diplom\\u00e1ticos, lo que podr\\u00eda poner en peligro las negociaciones de paz entre el gobierno y la oposici\\u00f3n que se llevan a cabo en Ginebra. La informaci\\u00f3n provoc\\u00f3 el enfado del viceministro\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":453154,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\\\/#mainImage\"},\"datePublished\":\"2014-01-30T00:38:45+01:00\",\"dateModified\":\"2014-01-30T00:38:45+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Occidente dobla el suministro de armas a los rebeldes Sirios - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Occidente dobla el suministro de armas a los rebeldes Sirios - El Digital de Asturias","description":"Amm\u00e1n, 29 ene (dpa) - Las naciones occidentales est\u00e1n pr\u00e1cticamente doblando sus suministros de armas a los rebeldes sirios, informaron oficiales rebeldes y fuentes diplom\u00e1ticos, lo que podr\u00eda poner en peligro las negociaciones de paz entre el gobierno y la oposici\u00f3n que se llevan a cabo en Ginebra. La informaci\u00f3n provoc\u00f3 el enfado del viceministro","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/#blogposting","name":"Occidente dobla el suministro de armas a los rebeldes Sirios - El Digital de Asturias","headline":"Occidente dobla el suministro de armas a los rebeldes Sirios","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":453154},"datePublished":"2014-01-30T00:38:45+01:00","dateModified":"2014-01-30T00:38:45+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/#webpage"},"articleSection":"Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/#listItem","name":"Occidente dobla el suministro de armas a los rebeldes Sirios"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/#listItem","position":3,"name":"Occidente dobla el suministro de armas a los rebeldes Sirios","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/","name":"Occidente dobla el suministro de armas a los rebeldes Sirios - El Digital de Asturias","description":"Amm\u00e1n, 29 ene (dpa) - Las naciones occidentales est\u00e1n pr\u00e1cticamente doblando sus suministros de armas a los rebeldes sirios, informaron oficiales rebeldes y fuentes diplom\u00e1ticos, lo que podr\u00eda poner en peligro las negociaciones de paz entre el gobierno y la oposici\u00f3n que se llevan a cabo en Ginebra. La informaci\u00f3n provoc\u00f3 el enfado del viceministro","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":453154,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/#mainImage"},"datePublished":"2014-01-30T00:38:45+01:00","dateModified":"2014-01-30T00:38:45+01:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Occidente dobla el suministro de armas a los rebeldes Sirios - El Digital de Asturias","og:description":"Amm\u00e1n, 29 ene (dpa) - Las naciones occidentales est\u00e1n pr\u00e1cticamente doblando sus suministros de armas a los rebeldes sirios, informaron oficiales rebeldes y fuentes diplom\u00e1ticos, lo que podr\u00eda poner en peligro las negociaciones de paz entre el gobierno y la oposici\u00f3n que se llevan a cabo en Ginebra. La informaci\u00f3n provoc\u00f3 el enfado del viceministro","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/","article:tag":["actualidad"],"article:published_time":"2014-01-30T01:38:45+00:00","article:modified_time":"2014-01-30T01:38:45+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Occidente dobla el suministro de armas a los rebeldes Sirios - El Digital de Asturias","twitter:description":"Amm\u00e1n, 29 ene (dpa) - Las naciones occidentales est\u00e1n pr\u00e1cticamente doblando sus suministros de armas a los rebeldes sirios, informaron oficiales rebeldes y fuentes diplom\u00e1ticos, lo que podr\u00eda poner en peligro las negociaciones de paz entre el gobierno y la oposici\u00f3n que se llevan a cabo en Ginebra. La informaci\u00f3n provoc\u00f3 el enfado del viceministro","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"480333","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-06-02 03:23:57","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-11-14 22:54:10","updated":"2026-06-02 03:23:57","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/\" title=\"Occidente dobla el suministro de armas a los rebeldes Sirios\">Occidente dobla el suministro de armas a los rebeldes Sirios<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Actualidad","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/"},{"label":"Occidente dobla el suministro de armas a los rebeldes Sirios","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/occidente-dobla-el-suministro-de-armas-a-los-rebeldes-sirios\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/480333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=480333"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/480333\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=480333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=480333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=480333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}