{"id":479474,"date":"2014-01-27T14:12:12","date_gmt":"2014-01-27T15:12:12","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=479474"},"modified":"2014-01-27T14:12:12","modified_gmt":"2014-01-27T15:12:12","slug":"las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/","title":{"rendered":"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-479475\" alt=\"5878584w\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2014\/01\/5878584w-360x262.jpg\" width=\"360\" height=\"262\" \/>Shangh\u00e1i (China), 27 ene (EFE).- Las obras de la Torre de Shangh\u00e1i, que en 2015 se inaugurar\u00e1 como en el segundo rascacielos m\u00e1s alto del mundo, con 632 metros, alcanzaron ya los 603 metros, por encima ya de los 601 metros del Makkah Royal Clock Tower Hotel de La Meca (Arabia Saud\u00ed), que a\u00fan es el segundo mayor terminado.<\/p>\n<p>La construcci\u00f3n del edificio est\u00e1 por ahora dentro de lo planificado, por lo que se espera que su estructura quede completamente terminada este mismo a\u00f1o, seg\u00fan publica hoy el diario oficial \u00abShanghai Daily\u00bb, organismo de difusi\u00f3n del Gobierno de Shangh\u00e1i.<\/p>\n<p>El rascacielos chino, que ser\u00e1 superado s\u00f3lo en altura por la torre Burj Khalifa de Dub\u00e1i (Emiratos \u00c1rabes Unidos), de 163 pisos y 828 metros, lleva seis a\u00f1os creciendo en el coraz\u00f3n de Lujiazui, el futurista barrio financiero de Shangh\u00e1i, entre cuyo bosque de centenares rascacielos hay algunos de los m\u00e1s altos del planeta.<\/p>\n<p>En su horizonte destacan emblem\u00e1ticos edificios gigantescos como el Centro Financiero Mundial de Shangh\u00e1i (el rascacielos m\u00e1s alto de China y sexto mayor del planeta, con 101 pisos y 492 metros), la torre Jin Mao (decimosexto mayor, con 88 pisos y 421 metros) y la emblem\u00e1tica torre de televisi\u00f3n Perla de Oriente (468 metros).<\/p>\n<p>La estructura de la Torre de Shangh\u00e1i, que empez\u00f3 a ser construida en 2008 y tendr\u00e1 127 pisos y 632 metros de altura, est\u00e1 dot\u00e1ndose en estos momentos de una subestaci\u00f3n el\u00e9ctrica subterr\u00e1nea que suministrar\u00e1 de energ\u00eda a todo el inmueble.<\/p>\n<p>El edificio dispondr\u00e1 de 381.600 metros cuadrados de superficie \u00fatil, de los cuales 210.000 estar\u00e1n destinados a oficinas.<\/p>\n<p>La torre contar\u00e1 con un observatorio tur\u00edstico en el piso 100, como ya lo tienen el Centro Financiero Mundial, conocido popularmente como el \u00abAbrebotellas\u00bb por el enorme vano trapezoidal que corona su fachada, en el 101, y la torre Jin Mao, en el 88.<\/p>\n<p>Aunque el mirador tendr\u00e1 todav\u00eda otros 20 pisos por encima, ser\u00e1 el m\u00e1s alto del mundo abierto al p\u00fablico, a 474 metros de altura, al menos como mirador cubierto, ya que est\u00e1 por encima de los 452 metros del mirador de la torre Burj Khalifa y tambi\u00e9n de los 449 del de la Torre de Cant\u00f3n, en la ciudad china del mismo nombre.<\/p>\n<p>Con todo, ser\u00e1 la misma Torre de Cant\u00f3n la que seguir\u00e1 manteniendo por ahora el r\u00e9cord mundial de mirador m\u00e1s alto del mundo abierto al aire libre, con el que tiene a 488 metros, en pleno centro financiero de la metr\u00f3poli suroriental china.<\/p>\n<p>Al sumarse al \u00abAbrebotellas\u00bb y a la torre Jin Mao, con la apertura, en 2015, de la Torre de Shangh\u00e1i, se cumplir\u00e1 el ambicioso plan del Gobierno de Shangh\u00e1i, anunciado en 1993, de levantar tres grandes rascacielos emblem\u00e1ticos en un terreno de 20.300 metros cuadrados, hasta entonces utilizado como campo de golf.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shangh\u00e1i (China), 27 ene (EFE).- Las obras de la Torre de Shangh\u00e1i, que en 2015 se inaugurar\u00e1 como en el segundo rascacielos m\u00e1s alto del mundo, con 632 metros, alcanzaron ya los 603 metros, por encima ya de los 601 metros del Makkah Royal Clock Tower Hotel de La Meca (Arabia Saud\u00ed), que a\u00fan es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1132184,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-479474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Shangh\u00e1i (China), 27 ene (EFE).- Las obras de la Torre de Shangh\u00e1i, que en 2015 se inaugurar\u00e1 como en el segundo rascacielos m\u00e1s alto del mundo, con 632 metros, alcanzaron ya los 603 metros, por encima ya de los 601 metros del Makkah Royal Clock Tower Hotel de La Meca (Arabia Saud\u00ed), que a\u00fan es\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"actualidad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Shangh\u00e1i (China), 27 ene (EFE).- Las obras de la Torre de Shangh\u00e1i, que en 2015 se inaugurar\u00e1 como en el segundo rascacielos m\u00e1s alto del mundo, con 632 metros, alcanzaron ya los 603 metros, por encima ya de los 601 metros del Makkah Royal Clock Tower Hotel de La Meca (Arabia Saud\u00ed), que a\u00fan es\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1265\" \/>\n\t\t<meta property=\"og:image:height\" content=\"697\" \/>\n\t\t<meta property=\"article:tag\" content=\"actualidad\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-01-27T15:12:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-01-27T15:12:12+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Shangh\u00e1i (China), 27 ene (EFE).- Las obras de la Torre de Shangh\u00e1i, que en 2015 se inaugurar\u00e1 como en el segundo rascacielos m\u00e1s alto del mundo, con 632 metros, alcanzaron ya los 603 metros, por encima ya de los 601 metros del Makkah Royal Clock Tower Hotel de La Meca (Arabia Saud\u00ed), que a\u00fan es\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\\\/#blogposting\",\"name\":\"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros - El Digital de Asturias\",\"headline\":\"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Contenidos.jpg\",\"width\":1265,\"height\":697,\"caption\":\"Contenidos\"},\"datePublished\":\"2014-01-27T14:12:12+01:00\",\"dateModified\":\"2014-01-27T14:12:12+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\\\/#webpage\"},\"articleSection\":\"Actualidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"position\":2,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\\\/#listItem\",\"name\":\"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\\\/#listItem\",\"position\":3,\"name\":\"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad\\\/#listItem\",\"name\":\"Actualidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\\\/\",\"name\":\"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros - El Digital de Asturias\",\"description\":\"Shangh\\u00e1i (China), 27 ene (EFE).- Las obras de la Torre de Shangh\\u00e1i, que en 2015 se inaugurar\\u00e1 como en el segundo rascacielos m\\u00e1s alto del mundo, con 632 metros, alcanzaron ya los 603 metros, por encima ya de los 601 metros del Makkah Royal Clock Tower Hotel de La Meca (Arabia Saud\\u00ed), que a\\u00fan es\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Contenidos.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\\\/#mainImage\",\"width\":1265,\"height\":697,\"caption\":\"Contenidos\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\\\/#mainImage\"},\"datePublished\":\"2014-01-27T14:12:12+01:00\",\"dateModified\":\"2014-01-27T14:12:12+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros - El Digital de Asturias","description":"Shangh\u00e1i (China), 27 ene (EFE).- Las obras de la Torre de Shangh\u00e1i, que en 2015 se inaugurar\u00e1 como en el segundo rascacielos m\u00e1s alto del mundo, con 632 metros, alcanzaron ya los 603 metros, por encima ya de los 601 metros del Makkah Royal Clock Tower Hotel de La Meca (Arabia Saud\u00ed), que a\u00fan es","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/","robots":"max-image-preview:large","keywords":"actualidad","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/#blogposting","name":"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros - El Digital de Asturias","headline":"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","width":1265,"height":697,"caption":"Contenidos"},"datePublished":"2014-01-27T14:12:12+01:00","dateModified":"2014-01-27T14:12:12+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/#webpage"},"articleSection":"Actualidad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","position":2,"name":"Actualidad","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/#listItem","name":"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/#listItem","position":3,"name":"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/#listItem","name":"Actualidad"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/","name":"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros - El Digital de Asturias","description":"Shangh\u00e1i (China), 27 ene (EFE).- Las obras de la Torre de Shangh\u00e1i, que en 2015 se inaugurar\u00e1 como en el segundo rascacielos m\u00e1s alto del mundo, con 632 metros, alcanzaron ya los 603 metros, por encima ya de los 601 metros del Makkah Royal Clock Tower Hotel de La Meca (Arabia Saud\u00ed), que a\u00fan es","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/#mainImage","width":1265,"height":697,"caption":"Contenidos"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/#mainImage"},"datePublished":"2014-01-27T14:12:12+01:00","dateModified":"2014-01-27T14:12:12+01:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros - El Digital de Asturias","og:description":"Shangh\u00e1i (China), 27 ene (EFE).- Las obras de la Torre de Shangh\u00e1i, que en 2015 se inaugurar\u00e1 como en el segundo rascacielos m\u00e1s alto del mundo, con 632 metros, alcanzaron ya los 603 metros, por encima ya de los 601 metros del Makkah Royal Clock Tower Hotel de La Meca (Arabia Saud\u00ed), que a\u00fan es","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/","og:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","og:image:secure_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","og:image:width":1265,"og:image:height":697,"article:tag":["actualidad"],"article:published_time":"2014-01-27T15:12:12+00:00","article:modified_time":"2014-01-27T15:12:12+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros - El Digital de Asturias","twitter:description":"Shangh\u00e1i (China), 27 ene (EFE).- Las obras de la Torre de Shangh\u00e1i, que en 2015 se inaugurar\u00e1 como en el segundo rascacielos m\u00e1s alto del mundo, con 632 metros, alcanzaron ya los 603 metros, por encima ya de los 601 metros del Makkah Royal Clock Tower Hotel de La Meca (Arabia Saud\u00ed), que a\u00fan es","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"479474","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-06-02 00:38:21","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-11-14 22:54:04","updated":"2026-06-02 00:38:21","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/\" title=\"Actualidad\">Actualidad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/\" title=\"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros\">Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Actualidad","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad\/"},{"label":"Las obras del segundo mayor rascacielos del mundo superan ya los 600 metros","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/las-obras-del-segundo-mayor-rascacielos-del-mundo-superan-ya-los-600-metros\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/479474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=479474"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/479474\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media\/1132184"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=479474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=479474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=479474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}