{"id":456571,"date":"2013-12-01T21:09:04","date_gmt":"2013-12-01T22:09:04","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=456571"},"modified":"2013-12-01T21:09:04","modified_gmt":"2013-12-01T22:09:04","slug":"500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/","title":{"rendered":"500 Voces cantar\u00e1n en el Teatro Real para conseguir 1000 becas de comedor"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-456572\" alt=\"5765314w\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2013\/12\/5765314w-360x236.jpg\" width=\"360\" height=\"236\" \/>Madrid, 1 dic (EFE).- El coro de ni\u00f1os de la Fundaci\u00f3n Sirimiri ha preparado esta tarde uno de los \u00faltimos ensayos generales para el concierto del pr\u00f3ximo d\u00eda 19 de diciembre, en el Teatro Real, donde homenajear\u00e1n a la Reina Fabiola de B\u00e9lgica y recaudar\u00e1n fondos para conseguir 1000 becas de comedor para las familias m\u00e1s necesitadas.<\/p>\n<p>\u00abNi\u00f1os espa\u00f1oles y belgas, de 19 colegios p\u00fablicos y privados, desde la Moraleja hasta Vallecas\u00bb todos est\u00e1n incluidos en un homenaje que es a la vez \u00abben\u00e9fico\u00bb, ha contado a EFE Ferm\u00edn Urbiola, director general de la Fundaci\u00f3n Sirimiri.<\/p>\n<p>Mientras los m\u00e1s rezagados se van sentando, el ensayo general ya ha comenzado. \u00ab\u00a1Se nos va el ensayo!\u00bb grita enfadado Luis Manchado, director de este particular coro de ni\u00f1os de cuarto, quinto y sexto de primaria y de primero de la ESO. Pide un Si bemol y comienza de nuevo la melod\u00eda mientras las fotos de la Reina quedan proyectadas en la pared.<\/p>\n<p>Luis Manchado asegura que es \u00abmuy f\u00e1cil\u00bb dirigir a este grupo de m\u00fasicos \u00abtanto en lo profesional como en lo personal\u00bb ya que los beneficios de esta iniciativa van a ayudar a muchas personas.<\/p>\n<p>Los fondos recaudados en la llamada \u00abfila cero\u00bb se destinar\u00e1n a la concesi\u00f3n 1000 becas de comedor a familias donde los ni\u00f1os \u00ab\u00fanicamente pueden comer lo que les ofrecen en el comedor\u00bb, seg\u00fan cuenta Urbiola, \u00aby muchas de ellas no llegan a cubrir este gasto.\u00bb<\/p>\n<p>Las organizaciones &#8216;C\u00e1ritas Espa\u00f1ola&#8217; y &#8216;Federaci\u00f3n Banco de Alimentos&#8217; trabajar\u00e1n en una especial armon\u00eda para gestionar estos fondos. La ONG \u00abPor la sonrisa de un ni\u00f1o\u00bb tambi\u00e9n colabora con la escolarizaci\u00f3n de quinientos ni\u00f1os en Camboya gracias a una donaci\u00f3n de la revista &#8216;\u00a1Hola!&#8217;.<\/p>\n<p>\u00abAlgunos prefieren jugar a la &#8216;playstation'\u00bb comenta Urbiola, mientras que otros como estos 500 ni\u00f1os prefieren cantar en un homenaje a una de las mujeres espa\u00f1olas \u00abm\u00e1s importantes del siglo XX\u00bb, la Reina Fabiola de B\u00e9lgica que cumple 85 a\u00f1os.<\/p>\n<p>David es director del coro del &#8216;Colegio del Recuerdo&#8217; y mientras narra c\u00f3mo se las apa\u00f1a para organizar a 45 peque\u00f1os cantores resalta la \u00abilusi\u00f3n de los ni\u00f1os\u00bb por participar en este evento. \u00abY mucho m\u00e1s cuando se celebra en el Teatro Real\u00bb a\u00f1ade Carmen, directora de otro de los coros.<\/p>\n<p>Entre melod\u00edas de Verdi, Caccini y alguna zarzuela, el repertorio hace un repaso musical sobre la vida de la Reina \u00aba la que los chicos sienten muy cerca\u00bb susurra Carmen en medio del ensayo.<\/p>\n<p>El final del ensayo coincide con un \u00ab\u00a1Adi\u00f3s!\u00bb cantado, parte de una de las piezas espa\u00f1olas que los ni\u00f1os cantar\u00e1n el pr\u00f3ximo 19 de Diciembre. Una de las participantes exclama \u00abyo he nacido para esto\u00bb, otro reconoce que est\u00e1 \u00abmuy emocionado\u00bb por tocar en el Real y \u00abayudar a tanta gente.\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 1 dic (EFE).- El coro de ni\u00f1os de la Fundaci\u00f3n Sirimiri ha preparado esta tarde uno de los \u00faltimos ensayos generales para el concierto del pr\u00f3ximo d\u00eda 19 de diciembre, en el Teatro Real, donde homenajear\u00e1n a la Reina Fabiola de B\u00e9lgica y recaudar\u00e1n fondos para conseguir 1000 becas de comedor para las familias [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":456572,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[],"class_list":["post-456571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revista-de-ocio"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Madrid, 1 dic (EFE).- El coro de ni\u00f1os de la Fundaci\u00f3n Sirimiri ha preparado esta tarde uno de los \u00faltimos ensayos generales para el concierto del pr\u00f3ximo d\u00eda 19 de diciembre, en el Teatro Real, donde homenajear\u00e1n a la Reina Fabiola de B\u00e9lgica y recaudar\u00e1n fondos para conseguir 1000 becas de comedor para las familias\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"revista de ocio\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"500 Voces cantar\u00e1n en el Teatro Real para conseguir 1000 becas de comedor - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Madrid, 1 dic (EFE).- El coro de ni\u00f1os de la Fundaci\u00f3n Sirimiri ha preparado esta tarde uno de los \u00faltimos ensayos generales para el concierto del pr\u00f3ximo d\u00eda 19 de diciembre, en el Teatro Real, donde homenajear\u00e1n a la Reina Fabiola de B\u00e9lgica y recaudar\u00e1n fondos para conseguir 1000 becas de comedor para las familias\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"revista de ocio\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-12-01T22:09:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-12-01T22:09:04+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"500 Voces cantar\u00e1n en el Teatro Real para conseguir 1000 becas de comedor - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Madrid, 1 dic (EFE).- El coro de ni\u00f1os de la Fundaci\u00f3n Sirimiri ha preparado esta tarde uno de los \u00faltimos ensayos generales para el concierto del pr\u00f3ximo d\u00eda 19 de diciembre, en el Teatro Real, donde homenajear\u00e1n a la Reina Fabiola de B\u00e9lgica y recaudar\u00e1n fondos para conseguir 1000 becas de comedor para las familias\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\\\/#blogposting\",\"name\":\"500 Voces cantar\\u00e1n en el Teatro Real para conseguir 1000 becas de comedor - El Digital de Asturias\",\"headline\":\"500 Voces cantar\\u00e1n en el Teatro Real para conseguir 1000 becas de comedor\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":456572},\"datePublished\":\"2013-12-01T21:09:04+01:00\",\"dateModified\":\"2013-12-01T21:09:04+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\\\/#webpage\"},\"articleSection\":\"Revista de Ocio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/revista-de-ocio\\\/#listItem\",\"name\":\"Revista de Ocio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/revista-de-ocio\\\/#listItem\",\"position\":2,\"name\":\"Revista de Ocio\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/revista-de-ocio\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\\\/#listItem\",\"name\":\"500 Voces cantar\\u00e1n en el Teatro Real para conseguir 1000 becas de comedor\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\\\/#listItem\",\"position\":3,\"name\":\"500 Voces cantar\\u00e1n en el Teatro Real para conseguir 1000 becas de comedor\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/revista-de-ocio\\\/#listItem\",\"name\":\"Revista de Ocio\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\\\/\",\"name\":\"500 Voces cantar\\u00e1n en el Teatro Real para conseguir 1000 becas de comedor - El Digital de Asturias\",\"description\":\"Madrid, 1 dic (EFE).- El coro de ni\\u00f1os de la Fundaci\\u00f3n Sirimiri ha preparado esta tarde uno de los \\u00faltimos ensayos generales para el concierto del pr\\u00f3ximo d\\u00eda 19 de diciembre, en el Teatro Real, donde homenajear\\u00e1n a la Reina Fabiola de B\\u00e9lgica y recaudar\\u00e1n fondos para conseguir 1000 becas de comedor para las familias\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":456572,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\\\/#mainImage\"},\"datePublished\":\"2013-12-01T21:09:04+01:00\",\"dateModified\":\"2013-12-01T21:09:04+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>500 Voces cantar\u00e1n en el Teatro Real para conseguir 1000 becas de comedor - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"500 Voces cantar\u00e1n en el Teatro Real para conseguir 1000 becas de comedor - El Digital de Asturias","description":"Madrid, 1 dic (EFE).- El coro de ni\u00f1os de la Fundaci\u00f3n Sirimiri ha preparado esta tarde uno de los \u00faltimos ensayos generales para el concierto del pr\u00f3ximo d\u00eda 19 de diciembre, en el Teatro Real, donde homenajear\u00e1n a la Reina Fabiola de B\u00e9lgica y recaudar\u00e1n fondos para conseguir 1000 becas de comedor para las familias","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/","robots":"max-image-preview:large","keywords":"revista de ocio","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/#blogposting","name":"500 Voces cantar\u00e1n en el Teatro Real para conseguir 1000 becas de comedor - El Digital de Asturias","headline":"500 Voces cantar\u00e1n en el Teatro Real para conseguir 1000 becas de comedor","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":456572},"datePublished":"2013-12-01T21:09:04+01:00","dateModified":"2013-12-01T21:09:04+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/#webpage"},"articleSection":"Revista de Ocio"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/revista-de-ocio\/#listItem","name":"Revista de Ocio"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/revista-de-ocio\/#listItem","position":2,"name":"Revista de Ocio","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/revista-de-ocio\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/#listItem","name":"500 Voces cantar\u00e1n en el Teatro Real para conseguir 1000 becas de comedor"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/#listItem","position":3,"name":"500 Voces cantar\u00e1n en el Teatro Real para conseguir 1000 becas de comedor","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/revista-de-ocio\/#listItem","name":"Revista de Ocio"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/","name":"500 Voces cantar\u00e1n en el Teatro Real para conseguir 1000 becas de comedor - El Digital de Asturias","description":"Madrid, 1 dic (EFE).- El coro de ni\u00f1os de la Fundaci\u00f3n Sirimiri ha preparado esta tarde uno de los \u00faltimos ensayos generales para el concierto del pr\u00f3ximo d\u00eda 19 de diciembre, en el Teatro Real, donde homenajear\u00e1n a la Reina Fabiola de B\u00e9lgica y recaudar\u00e1n fondos para conseguir 1000 becas de comedor para las familias","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":456572,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/#mainImage"},"datePublished":"2013-12-01T21:09:04+01:00","dateModified":"2013-12-01T21:09:04+01:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"500 Voces cantar\u00e1n en el Teatro Real para conseguir 1000 becas de comedor - El Digital de Asturias","og:description":"Madrid, 1 dic (EFE).- El coro de ni\u00f1os de la Fundaci\u00f3n Sirimiri ha preparado esta tarde uno de los \u00faltimos ensayos generales para el concierto del pr\u00f3ximo d\u00eda 19 de diciembre, en el Teatro Real, donde homenajear\u00e1n a la Reina Fabiola de B\u00e9lgica y recaudar\u00e1n fondos para conseguir 1000 becas de comedor para las familias","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/","article:tag":["revista de ocio"],"article:published_time":"2013-12-01T22:09:04+00:00","article:modified_time":"2013-12-01T22:09:04+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"500 Voces cantar\u00e1n en el Teatro Real para conseguir 1000 becas de comedor - El Digital de Asturias","twitter:description":"Madrid, 1 dic (EFE).- El coro de ni\u00f1os de la Fundaci\u00f3n Sirimiri ha preparado esta tarde uno de los \u00faltimos ensayos generales para el concierto del pr\u00f3ximo d\u00eda 19 de diciembre, en el Teatro Real, donde homenajear\u00e1n a la Reina Fabiola de B\u00e9lgica y recaudar\u00e1n fondos para conseguir 1000 becas de comedor para las familias","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"456571","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-29 22:26:58","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-11-14 22:45:59","updated":"2026-05-29 22:26:58","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/revista-de-ocio\/\" title=\"Revista de Ocio\">Revista de Ocio<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/\" title=\"500 Voces cantar\u00e1n en el Teatro Real para conseguir 1000 becas de comedor\">500 Voces cantar\u00e1n en el Teatro Real para conseguir 1000 becas de comedor<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Revista de Ocio","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/revista-de-ocio\/"},{"label":"500 Voces cantar\u00e1n en el Teatro Real para conseguir 1000 becas de comedor","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/500-voces-cantaran-en-el-teatro-real-para-conseguir-1000-becas-de-comedor\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/456571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=456571"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/456571\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=456571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=456571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=456571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}