{"id":432463,"date":"2013-10-03T02:04:51","date_gmt":"2013-10-03T02:04:51","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=432463"},"modified":"2013-10-03T02:04:51","modified_gmt":"2013-10-03T02:04:51","slug":"anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/","title":{"rendered":"Anulan la sanci\u00f3n a una autoescuela de Arag\u00f3n por discriminar a mujeres"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-432464\" alt=\"fotonoticia_20131002132623_800\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2013\/10\/fotonoticia_20131002132623_800-334x300.jpg\" width=\"334\" height=\"300\" \/>ZARAGOZA, 2 Oct. (EUROPA PRESS) &#8211;\u00a0La Uni\u00f3n de Consumidores de Arag\u00f3n (UCA) ha anunciado que va a realizar acciones jur\u00eddicas para \u00abcontrarrestar\u00bb la sentencia que anula una sanci\u00f3n de 4.000 euros de la direcci\u00f3n general de Consumo de la Comunidad aut\u00f3noma a una autoescuela por discriminar a mujeres ya que hab\u00eda establecido una tarifa plana para j\u00f3venes, pero era superior para ellas que para los hombres, de 850 euros frente a 665.<\/p>\n<p>El presidente de la UCA, Jos\u00e9 \u00c1ngel Oliv\u00e1n, ha advertido en rueda de prensa de las consecuencias que puede tener esta sentencia del juzgado de lo Contencioso-Administrativo n\u00famero 2 de Zaragoza, al transmitir que \u00abse puede discriminar por sexo sin que pase nada\u00bb porque esas conductas \u00abno son punibles\u00bb.<\/p>\n<p>A su entender, la sentencia no solo supone una anulaci\u00f3n de una sanci\u00f3n, sino que posee \u00abm\u00e1s amplitud\u00bb ya que en los fundamentos jur\u00eddicos \u00abse justifica la discriminaci\u00f3n\u00bb, apoy\u00e1ndose en \u00abcriterios estad\u00edsticos\u00bb, en los que se fundamenta \u00abgran parte de la argumentaci\u00f3n\u00bb.<\/p>\n<p>Concretamente, se aportan unos datos de la Direcci\u00f3n General de Tr\u00e1fico referidos al conjunto del Estado seg\u00fan los cu\u00e1les las mujeres tienen peores porcentajes en el porcentaje de aprobados a la primera, tanto en el examen te\u00f3rico como pr\u00e1ctico para obtener el permiso de conducir.<\/p>\n<p>A este respecto, Oliv\u00e1n ha mencionado la sentencia del Tribunal de Justicia de la Uni\u00f3n Europea de marzo de 2011 seg\u00fan la cual los criterios estad\u00edsticos \u00abno son aplicables a cuestiones relacionadas con la discriminaci\u00f3n\u00bb.<\/p>\n<p>OBVIADA<\/p>\n<p>El presidente de la UCA ha opinado que la sentencia del juzgado de lo Contencioso-Administrativo n\u00famero 2 de Zaragoza \u00abobvia\u00bb al Tribunal europeo, al citarlo de pasada, adem\u00e1s de que \u00abha olvidado el corpus ideol\u00f3gico y jur\u00eddico de estudios e informes que reflejan que los colectivos que han sufrido una discriminaci\u00f3n van a dar resultados estad\u00edsticos malos\u00bb.<\/p>\n<p>A su entender, esto \u00faltimo deber\u00eda haber sido aportado por la Diputaci\u00f3n General de Arag\u00f3n (DGA), para manifestar, por otra parte, que \u00abnos parece mal que no se nos diera parte en el juicio\u00bb, cuando el procedimiento sancionador fue iniciado tras presentar la UCA una denuncia ante la Direcci\u00f3n General de Consumo una vez que hab\u00eda recibido varias llamadas de afectadas.<\/p>\n<p>La Comunidad aut\u00f3noma sancion\u00f3 a tres autoescuelas por procedimientos similares, aunque solo una recurri\u00f3 a la Justicia. Adem\u00e1s, Jos\u00e9 \u00c1ngel Oliv\u00e1n ha estimado que si bien la DGA actu\u00f3 adecuadamente al sancionarlas, \u00abno fue beligerante y no defendi\u00f3 de manera contundente los intereses de las mujeres\u00bb en el proceso judicial.<\/p>\n<p>En este sentido, el presidente de la UCA ha manifestado su \u00abenfado e indignaci\u00f3n\u00bb por una sentencia \u00ablesiva para los intereses de las mujeres en Espa\u00f1a\u00bb, que \u00abavala la discriminaci\u00f3n\u00bb.<\/p>\n<p>Asimismo, ha comentado que la autoescuela \u00abno ha devuelto el dinero en efectivo a las mujeres afectadas\u00bb, sino que les ha ofrecido \u00abcosas extra\u00f1as\u00bb como cursos de maquillaje o un viaje a Madrid, para incidir en que la sanci\u00f3n es un \u00abelemento disuasorio\u00bb que debe evidenciar \u00abque la discriminaci\u00f3n tenga consecuencias\u00bb.<\/p>\n<p>ACCIONES JUR\u00cdDICAS<\/p>\n<p>El presidente de la UCA ha se\u00f1alado que la sentencia del juzgado de lo Contencioso-Administrativo n\u00famero 2 de Zaragoza no es recurrible puesto que la sanci\u00f3n no supera los 30.000 euros, para agregar que est\u00e1n estudiando, en colaboraci\u00f3n con el Colegio de Abogados de Zaragoza, c\u00f3mo se puede \u00abactuar contra ella\u00bb ya que \u00abestablece criterios inaceptables, con consecuencias sociales da\u00f1inas\u00bb.<\/p>\n<p>La UCA quiere que los efectos de esta sentencia \u00abno se difundan al resto de la sociedad\u00bb. \u00abNo podemos quedarnos quietos ante un documento importante, como es una sentencia, que puede establecer el principio de la discriminaci\u00f3n\u00bb, ha apostillado Oliv\u00e1n.<\/p>\n<p>Entre las posibilidades que estudian, se encuentra iniciar un nuevo proceso judicial ante el Tribunal Constitucional a trav\u00e9s del Defensor del Pueblo o del Justicia de Arag\u00f3n, ya que como organizaci\u00f3n no tienen capacidad para hacerlo, puesto que \u00abse vulnera el derecho constitucional\u00bb de la igualdad.<\/p>\n<p>Otra opci\u00f3n ser\u00eda acudir al Tribunal de Justicia de la Uni\u00f3n Europea, cuya sentencia \u00abse contempla de manera ligera\u00bb. Tambi\u00e9n analizan si el hecho de que no se haya dado parte a la UCA, gracias a quien se inici\u00f3 el proceso sancionador, puede suponer un defecto de forma, y otros aspectos en los que la sentencia puede considerarse que no es correcta.<\/p>\n<p>As\u00ed, para la UCA el juez no justifica su resoluci\u00f3n ya que, por un lado, un \u00absimple argumento estad\u00edstico\u00bb no puede justificar una diferencia de trato y, por otro, los datos de la DGT \u00abno demuestran que las mujeres necesiten m\u00e1s o menos clases, ni tampoco que en la franja de edad de 18 a 22 a\u00f1os las j\u00f3venes necesiten m\u00e1s clases que los chicos\u00bb. Tambi\u00e9n rechazan otro argumento dado por el juez de que es una \u00abpr\u00e1ctica mercantil habitual\u00bb.<\/p>\n<p>Oliv\u00e1n ha precisado que el objetivo es que si bien la sentencia \u00abno es anulable, s\u00ed lo sean sus consecuencias\u00bb, al tiempo que ha explicado que aceptan la cr\u00edtica que les hace el juez al se\u00f1alar que solo advirtieron a la DGA de la discriminaci\u00f3n por sexo, pero no por edad, cuando \u00abtampoco es aceptable\u00bb, ha reconocido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ZARAGOZA, 2 Oct. (EUROPA PRESS) &#8211;\u00a0La Uni\u00f3n de Consumidores de Arag\u00f3n (UCA) ha anunciado que va a realizar acciones jur\u00eddicas para \u00abcontrarrestar\u00bb la sentencia que anula una sanci\u00f3n de 4.000 euros de la direcci\u00f3n general de Consumo de la Comunidad aut\u00f3noma a una autoescuela por discriminar a mujeres ya que hab\u00eda establecido una tarifa plana [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":432464,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-432463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"ZARAGOZA, 2 Oct. (EUROPA PRESS) - La Uni\u00f3n de Consumidores de Arag\u00f3n (UCA) ha anunciado que va a realizar acciones jur\u00eddicas para &quot;contrarrestar&quot; la sentencia que anula una sanci\u00f3n de 4.000 euros de la direcci\u00f3n general de Consumo de la Comunidad aut\u00f3noma a una autoescuela por discriminar a mujeres ya que hab\u00eda establecido una tarifa plana\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"sociedad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Anulan la sanci\u00f3n a una autoescuela de Arag\u00f3n por discriminar a mujeres - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"ZARAGOZA, 2 Oct. (EUROPA PRESS) - La Uni\u00f3n de Consumidores de Arag\u00f3n (UCA) ha anunciado que va a realizar acciones jur\u00eddicas para &quot;contrarrestar&quot; la sentencia que anula una sanci\u00f3n de 4.000 euros de la direcci\u00f3n general de Consumo de la Comunidad aut\u00f3noma a una autoescuela por discriminar a mujeres ya que hab\u00eda establecido una tarifa plana\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"sociedad\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-10-03T02:04:51+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-10-03T02:04:51+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Anulan la sanci\u00f3n a una autoescuela de Arag\u00f3n por discriminar a mujeres - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"ZARAGOZA, 2 Oct. (EUROPA PRESS) - La Uni\u00f3n de Consumidores de Arag\u00f3n (UCA) ha anunciado que va a realizar acciones jur\u00eddicas para &quot;contrarrestar&quot; la sentencia que anula una sanci\u00f3n de 4.000 euros de la direcci\u00f3n general de Consumo de la Comunidad aut\u00f3noma a una autoescuela por discriminar a mujeres ya que hab\u00eda establecido una tarifa plana\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\\\/#blogposting\",\"name\":\"Anulan la sanci\\u00f3n a una autoescuela de Arag\\u00f3n por discriminar a mujeres - El Digital de Asturias\",\"headline\":\"Anulan la sanci\\u00f3n a una autoescuela de Arag\\u00f3n por discriminar a mujeres\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":432464},\"datePublished\":\"2013-10-03T02:04:51+02:00\",\"dateModified\":\"2013-10-03T02:04:51+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\\\/#webpage\"},\"articleSection\":\"Sociedad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"name\":\"Sociedad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"position\":2,\"name\":\"Sociedad\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sociedad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\\\/#listItem\",\"name\":\"Anulan la sanci\\u00f3n a una autoescuela de Arag\\u00f3n por discriminar a mujeres\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\\\/#listItem\",\"position\":3,\"name\":\"Anulan la sanci\\u00f3n a una autoescuela de Arag\\u00f3n por discriminar a mujeres\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"name\":\"Sociedad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\\\/\",\"name\":\"Anulan la sanci\\u00f3n a una autoescuela de Arag\\u00f3n por discriminar a mujeres - El Digital de Asturias\",\"description\":\"ZARAGOZA, 2 Oct. (EUROPA PRESS) - La Uni\\u00f3n de Consumidores de Arag\\u00f3n (UCA) ha anunciado que va a realizar acciones jur\\u00eddicas para \\\"contrarrestar\\\" la sentencia que anula una sanci\\u00f3n de 4.000 euros de la direcci\\u00f3n general de Consumo de la Comunidad aut\\u00f3noma a una autoescuela por discriminar a mujeres ya que hab\\u00eda establecido una tarifa plana\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":432464,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\\\/#mainImage\"},\"datePublished\":\"2013-10-03T02:04:51+02:00\",\"dateModified\":\"2013-10-03T02:04:51+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Anulan la sanci\u00f3n a una autoescuela de Arag\u00f3n por discriminar a mujeres - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Anulan la sanci\u00f3n a una autoescuela de Arag\u00f3n por discriminar a mujeres - El Digital de Asturias","description":"ZARAGOZA, 2 Oct. (EUROPA PRESS) - La Uni\u00f3n de Consumidores de Arag\u00f3n (UCA) ha anunciado que va a realizar acciones jur\u00eddicas para \"contrarrestar\" la sentencia que anula una sanci\u00f3n de 4.000 euros de la direcci\u00f3n general de Consumo de la Comunidad aut\u00f3noma a una autoescuela por discriminar a mujeres ya que hab\u00eda establecido una tarifa plana","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/","robots":"max-image-preview:large","keywords":"sociedad","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/#blogposting","name":"Anulan la sanci\u00f3n a una autoescuela de Arag\u00f3n por discriminar a mujeres - El Digital de Asturias","headline":"Anulan la sanci\u00f3n a una autoescuela de Arag\u00f3n por discriminar a mujeres","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":432464},"datePublished":"2013-10-03T02:04:51+02:00","dateModified":"2013-10-03T02:04:51+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/#webpage"},"articleSection":"Sociedad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/#listItem","name":"Sociedad"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/#listItem","position":2,"name":"Sociedad","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/#listItem","name":"Anulan la sanci\u00f3n a una autoescuela de Arag\u00f3n por discriminar a mujeres"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/#listItem","position":3,"name":"Anulan la sanci\u00f3n a una autoescuela de Arag\u00f3n por discriminar a mujeres","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/#listItem","name":"Sociedad"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/","name":"Anulan la sanci\u00f3n a una autoescuela de Arag\u00f3n por discriminar a mujeres - El Digital de Asturias","description":"ZARAGOZA, 2 Oct. (EUROPA PRESS) - La Uni\u00f3n de Consumidores de Arag\u00f3n (UCA) ha anunciado que va a realizar acciones jur\u00eddicas para \"contrarrestar\" la sentencia que anula una sanci\u00f3n de 4.000 euros de la direcci\u00f3n general de Consumo de la Comunidad aut\u00f3noma a una autoescuela por discriminar a mujeres ya que hab\u00eda establecido una tarifa plana","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":432464,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/#mainImage"},"datePublished":"2013-10-03T02:04:51+02:00","dateModified":"2013-10-03T02:04:51+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Anulan la sanci\u00f3n a una autoescuela de Arag\u00f3n por discriminar a mujeres - El Digital de Asturias","og:description":"ZARAGOZA, 2 Oct. (EUROPA PRESS) - La Uni\u00f3n de Consumidores de Arag\u00f3n (UCA) ha anunciado que va a realizar acciones jur\u00eddicas para &quot;contrarrestar&quot; la sentencia que anula una sanci\u00f3n de 4.000 euros de la direcci\u00f3n general de Consumo de la Comunidad aut\u00f3noma a una autoescuela por discriminar a mujeres ya que hab\u00eda establecido una tarifa plana","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/","article:tag":["sociedad"],"article:published_time":"2013-10-03T02:04:51+00:00","article:modified_time":"2013-10-03T02:04:51+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Anulan la sanci\u00f3n a una autoescuela de Arag\u00f3n por discriminar a mujeres - El Digital de Asturias","twitter:description":"ZARAGOZA, 2 Oct. (EUROPA PRESS) - La Uni\u00f3n de Consumidores de Arag\u00f3n (UCA) ha anunciado que va a realizar acciones jur\u00eddicas para &quot;contrarrestar&quot; la sentencia que anula una sanci\u00f3n de 4.000 euros de la direcci\u00f3n general de Consumo de la Comunidad aut\u00f3noma a una autoescuela por discriminar a mujeres ya que hab\u00eda establecido una tarifa plana","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"5 minutos"},"aioseo_meta_data":{"post_id":"432463","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 11:32:56","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-11-14 22:38:03","updated":"2026-05-15 11:32:56"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/\" title=\"Sociedad\">Sociedad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/\" title=\"Anulan la sanci\u00f3n a una autoescuela de Arag\u00f3n por discriminar a mujeres\">Anulan la sanci\u00f3n a una autoescuela de Arag\u00f3n por discriminar a mujeres<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Sociedad","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/"},{"label":"Anulan la sanci\u00f3n a una autoescuela de Arag\u00f3n por discriminar a mujeres","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/anulan-la-sancion-a-una-autoescuela-de-aragon-por-discriminar-a-mujeres\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/432463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=432463"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/432463\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=432463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=432463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=432463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}