{"id":432417,"date":"2013-10-03T01:15:45","date_gmt":"2013-10-03T01:15:45","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=432417"},"modified":"2013-10-03T01:15:45","modified_gmt":"2013-10-03T01:15:45","slug":"ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/","title":{"rendered":"Ana Pastor, satisfecha de la contribuci\u00f3n de Fomento a la conservaci\u00f3n del Monasterio de San Pelayo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-432418\" alt=\"fotonoticia_20131002181119_800\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2013\/10\/fotonoticia_20131002181119_800-360x269.jpg\" width=\"360\" height=\"269\" \/>OVIEDO, 2 Oct. (EUROPA PRESS) &#8211;\u00a0La ministra de Fomento, Ana Pastor, se ha mostrado satisfecha de la contribuci\u00f3n del Ministerio a la conservaci\u00f3n del Monasterio de San Pelayo de Oviedo \u00abdado su valor hist\u00f3rico\u00bb, durante la inauguraci\u00f3n de las obras de rehabilitaci\u00f3n, que han consistido en la renovaci\u00f3n de las cubiertas.<\/p>\n<p>\u00abSe ha recuperado una parte importante, que es la de las cubiertas y vamos a seguir colaborando, en la medida que podamos, para que estos edificios que forman parte del patrimonio hist\u00f3rico-art\u00edstico y arquitect\u00f3nico de nuestro pa\u00eds se puedan seguir manteniendo\u00bb, ha afirmado en declaraciones a los medios.<\/p>\n<p>En el transcurso de la visita, en la que la ministra estuvo acompa\u00f1ada por representantes del Gobierno del Principado, de la Delegaci\u00f3n del Gobierno en Asturias, de miembros de la Corporaci\u00f3n Municipal de Oviedo y del PP asturiano, Pastor remarc\u00f3 que su departamento va a seguir actuando \u00aben todo el patrimonio\u00bb.<\/p>\n<p>La actuaci\u00f3n concreta en el monasterio ovetense, se ha realizado con cargo a los fondos del 1% Cultural, con una aportaci\u00f3n de algo m\u00e1s de 358.000 euros, a trav\u00e9s de un convenio que se firm\u00f3 en 2009 con el Principado de Asturias, que aport\u00f3 200.000 euros.<\/p>\n<p>La titular de Fomento, que firm\u00f3 en el libro de honor y agradeci\u00f3 que &#8216;las pelayas&#8217; entonasen la bendici\u00f3n para despedir a la comitiva resaltando que \u00abcantan como los \u00e1ngeles\u00bb, ha incidido en que el 1% Cultural pasar\u00e1 a ser el 1,5% atendiendo a las necesidades de la actual \u00e9poca de crisis.<\/p>\n<p>Por su parte, la consejera de Educaci\u00f3n, Cultura y Deporte del Principado, Ana Gonz\u00e1lez, ha reiterado la relevancia de trabajar en la recuperaci\u00f3n del patrimonio, valorando \u00abla especial congregaci\u00f3n\u00bb del Monasterio de San Pelayo. \u00abSon una de las referencias de Oviedo\u00bb, ha dicho en referencia a las 28 monjas que la integran.<\/p>\n<p>Asimismo, la abadesa Asunci\u00f3n del Camino ha remarcado la importancia que ha tenido la restauraci\u00f3n de la cubierta del Monasterio, haciendo hincapi\u00e9 en la urgencia de acometer obras de reparaci\u00f3n en la fachada.<\/p>\n<p>LAS OBRAS<\/p>\n<p>El Monasterio de San Pelayo, fundado por Alfonso II, el Casto (791-842), constituye un conjunto incluido en el Cat\u00e1logo Urban\u00edstico del Concejo de Oviedo, formado por seis elementos diferenciados: &#8216;Archivo&#8217;, &#8216;Claustrillo&#8217;, &#8216;Claustro de San Pelayo&#8217;, &#8216;Iglesia de San Pelayo&#8217;, &#8216;Monumento a Jovellanos&#8217; y &#8216;Vicar\u00eda&#8217;.<\/p>\n<p>El \u00e1rea restaurada se ubica en el &#8216;Archivo&#8217;, donde se ha llevado a cabo la sustituci\u00f3n de las cubiertas. Los trabajos previos han consistido en la demolici\u00f3n y desmontaje de antiguas cubiertas y en la ejecuci\u00f3n de un nuevo forjado sobre la planta segunda.<\/p>\n<p>El &#8216;Archivo&#8217; est\u00e1 formado por dos cuerpos de edificaci\u00f3n, sensiblemente perpendiculares, comprendidos entre el patio de entrada y las calles Jovellanos y del \u00c1guila. Tras sufrir un incendio en 1936, se iniciaron diversas fases de reconstrucci\u00f3n en las que se sustituyeron totalmente sus tejados y desde entonces ha sido objeto de m\u00faltiples reformas.<\/p>\n<p>NOCHE BLANCA<\/p>\n<p>Por otra parte, tanto la consejera como la abadesa han hecho referencia a la participaci\u00f3n de &#8216;las pelayas&#8217; en la Noche Blanca que se celebra este s\u00e1bado, 5 de octubre, en Oviedo.<\/p>\n<p>Para la madre Asunci\u00f3n se trata de una \u00abiniciativa preciosa\u00bb que les permitir\u00e1 abrir sus puertas a la ciudadan\u00eda a las 21.00 horas y hacer part\u00edcipes a quienes se acerquen de sus oraciones, a partir de las 21.45 horas. \u00abJam\u00e1s nos hemos sentido aparte y esta es una expresi\u00f3n m\u00e1s\u00bb, ha afirmado.<\/p>\n<p>En la misma l\u00ednea, la titular de Cultura ha animado a los ciudadanos a que vayan al monasterio este s\u00e1bado. \u00abYo le digo a la gente que se acerque. Merece la pena acercarse a estas hermanas, porque es verdad que transmiten fuerza, espiritualidad, coraje y solidaridad\u00bb, ha dicho Ana Gonz\u00e1lez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OVIEDO, 2 Oct. (EUROPA PRESS) &#8211;\u00a0La ministra de Fomento, Ana Pastor, se ha mostrado satisfecha de la contribuci\u00f3n del Ministerio a la conservaci\u00f3n del Monasterio de San Pelayo de Oviedo \u00abdado su valor hist\u00f3rico\u00bb, durante la inauguraci\u00f3n de las obras de rehabilitaci\u00f3n, que han consistido en la renovaci\u00f3n de las cubiertas. \u00abSe ha recuperado una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":432418,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-432417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-asturias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"OVIEDO, 2 Oct. (EUROPA PRESS) - La ministra de Fomento, Ana Pastor, se ha mostrado satisfecha de la contribuci\u00f3n del Ministerio a la conservaci\u00f3n del Monasterio de San Pelayo de Oviedo &quot;dado su valor hist\u00f3rico&quot;, durante la inauguraci\u00f3n de las obras de rehabilitaci\u00f3n, que han consistido en la renovaci\u00f3n de las cubiertas. &quot;Se ha recuperado una\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"actualidad asturias\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ana Pastor, satisfecha de la contribuci\u00f3n de Fomento a la conservaci\u00f3n del Monasterio de San Pelayo - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"OVIEDO, 2 Oct. (EUROPA PRESS) - La ministra de Fomento, Ana Pastor, se ha mostrado satisfecha de la contribuci\u00f3n del Ministerio a la conservaci\u00f3n del Monasterio de San Pelayo de Oviedo &quot;dado su valor hist\u00f3rico&quot;, durante la inauguraci\u00f3n de las obras de rehabilitaci\u00f3n, que han consistido en la renovaci\u00f3n de las cubiertas. &quot;Se ha recuperado una\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"actualidad asturias\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-10-03T01:15:45+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-10-03T01:15:45+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ana Pastor, satisfecha de la contribuci\u00f3n de Fomento a la conservaci\u00f3n del Monasterio de San Pelayo - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"OVIEDO, 2 Oct. (EUROPA PRESS) - La ministra de Fomento, Ana Pastor, se ha mostrado satisfecha de la contribuci\u00f3n del Ministerio a la conservaci\u00f3n del Monasterio de San Pelayo de Oviedo &quot;dado su valor hist\u00f3rico&quot;, durante la inauguraci\u00f3n de las obras de rehabilitaci\u00f3n, que han consistido en la renovaci\u00f3n de las cubiertas. &quot;Se ha recuperado una\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\\\/#blogposting\",\"name\":\"Ana Pastor, satisfecha de la contribuci\\u00f3n de Fomento a la conservaci\\u00f3n del Monasterio de San Pelayo - El Digital de Asturias\",\"headline\":\"Ana Pastor, satisfecha de la contribuci\\u00f3n de Fomento a la conservaci\\u00f3n del Monasterio de San Pelayo\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":432418},\"datePublished\":\"2013-10-03T01:15:45+02:00\",\"dateModified\":\"2013-10-03T01:15:45+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\\\/#webpage\"},\"articleSection\":\"Actualidad Asturias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad-asturias\\\/#listItem\",\"name\":\"Actualidad Asturias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad-asturias\\\/#listItem\",\"position\":2,\"name\":\"Actualidad Asturias\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad-asturias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\\\/#listItem\",\"name\":\"Ana Pastor, satisfecha de la contribuci\\u00f3n de Fomento a la conservaci\\u00f3n del Monasterio de San Pelayo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\\\/#listItem\",\"position\":3,\"name\":\"Ana Pastor, satisfecha de la contribuci\\u00f3n de Fomento a la conservaci\\u00f3n del Monasterio de San Pelayo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/actualidad-asturias\\\/#listItem\",\"name\":\"Actualidad Asturias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\\\/\",\"name\":\"Ana Pastor, satisfecha de la contribuci\\u00f3n de Fomento a la conservaci\\u00f3n del Monasterio de San Pelayo - El Digital de Asturias\",\"description\":\"OVIEDO, 2 Oct. (EUROPA PRESS) - La ministra de Fomento, Ana Pastor, se ha mostrado satisfecha de la contribuci\\u00f3n del Ministerio a la conservaci\\u00f3n del Monasterio de San Pelayo de Oviedo \\\"dado su valor hist\\u00f3rico\\\", durante la inauguraci\\u00f3n de las obras de rehabilitaci\\u00f3n, que han consistido en la renovaci\\u00f3n de las cubiertas. \\\"Se ha recuperado una\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":432418,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\\\/#mainImage\"},\"datePublished\":\"2013-10-03T01:15:45+02:00\",\"dateModified\":\"2013-10-03T01:15:45+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Ana Pastor, satisfecha de la contribuci\u00f3n de Fomento a la conservaci\u00f3n del Monasterio de San Pelayo - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Ana Pastor, satisfecha de la contribuci\u00f3n de Fomento a la conservaci\u00f3n del Monasterio de San Pelayo - El Digital de Asturias","description":"OVIEDO, 2 Oct. (EUROPA PRESS) - La ministra de Fomento, Ana Pastor, se ha mostrado satisfecha de la contribuci\u00f3n del Ministerio a la conservaci\u00f3n del Monasterio de San Pelayo de Oviedo \"dado su valor hist\u00f3rico\", durante la inauguraci\u00f3n de las obras de rehabilitaci\u00f3n, que han consistido en la renovaci\u00f3n de las cubiertas. \"Se ha recuperado una","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/","robots":"max-image-preview:large","keywords":"actualidad asturias","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/#blogposting","name":"Ana Pastor, satisfecha de la contribuci\u00f3n de Fomento a la conservaci\u00f3n del Monasterio de San Pelayo - El Digital de Asturias","headline":"Ana Pastor, satisfecha de la contribuci\u00f3n de Fomento a la conservaci\u00f3n del Monasterio de San Pelayo","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":432418},"datePublished":"2013-10-03T01:15:45+02:00","dateModified":"2013-10-03T01:15:45+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/#webpage"},"articleSection":"Actualidad Asturias"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad-asturias\/#listItem","name":"Actualidad Asturias"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad-asturias\/#listItem","position":2,"name":"Actualidad Asturias","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad-asturias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/#listItem","name":"Ana Pastor, satisfecha de la contribuci\u00f3n de Fomento a la conservaci\u00f3n del Monasterio de San Pelayo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/#listItem","position":3,"name":"Ana Pastor, satisfecha de la contribuci\u00f3n de Fomento a la conservaci\u00f3n del Monasterio de San Pelayo","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad-asturias\/#listItem","name":"Actualidad Asturias"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/","name":"Ana Pastor, satisfecha de la contribuci\u00f3n de Fomento a la conservaci\u00f3n del Monasterio de San Pelayo - El Digital de Asturias","description":"OVIEDO, 2 Oct. (EUROPA PRESS) - La ministra de Fomento, Ana Pastor, se ha mostrado satisfecha de la contribuci\u00f3n del Ministerio a la conservaci\u00f3n del Monasterio de San Pelayo de Oviedo \"dado su valor hist\u00f3rico\", durante la inauguraci\u00f3n de las obras de rehabilitaci\u00f3n, que han consistido en la renovaci\u00f3n de las cubiertas. \"Se ha recuperado una","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":432418,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/#mainImage"},"datePublished":"2013-10-03T01:15:45+02:00","dateModified":"2013-10-03T01:15:45+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Ana Pastor, satisfecha de la contribuci\u00f3n de Fomento a la conservaci\u00f3n del Monasterio de San Pelayo - El Digital de Asturias","og:description":"OVIEDO, 2 Oct. (EUROPA PRESS) - La ministra de Fomento, Ana Pastor, se ha mostrado satisfecha de la contribuci\u00f3n del Ministerio a la conservaci\u00f3n del Monasterio de San Pelayo de Oviedo &quot;dado su valor hist\u00f3rico&quot;, durante la inauguraci\u00f3n de las obras de rehabilitaci\u00f3n, que han consistido en la renovaci\u00f3n de las cubiertas. &quot;Se ha recuperado una","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/","article:tag":["actualidad asturias"],"article:published_time":"2013-10-03T01:15:45+00:00","article:modified_time":"2013-10-03T01:15:45+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Ana Pastor, satisfecha de la contribuci\u00f3n de Fomento a la conservaci\u00f3n del Monasterio de San Pelayo - El Digital de Asturias","twitter:description":"OVIEDO, 2 Oct. (EUROPA PRESS) - La ministra de Fomento, Ana Pastor, se ha mostrado satisfecha de la contribuci\u00f3n del Ministerio a la conservaci\u00f3n del Monasterio de San Pelayo de Oviedo &quot;dado su valor hist\u00f3rico&quot;, durante la inauguraci\u00f3n de las obras de rehabilitaci\u00f3n, que han consistido en la renovaci\u00f3n de las cubiertas. &quot;Se ha recuperado una","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"432417","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 11:21:53","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-11-14 22:38:03","updated":"2026-05-15 11:21:53"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad-asturias\/\" title=\"Actualidad Asturias\">Actualidad Asturias<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/\" title=\"Ana Pastor, satisfecha de la contribuci\u00f3n de Fomento a la conservaci\u00f3n del Monasterio de San Pelayo\">Ana Pastor, satisfecha de la contribuci\u00f3n de Fomento a la conservaci\u00f3n del Monasterio de San Pelayo<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Actualidad Asturias","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/actualidad-asturias\/"},{"label":"Ana Pastor, satisfecha de la contribuci\u00f3n de Fomento a la conservaci\u00f3n del Monasterio de San Pelayo","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ana-pastor-satisfecha-de-la-contribucion-de-fomento-a-la-conservacion-del-monasterio-de-san-pelayo\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/432417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=432417"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/432417\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=432417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=432417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=432417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}