{"id":432337,"date":"2013-10-02T18:17:43","date_gmt":"2013-10-02T18:17:43","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=432337"},"modified":"2013-10-02T18:17:43","modified_gmt":"2013-10-02T18:17:43","slug":"katie-holmes-destaca-en-el-preestreno-de-gravity","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/","title":{"rendered":"Katie Holmes destaca en el preestreno de &#8216;Gravity&#8217;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-432338\" alt=\"Katie Holmes attends the world premiere of 'Gravity' in NYC\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2013\/10\/Katie-Holmes-destaca-en-el-preestreno-de-Gravity.jpg\" width=\"650\" height=\"650\" \/>La actriz Katie Holmes asisti\u00f3 al preestreno de la pel\u00edcula &#8216;Gravity&#8217; en Nueva York con un colorido vestido en tono rosa fl\u00faor que logr\u00f3 acaparar todas las miradas, no solo debido a su llamativo color sino tambi\u00e9n a que dejaba ver las esculturales piernas de la exmujer de Tom Cruise.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actriz Katie Holmes asisti\u00f3 al preestreno de la pel\u00edcula &#8216;Gravity&#8217; en Nueva York con un colorido vestido en tono rosa fl\u00faor que logr\u00f3 acaparar todas las miradas, no solo debido a su llamativo color sino tambi\u00e9n a que dejaba ver las esculturales piernas de la exmujer de Tom Cruise. &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":432338,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-432337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"La actriz Katie Holmes asisti\u00f3 al preestreno de la pel\u00edcula &#039;Gravity&#039; en Nueva York con un colorido vestido en tono rosa fl\u00faor que logr\u00f3 acaparar todas las miradas, no solo debido a su llamativo color sino tambi\u00e9n a que dejaba ver las esculturales piernas de la exmujer de Tom Cruise.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"sociedad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Katie Holmes destaca en el preestreno de \u2018Gravity\u2019 - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La actriz Katie Holmes asisti\u00f3 al preestreno de la pel\u00edcula &#039;Gravity&#039; en Nueva York con un colorido vestido en tono rosa fl\u00faor que logr\u00f3 acaparar todas las miradas, no solo debido a su llamativo color sino tambi\u00e9n a que dejaba ver las esculturales piernas de la exmujer de Tom Cruise.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"sociedad\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-10-02T18:17:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-10-02T18:17:43+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Katie Holmes destaca en el preestreno de \u2018Gravity\u2019 - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La actriz Katie Holmes asisti\u00f3 al preestreno de la pel\u00edcula &#039;Gravity&#039; en Nueva York con un colorido vestido en tono rosa fl\u00faor que logr\u00f3 acaparar todas las miradas, no solo debido a su llamativo color sino tambi\u00e9n a que dejaba ver las esculturales piernas de la exmujer de Tom Cruise.\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/katie-holmes-destaca-en-el-preestreno-de-gravity\\\/#blogposting\",\"name\":\"Katie Holmes destaca en el preestreno de \\u2018Gravity\\u2019 - El Digital de Asturias\",\"headline\":\"Katie Holmes destaca en el preestreno de &#8216;Gravity&#8217;\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":432338},\"datePublished\":\"2013-10-02T18:17:43+02:00\",\"dateModified\":\"2013-10-02T18:17:43+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/katie-holmes-destaca-en-el-preestreno-de-gravity\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/katie-holmes-destaca-en-el-preestreno-de-gravity\\\/#webpage\"},\"articleSection\":\"Sociedad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/katie-holmes-destaca-en-el-preestreno-de-gravity\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"name\":\"Sociedad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"position\":2,\"name\":\"Sociedad\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sociedad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/katie-holmes-destaca-en-el-preestreno-de-gravity\\\/#listItem\",\"name\":\"Katie Holmes destaca en el preestreno de &#8216;Gravity&#8217;\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/katie-holmes-destaca-en-el-preestreno-de-gravity\\\/#listItem\",\"position\":3,\"name\":\"Katie Holmes destaca en el preestreno de &#8216;Gravity&#8217;\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"name\":\"Sociedad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/katie-holmes-destaca-en-el-preestreno-de-gravity\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/katie-holmes-destaca-en-el-preestreno-de-gravity\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/katie-holmes-destaca-en-el-preestreno-de-gravity\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/katie-holmes-destaca-en-el-preestreno-de-gravity\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/katie-holmes-destaca-en-el-preestreno-de-gravity\\\/\",\"name\":\"Katie Holmes destaca en el preestreno de \\u2018Gravity\\u2019 - El Digital de Asturias\",\"description\":\"La actriz Katie Holmes asisti\\u00f3 al preestreno de la pel\\u00edcula 'Gravity' en Nueva York con un colorido vestido en tono rosa fl\\u00faor que logr\\u00f3 acaparar todas las miradas, no solo debido a su llamativo color sino tambi\\u00e9n a que dejaba ver las esculturales piernas de la exmujer de Tom Cruise.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/katie-holmes-destaca-en-el-preestreno-de-gravity\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":432338,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/katie-holmes-destaca-en-el-preestreno-de-gravity\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/katie-holmes-destaca-en-el-preestreno-de-gravity\\\/#mainImage\"},\"datePublished\":\"2013-10-02T18:17:43+02:00\",\"dateModified\":\"2013-10-02T18:17:43+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Katie Holmes destaca en el preestreno de \u2018Gravity\u2019 - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Katie Holmes destaca en el preestreno de \u2018Gravity\u2019 - El Digital de Asturias","description":"La actriz Katie Holmes asisti\u00f3 al preestreno de la pel\u00edcula 'Gravity' en Nueva York con un colorido vestido en tono rosa fl\u00faor que logr\u00f3 acaparar todas las miradas, no solo debido a su llamativo color sino tambi\u00e9n a que dejaba ver las esculturales piernas de la exmujer de Tom Cruise.","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/","robots":"max-image-preview:large","keywords":"sociedad","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/#blogposting","name":"Katie Holmes destaca en el preestreno de \u2018Gravity\u2019 - El Digital de Asturias","headline":"Katie Holmes destaca en el preestreno de &#8216;Gravity&#8217;","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":432338},"datePublished":"2013-10-02T18:17:43+02:00","dateModified":"2013-10-02T18:17:43+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/#webpage"},"articleSection":"Sociedad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/#listItem","name":"Sociedad"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/#listItem","position":2,"name":"Sociedad","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/#listItem","name":"Katie Holmes destaca en el preestreno de &#8216;Gravity&#8217;"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/#listItem","position":3,"name":"Katie Holmes destaca en el preestreno de &#8216;Gravity&#8217;","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/#listItem","name":"Sociedad"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/","name":"Katie Holmes destaca en el preestreno de \u2018Gravity\u2019 - El Digital de Asturias","description":"La actriz Katie Holmes asisti\u00f3 al preestreno de la pel\u00edcula 'Gravity' en Nueva York con un colorido vestido en tono rosa fl\u00faor que logr\u00f3 acaparar todas las miradas, no solo debido a su llamativo color sino tambi\u00e9n a que dejaba ver las esculturales piernas de la exmujer de Tom Cruise.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":432338,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/#mainImage"},"datePublished":"2013-10-02T18:17:43+02:00","dateModified":"2013-10-02T18:17:43+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Katie Holmes destaca en el preestreno de \u2018Gravity\u2019 - El Digital de Asturias","og:description":"La actriz Katie Holmes asisti\u00f3 al preestreno de la pel\u00edcula 'Gravity' en Nueva York con un colorido vestido en tono rosa fl\u00faor que logr\u00f3 acaparar todas las miradas, no solo debido a su llamativo color sino tambi\u00e9n a que dejaba ver las esculturales piernas de la exmujer de Tom Cruise.","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/","article:tag":["sociedad"],"article:published_time":"2013-10-02T18:17:43+00:00","article:modified_time":"2013-10-02T18:17:43+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Katie Holmes destaca en el preestreno de \u2018Gravity\u2019 - El Digital de Asturias","twitter:description":"La actriz Katie Holmes asisti\u00f3 al preestreno de la pel\u00edcula 'Gravity' en Nueva York con un colorido vestido en tono rosa fl\u00faor que logr\u00f3 acaparar todas las miradas, no solo debido a su llamativo color sino tambi\u00e9n a que dejaba ver las esculturales piernas de la exmujer de Tom Cruise.","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias"},"aioseo_meta_data":{"post_id":"432337","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 10:56:59","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-11-14 22:38:02","updated":"2026-05-15 10:56:59"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/\" title=\"Sociedad\">Sociedad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/\" title=\"Katie Holmes destaca en el preestreno de \u2018Gravity\u2019\">Katie Holmes destaca en el preestreno de \u2018Gravity\u2019<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Sociedad","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/"},{"label":"Katie Holmes destaca en el preestreno de &#8216;Gravity&#8217;","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/katie-holmes-destaca-en-el-preestreno-de-gravity\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/432337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=432337"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/432337\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=432337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=432337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=432337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}