{"id":432264,"date":"2013-10-02T16:48:33","date_gmt":"2013-10-02T16:48:33","guid":{"rendered":"http:\/\/www.eldigitaldeasturias.com\/noticias\/?p=432264"},"modified":"2013-10-02T16:48:33","modified_gmt":"2013-10-02T16:48:33","slug":"eiza-gonzalez-quiere-triunfar-en-hollywood","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/","title":{"rendered":"Eiza Gonz\u00e1lez quiere triunfar en Hollywood"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-432265\" alt=\"Eiza Gonzalez who is romantically linked to Liam Hemsworth  presenting the DVD of the animated film 'The Croods' at Papalote Museo Del Nino in Mexico City.\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2013\/10\/Eiza-Gonz\u00e1lez-quiere-triunfar-en-Hollywood-300x300.jpg\" width=\"300\" height=\"300\" \/>En la opini\u00f3n p\u00fablica se la conoce mejor por haber encandilado al guapo Liam Hemsworth poco despu\u00e9s de que el australiano se separara de Miley Cyrus, pero la joven int\u00e9rprete Eiza Gonz\u00e1lez no quiere que su repentina presencia en la prensa norteamericana eclipse por un momento su gran ambici\u00f3n como actriz. De hecho, en sus escasas entrevistas la artista mexicana solo presume con orgullo de las ofertas laborales que no paran de llegarle y de aquellas caras conocidas con las que empezar\u00e1 a rodar pr\u00f3ximamente: una actitud que indica que Eiza busca en Hollywood algo m\u00e1s que los besos del cu\u00f1ado de Elsa Pataky.<\/p>\n<p>\u00abEn febrero empiezo a filmar una pel\u00edcula que ser\u00e1 incre\u00edble. Es una cinta con un guion muy interesante porque me recuerda a aquellas pel\u00edculas sobre j\u00f3venes inadaptados que tienen que sobrevivir en un mundo hostil. Me toca trabajar con actores muy buenos como Bonnie Wright, que estuvo en &#8216;Harry Potter&#8217; [interpretaba el personaje de Ginny Weasley] y con estrellas que han estado siempre presentes en mi vida a medida que iba creciendo. Estoy muy entusiasmada, la verdad\u00bb, revel\u00f3 la guapa int\u00e9rprete en el programa &#8216;Hoy&#8217; de la cadena Televisa.<\/p>\n<p>Pero no todo son alegr\u00edas en la ajetreada vida que la rubia actriz ha emprendido en la meca del cine, ya que ni sus futuros compromisos profesionales ni el idilio que mantiene con Liam han logrado que Eiza Gonz\u00e1lez se distraiga temporalmente de la profunda nostalgia que siente por su casa. Adem\u00e1s de confesarse una persona familiar que necesita mantener el estrecho v\u00ednculo que le une a sus seres queridos y a la cultura mexicana, la aspirante a estrella del cine admite que la debilidad que siente por su peque\u00f1a sobrina y la distancia que le separa de ella le han llevado a pensar en regresar a casa.<\/p>\n<p>\u00abExtra\u00f1o much\u00edsimo a mi mam\u00e1, a mi familia, a mi hermana y sobre todo a mi sobrina que tiene un a\u00f1o. Estoy enamorada de mi familia y, obviamente, ellos son el principal pilar de mi vida. No es f\u00e1cil poner rumbo a una ciudad extra\u00f1a y dejar que pase el tiempo. Soy una persona muy familiar y la familia es algo b\u00e1sico para m\u00ed. Necesito convivir con aquellas personas que me hacen regresar a mis ra\u00edces y que me aportan tranquilidad\u00bb, a\u00f1adi\u00f3 Eiza.<\/p>\n<p>A la preocupaci\u00f3n que le invade cuando est\u00e1 separada de su familia se une ahora el fr\u00edo recibimiento que le han dedicado algunos medios de comunicaci\u00f3n en Estados Unidos por su aparente romance con Liam Hemsworth, ya que los besos que comparti\u00f3 con el actor y que fueron r\u00e1pidamente captados por los paparazzi le han colocado en el punto de mira de aquellos que ya la culpan de las penalidades que atraviesa la irreverente Miley Cyrus.<\/p>\n<p>\u00abCuando Miley vio las fotos en las que aparec\u00edan Liam y Eiza bes\u00e1ndose le entr\u00f3 un ataque de nervios y no par\u00f3 de chillar en toda la tarde. Aunque mantuvo la normalidad durante su actuaci\u00f3n en Las Vegas, tan pronto como termin\u00f3 el espect\u00e1culo se encerr\u00f3 en su camerino y se puso a llorar desconsoladamente\u00bb, asegur\u00f3 una fuente cercana a la revista Life &amp; Style.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la opini\u00f3n p\u00fablica se la conoce mejor por haber encandilado al guapo Liam Hemsworth poco despu\u00e9s de que el australiano se separara de Miley Cyrus, pero la joven int\u00e9rprete Eiza Gonz\u00e1lez no quiere que su repentina presencia en la prensa norteamericana eclipse por un momento su gran ambici\u00f3n como actriz. De hecho, en sus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":432265,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-432264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"En la opini\u00f3n p\u00fablica se la conoce mejor por haber encandilado al guapo Liam Hemsworth poco despu\u00e9s de que el australiano se separara de Miley Cyrus, pero la joven int\u00e9rprete Eiza Gonz\u00e1lez no quiere que su repentina presencia en la prensa norteamericana eclipse por un momento su gran ambici\u00f3n como actriz. De hecho, en sus\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"sociedad\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Eiza Gonz\u00e1lez quiere triunfar en Hollywood - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"En la opini\u00f3n p\u00fablica se la conoce mejor por haber encandilado al guapo Liam Hemsworth poco despu\u00e9s de que el australiano se separara de Miley Cyrus, pero la joven int\u00e9rprete Eiza Gonz\u00e1lez no quiere que su repentina presencia en la prensa norteamericana eclipse por un momento su gran ambici\u00f3n como actriz. De hecho, en sus\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"sociedad\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-10-02T16:48:33+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-10-02T16:48:33+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Eiza Gonz\u00e1lez quiere triunfar en Hollywood - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En la opini\u00f3n p\u00fablica se la conoce mejor por haber encandilado al guapo Liam Hemsworth poco despu\u00e9s de que el australiano se separara de Miley Cyrus, pero la joven int\u00e9rprete Eiza Gonz\u00e1lez no quiere que su repentina presencia en la prensa norteamericana eclipse por un momento su gran ambici\u00f3n como actriz. De hecho, en sus\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/eiza-gonzalez-quiere-triunfar-en-hollywood\\\/#blogposting\",\"name\":\"Eiza Gonz\\u00e1lez quiere triunfar en Hollywood - El Digital de Asturias\",\"headline\":\"Eiza Gonz\\u00e1lez quiere triunfar en Hollywood\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":432265},\"datePublished\":\"2013-10-02T16:48:33+02:00\",\"dateModified\":\"2013-10-02T16:48:33+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/eiza-gonzalez-quiere-triunfar-en-hollywood\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/eiza-gonzalez-quiere-triunfar-en-hollywood\\\/#webpage\"},\"articleSection\":\"Sociedad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/eiza-gonzalez-quiere-triunfar-en-hollywood\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"name\":\"Sociedad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"position\":2,\"name\":\"Sociedad\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sociedad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/eiza-gonzalez-quiere-triunfar-en-hollywood\\\/#listItem\",\"name\":\"Eiza Gonz\\u00e1lez quiere triunfar en Hollywood\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/eiza-gonzalez-quiere-triunfar-en-hollywood\\\/#listItem\",\"position\":3,\"name\":\"Eiza Gonz\\u00e1lez quiere triunfar en Hollywood\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sociedad\\\/#listItem\",\"name\":\"Sociedad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/eiza-gonzalez-quiere-triunfar-en-hollywood\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/eiza-gonzalez-quiere-triunfar-en-hollywood\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/eiza-gonzalez-quiere-triunfar-en-hollywood\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/eiza-gonzalez-quiere-triunfar-en-hollywood\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/eiza-gonzalez-quiere-triunfar-en-hollywood\\\/\",\"name\":\"Eiza Gonz\\u00e1lez quiere triunfar en Hollywood - El Digital de Asturias\",\"description\":\"En la opini\\u00f3n p\\u00fablica se la conoce mejor por haber encandilado al guapo Liam Hemsworth poco despu\\u00e9s de que el australiano se separara de Miley Cyrus, pero la joven int\\u00e9rprete Eiza Gonz\\u00e1lez no quiere que su repentina presencia en la prensa norteamericana eclipse por un momento su gran ambici\\u00f3n como actriz. De hecho, en sus\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/eiza-gonzalez-quiere-triunfar-en-hollywood\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":432265,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/eiza-gonzalez-quiere-triunfar-en-hollywood\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/eiza-gonzalez-quiere-triunfar-en-hollywood\\\/#mainImage\"},\"datePublished\":\"2013-10-02T16:48:33+02:00\",\"dateModified\":\"2013-10-02T16:48:33+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Eiza Gonz\u00e1lez quiere triunfar en Hollywood - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Eiza Gonz\u00e1lez quiere triunfar en Hollywood - El Digital de Asturias","description":"En la opini\u00f3n p\u00fablica se la conoce mejor por haber encandilado al guapo Liam Hemsworth poco despu\u00e9s de que el australiano se separara de Miley Cyrus, pero la joven int\u00e9rprete Eiza Gonz\u00e1lez no quiere que su repentina presencia en la prensa norteamericana eclipse por un momento su gran ambici\u00f3n como actriz. De hecho, en sus","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/","robots":"max-image-preview:large","keywords":"sociedad","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/#blogposting","name":"Eiza Gonz\u00e1lez quiere triunfar en Hollywood - El Digital de Asturias","headline":"Eiza Gonz\u00e1lez quiere triunfar en Hollywood","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":432265},"datePublished":"2013-10-02T16:48:33+02:00","dateModified":"2013-10-02T16:48:33+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/#webpage"},"articleSection":"Sociedad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/#listItem","name":"Sociedad"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/#listItem","position":2,"name":"Sociedad","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/#listItem","name":"Eiza Gonz\u00e1lez quiere triunfar en Hollywood"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/#listItem","position":3,"name":"Eiza Gonz\u00e1lez quiere triunfar en Hollywood","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/#listItem","name":"Sociedad"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/","name":"Eiza Gonz\u00e1lez quiere triunfar en Hollywood - El Digital de Asturias","description":"En la opini\u00f3n p\u00fablica se la conoce mejor por haber encandilado al guapo Liam Hemsworth poco despu\u00e9s de que el australiano se separara de Miley Cyrus, pero la joven int\u00e9rprete Eiza Gonz\u00e1lez no quiere que su repentina presencia en la prensa norteamericana eclipse por un momento su gran ambici\u00f3n como actriz. De hecho, en sus","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":432265,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/#mainImage"},"datePublished":"2013-10-02T16:48:33+02:00","dateModified":"2013-10-02T16:48:33+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Eiza Gonz\u00e1lez quiere triunfar en Hollywood - El Digital de Asturias","og:description":"En la opini\u00f3n p\u00fablica se la conoce mejor por haber encandilado al guapo Liam Hemsworth poco despu\u00e9s de que el australiano se separara de Miley Cyrus, pero la joven int\u00e9rprete Eiza Gonz\u00e1lez no quiere que su repentina presencia en la prensa norteamericana eclipse por un momento su gran ambici\u00f3n como actriz. De hecho, en sus","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/","article:tag":["sociedad"],"article:published_time":"2013-10-02T16:48:33+00:00","article:modified_time":"2013-10-02T16:48:33+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Eiza Gonz\u00e1lez quiere triunfar en Hollywood - El Digital de Asturias","twitter:description":"En la opini\u00f3n p\u00fablica se la conoce mejor por haber encandilado al guapo Liam Hemsworth poco despu\u00e9s de que el australiano se separara de Miley Cyrus, pero la joven int\u00e9rprete Eiza Gonz\u00e1lez no quiere que su repentina presencia en la prensa norteamericana eclipse por un momento su gran ambici\u00f3n como actriz. De hecho, en sus","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"432264","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-15 10:38:47","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-11-14 22:38:02","updated":"2026-05-15 10:38:47"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/\" title=\"Sociedad\">Sociedad<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/\" title=\"Eiza Gonz\u00e1lez quiere triunfar en Hollywood\">Eiza Gonz\u00e1lez quiere triunfar en Hollywood<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Sociedad","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sociedad\/"},{"label":"Eiza Gonz\u00e1lez quiere triunfar en Hollywood","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/eiza-gonzalez-quiere-triunfar-en-hollywood\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/432264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=432264"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/432264\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=432264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=432264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=432264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}