{"id":1122215,"date":"2023-04-20T09:28:02","date_gmt":"2023-04-20T07:28:02","guid":{"rendered":"https:\/\/www.eldigitaldeasturias.com\/noticias\/?p=1122215"},"modified":"2023-04-20T09:29:56","modified_gmt":"2023-04-20T07:29:56","slug":"a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/","title":{"rendered":"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios"},"content":{"rendered":"<p><em><strong>El caso se est\u00e1 dirimiendo en el Juzgado de Oviedo, donde las pesquisas policiales apuntan a un entramado similar a una organizaci\u00f3n criminal<\/strong><\/em><\/p>\n<p>El peso de las diligencias recae sobre el Juzgado de Instrucci\u00f3n n\u00ba3 de Oviedo, mientras que las defensas de los encausados son ejercidas por algunos de los mejores abogados penalistas del pa\u00eds, conoci\u00e9ndose que uno de los implicados ha contratado los servicios de Ospina Abogados, despacho penalista con sede en Madrid.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1122216 size-large\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2023\/04\/Guardia-Civil-1-650x361.jpg\" alt=\"Guardia Civil\" width=\"650\" height=\"361\" \/><\/p>\n<h2><strong>LOS HECHOS<\/strong><\/h2>\n<p>Una inspecci\u00f3n realizada a primeros de agosto del a\u00f1o 2022 por el Seprona de la Guardia Civil, tras una denuncia an\u00f3nima, determina el estado de riesgo sanitario que presentaba un almac\u00e9n de distribuci\u00f3n de vinos y reutilizaci\u00f3n de botellas de vidrio en la localidad asturiana de Llanera.<\/p>\n<p>Los agentes, acompa\u00f1ados por inspecci\u00f3n sanitaria, visitaron en tres ocasiones las instalaciones, las cuales presentaban no solo un estado sanitario insuficiente, lleno de moho y con fuertes olores a putrefacci\u00f3n, sino que el producto que all\u00ed se almacenaba para su posterior distribuci\u00f3n estaba caducado, sin trazabilidad y en mal estado. Las actas levantadas en el lugar son incapaces de determinar ni tan siquiera el origen de gran parte del vino, registrado mediante un confuso sistema en base a un Excel y sin tener etiquetados los dep\u00f3sitos que conten\u00edan el producto. Algunos de ellos ocultos por los gestores para que no se descubriesen los miles de litros de vino caducado con los que rellenaban las botellas que posteriormente distribu\u00edan.<\/p>\n<h2><strong>LOS IMPLICADOS <\/strong><\/h2>\n<figure id=\"attachment_1122217\" aria-describedby=\"caption-attachment-1122217\" style=\"width: 544px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1122217 size-large\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2023\/04\/abogados-544x480.jpg\" alt=\"abogados\" width=\"544\" height=\"480\" \/><figcaption id=\"caption-attachment-1122217\" class=\"wp-caption-text\">Juan Gonzalo Ospina y Beatriz Uriarte, abogados penalistas.<\/figcaption><\/figure>\n<p>Sobre la empresa tambi\u00e9n pesa una denuncia por los vertidos ilegales de productos qu\u00edmicos, sosa caustica y el resto del lavado de las botellas al sistema de saneamiento general, entre otros delitos contra la salud p\u00fablica, por los que los se\u00f1alados deben responder ante la justicia.<\/p>\n<p>Entre los letrados personados en la causa destaca el penalista Juan Gonzalo Ospina, abogado experto en delitos contra la salud p\u00fablica, quien al menos ejerce la defensa de uno de los implicados en la empresa, la cual sorprende por su actividad, dado que est\u00e1 a la espera de entrar en concurso de acreedores.<\/p>\n<p>Las autoridades piden responsabilidades tras la investigaci\u00f3n a tres de los implicados, como son el administrador de la empresa, el responsable comercial y el responsable de la trazabilidad y conservaci\u00f3n de los productos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El caso se est\u00e1 dirimiendo en el Juzgado de Oviedo, donde las pesquisas policiales apuntan a un entramado similar a una organizaci\u00f3n criminal El peso de las diligencias recae sobre el Juzgado de Instrucci\u00f3n n\u00ba3 de Oviedo, mientras que las defensas de los encausados son ejercidas por algunos de los mejores abogados penalistas del pa\u00eds, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1122217,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1122215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sucesos"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"El caso se est\u00e1 dirimiendo en el Juzgado de Oviedo, donde las pesquisas policiales apuntan a un entramado similar a una organizaci\u00f3n criminal\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"sucesos\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"El caso se est\u00e1 dirimiendo en el Juzgado de Oviedo, donde las pesquisas policiales apuntan a un entramado similar a una organizaci\u00f3n criminal\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"sucesos\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-04-20T07:28:02+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-04-20T07:29:56+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El caso se est\u00e1 dirimiendo en el Juzgado de Oviedo, donde las pesquisas policiales apuntan a un entramado similar a una organizaci\u00f3n criminal\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\\\/#blogposting\",\"name\":\"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios - El Digital de Asturias\",\"headline\":\"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1122217},\"datePublished\":\"2023-04-20T09:28:02+02:00\",\"dateModified\":\"2023-04-20T09:29:56+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\\\/#webpage\"},\"articleSection\":\"Sucesos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sucesos\\\/#listItem\",\"name\":\"Sucesos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sucesos\\\/#listItem\",\"position\":2,\"name\":\"Sucesos\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sucesos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\\\/#listItem\",\"name\":\"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\\\/#listItem\",\"position\":3,\"name\":\"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sucesos\\\/#listItem\",\"name\":\"Sucesos\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\\\/\",\"name\":\"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios - El Digital de Asturias\",\"description\":\"El caso se est\\u00e1 dirimiendo en el Juzgado de Oviedo, donde las pesquisas policiales apuntan a un entramado similar a una organizaci\\u00f3n criminal\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1122217,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\\\/#mainImage\"},\"datePublished\":\"2023-04-20T09:28:02+02:00\",\"dateModified\":\"2023-04-20T09:29:56+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios - El Digital de Asturias","description":"El caso se est\u00e1 dirimiendo en el Juzgado de Oviedo, donde las pesquisas policiales apuntan a un entramado similar a una organizaci\u00f3n criminal","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/","robots":"max-image-preview:large","keywords":"sucesos","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/#blogposting","name":"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios - El Digital de Asturias","headline":"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":1122217},"datePublished":"2023-04-20T09:28:02+02:00","dateModified":"2023-04-20T09:29:56+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/#webpage"},"articleSection":"Sucesos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sucesos\/#listItem","name":"Sucesos"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sucesos\/#listItem","position":2,"name":"Sucesos","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sucesos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/#listItem","name":"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/#listItem","position":3,"name":"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sucesos\/#listItem","name":"Sucesos"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/","name":"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios - El Digital de Asturias","description":"El caso se est\u00e1 dirimiendo en el Juzgado de Oviedo, donde las pesquisas policiales apuntan a un entramado similar a una organizaci\u00f3n criminal","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":1122217,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/#mainImage"},"datePublished":"2023-04-20T09:28:02+02:00","dateModified":"2023-04-20T09:29:56+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios - El Digital de Asturias","og:description":"El caso se est\u00e1 dirimiendo en el Juzgado de Oviedo, donde las pesquisas policiales apuntan a un entramado similar a una organizaci\u00f3n criminal","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/","article:tag":["sucesos"],"article:published_time":"2023-04-20T07:28:02+00:00","article:modified_time":"2023-04-20T07:29:56+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios - El Digital de Asturias","twitter:description":"El caso se est\u00e1 dirimiendo en el Juzgado de Oviedo, donde las pesquisas policiales apuntan a un entramado similar a una organizaci\u00f3n criminal","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"1122215","title":null,"description":"El caso se est\u00e1 dirimiendo en el Juzgado de Oviedo, donde las pesquisas policiales apuntan a un entramado similar a una organizaci\u00f3n criminal","keywords":[],"keyphrases":{"focus":{"keyphrase":"Juzgado","score":63,"analysis":{"keyphraseInTitle":{"score":3,"maxScore":9,"error":1},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1}}},"additional":[{"keyphrase":"abogados","score":67,"analysis":{"keyphraseInDescription":{"score":3,"maxScore":9,"error":1},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}},{"keyphrase":"Oviedo","score":83,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1}}},{"keyphrase":"Juzgado","score":83,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-10-05 03:10:40","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2023-04-20 07:15:21","updated":"2025-10-05 03:10:40"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sucesos\/\" title=\"Sucesos\">Sucesos<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/\" title=\"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios\">A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Sucesos","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sucesos\/"},{"label":"A juicio una trama dedicada a la venta de vino manipulado para engordar los beneficios","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/a-juicio-una-trama-dedicada-a-la-venta-de-vino-manipulado-para-engordar-los-beneficios\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1122215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=1122215"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1122215\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=1122215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=1122215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=1122215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}