{"id":1122153,"date":"2023-04-18T02:56:49","date_gmt":"2023-04-18T00:56:49","guid":{"rendered":"https:\/\/www.eldigitaldeasturias.com\/noticias\/?p=1122153"},"modified":"2023-04-18T02:56:49","modified_gmt":"2023-04-18T00:56:49","slug":"operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/","title":{"rendered":"Operaci\u00f3n Arqu\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\u00f3n de explosivos"},"content":{"rendered":"<p>(EP) &#8211; La Polic\u00eda Foral de Navarra y la Guardia Civil de Navarra, en el marco de una investigaci\u00f3n conjunta denominada &#8216;Operaci\u00f3n Arqu\u00edmedes&#8217;, han logrado el completo <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sucesos\/\"><strong>desmantelamiento de un laboratorio clandestino<\/strong> <\/a><\/span>de fabricaci\u00f3n de explosivos a partir de la s\u00edntesis de sustancias precursoras de explosivos, ubicado en una localidad de la Cuenca de Pamplona.<\/p>\n<figure id=\"attachment_1122154\" aria-describedby=\"caption-attachment-1122154\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1122154 size-large\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2023\/04\/Operacion-Arquimedes-650x352.jpg\" alt=\"Operaci\u00f3n Arqu\u00edmedes\" width=\"650\" height=\"352\" \/><figcaption id=\"caption-attachment-1122154\" class=\"wp-caption-text\">Foto: POLIC\u00cdA FORAL \/ Europa Press<\/figcaption><\/figure>\n<p>Los precursores de explosivos son sustancias qu\u00edmicas que, a partir de determinadas concentraciones y mezcladas entre s\u00ed o con otros productos, son susceptibles de utilizarse para la fabricaci\u00f3n casera e il\u00edcita de explosivos, por lo que su comercio, adquisici\u00f3n, tenencia y uso est\u00e1n rigurosamente controlados para evitar su desv\u00edo a fines il\u00edcitos, violentos o terroristas.<\/p>\n<p>Para su legal adquisici\u00f3n en nuestro pa\u00eds es necesario contar previamente con una licencia que otorga el Ministerio del Interior a trav\u00e9s del Centro de Inteligencia contra el Terrorismo y el Crimen Organizado (CITCO), que es el Punto de Contacto Nacional en materia de precursores.<\/p>\n<p>Seg\u00fan han informado los cuerpos responsables de esta operaci\u00f3n, las investigaciones comenzaron a ra\u00edz de la detenci\u00f3n de un individuo por un episodio de malos tratos en el \u00e1mbito familiar. Este hecho motiv\u00f3 la creaci\u00f3n de un Equipo Conjunto de Investigaci\u00f3n conformado por agentes especialistas de la Polic\u00eda Foral y del Servicio de Informaci\u00f3n de la Guardia Civil para investigar la posible comisi\u00f3n de un delito de fabricaci\u00f3n ilegal y dep\u00f3sito de sustancias explosivas.<\/p>\n<p>Tras la pr\u00e1ctica de un registro en el domicilio familiar del investigado, se hallaron todos los elementos necesarios para la fabricaci\u00f3n de explosivos, tales como sustancias precursoras de explosivos, otros productos qu\u00edmicos tambi\u00e9n utilizados para su fabricaci\u00f3n, adem\u00e1s de peque\u00f1os artefactos explosivos ya terminados, cerillas el\u00e9ctricas (detonadores), f\u00f3rmulas qu\u00edmicas e instrucciones y material de laboratorio para la s\u00edntesis de los explosivos (pipetas, matraces, term\u00f3metros y vasos de precipitado).<\/p>\n<p>Con los productos incautados en el laboratorio clandestino se podr\u00edan haber elaborado los siguientes explosivos artesanales: triper\u00f3xido de triacetona (TATP), amonal, p\u00f3lvora negra y termita; todos ellos muy peligrosos y de alto poder destructivo.<\/p>\n<p>Entre todos los explosivos que hab\u00eda elaborado o tratado de elaborar destaca por su peligrosidad el TATP, tambi\u00e9n conocido como la &#8216;Madre de Sat\u00e1n&#8217;, explosivo habitualmente utilizado por grupos terroristas islamistas, han explicado Polic\u00eda Foral y Guardia Civil.<\/p>\n<p>La investigaci\u00f3n desarrollada ha permitido determinar que el investigado hab\u00eda adquirido los conocimientos necesarios para la fabricaci\u00f3n de explosivos a trav\u00e9s de manuales y v\u00eddeo tutoriales descargados de internet. As\u00ed mismo, se han localizado numerosas fotograf\u00edas y v\u00eddeos (realizados por \u00e9l mismo), en los que se deja constancia de la metodolog\u00eda utilizada en la fabricaci\u00f3n de explosivos y los resultados de las explosiones de pruebas realizadas con los mismos en las que queda patente su poder destructivo.<\/p>\n<p>Como resultado de la investigaci\u00f3n igualmente se logr\u00f3 identificar a varios establecimientos ubicados en diferentes provincias espa\u00f1olas que, de forma indebida, hab\u00edan vendido los precursores de explosivos al detenido; establecimientos estos que posteriormente han sido objeto de inspecciones administrativas llevadas a cabo conjuntamente por agentes del CITCO y del Servicio de Informaci\u00f3n Guardia Civil, formul\u00e1ndoles las correspondientes denuncias por la puesta a disposici\u00f3n de particulares de sustancias precursoras de explosivos que carec\u00edan de la correspondiente licencia para su legal adquisici\u00f3n.<\/p>\n<p>Con la presente actuaci\u00f3n no s\u00f3lo se ha impedido que los explosivos que trataba de fabricar el detenido pudieran ser utilizados con fines il\u00edcitos o desviados al mercado negro; sino tambi\u00e9n se ha evitado el enorme riesgo existente para la vida e integridad f\u00edsica tanto del propio detenido como de los familiares que con \u00e9l conviv\u00edan en el domicilio donde ten\u00eda instalado el taller clandestino en caso de una explosi\u00f3n accidental durante su manipulaci\u00f3n o almacenamiento.<\/p>\n<p>La operaci\u00f3n ha sido desarrollada por efectivos de la Divisi\u00f3n de Informaci\u00f3n de la Polic\u00eda Foral y del Grupo de Informaci\u00f3n de la Guardia Civil de Navarra, con el apoyo de la Jefatura de Informaci\u00f3n (UCE-3) de la Guardia Civil, el Grupo de Desactivaci\u00f3n de Artefactos Explosivos y Defensa NRBQ de la Guardia Civil de Navarra (GEDEX), la Brigada de Delitos contra las Personas de la Polic\u00eda Foral, la Brigada Asistencial de la Polic\u00eda Foral, la Brigada de Criminal\u00edstica de Laboratorio de Polic\u00eda Foral y el Servicio de Criminal\u00edstica de la Guardia Civil (SECRIM).<\/p>\n<p>La investigaci\u00f3n ha estado coordinada por el Juzgado de Primera Instancia e Instrucci\u00f3n N\u00famero Uno de Aoiz (Navarra).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(EP) &#8211; La Polic\u00eda Foral de Navarra y la Guardia Civil de Navarra, en el marco de una investigaci\u00f3n conjunta denominada &#8216;Operaci\u00f3n Arqu\u00edmedes&#8217;, han logrado el completo desmantelamiento de un laboratorio clandestino de fabricaci\u00f3n de explosivos a partir de la s\u00edntesis de sustancias precursoras de explosivos, ubicado en una localidad de la Cuenca de Pamplona. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1122154,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1122153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sucesos"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"(EP) - La Polic\u00eda Foral de Navarra y la Guardia Civil de Navarra, en el marco de una investigaci\u00f3n conjunta denominada &#039;Operaci\u00f3n Arqu\u00edmedes&#039;\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"sucesos\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Operaci\u00f3n Arqu\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\u00f3n de explosivos - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"(EP) - La Polic\u00eda Foral de Navarra y la Guardia Civil de Navarra, en el marco de una investigaci\u00f3n conjunta denominada &#039;Operaci\u00f3n Arqu\u00edmedes&#039;\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"sucesos\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-04-18T00:56:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-04-18T00:56:49+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Operaci\u00f3n Arqu\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\u00f3n de explosivos - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(EP) - La Polic\u00eda Foral de Navarra y la Guardia Civil de Navarra, en el marco de una investigaci\u00f3n conjunta denominada &#039;Operaci\u00f3n Arqu\u00edmedes&#039;\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\\\/#blogposting\",\"name\":\"Operaci\\u00f3n Arqu\\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\\u00f3n de explosivos - El Digital de Asturias\",\"headline\":\"Operaci\\u00f3n Arqu\\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\\u00f3n de explosivos\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1122154},\"datePublished\":\"2023-04-18T02:56:49+02:00\",\"dateModified\":\"2023-04-18T02:56:49+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\\\/#webpage\"},\"articleSection\":\"Sucesos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sucesos\\\/#listItem\",\"name\":\"Sucesos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sucesos\\\/#listItem\",\"position\":2,\"name\":\"Sucesos\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sucesos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\\\/#listItem\",\"name\":\"Operaci\\u00f3n Arqu\\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\\u00f3n de explosivos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\\\/#listItem\",\"position\":3,\"name\":\"Operaci\\u00f3n Arqu\\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\\u00f3n de explosivos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/sucesos\\\/#listItem\",\"name\":\"Sucesos\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\\\/\",\"name\":\"Operaci\\u00f3n Arqu\\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\\u00f3n de explosivos - El Digital de Asturias\",\"description\":\"(EP) - La Polic\\u00eda Foral de Navarra y la Guardia Civil de Navarra, en el marco de una investigaci\\u00f3n conjunta denominada 'Operaci\\u00f3n Arqu\\u00edmedes'\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1122154,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\\\/#mainImage\"},\"datePublished\":\"2023-04-18T02:56:49+02:00\",\"dateModified\":\"2023-04-18T02:56:49+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Operaci\u00f3n Arqu\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\u00f3n de explosivos - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Operaci\u00f3n Arqu\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\u00f3n de explosivos - El Digital de Asturias","description":"(EP) - La Polic\u00eda Foral de Navarra y la Guardia Civil de Navarra, en el marco de una investigaci\u00f3n conjunta denominada 'Operaci\u00f3n Arqu\u00edmedes'","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/","robots":"max-image-preview:large","keywords":"sucesos","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/#blogposting","name":"Operaci\u00f3n Arqu\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\u00f3n de explosivos - El Digital de Asturias","headline":"Operaci\u00f3n Arqu\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\u00f3n de explosivos","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":1122154},"datePublished":"2023-04-18T02:56:49+02:00","dateModified":"2023-04-18T02:56:49+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/#webpage"},"articleSection":"Sucesos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sucesos\/#listItem","name":"Sucesos"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sucesos\/#listItem","position":2,"name":"Sucesos","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sucesos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/#listItem","name":"Operaci\u00f3n Arqu\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\u00f3n de explosivos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/#listItem","position":3,"name":"Operaci\u00f3n Arqu\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\u00f3n de explosivos","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sucesos\/#listItem","name":"Sucesos"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/","name":"Operaci\u00f3n Arqu\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\u00f3n de explosivos - El Digital de Asturias","description":"(EP) - La Polic\u00eda Foral de Navarra y la Guardia Civil de Navarra, en el marco de una investigaci\u00f3n conjunta denominada 'Operaci\u00f3n Arqu\u00edmedes'","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":1122154,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/#mainImage"},"datePublished":"2023-04-18T02:56:49+02:00","dateModified":"2023-04-18T02:56:49+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Operaci\u00f3n Arqu\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\u00f3n de explosivos - El Digital de Asturias","og:description":"(EP) - La Polic\u00eda Foral de Navarra y la Guardia Civil de Navarra, en el marco de una investigaci\u00f3n conjunta denominada 'Operaci\u00f3n Arqu\u00edmedes'","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/","article:tag":["sucesos"],"article:published_time":"2023-04-18T00:56:49+00:00","article:modified_time":"2023-04-18T00:56:49+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Operaci\u00f3n Arqu\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\u00f3n de explosivos - El Digital de Asturias","twitter:description":"(EP) - La Polic\u00eda Foral de Navarra y la Guardia Civil de Navarra, en el marco de una investigaci\u00f3n conjunta denominada 'Operaci\u00f3n Arqu\u00edmedes'","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"4 minutos"},"aioseo_meta_data":{"post_id":"1122153","title":null,"description":"(EP) - La Polic\u00eda Foral de Navarra y la Guardia Civil de Navarra, en el marco de una investigaci\u00f3n conjunta denominada 'Operaci\u00f3n Arqu\u00edmedes'","keywords":[],"keyphrases":{"focus":{"keyphrase":"Operaci\u00f3n ","score":92,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"Operaci\u00f3n Arqu\u00edmedes","score":83,"analysis":{"keyphraseInDescription":{"score":3,"maxScore":9,"error":1},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-10-05 02:56:31","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2023-04-18 00:51:10","updated":"2025-10-05 02:56:31"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sucesos\/\" title=\"Sucesos\">Sucesos<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/\" title=\"Operaci\u00f3n Arqu\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\u00f3n de explosivos\">Operaci\u00f3n Arqu\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\u00f3n de explosivos<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Sucesos","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/sucesos\/"},{"label":"Operaci\u00f3n Arqu\u00edmedes: Desmantelado un laboratorio clandestino de fabricaci\u00f3n de explosivos","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/operacion-arquimedes-desmantelado-un-laboratorio-clandestino-de-fabricacion-de-explosivos\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1122153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=1122153"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1122153\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=1122153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=1122153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=1122153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}