{"id":1107103,"date":"2022-02-23T17:24:07","date_gmt":"2022-02-23T16:24:07","guid":{"rendered":"https:\/\/www.eldigitaldeasturias.com\/noticias\/?p=1107103"},"modified":"2022-02-23T17:32:51","modified_gmt":"2022-02-23T16:32:51","slug":"ruta-con-mascota-en-asturias-la-costa-de-perlora","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/","title":{"rendered":"Ruta con mascota en Asturias: La costa de Perlora"},"content":{"rendered":"<p>\u00bfBuscas un plan para el fin de semana?, Asturias es sabor y naturaleza; y hoy nosotros te proponemos un buen plan<strong> para que disfrutes con con tu <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/\">mascota<\/a><\/span><\/strong> del \u00faltimo fin de semana del mes de febrero de 2022.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/53HqXTulrOI\" width=\"663\" height=\"373\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<h2>Una ruta por Perlora<\/h2>\n<p>S\u00ed eres amante de la naturaleza<strong> Perlora es una opci\u00f3n ideal para disfrutar de un d\u00eda en pareja, en familia y con tu mascota<\/strong>; bellas playas, zonas verdes, parque de juegos para ni\u00f1os, y adem\u00e1s merenderos para que disfrutes de una buena barbacoa.<\/p>\n<p>\u00bfTienes un peludo?, \u00e9l o ella podr\u00e1 disfrutar de la playa, pues ahora mismo se permite llevar a los perros a los arenales de Perlora, <a href=\"https:\/\/www.youtube.com\/watch?v=53HqXTulrOI\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"><strong>mira el siguiente video<\/strong><\/span><\/a> y podr\u00e1s ver como se lo pasan \u00a1!<\/p>\n<p>No tendr\u00e1s problema de aparcamiento, y adem\u00e1s puedes llegar en bus desde Gij\u00f3n, o en tren desde Avil\u00e9s, Gij\u00f3n y las l\u00edneas que te conecten.<\/p>\n<p>Sin duda Perlora, en el <strong><span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/candas365.es\/noticias\/category\/noticias-carreno\/\" target=\"_blank\" rel=\"noopener\">Concejo de Carre\u00f1o<\/a><\/span><\/strong> puede ser la mejor propuesta para un fin de semana activo y diferente en Asturias.<\/p>\n<p>Recuerda <strong>actuar siempre con responsabilidad<\/strong> a la hora de disfrutar con tu mascota.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfBuscas un plan para el fin de semana?, Asturias es sabor y naturaleza; y hoy nosotros te proponemos un buen plan para que disfrutes con con tu mascota del \u00faltimo fin de semana del mes de febrero de 2022. \ufeff Una ruta por Perlora S\u00ed eres amante de la naturaleza Perlora es una opci\u00f3n ideal [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1132184,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[598],"tags":[],"class_list":["post-1107103","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-mascotas","post_format-post-format-video"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u00bfBuscas un plan para el fin de semana?, Asturias es sabor y naturaleza; y hoy nosotros te proponemos un buen plan para que disfrutes con con tu mascota\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"mascotas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ruta con mascota en Asturias: La costa de Perlora - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"\u00bfBuscas un plan para el fin de semana?, Asturias es sabor y naturaleza; y hoy nosotros te proponemos un buen plan para que disfrutes con con tu mascota\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1265\" \/>\n\t\t<meta property=\"og:image:height\" content=\"697\" \/>\n\t\t<meta property=\"article:tag\" content=\"mascotas\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-02-23T16:24:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-02-23T16:32:51+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ruta con mascota en Asturias: La costa de Perlora - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u00bfBuscas un plan para el fin de semana?, Asturias es sabor y naturaleza; y hoy nosotros te proponemos un buen plan para que disfrutes con con tu mascota\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ruta-con-mascota-en-asturias-la-costa-de-perlora\\\/#blogposting\",\"name\":\"Ruta con mascota en Asturias: La costa de Perlora - El Digital de Asturias\",\"headline\":\"Ruta con mascota en Asturias: La costa de Perlora\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Contenidos.jpg\",\"width\":1265,\"height\":697,\"caption\":\"Contenidos\"},\"datePublished\":\"2022-02-23T17:24:07+01:00\",\"dateModified\":\"2022-02-23T17:32:51+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ruta-con-mascota-en-asturias-la-costa-de-perlora\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ruta-con-mascota-en-asturias-la-costa-de-perlora\\\/#webpage\"},\"articleSection\":\"Mascotas, V\\u00eddeo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ruta-con-mascota-en-asturias-la-costa-de-perlora\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/#listItem\",\"name\":\"Mascotas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/#listItem\",\"position\":2,\"name\":\"Mascotas\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ruta-con-mascota-en-asturias-la-costa-de-perlora\\\/#listItem\",\"name\":\"Ruta con mascota en Asturias: La costa de Perlora\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ruta-con-mascota-en-asturias-la-costa-de-perlora\\\/#listItem\",\"position\":3,\"name\":\"Ruta con mascota en Asturias: La costa de Perlora\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/#listItem\",\"name\":\"Mascotas\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ruta-con-mascota-en-asturias-la-costa-de-perlora\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ruta-con-mascota-en-asturias-la-costa-de-perlora\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ruta-con-mascota-en-asturias-la-costa-de-perlora\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ruta-con-mascota-en-asturias-la-costa-de-perlora\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ruta-con-mascota-en-asturias-la-costa-de-perlora\\\/\",\"name\":\"Ruta con mascota en Asturias: La costa de Perlora - El Digital de Asturias\",\"description\":\"\\u00bfBuscas un plan para el fin de semana?, Asturias es sabor y naturaleza; y hoy nosotros te proponemos un buen plan para que disfrutes con con tu mascota\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ruta-con-mascota-en-asturias-la-costa-de-perlora\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Contenidos.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ruta-con-mascota-en-asturias-la-costa-de-perlora\\\/#mainImage\",\"width\":1265,\"height\":697,\"caption\":\"Contenidos\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/ruta-con-mascota-en-asturias-la-costa-de-perlora\\\/#mainImage\"},\"datePublished\":\"2022-02-23T17:24:07+01:00\",\"dateModified\":\"2022-02-23T17:32:51+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Ruta con mascota en Asturias: La costa de Perlora - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Ruta con mascota en Asturias: La costa de Perlora - El Digital de Asturias","description":"\u00bfBuscas un plan para el fin de semana?, Asturias es sabor y naturaleza; y hoy nosotros te proponemos un buen plan para que disfrutes con con tu mascota","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/","robots":"max-image-preview:large","keywords":"mascotas","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/#blogposting","name":"Ruta con mascota en Asturias: La costa de Perlora - El Digital de Asturias","headline":"Ruta con mascota en Asturias: La costa de Perlora","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","width":1265,"height":697,"caption":"Contenidos"},"datePublished":"2022-02-23T17:24:07+01:00","dateModified":"2022-02-23T17:32:51+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/#webpage"},"articleSection":"Mascotas, V\u00eddeo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/#listItem","name":"Mascotas"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/#listItem","position":2,"name":"Mascotas","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/#listItem","name":"Ruta con mascota en Asturias: La costa de Perlora"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/#listItem","position":3,"name":"Ruta con mascota en Asturias: La costa de Perlora","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/#listItem","name":"Mascotas"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/","name":"Ruta con mascota en Asturias: La costa de Perlora - El Digital de Asturias","description":"\u00bfBuscas un plan para el fin de semana?, Asturias es sabor y naturaleza; y hoy nosotros te proponemos un buen plan para que disfrutes con con tu mascota","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/#mainImage","width":1265,"height":697,"caption":"Contenidos"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/#mainImage"},"datePublished":"2022-02-23T17:24:07+01:00","dateModified":"2022-02-23T17:32:51+01:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Ruta con mascota en Asturias: La costa de Perlora - El Digital de Asturias","og:description":"\u00bfBuscas un plan para el fin de semana?, Asturias es sabor y naturaleza; y hoy nosotros te proponemos un buen plan para que disfrutes con con tu mascota","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/","og:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","og:image:secure_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","og:image:width":1265,"og:image:height":697,"article:tag":["mascotas"],"article:published_time":"2022-02-23T16:24:07+00:00","article:modified_time":"2022-02-23T16:32:51+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Ruta con mascota en Asturias: La costa de Perlora - El Digital de Asturias","twitter:description":"\u00bfBuscas un plan para el fin de semana?, Asturias es sabor y naturaleza; y hoy nosotros te proponemos un buen plan para que disfrutes con con tu mascota","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2026\/06\/Contenidos.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"1107103","title":null,"description":"\u00bfBuscas un plan para el fin de semana?, Asturias es sabor y naturaleza; y hoy nosotros te proponemos un buen plan para que disfrutes con con tu mascota","keywords":[],"keyphrases":{"focus":{"keyphrase":"mascota","score":88,"analysis":{"keyphraseInTitle":{"title":"Focus keyphrase in SEO title","description":"Focus keyphrase found in SEO title.","score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"title":"Focus keyphrase in meta description","description":"Focus keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Focus keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"title":"Focus keyphrase in URL","description":"Focus keyphrase used in the URL.","score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"title":"Focus keyphrase in introduction","description":"Your Focus keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"title":"Focus keyphrase in Subheadings","description":"Use your focus keyphrase more in your H2 and H3 subheadings.","score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":[]}},"additional":[{"keyphrase":"Asturias ","score":100,"analysis":{"keyphraseInDescription":{"title":"Keyphrase in meta description","description":"Keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"title":"Keyphrase in introduction","description":"Your Keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":[]}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-10-02 00:34:02","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2022-02-23 15:57:00","updated":"2025-10-02 00:34:02"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/\" title=\"Mascotas\">Mascotas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/\" title=\"Ruta con mascota en Asturias: La costa de Perlora\">Ruta con mascota en Asturias: La costa de Perlora<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Mascotas","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/"},{"label":"Ruta con mascota en Asturias: La costa de Perlora","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/ruta-con-mascota-en-asturias-la-costa-de-perlora\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1107103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=1107103"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1107103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media\/1132184"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=1107103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=1107103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=1107103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}