{"id":1098646,"date":"2021-09-10T18:47:12","date_gmt":"2021-09-10T16:47:12","guid":{"rendered":"https:\/\/www.eldigitaldeasturias.com\/noticias\/?p=1098646"},"modified":"2021-09-10T18:47:12","modified_gmt":"2021-09-10T16:47:12","slug":"cachorro-en-casa-como-educarle","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/","title":{"rendered":"Cachorro en casa: \u00bfC\u00f3mo educarle?"},"content":{"rendered":"<p>(dpa) &#8211; Si un cachorro es nuevo en la familia, los propietarios deben marcar el rumbo de su nueva vida desde el principio. <strong>Pero \u00bfqu\u00e9 necesita realmente un cachorro para aprender r\u00e1pidamente?<\/strong><\/p>\n<figure id=\"attachment_1098647\" aria-describedby=\"caption-attachment-1098647\" style=\"width: 645px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1098647\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2021\/09\/cachorro-360x244.jpg\" alt=\"cachorro\" width=\"645\" height=\"437\" \/><figcaption id=\"caption-attachment-1098647\" class=\"wp-caption-text\">Los cachorros no pueden controlar esf\u00ednteres, por lo que conviene sacarlos con frecuencia, aunque sea a un peque\u00f1o espacio verde, para que puedan hacer sus necesidades. Foto: Christiane Oelrich\/dpa<\/figcaption><\/figure>\n<p>Adem\u00e1s de conocer a todos los miembros de la familia, someterse al adiestramiento en el hogar es una lecci\u00f3n que el cachorro debe aprender desde el inicio.<\/p>\n<blockquote><p>Para ello, los propietarios tienen que estar pendientes del reloj desde el minuto uno y vigilar constantemente al cachorro, se\u00f1ala la revista alemana \u00abEin Herz f\u00fcr Tiere\u00bb (Un coraz\u00f3n para los animales) (n\u00famero de abril de 2021).<\/p><\/blockquote>\n<p>Estos perros j\u00f3venes no pueden controlar todav\u00eda la vejiga y los intestinos. Por ello, necesitan hacer sus necesidades cuando se despiertan, despu\u00e9s de una larga siesta, adem\u00e1s de a los 10 o 20 minutos despu\u00e9s de cada comida.<\/p>\n<h2>Lo mejor es sacar a los cachorros al exterior r\u00e1pidamente<\/h2>\n<p>Los animales tambi\u00e9n demuestran esa necesidad con su comportamiento. <strong>Si se mueven como si estuvieran buscando algo y dando vueltas sin descanso, entonces hay que salir de casa r\u00e1pido<\/strong>.<\/p>\n<p>Lo mejor es coger al perro en brazos y llevarlo a donde se les permita hacer sus necesidades ya sea en el jard\u00edn, en una franja de c\u00e9sped o en un campo. En cuanto el cachorro lo haga bien, hay que elogiarlo efusivamente.<\/p>\n<p>Quien no tenga jard\u00edn o un camino m\u00e1s lejano hasta el pr\u00f3ximo parque, puede tomar el balc\u00f3n como sustituto al principio. <strong>Un metro cuadrado de c\u00e9sped es suficiente como lugar tranquilo<\/strong>. Como inodoro de emergencia dentro de la casa, el trozo de c\u00e9sped tambi\u00e9n es una posibilidad si se instala un contenedor amplio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(dpa) &#8211; Si un cachorro es nuevo en la familia, los propietarios deben marcar el rumbo de su nueva vida desde el principio. Pero \u00bfqu\u00e9 necesita realmente un cachorro para aprender r\u00e1pidamente? Adem\u00e1s de conocer a todos los miembros de la familia, someterse al adiestramiento en el hogar es una lecci\u00f3n que el cachorro debe [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1098647,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[598],"tags":[],"class_list":["post-1098646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mascotas"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Si un cachorro es nuevo en la familia, los propietarios deben marcar el rumbo de su nueva vida desde el principio. Pero \u00bfqu\u00e9 necesita realmente un cachorro\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"mascotas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Cachorro en casa: \u00bfC\u00f3mo educarle? - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Si un cachorro es nuevo en la familia, los propietarios deben marcar el rumbo de su nueva vida desde el principio. Pero \u00bfqu\u00e9 necesita realmente un cachorro\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"mascotas\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-09-10T16:47:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-09-10T16:47:12+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Cachorro en casa: \u00bfC\u00f3mo educarle? - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Si un cachorro es nuevo en la familia, los propietarios deben marcar el rumbo de su nueva vida desde el principio. Pero \u00bfqu\u00e9 necesita realmente un cachorro\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cachorro-en-casa-como-educarle\\\/#blogposting\",\"name\":\"Cachorro en casa: \\u00bfC\\u00f3mo educarle? - El Digital de Asturias\",\"headline\":\"Cachorro en casa: \\u00bfC\\u00f3mo educarle?\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1098647},\"datePublished\":\"2021-09-10T18:47:12+02:00\",\"dateModified\":\"2021-09-10T18:47:12+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cachorro-en-casa-como-educarle\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cachorro-en-casa-como-educarle\\\/#webpage\"},\"articleSection\":\"Mascotas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cachorro-en-casa-como-educarle\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/#listItem\",\"name\":\"Mascotas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/#listItem\",\"position\":2,\"name\":\"Mascotas\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cachorro-en-casa-como-educarle\\\/#listItem\",\"name\":\"Cachorro en casa: \\u00bfC\\u00f3mo educarle?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cachorro-en-casa-como-educarle\\\/#listItem\",\"position\":3,\"name\":\"Cachorro en casa: \\u00bfC\\u00f3mo educarle?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/#listItem\",\"name\":\"Mascotas\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cachorro-en-casa-como-educarle\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cachorro-en-casa-como-educarle\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cachorro-en-casa-como-educarle\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cachorro-en-casa-como-educarle\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cachorro-en-casa-como-educarle\\\/\",\"name\":\"Cachorro en casa: \\u00bfC\\u00f3mo educarle? - El Digital de Asturias\",\"description\":\"Si un cachorro es nuevo en la familia, los propietarios deben marcar el rumbo de su nueva vida desde el principio. Pero \\u00bfqu\\u00e9 necesita realmente un cachorro\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cachorro-en-casa-como-educarle\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1098647,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cachorro-en-casa-como-educarle\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/cachorro-en-casa-como-educarle\\\/#mainImage\"},\"datePublished\":\"2021-09-10T18:47:12+02:00\",\"dateModified\":\"2021-09-10T18:47:12+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Cachorro en casa: \u00bfC\u00f3mo educarle? - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Cachorro en casa: \u00bfC\u00f3mo educarle? - El Digital de Asturias","description":"Si un cachorro es nuevo en la familia, los propietarios deben marcar el rumbo de su nueva vida desde el principio. Pero \u00bfqu\u00e9 necesita realmente un cachorro","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/","robots":"max-image-preview:large","keywords":"mascotas","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/#blogposting","name":"Cachorro en casa: \u00bfC\u00f3mo educarle? - El Digital de Asturias","headline":"Cachorro en casa: \u00bfC\u00f3mo educarle?","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":1098647},"datePublished":"2021-09-10T18:47:12+02:00","dateModified":"2021-09-10T18:47:12+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/#webpage"},"articleSection":"Mascotas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/#listItem","name":"Mascotas"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/#listItem","position":2,"name":"Mascotas","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/#listItem","name":"Cachorro en casa: \u00bfC\u00f3mo educarle?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/#listItem","position":3,"name":"Cachorro en casa: \u00bfC\u00f3mo educarle?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/#listItem","name":"Mascotas"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/","name":"Cachorro en casa: \u00bfC\u00f3mo educarle? - El Digital de Asturias","description":"Si un cachorro es nuevo en la familia, los propietarios deben marcar el rumbo de su nueva vida desde el principio. Pero \u00bfqu\u00e9 necesita realmente un cachorro","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":1098647,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/#mainImage"},"datePublished":"2021-09-10T18:47:12+02:00","dateModified":"2021-09-10T18:47:12+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Cachorro en casa: \u00bfC\u00f3mo educarle? - El Digital de Asturias","og:description":"Si un cachorro es nuevo en la familia, los propietarios deben marcar el rumbo de su nueva vida desde el principio. Pero \u00bfqu\u00e9 necesita realmente un cachorro","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/","article:tag":["mascotas"],"article:published_time":"2021-09-10T16:47:12+00:00","article:modified_time":"2021-09-10T16:47:12+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Cachorro en casa: \u00bfC\u00f3mo educarle? - El Digital de Asturias","twitter:description":"Si un cachorro es nuevo en la familia, los propietarios deben marcar el rumbo de su nueva vida desde el principio. Pero \u00bfqu\u00e9 necesita realmente un cachorro","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"1098646","title":null,"description":"Si un cachorro es nuevo en la familia, los propietarios deben marcar el rumbo de su nueva vida desde el principio. Pero \u00bfqu\u00e9 necesita realmente un cachorro&nbsp;","keywords":[],"keyphrases":{"focus":{"keyphrase":"cachorro ","score":83,"analysis":{"keyphraseInTitle":{"title":"Frase clave objetivo en el t\u00edtulo SEO","description":"Frase clave objetivo encontrada en el t\u00edtulo SEO.","score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"title":"Frase clave objetivo en la meta descripci\u00f3n","description":"Frase clave objetivo encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseInURL":{"title":"Frase clave objetivo en la URL","description":"Frase clave objetivo no encontrada en la URL.","score":1,"maxScore":5,"error":1},"keyphraseLength":{"title":"Longitud de la Frase clave objetivo","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"title":"Frase clave objetivo en la introducci\u00f3n","description":"Su Frase clave objetivo aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"title":"Frase clave objetivo sus subt\u00edtulos","description":"Use tu frase clave objetivo m\u00e1s en tus subencabezados H2 y H3.","score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"title":"Frase clave objetivo en los atributos alt de las im\u00e1genes","description":"Frase clave objetivo encontrada en los atributos alt de la(s) imagen(es).","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"nueva vida ","score":83,"analysis":{"keyphraseInDescription":{"title":"Frase clave en la meta descripci\u00f3n","description":"Frase clave encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Longitud de la Frase clave","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"title":"Frase clave en la introducci\u00f3n","description":"Su Frase clave aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Frase clave en los atributos alt de las im\u00e1genes","description":"Frase clave no se encuentra en los atributos alt de la imagen. A\u00f1ada una imagen con su Frase clave como texto alternativo.","score":3,"maxScore":9,"error":1}}},{"keyphrase":"un cachorro ","score":83,"analysis":{"keyphraseInDescription":{"title":"Frase clave en la meta descripci\u00f3n","description":"Frase clave encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Longitud de la Frase clave","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"title":"Frase clave en la introducci\u00f3n","description":"Su Frase clave aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Frase clave en los atributos alt de las im\u00e1genes","description":"Frase clave no se encuentra en los atributos alt de la imagen. A\u00f1ada una imagen con su Frase clave como texto alternativo.","score":3,"maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-09-19 08:14:19","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-09-10 16:33:12","updated":"2025-09-24 00:16:30"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/\" title=\"Mascotas\">Mascotas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/\" title=\"Cachorro en casa: \u00bfC\u00f3mo educarle?\">Cachorro en casa: \u00bfC\u00f3mo educarle?<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Mascotas","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/"},{"label":"Cachorro en casa: \u00bfC\u00f3mo educarle?","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/cachorro-en-casa-como-educarle\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1098646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=1098646"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1098646\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=1098646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=1098646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=1098646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}