{"id":1096528,"date":"2021-08-03T12:08:07","date_gmt":"2021-08-03T10:08:07","guid":{"rendered":"https:\/\/www.eldigitaldeasturias.com\/noticias\/?p=1096528"},"modified":"2021-08-03T12:08:07","modified_gmt":"2021-08-03T10:08:07","slug":"los-gasol-dejan-la-seleccion","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/","title":{"rendered":"Los Gasol dejan la selecci\u00f3n"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1074027\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/08\/Noticias-Urgentes-360x225.jpg\" alt=\"News\" width=\"360\" height=\"225\" \/>(EP) &#8211; El p\u00edvot de la selecci\u00f3n espa\u00f1ola <strong>Marc Gasol ha anunciado este martes su retirada del equipo nacional<\/strong>, despu\u00e9s de la eliminaci\u00f3n ol\u00edmpica ante Estados Unidos, cerrando una exitosa trayectoria de 15 a\u00f1os, 191 partidos y nueve medallas.<\/p>\n<p>A sus 36 a\u00f1os,<strong> Marc se une a su hermano Pau<\/strong>, que ya hab\u00eda anunciado que dejar\u00eda la selecci\u00f3n despu\u00e9s de estos Juegos, y clausura un periplo con la selecci\u00f3n absoluta que comenz\u00f3 en 2006 con el recordado oro en el Mundial de Jap\u00f3n.<\/p>\n<p>En total, el catal\u00e1n ha conquistado cuatro oros (dos mundiales y dos europeos), tres platas (dos ol\u00edmpicas y una europea) y dos bronces (ambos europeos). Con poco protagonismo estos d\u00edas en Tokio, su \u00faltima gran aportaci\u00f3n se produjo hace dos a\u00f1os, cuando fue clave para que Espa\u00f1a levantara el t\u00edtulo en el Mundial de China.<\/p>\n<p>El jugador de Los Angeles Lakers ha vestido en 191 ocasiones la camiseta del equipo nacional, octavo en esta lista hist\u00f3rica empatado con Wayne Brabender y por detr\u00e1s de compa\u00f1eros como Juan Carlos Navarro (253), Rudy Fern\u00e1ndez (233) o su hermano Pau (216), otros miembros clave de la mejor generaci\u00f3n en la historia del baloncesto espa\u00f1ol.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(EP) &#8211; El p\u00edvot de la selecci\u00f3n espa\u00f1ola Marc Gasol ha anunciado este martes su retirada del equipo nacional, despu\u00e9s de la eliminaci\u00f3n ol\u00edmpica ante Estados Unidos, cerrando una exitosa trayectoria de 15 a\u00f1os, 191 partidos y nueve medallas. A sus 36 a\u00f1os, Marc se une a su hermano Pau, que ya hab\u00eda anunciado que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1074027,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[190],"tags":[],"class_list":["post-1096528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"El p\u00edvot de la selecci\u00f3n espa\u00f1ola Marc Gasol ha anunciado este martes su retirada del equipo nacional\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"deportes\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los Gasol dejan la selecci\u00f3n - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"El p\u00edvot de la selecci\u00f3n espa\u00f1ola Marc Gasol ha anunciado este martes su retirada del equipo nacional\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"deportes\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-08-03T10:08:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-08-03T10:08:07+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los Gasol dejan la selecci\u00f3n - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El p\u00edvot de la selecci\u00f3n espa\u00f1ola Marc Gasol ha anunciado este martes su retirada del equipo nacional\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/los-gasol-dejan-la-seleccion\\\/#blogposting\",\"name\":\"Los Gasol dejan la selecci\\u00f3n - El Digital de Asturias\",\"headline\":\"Los Gasol dejan la selecci\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1074027},\"datePublished\":\"2021-08-03T12:08:07+02:00\",\"dateModified\":\"2021-08-03T12:08:07+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/los-gasol-dejan-la-seleccion\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/los-gasol-dejan-la-seleccion\\\/#webpage\"},\"articleSection\":\"Deportes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/los-gasol-dejan-la-seleccion\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"position\":2,\"name\":\"Deportes\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/los-gasol-dejan-la-seleccion\\\/#listItem\",\"name\":\"Los Gasol dejan la selecci\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/los-gasol-dejan-la-seleccion\\\/#listItem\",\"position\":3,\"name\":\"Los Gasol dejan la selecci\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/los-gasol-dejan-la-seleccion\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/los-gasol-dejan-la-seleccion\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/los-gasol-dejan-la-seleccion\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/los-gasol-dejan-la-seleccion\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/los-gasol-dejan-la-seleccion\\\/\",\"name\":\"Los Gasol dejan la selecci\\u00f3n - El Digital de Asturias\",\"description\":\"El p\\u00edvot de la selecci\\u00f3n espa\\u00f1ola Marc Gasol ha anunciado este martes su retirada del equipo nacional\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/los-gasol-dejan-la-seleccion\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1074027,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/los-gasol-dejan-la-seleccion\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/los-gasol-dejan-la-seleccion\\\/#mainImage\"},\"datePublished\":\"2021-08-03T12:08:07+02:00\",\"dateModified\":\"2021-08-03T12:08:07+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Los Gasol dejan la selecci\u00f3n - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Los Gasol dejan la selecci\u00f3n - El Digital de Asturias","description":"El p\u00edvot de la selecci\u00f3n espa\u00f1ola Marc Gasol ha anunciado este martes su retirada del equipo nacional","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/","robots":"max-image-preview:large","keywords":"deportes","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/#blogposting","name":"Los Gasol dejan la selecci\u00f3n - El Digital de Asturias","headline":"Los Gasol dejan la selecci\u00f3n","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":1074027},"datePublished":"2021-08-03T12:08:07+02:00","dateModified":"2021-08-03T12:08:07+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/#webpage"},"articleSection":"Deportes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","position":2,"name":"Deportes","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/#listItem","name":"Los Gasol dejan la selecci\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/#listItem","position":3,"name":"Los Gasol dejan la selecci\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/","name":"Los Gasol dejan la selecci\u00f3n - El Digital de Asturias","description":"El p\u00edvot de la selecci\u00f3n espa\u00f1ola Marc Gasol ha anunciado este martes su retirada del equipo nacional","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":1074027,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/#mainImage"},"datePublished":"2021-08-03T12:08:07+02:00","dateModified":"2021-08-03T12:08:07+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Los Gasol dejan la selecci\u00f3n - El Digital de Asturias","og:description":"El p\u00edvot de la selecci\u00f3n espa\u00f1ola Marc Gasol ha anunciado este martes su retirada del equipo nacional","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/","article:tag":["deportes"],"article:published_time":"2021-08-03T10:08:07+00:00","article:modified_time":"2021-08-03T10:08:07+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Los Gasol dejan la selecci\u00f3n - El Digital de Asturias","twitter:description":"El p\u00edvot de la selecci\u00f3n espa\u00f1ola Marc Gasol ha anunciado este martes su retirada del equipo nacional","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"1096528","title":null,"description":"El p\u00edvot de la selecci\u00f3n espa\u00f1ola Marc Gasol ha anunciado este martes su retirada del equipo nacional","keywords":[],"keyphrases":{"focus":{"keyphrase":"Gasol","score":80,"analysis":{"keyphraseInTitle":{"title":"Frase clave objetivo en el t\u00edtulo SEO","description":"Frase clave objetivo encontrada en el t\u00edtulo SEO.","score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"title":"Frase clave objetivo en la meta descripci\u00f3n","description":"Frase clave objetivo encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseInURL":{"title":"Frase clave objetivo en la URL","description":"Frase clave objetivo no encontrada en la URL.","score":1,"maxScore":5,"error":1},"keyphraseLength":{"title":"Longitud de la Frase clave objetivo","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"title":"Frase clave objetivo en la introducci\u00f3n","description":"Su Frase clave objetivo aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"title":"Frase clave objetivo en los atributos alt de la imagen.","description":"Frase clave objetivo no se encuentra en los atributos alt de la imagen. A\u00f1ada una imagen con su Frase clave objetivo como texto alternativo.","score":3,"maxScore":9,"error":1}}},"additional":[{"keyphrase":"retirada del equipo","score":83,"analysis":{"keyphraseInDescription":{"title":"Frase clave en la meta descripci\u00f3n","description":"Frase clave encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Longitud de la Frase clave","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":3},"keyphraseInIntroduction":{"title":"Frase clave en la introducci\u00f3n","description":"Su Frase clave aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Frase clave en los atributos alt de la imagen.","description":"Frase clave no se encuentra en los atributos alt de la imagen. A\u00f1ada una imagen con su Frase clave como texto alternativo.","score":3,"maxScore":9,"error":1}}},{"keyphrase":"selecci\u00f3n espa\u00f1ola","score":83,"analysis":{"keyphraseInDescription":{"title":"Frase clave en la meta descripci\u00f3n","description":"Frase clave encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Longitud de la Frase clave","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"title":"Frase clave en la introducci\u00f3n","description":"Su Frase clave aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Frase clave en los atributos alt de la imagen.","description":"Frase clave no se encuentra en los atributos alt de la imagen. A\u00f1ada una imagen con su Frase clave como texto alternativo.","score":3,"maxScore":9,"error":1}}},{"keyphrase":"selecci\u00f3n","score":83,"analysis":{"keyphraseInDescription":{"title":"Frase clave en la meta descripci\u00f3n","description":"Frase clave encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Longitud de la Frase clave","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"title":"Frase clave en la introducci\u00f3n","description":"Su Frase clave aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Frase clave en los atributos alt de la imagen.","description":"Frase clave no se encuentra en los atributos alt de la imagen. A\u00f1ada una imagen con su Frase clave como texto alternativo.","score":3,"maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"email":"","phone":"","phoneFormatted":"","fax":"","faxFormatted":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"seo_analyzer_scan_date":"2025-09-18 10:03:30","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-08-03 10:05:32","updated":"2025-09-23 17:54:59"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/\" title=\"Deportes\">Deportes<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/\" title=\"Los Gasol dejan la selecci\u00f3n\">Los Gasol dejan la selecci\u00f3n<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Deportes","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/"},{"label":"Los Gasol dejan la selecci\u00f3n","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/los-gasol-dejan-la-seleccion\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1096528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=1096528"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1096528\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=1096528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=1096528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=1096528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}