{"id":1094450,"date":"2021-06-25T11:29:28","date_gmt":"2021-06-25T10:29:28","guid":{"rendered":"https:\/\/www.eldigitaldeasturias.com\/noticias\/?p=1094450"},"modified":"2021-06-25T11:29:28","modified_gmt":"2021-06-25T10:29:28","slug":"luis-enrique-yo-voy-paso-a-paso","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/","title":{"rendered":"Luis Enrique: \u00abYo voy paso a paso\u00bb"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1067967\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/06\/football-360x241.jpg\" alt=\"\" width=\"360\" height=\"241\" \/>El seleccionador nacional de f\u00fatbol, el asturiano, Luis Enrique Mart\u00ednez, celebr\u00f3 poder \u00abdescorchar el cava\u00bb del pase a octavos de final de la Eurocopa 2020, como un \u00abalivio\u00bb y un subid\u00f3n para sus jugadores, que <strong>piensan ya en Croacia despu\u00e9s de golear (0-5) a Eslovaquia<\/strong>.<\/p>\n<p>\u00abYo voy paso a paso, digo las expectativas que tenemos y no lo he cambiado. Es evidente que se ha descorchado la botella de cava, nos alegramos por la afici\u00f3n y la selecci\u00f3n y a partir de aqu\u00ed a sacar otra botella de cava, vamos a ver si la podemos descorchar\u00bb, dijo en rueda de prensa en La Cartuja (Sevilla).<\/p>\n<p>El preparador de &#8216;La Roja&#8217; fue preguntado por el papel de Sergio Busquets en su estreno en la Euro tras su positivo por coronavirus en los d\u00edas previos al inicio del torneo. <strong>\u00abEl partido de Busquets es de manual, de lo que tiene que hacer un pivote en defensa y ataque, sab\u00edamos de la importante de Busquets, ha acabado reventado pero sab\u00edamos de su nivel. Es bastante incomprendido porque lleva muchos a\u00f1os pero es un jugador \u00fanico y una garant\u00eda\u00bb<\/strong>, apunt\u00f3.<\/p>\n<p>\u00abEs un alivio, no solo para m\u00ed, por lo que significa en seguir insistiendo en los conceptos a los jugadores y que vean que se puede llegar al resultado de manera clara jugando a lo que jugamos. <strong>Refrenda lo que buscamos<\/strong>, viene en el mejor momento y nos prepara para los octavos con mucha confianza\u00bb, a\u00f1adi\u00f3 sobre el partido.<\/p>\n<p>\u00abNo est\u00e1bamos para escoger rival, quer\u00edamos ganar nuestro partido y el que nos tocara. <strong>Nos toca Croacia, en Copenhague, ciudad bonita y equipo de alto nivel, les conocemos bien, hemos<\/strong> jugado en la Liga de Naciones, ser\u00e1 un rival complicado pero no puedes esperar que haya rivales asequibles\u00bb, coment\u00f3 sobre el cruce de octavos.<\/p>\n<p>Luis Enrique explic\u00f3 sus cambios en el once. \u00abHay veces que hay una especie de bloqueo y muchas veces menando un poco el avispero aparece lo que ha aparecido hoy, que ahora tengo otra vez a los 24 empalmados, todos con ganas y nivel para jugar. A veces tiene sus riegos pero cuando sale bien es algo muy positivo\u00bb, explic\u00f3.<\/p>\n<p><strong>El t\u00e9cnico asturiano no dio importancia a las cr\u00edticas ni a los elogios<\/strong>. \u00abEs cierto que la concentraci\u00f3n ha sido \u00fanica en el plano mental, nunca ha sido una excusa. Hoy en el plano f\u00edsico ha sido un ritmo muy alto y hemos utilizados los cambios, pero nada importante. Cuando se gana se reciben elogios y cuando se pierde vas a recibir criticas, si alguien lo sabe son los entrenadores\u00bb, zanj\u00f3.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El seleccionador nacional de f\u00fatbol, el asturiano, Luis Enrique Mart\u00ednez, celebr\u00f3 poder \u00abdescorchar el cava\u00bb del pase a octavos de final de la Eurocopa 2020, como un \u00abalivio\u00bb y un subid\u00f3n para sus jugadores, que piensan ya en Croacia despu\u00e9s de golear (0-5) a Eslovaquia. \u00abYo voy paso a paso, digo las expectativas que tenemos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1067967,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[190],"tags":[],"class_list":["post-1094450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"El seleccionador nacional de f\u00fatbol, el asturiano, Luis Enrique Mart\u00ednez, celebr\u00f3 poder &quot;descorchar el cava&quot; del pase a octavos de final de la Eurocopa 2020\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"deportes\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Luis Enrique: \u00abYo voy paso a paso\u00bb - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"El seleccionador nacional de f\u00fatbol, el asturiano, Luis Enrique Mart\u00ednez, celebr\u00f3 poder &quot;descorchar el cava&quot; del pase a octavos de final de la Eurocopa 2020\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"deportes\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-06-25T10:29:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-06-25T10:29:28+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Luis Enrique: \u00abYo voy paso a paso\u00bb - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El seleccionador nacional de f\u00fatbol, el asturiano, Luis Enrique Mart\u00ednez, celebr\u00f3 poder &quot;descorchar el cava&quot; del pase a octavos de final de la Eurocopa 2020\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/luis-enrique-yo-voy-paso-a-paso\\\/#blogposting\",\"name\":\"Luis Enrique: \\u00abYo voy paso a paso\\u00bb - El Digital de Asturias\",\"headline\":\"Luis Enrique: \\u00abYo voy paso a paso\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1067967},\"datePublished\":\"2021-06-25T11:29:28+02:00\",\"dateModified\":\"2021-06-25T11:29:28+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/luis-enrique-yo-voy-paso-a-paso\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/luis-enrique-yo-voy-paso-a-paso\\\/#webpage\"},\"articleSection\":\"Deportes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/luis-enrique-yo-voy-paso-a-paso\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"position\":2,\"name\":\"Deportes\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/luis-enrique-yo-voy-paso-a-paso\\\/#listItem\",\"name\":\"Luis Enrique: \\u00abYo voy paso a paso\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/luis-enrique-yo-voy-paso-a-paso\\\/#listItem\",\"position\":3,\"name\":\"Luis Enrique: \\u00abYo voy paso a paso\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/luis-enrique-yo-voy-paso-a-paso\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/luis-enrique-yo-voy-paso-a-paso\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/luis-enrique-yo-voy-paso-a-paso\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/luis-enrique-yo-voy-paso-a-paso\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/luis-enrique-yo-voy-paso-a-paso\\\/\",\"name\":\"Luis Enrique: \\u00abYo voy paso a paso\\u00bb - El Digital de Asturias\",\"description\":\"El seleccionador nacional de f\\u00fatbol, el asturiano, Luis Enrique Mart\\u00ednez, celebr\\u00f3 poder \\\"descorchar el cava\\\" del pase a octavos de final de la Eurocopa 2020\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/luis-enrique-yo-voy-paso-a-paso\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1067967,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/luis-enrique-yo-voy-paso-a-paso\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/luis-enrique-yo-voy-paso-a-paso\\\/#mainImage\"},\"datePublished\":\"2021-06-25T11:29:28+02:00\",\"dateModified\":\"2021-06-25T11:29:28+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Luis Enrique: \u00abYo voy paso a paso\u00bb - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Luis Enrique: \u00abYo voy paso a paso\u00bb - El Digital de Asturias","description":"El seleccionador nacional de f\u00fatbol, el asturiano, Luis Enrique Mart\u00ednez, celebr\u00f3 poder \"descorchar el cava\" del pase a octavos de final de la Eurocopa 2020","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/","robots":"max-image-preview:large","keywords":"deportes","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/#blogposting","name":"Luis Enrique: \u00abYo voy paso a paso\u00bb - El Digital de Asturias","headline":"Luis Enrique: \u00abYo voy paso a paso\u00bb","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":1067967},"datePublished":"2021-06-25T11:29:28+02:00","dateModified":"2021-06-25T11:29:28+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/#webpage"},"articleSection":"Deportes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","position":2,"name":"Deportes","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/#listItem","name":"Luis Enrique: \u00abYo voy paso a paso\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/#listItem","position":3,"name":"Luis Enrique: \u00abYo voy paso a paso\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/","name":"Luis Enrique: \u00abYo voy paso a paso\u00bb - El Digital de Asturias","description":"El seleccionador nacional de f\u00fatbol, el asturiano, Luis Enrique Mart\u00ednez, celebr\u00f3 poder \"descorchar el cava\" del pase a octavos de final de la Eurocopa 2020","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":1067967,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/#mainImage"},"datePublished":"2021-06-25T11:29:28+02:00","dateModified":"2021-06-25T11:29:28+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Luis Enrique: \u00abYo voy paso a paso\u00bb - El Digital de Asturias","og:description":"El seleccionador nacional de f\u00fatbol, el asturiano, Luis Enrique Mart\u00ednez, celebr\u00f3 poder &quot;descorchar el cava&quot; del pase a octavos de final de la Eurocopa 2020","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/","article:tag":["deportes"],"article:published_time":"2021-06-25T10:29:28+00:00","article:modified_time":"2021-06-25T10:29:28+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Luis Enrique: \u00abYo voy paso a paso\u00bb - El Digital de Asturias","twitter:description":"El seleccionador nacional de f\u00fatbol, el asturiano, Luis Enrique Mart\u00ednez, celebr\u00f3 poder &quot;descorchar el cava&quot; del pase a octavos de final de la Eurocopa 2020","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"2 minutos"},"aioseo_meta_data":{"post_id":"1094450","title":null,"description":"El seleccionador nacional de f\u00fatbol, el asturiano, Luis Enrique Mart\u00ednez, celebr\u00f3 poder \"descorchar el cava\" del pase a octavos de final de la Eurocopa 2020","keywords":[],"keyphrases":{"focus":{"keyphrase":"seleccionador ","score":73,"analysis":{"keyphraseInTitle":{"title":"Frase clave objetivo en el t\u00edtulo SEO","description":"Frase clave objetivo no se encuentra en el t\u00edtulo SEO.","score":3,"maxScore":9,"error":1},"keyphraseInDescription":{"title":"Frase clave objetivo en la meta descripci\u00f3n","description":"Frase clave objetivo encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseInURL":[],"keyphraseLength":{"title":"Longitud de la Frase clave objetivo","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInIntroduction":{"title":"Frase clave objetivo en la introducci\u00f3n","description":"Su Frase clave objetivo aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"title":"Frase clave objetivo en los atributos alt de la imagen.","description":"Frase clave objetivo no se encuentra en los atributos alt de la imagen. A\u00f1ada una imagen con su Frase clave objetivo como texto alternativo.","score":3,"maxScore":9,"error":1}}},"additional":[{"keyphrase":"el asturiano","score":83,"analysis":{"keyphraseInDescription":{"title":"Frase clave en la meta descripci\u00f3n","description":"Frase clave encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Longitud de la Frase clave","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"title":"Frase clave en la introducci\u00f3n","description":"Su Frase clave aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Frase clave en los atributos alt de la imagen.","description":"Frase clave no se encuentra en los atributos alt de la imagen. A\u00f1ada una imagen con su Frase clave como texto alternativo.","score":3,"maxScore":9,"error":1}}},{"keyphrase":"Luis Enrique","score":83,"analysis":{"keyphraseInDescription":{"title":"Frase clave en la meta descripci\u00f3n","description":"Frase clave encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseLength":{"title":"Longitud de la Frase clave","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"title":"Frase clave en la introducci\u00f3n","description":"Su Frase clave aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Frase clave en los atributos alt de la imagen.","description":"Frase clave no se encuentra en los atributos alt de la imagen. A\u00f1ada una imagen con su Frase clave como texto alternativo.","score":3,"maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"email":"","phone":"","phoneFormatted":"","fax":"","faxFormatted":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"seo_analyzer_scan_date":"2025-09-18 03:36:04","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-06-25 10:25:29","updated":"2025-09-23 12:07:33"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/\" title=\"Deportes\">Deportes<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/\" title=\"Luis Enrique: \u00abYo voy paso a paso\u00bb\">Luis Enrique: \u00abYo voy paso a paso\u00bb<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Deportes","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/"},{"label":"Luis Enrique: \u00abYo voy paso a paso\u00bb","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/luis-enrique-yo-voy-paso-a-paso\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1094450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=1094450"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1094450\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=1094450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=1094450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=1094450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}