{"id":1094196,"date":"2021-06-21T16:59:13","date_gmt":"2021-06-21T15:59:13","guid":{"rendered":"https:\/\/www.eldigitaldeasturias.com\/noticias\/?p=1094196"},"modified":"2021-06-21T16:59:13","modified_gmt":"2021-06-21T15:59:13","slug":"el-rayo-vallecano-logro-el-ascenso","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/","title":{"rendered":"El Rayo Vallecano logr\u00f3 el ascenso"},"content":{"rendered":"<figure id=\"attachment_1094197\" aria-describedby=\"caption-attachment-1094197\" style=\"width: 360px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1094197\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2021\/06\/Rayo-Vallecano-360x231.jpg\" alt=\"Rayo Vallecano\" width=\"360\" height=\"231\" \/><figcaption id=\"caption-attachment-1094197\" class=\"wp-caption-text\">FOTO: LALIGA \/ Europa Press<\/figcaption><\/figure>\n<p>(EP) &#8211; <strong>El Rayo Vallecano logr\u00f3 el ascenso a LaLiga Santander<\/strong> el domingo al ganar (0-2) en el partido de vuelta de la final del &#8216;playoff&#8217; de LaLiga SmartBank al Girona, regreso dos temporadas despu\u00e9s a la elite para los madrile\u00f1os.<\/p>\n<p>Los de <strong>Andoni Iraola<\/strong> dieron la vuelta al 1-2 que sac\u00f3 el cuadro catal\u00e1n en Vallecas el pasado fin de semana, con los tantos de \u00c1lvaro Garc\u00eda y Trejo en el primer tiempo y jugando con uno menos, por segunda amarilla a Emiliano Vel\u00e1zquez, desde el minuto 56.<\/p>\n<p>El conjunto madrile\u00f1o, que ya tuvo una buena reacci\u00f3n siete d\u00edas antes, demostr\u00f3 tener las ideas mucho m\u00e1s claras sobre lo que hab\u00eda que hacer en Montilivi. El Rayo sali\u00f3 a morder, a buscar mucho la espalda rival, a por el gol. Los de Francisco no fueron fieles a s\u00ed mismos y 12 partidos despu\u00e9s volvieron a perder.<\/p>\n<p>El Rayo fue el \u00faltimo capaz de ganar a los catalanes y lo hizo de nuevo en el d\u00eda m\u00e1s se\u00f1alado. A los seis minutos, un tremendo pase de Emiliano lo caz\u00f3 \u00c1lvaro, con gran control y mejor definici\u00f3n, para hacer el 0-1. El VAR le dio suspense para confirmar que no hubo fuera de juego. El propio \u00c1lvaro, en su presi\u00f3n, estuvo cerca de robar a Juan Carlos y hacer el segundo poco despu\u00e9s.<\/p>\n<p>A los de Francisco no les sal\u00eda nada, obligados a defender en vez de buscar sus opciones arriba. <strong>Ni Sylla, ni Franquesa, ni B\u00e1rcenas, las opciones habituales del Girona estaban neutralizadas por el continuo desgaste ofensivo del Rayo<\/strong>. As\u00ed fue todo el primer tiempo. Al borde del descanso lleg\u00f3 la \u00fanica local, con Arnau Mart\u00ednez disparando muy cerca de Luca Zidane, quien detuvo como pudo.<\/p>\n<p>Sin embargo, en un robo de Andr\u00e9s y otra carrera de \u00c1lvaro, <strong>Trejo firm\u00f3 el 0-2 ya en el descuento<\/strong>. Un ascenso ya moment\u00e1neo para los visitantes y el objetivo m\u00e1s que cumplido de cara a la segunda parte. El Rayo, con Andr\u00e9s, tuvo la primera llegada del segundo tiempo, pero Zidane bajo palos comenz\u00f3 a tener m\u00e1s trabajo.<\/p>\n<p>Samu, refuerzo del banquillo, dio m\u00e1s profundidad, y B\u00e1rcenas despert\u00f3. Al Rayo se le complic\u00f3 con la expulsi\u00f3n de Emiliano, una segunda amarilla por un tropez\u00f3n, pero los de Iraola supieron hacer que el partido se trabara. Poco se jug\u00f3 en el segundo tiempo aunque con un gol le bastaba para forzar la pr\u00f3rroga al Girona.<\/p>\n<p>Ni siquiera la <strong>entrada de Stuani, con media hora por delante<\/strong>, hizo dudar al Rayo. No tuvo claridad el Girona para encontrar esa buena ocasi\u00f3n. El Rayo, sexto esta temporada con emoci\u00f3n hasta la \u00faltima jornada, logr\u00f3 la haza\u00f1a en casa del favorito, un Girona que tambi\u00e9n quer\u00eda volver a Primera dos a\u00f1os despu\u00e9s, los dos jugando la final por el ascenso.<\/p>\n<h2>FICHA T\u00c9CNICA.<\/h2>\n<p>RESULTADO: GIRONA, 0 &#8211; RAYO VALLECANO, 2. (0-2, al descanso)<\/p>\n<p>ALINEACIONES.<\/p>\n<p>GIRONA: Juan Carlos; Santi Bueno, Juanpe, Arnau (Stuani, min.60); Yan Couto (Aday, min.66), Crist\u00f3foro (Terrats, min.46), Franquesa (Luna, min.77), Gumbau (Samu, min.46), Monchu; B\u00e1rcenas y Sylla.<\/p>\n<p>RAYO VALLECANO: Luca Zidane; Mario Hern\u00e1ndez (Adv\u00edncula, min.77), Vel\u00e1zquez, Catena, Fran Garc\u00eda; \u00d3scar Valent\u00edn (Martos, min.85), Trejo (Qasmi, min.77), Santi Comesa\u00f1a; Isi, \u00c1lvaro Garc\u00eda (Mario Su\u00e1rez, min.85) y Andr\u00e9s Mart\u00edn (Saveljich, min.58).<\/p>\n<h3>GOLES:<\/h3>\n<p>0 &#8211; 1, min.7, \u00c1lvaro Garc\u00eda.<\/p>\n<p>0 &#8211; 2, min.45+1, Trejo.<\/p>\n<p>\u00c1RBITRO: Iglesias Villanueva (C.Gallego). Amonest\u00f3 a B\u00e1rcenas (min.30) y Juanpe (min.85) por parte del Girona. Y a Vel\u00e1zquez (min.40), Trejo (min.76) y Catena (min.96) en el Rayo. Expuls\u00f3 por segunda amarilla a Vel\u00e1zquez (min.56).<\/p>\n<p>ESTADIO: Montilivi.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(EP) &#8211; El Rayo Vallecano logr\u00f3 el ascenso a LaLiga Santander el domingo al ganar (0-2) en el partido de vuelta de la final del &#8216;playoff&#8217; de LaLiga SmartBank al Girona, regreso dos temporadas despu\u00e9s a la elite para los madrile\u00f1os. Los de Andoni Iraola dieron la vuelta al 1-2 que sac\u00f3 el cuadro catal\u00e1n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1094197,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[190],"tags":[],"class_list":["post-1094196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Rayo Vallecano logr\u00f3 el ascenso a LaLiga Santander el domingo al ganar (0-2) en el partido de vuelta de la final del &#039;playoff&#039; de LaLiga SmartBank al Girona\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"deportes\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Rayo Vallecano logr\u00f3 el ascenso - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"El Rayo Vallecano logr\u00f3 el ascenso a LaLiga Santander el domingo al ganar (0-2) en el partido de vuelta de la final del &#039;playoff&#039; de LaLiga SmartBank al Girona\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"deportes\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-06-21T15:59:13+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-06-21T15:59:13+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Rayo Vallecano logr\u00f3 el ascenso - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Rayo Vallecano logr\u00f3 el ascenso a LaLiga Santander el domingo al ganar (0-2) en el partido de vuelta de la final del &#039;playoff&#039; de LaLiga SmartBank al Girona\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-rayo-vallecano-logro-el-ascenso\\\/#blogposting\",\"name\":\"El Rayo Vallecano logr\\u00f3 el ascenso - El Digital de Asturias\",\"headline\":\"El Rayo Vallecano logr\\u00f3 el ascenso\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1094197},\"datePublished\":\"2021-06-21T16:59:13+02:00\",\"dateModified\":\"2021-06-21T16:59:13+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-rayo-vallecano-logro-el-ascenso\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-rayo-vallecano-logro-el-ascenso\\\/#webpage\"},\"articleSection\":\"Deportes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-rayo-vallecano-logro-el-ascenso\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"position\":2,\"name\":\"Deportes\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-rayo-vallecano-logro-el-ascenso\\\/#listItem\",\"name\":\"El Rayo Vallecano logr\\u00f3 el ascenso\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-rayo-vallecano-logro-el-ascenso\\\/#listItem\",\"position\":3,\"name\":\"El Rayo Vallecano logr\\u00f3 el ascenso\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-rayo-vallecano-logro-el-ascenso\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-rayo-vallecano-logro-el-ascenso\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-rayo-vallecano-logro-el-ascenso\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-rayo-vallecano-logro-el-ascenso\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-rayo-vallecano-logro-el-ascenso\\\/\",\"name\":\"El Rayo Vallecano logr\\u00f3 el ascenso - El Digital de Asturias\",\"description\":\"El Rayo Vallecano logr\\u00f3 el ascenso a LaLiga Santander el domingo al ganar (0-2) en el partido de vuelta de la final del 'playoff' de LaLiga SmartBank al Girona\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-rayo-vallecano-logro-el-ascenso\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1094197,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-rayo-vallecano-logro-el-ascenso\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/el-rayo-vallecano-logro-el-ascenso\\\/#mainImage\"},\"datePublished\":\"2021-06-21T16:59:13+02:00\",\"dateModified\":\"2021-06-21T16:59:13+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El Rayo Vallecano logr\u00f3 el ascenso - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"El Rayo Vallecano logr\u00f3 el ascenso - El Digital de Asturias","description":"El Rayo Vallecano logr\u00f3 el ascenso a LaLiga Santander el domingo al ganar (0-2) en el partido de vuelta de la final del 'playoff' de LaLiga SmartBank al Girona","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/","robots":"max-image-preview:large","keywords":"deportes","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/#blogposting","name":"El Rayo Vallecano logr\u00f3 el ascenso - El Digital de Asturias","headline":"El Rayo Vallecano logr\u00f3 el ascenso","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":1094197},"datePublished":"2021-06-21T16:59:13+02:00","dateModified":"2021-06-21T16:59:13+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/#webpage"},"articleSection":"Deportes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","position":2,"name":"Deportes","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/#listItem","name":"El Rayo Vallecano logr\u00f3 el ascenso"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/#listItem","position":3,"name":"El Rayo Vallecano logr\u00f3 el ascenso","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/","name":"El Rayo Vallecano logr\u00f3 el ascenso - El Digital de Asturias","description":"El Rayo Vallecano logr\u00f3 el ascenso a LaLiga Santander el domingo al ganar (0-2) en el partido de vuelta de la final del 'playoff' de LaLiga SmartBank al Girona","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":1094197,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/#mainImage"},"datePublished":"2021-06-21T16:59:13+02:00","dateModified":"2021-06-21T16:59:13+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"El Rayo Vallecano logr\u00f3 el ascenso - El Digital de Asturias","og:description":"El Rayo Vallecano logr\u00f3 el ascenso a LaLiga Santander el domingo al ganar (0-2) en el partido de vuelta de la final del 'playoff' de LaLiga SmartBank al Girona","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/","article:tag":["deportes"],"article:published_time":"2021-06-21T15:59:13+00:00","article:modified_time":"2021-06-21T15:59:13+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"El Rayo Vallecano logr\u00f3 el ascenso - El Digital de Asturias","twitter:description":"El Rayo Vallecano logr\u00f3 el ascenso a LaLiga Santander el domingo al ganar (0-2) en el partido de vuelta de la final del 'playoff' de LaLiga SmartBank al Girona","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"1094196","title":null,"description":"El Rayo Vallecano logr\u00f3 el ascenso a LaLiga Santander el domingo al ganar (0-2) en el partido de vuelta de la final del 'playoff' de LaLiga SmartBank al Girona","keywords":[],"keyphrases":{"focus":{"keyphrase":"Rayo Vallecano","score":89,"analysis":{"keyphraseInTitle":{"title":"Frase clave objetivo en el t\u00edtulo SEO","description":"Frase clave objetivo encontrada en el t\u00edtulo SEO.","score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"title":"Frase clave objetivo en la meta descripci\u00f3n","description":"Frase clave objetivo encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseInURL":[],"keyphraseInIntroduction":{"title":"Frase clave objetivo en la introducci\u00f3n","description":"Su Frase clave objetivo aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"title":"Frase clave objetivo sus subt\u00edtulos","description":"Use your focus keyphrase more in your H2 and H3 subheadings.","score":3,"maxScore":9,"error":1},"keyphraseLength":{"title":"Longitud de la Frase clave objetivo","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":2},"keyphraseInImageAlt":{"title":"Frase clave objetivo en los atributos alt de la imagen.","description":"Frase clave objetivo encontrada en los atributos alt de la(s) imagen(es).","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"el ascenso","score":83,"analysis":{"keyphraseInDescription":{"title":"Frase clave en la meta descripci\u00f3n","description":"Frase clave encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseInIntroduction":{"title":"Frase clave en la introducci\u00f3n","description":"Su Frase clave aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Frase clave en los atributos alt de la imagen.","description":"Frase clave no se encuentra en los atributos alt de la imagen. A\u00f1ada una imagen con su Frase clave como texto alternativo.","score":3,"maxScore":9,"error":1},"keyphraseLength":{"title":"Longitud de la Frase clave","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":2}}},{"keyphrase":"LaLiga ","score":83,"analysis":{"keyphraseInDescription":{"title":"Frase clave en la meta descripci\u00f3n","description":"Frase clave encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseInIntroduction":{"title":"Frase clave en la introducci\u00f3n","description":"Su Frase clave aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Frase clave en los atributos alt de la imagen.","description":"Frase clave no se encuentra en los atributos alt de la imagen. A\u00f1ada una imagen con su Frase clave como texto alternativo.","score":3,"maxScore":9,"error":1},"keyphraseLength":{"title":"Longitud de la Frase clave","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"email":"","phone":"","phoneFormatted":"","fax":"","faxFormatted":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"seo_analyzer_scan_date":"2025-09-18 02:46:07","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-06-21 15:53:12","updated":"2025-09-23 11:20:34"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/\" title=\"Deportes\">Deportes<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/\" title=\"El Rayo Vallecano logr\u00f3 el ascenso\">El Rayo Vallecano logr\u00f3 el ascenso<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Deportes","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/"},{"label":"El Rayo Vallecano logr\u00f3 el ascenso","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/el-rayo-vallecano-logro-el-ascenso\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1094196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=1094196"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1094196\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=1094196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=1094196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=1094196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}