{"id":1094134,"date":"2021-06-20T13:12:40","date_gmt":"2021-06-20T12:12:40","guid":{"rendered":"https:\/\/www.eldigitaldeasturias.com\/noticias\/?p=1094134"},"modified":"2021-06-20T13:12:40","modified_gmt":"2021-06-20T12:12:40","slug":"girona-y-rayo-vallecano-buscan-el-ascenso","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/","title":{"rendered":"Girona y Rayo Vallecano buscan el ascenso"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1067967\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/06\/football-360x241.jpg\" alt=\"\" width=\"360\" height=\"241\" \/>(EP) &#8211; El Girona busca regresar a Primera Divisi\u00f3n dos temporadas despu\u00e9s en la final del &#8216;playoff&#8217; de ascenso ante el Rayo Vallecano (21.00 horas),<strong> un duelo que afronta este domingo con ventaja tras el 1-2 de la ida y como gran favorito para hacerse con el \u00faltimo billete en juego para la Liga Santander<\/strong>.<\/p>\n<p>El equipo de Francisco quiere unirse este domingo a Espanyol y Mallorca, que lograron el ascenso directo, en el partido de vuelta de la final del &#8216;playoff&#8217; ante su p\u00fablico -1.500 espectadores- y tras haber firmado la mejor recta final de todo el campeonato en la categor\u00eda de plata del f\u00fatbol espa\u00f1ol.<\/p>\n<p>El cuadro catal\u00e1n suma 11 partidos sin perder y precisamente su \u00faltima derrota fue en el campeonato regular ante el Rayo. Aquel choque fue un punto de inflexi\u00f3n para el Girona, que se mostr\u00f3 firme desde entonces con una racha espectacular. Hasta el &#8216;playoff&#8217;, siete victorias en ocho jornadas, la \u00faltima fue un empate en Cartagena.<\/p>\n<p>Y en las eliminatorias por el ascenso, acab\u00f3 con el Almer\u00eda en semifinales (3-0 y 0-0) y ahora tiene todas las de la ley para volver a Primera porque incluso el empate -tras la pr\u00f3rroga- le otorgar\u00eda el ascenso por su mejor posici\u00f3n en la tabla al t\u00e9rmino de las 42 jornadas (5\u00ba vs 6\u00ba).<\/p>\n<p>\u00abTenemos que competir al m\u00e1ximo, con la ambici\u00f3n de ganar como hemos hecho durante toda la temporada. S\u00f3lo se trata de convencer al jugador de que podemos ganar. No habr\u00e1 muchas diferencias respecto a los partidos anteriores de &#8216;playoff&#8217;. El diferente es el Rayo, al equipo que nos enfrentamos, y esto es lo importante\u00bb, dijo Francisco en rueda de prensa.<\/p>\n<p>Los de Andoni Iraola, por su parte, vencieron al Legan\u00e9s en la primera eliminatoria, y arrancaron con fuerza hace siete d\u00edas pero vieron c\u00f3mo el tanto de Isi era remontado en la segunda mitad por un Girona muy eficaz. Los de la barriada madrile\u00f1a deber\u00e1n buscar el 0-2 o el 1-3 en tierras catalanas si quieren estar en Primera la pr\u00f3xima temporada.<\/p>\n<p><strong>\u00abSomos capaces de conseguirlo\u00bb, dijo Iraola ante los medio<\/strong>s. \u00abPara remontar el partido tenemos que hacer las cosas pr\u00e1cticamente perfectas, porque hasta ahora el Girona no est\u00e1 perdonando\u00bb, a\u00f1adi\u00f3 el t\u00e9cnico del Rayo Vallecano.<\/p>\n<p>Ambos t\u00e9cnicos no han dado pistas sobre sus posibles alineaciones este domingo, pero tras una semana para preparar el partido es posible que repitan el once de la ida. Girona o Rayo tocar\u00e1n la gloria en Montilivi. Para los dos equipos supondr\u00eda regresar a la \u00e9lite tan solo dos temporadas despu\u00e9s de haber dejado Primera.<\/p>\n<h2>FICHA T\u00c9CNICA.<\/h2>\n<p>POSIBLES ALINEACIONES.<\/p>\n<p>GIRONA: Juan Carlos; Santi Bueno, Juanpe, Arnau; Yan Couto, Crist\u00f3foro, Franquesa, Gumbau, Monchu; Nahuel Bustos y Sylla.<\/p>\n<p>RAYO VALLECANO: Luca Zidane; Adv\u00edncula, Catena, Saveljich, Fran Garc\u00eda; \u00d3scar Valent\u00edn, Trejo, Santi Comesa\u00f1a; Isi, \u00c1lvaro Garc\u00eda; y Qasmi.<\/p>\n<p>\u00c1RBITRO: Iglesias Villanueva (C.Gallego).<\/p>\n<p>ESTADIO: Montilivi.<\/p>\n<p>HORA: 21.00\/Movistar LaLiga.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(EP) &#8211; El Girona busca regresar a Primera Divisi\u00f3n dos temporadas despu\u00e9s en la final del &#8216;playoff&#8217; de ascenso ante el Rayo Vallecano (21.00 horas), un duelo que afronta este domingo con ventaja tras el 1-2 de la ida y como gran favorito para hacerse con el \u00faltimo billete en juego para la Liga Santander. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1067967,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[190],"tags":[],"class_list":["post-1094134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Girona busca regresar a Primera Divisi\u00f3n dos temporadas despu\u00e9s en la final del &#039;playoff&#039; de ascenso ante el Rayo Vallecano\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"deportes\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Girona y Rayo Vallecano buscan el ascenso - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"El Girona busca regresar a Primera Divisi\u00f3n dos temporadas despu\u00e9s en la final del &#039;playoff&#039; de ascenso ante el Rayo Vallecano\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"deportes\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-06-20T12:12:40+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-06-20T12:12:40+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Girona y Rayo Vallecano buscan el ascenso - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Girona busca regresar a Primera Divisi\u00f3n dos temporadas despu\u00e9s en la final del &#039;playoff&#039; de ascenso ante el Rayo Vallecano\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/girona-y-rayo-vallecano-buscan-el-ascenso\\\/#blogposting\",\"name\":\"Girona y Rayo Vallecano buscan el ascenso - El Digital de Asturias\",\"headline\":\"Girona y Rayo Vallecano buscan el ascenso\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1067967},\"datePublished\":\"2021-06-20T13:12:40+02:00\",\"dateModified\":\"2021-06-20T13:12:40+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/girona-y-rayo-vallecano-buscan-el-ascenso\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/girona-y-rayo-vallecano-buscan-el-ascenso\\\/#webpage\"},\"articleSection\":\"Deportes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/girona-y-rayo-vallecano-buscan-el-ascenso\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"position\":2,\"name\":\"Deportes\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/girona-y-rayo-vallecano-buscan-el-ascenso\\\/#listItem\",\"name\":\"Girona y Rayo Vallecano buscan el ascenso\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/girona-y-rayo-vallecano-buscan-el-ascenso\\\/#listItem\",\"position\":3,\"name\":\"Girona y Rayo Vallecano buscan el ascenso\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/deportes\\\/#listItem\",\"name\":\"Deportes\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/girona-y-rayo-vallecano-buscan-el-ascenso\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/girona-y-rayo-vallecano-buscan-el-ascenso\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/girona-y-rayo-vallecano-buscan-el-ascenso\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/girona-y-rayo-vallecano-buscan-el-ascenso\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/girona-y-rayo-vallecano-buscan-el-ascenso\\\/\",\"name\":\"Girona y Rayo Vallecano buscan el ascenso - El Digital de Asturias\",\"description\":\"El Girona busca regresar a Primera Divisi\\u00f3n dos temporadas despu\\u00e9s en la final del 'playoff' de ascenso ante el Rayo Vallecano\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/girona-y-rayo-vallecano-buscan-el-ascenso\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1067967,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/girona-y-rayo-vallecano-buscan-el-ascenso\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/girona-y-rayo-vallecano-buscan-el-ascenso\\\/#mainImage\"},\"datePublished\":\"2021-06-20T13:12:40+02:00\",\"dateModified\":\"2021-06-20T13:12:40+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Girona y Rayo Vallecano buscan el ascenso - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Girona y Rayo Vallecano buscan el ascenso - El Digital de Asturias","description":"El Girona busca regresar a Primera Divisi\u00f3n dos temporadas despu\u00e9s en la final del 'playoff' de ascenso ante el Rayo Vallecano","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/","robots":"max-image-preview:large","keywords":"deportes","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/#blogposting","name":"Girona y Rayo Vallecano buscan el ascenso - El Digital de Asturias","headline":"Girona y Rayo Vallecano buscan el ascenso","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":1067967},"datePublished":"2021-06-20T13:12:40+02:00","dateModified":"2021-06-20T13:12:40+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/#webpage"},"articleSection":"Deportes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","position":2,"name":"Deportes","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/#listItem","name":"Girona y Rayo Vallecano buscan el ascenso"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/#listItem","position":3,"name":"Girona y Rayo Vallecano buscan el ascenso","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/#listItem","name":"Deportes"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/","name":"Girona y Rayo Vallecano buscan el ascenso - El Digital de Asturias","description":"El Girona busca regresar a Primera Divisi\u00f3n dos temporadas despu\u00e9s en la final del 'playoff' de ascenso ante el Rayo Vallecano","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":1067967,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/#mainImage"},"datePublished":"2021-06-20T13:12:40+02:00","dateModified":"2021-06-20T13:12:40+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Girona y Rayo Vallecano buscan el ascenso - El Digital de Asturias","og:description":"El Girona busca regresar a Primera Divisi\u00f3n dos temporadas despu\u00e9s en la final del 'playoff' de ascenso ante el Rayo Vallecano","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/","article:tag":["deportes"],"article:published_time":"2021-06-20T12:12:40+00:00","article:modified_time":"2021-06-20T12:12:40+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Girona y Rayo Vallecano buscan el ascenso - El Digital de Asturias","twitter:description":"El Girona busca regresar a Primera Divisi\u00f3n dos temporadas despu\u00e9s en la final del 'playoff' de ascenso ante el Rayo Vallecano","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"3 minutos"},"aioseo_meta_data":{"post_id":"1094134","title":null,"description":"El Girona busca regresar a Primera Divisi\u00f3n dos temporadas despu\u00e9s en la final del 'playoff' de ascenso ante el Rayo Vallecano&nbsp;","keywords":[],"keyphrases":{"focus":{"keyphrase":"ascenso","score":78,"analysis":{"keyphraseInTitle":{"title":"Frase clave objetivo en el t\u00edtulo SEO","description":"Frase clave objetivo encontrada en el t\u00edtulo SEO.","score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"title":"Frase clave objetivo en la meta descripci\u00f3n","description":"Frase clave objetivo encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseInURL":[],"keyphraseInIntroduction":{"title":"Frase clave objetivo en la introducci\u00f3n","description":"Su Frase clave objetivo aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"title":"Frase clave objetivo sus subt\u00edtulos","description":"Use your focus keyphrase more in your H2 and H3 subheadings.","score":3,"maxScore":9,"error":1},"keyphraseLength":{"title":"Longitud de la Frase clave objetivo","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInImageAlt":{"title":"Frase clave objetivo en los atributos alt de la imagen.","description":"Frase clave objetivo no se encuentra en los atributos alt de la imagen. A\u00f1ada una imagen con su Frase clave objetivo como texto alternativo.","score":3,"maxScore":9,"error":1}}},"additional":[{"keyphrase":"Rayo Vallecano","score":83,"analysis":{"keyphraseInDescription":{"title":"Frase clave en la meta descripci\u00f3n","description":"Frase clave encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseInIntroduction":{"title":"Frase clave en la introducci\u00f3n","description":"Su Frase clave aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Frase clave en los atributos alt de la imagen.","description":"Frase clave no se encuentra en los atributos alt de la imagen. A\u00f1ada una imagen con su Frase clave como texto alternativo.","score":3,"maxScore":9,"error":1},"keyphraseLength":{"title":"Longitud de la Frase clave","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":2}}},{"keyphrase":"Girona","score":83,"analysis":{"keyphraseInDescription":{"title":"Frase clave en la meta descripci\u00f3n","description":"Frase clave encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseInIntroduction":{"title":"Frase clave en la introducci\u00f3n","description":"Su Frase clave aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Frase clave en los atributos alt de la imagen.","description":"Frase clave no se encuentra en los atributos alt de la imagen. A\u00f1ada una imagen con su Frase clave como texto alternativo.","score":3,"maxScore":9,"error":1},"keyphraseLength":{"title":"Longitud de la Frase clave","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":1}}},{"keyphrase":"el","score":83,"analysis":{"keyphraseInDescription":{"title":"Frase clave en la meta descripci\u00f3n","description":"Frase clave encontrada en la meta descripci\u00f3n.","score":9,"maxScore":9,"error":0},"keyphraseInIntroduction":{"title":"Frase clave en la introducci\u00f3n","description":"Su Frase clave aparece en el primer p\u00e1rrafo. \u00a1Bien hecho!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Frase clave en los atributos alt de la imagen.","description":"Frase clave no se encuentra en los atributos alt de la imagen. A\u00f1ada una imagen con su Frase clave como texto alternativo.","score":3,"maxScore":9,"error":1},"keyphraseLength":{"title":"Longitud de la Frase clave","description":"\u00a1Buen trabajo!","score":9,"maxScore":9,"error":0,"length":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"email":"","phone":"","phoneFormatted":"","fax":"","faxFormatted":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"seo_analyzer_scan_date":"2025-09-18 02:30:28","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-06-20 12:09:00","updated":"2025-09-23 11:08:31"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/\" title=\"Deportes\">Deportes<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/\" title=\"Girona y Rayo Vallecano buscan el ascenso\">Girona y Rayo Vallecano buscan el ascenso<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Deportes","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/deportes\/"},{"label":"Girona y Rayo Vallecano buscan el ascenso","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/girona-y-rayo-vallecano-buscan-el-ascenso\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1094134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=1094134"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1094134\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=1094134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=1094134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=1094134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}