{"id":1068688,"date":"2020-06-22T01:44:46","date_gmt":"2020-06-21T23:44:46","guid":{"rendered":"https:\/\/www.eldigitaldeasturias.com\/noticias\/?p=1068688"},"modified":"2020-06-22T01:44:46","modified_gmt":"2020-06-21T23:44:46","slug":"perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/","title":{"rendered":"Perros y gatos deben viajar en jaula transportadora en el coche"},"content":{"rendered":"<figure id=\"attachment_1068689\" aria-describedby=\"caption-attachment-1068689\" style=\"width: 360px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1068689\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/06\/transportar-mascotas-360x239.jpg\" alt=\"\" width=\"360\" height=\"239\" \/><figcaption id=\"caption-attachment-1068689\" class=\"wp-caption-text\">Gato a bordo: siempre es mejor llevarlo en una jaula de transporte. Foto: Christin Klose\/dpa-tmn<\/figcaption><\/figure>\n<p>(dpa) &#8211; Dentro de la jaula transportadora: <strong>esa es la disposici\u00f3n m\u00e1s segura para mascotas como perros y gatos cuando estos deben ser trasladados en coche<\/strong>.<\/p>\n<p>Tanto legalmente como por su propia protecci\u00f3n, s\u00f3lo pueden ser transportados con la seguridad adecuada, explica el Auto Club Europa (ACE).<\/p>\n<p>Y esto tambi\u00e9n debe cumplirse en un viaje tan corto como ir al veterinario que est\u00e1 en la esquina.<strong> De lo contrario, puede arriesgarse a que le pongan multas o un punto y a problemas con la aseguradora<\/strong>.<\/p>\n<p>Las jaulas m\u00e1s peque\u00f1as pueden colocarse en posici\u00f3n transversal a la direcci\u00f3n de la marcha en el hueco para los pies del asiento del acompa\u00f1ante, mientras que las m\u00e1s grandes pueden ir mejor en el asiento trasero o en el \u00e1rea de carga.<\/p>\n<p>Sin embargo, en este \u00faltimo espacio deben ser aseguradas adem\u00e1s con cinturones o rejillas divisoras.<\/p>\n<p>Especialmente en los coches m\u00e1s antiguos la estabilidad de los respaldos de las butacas no suele ser suficiente para contener una jaula transportadora. Tambi\u00e9n hay modelos que pueden ser fijados.<\/p>\n<p>En el mercado asimismo pueden encontrarse cinturones especiales de seguridad, <strong>arneses e incluso asientos de seguridad para mascotas<\/strong>, que al igual que los asientos de los ni\u00f1os pueden ser fijados a los anclajes Isofix o montados con los cinturones de seguridad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(dpa) &#8211; Dentro de la jaula transportadora: esa es la disposici\u00f3n m\u00e1s segura para mascotas como perros y gatos cuando estos deben ser trasladados en coche. Tanto legalmente como por su propia protecci\u00f3n, s\u00f3lo pueden ser transportados con la seguridad adecuada, explica el Auto Club Europa (ACE). Y esto tambi\u00e9n debe cumplirse en un viaje [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1068689,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[598],"tags":[],"class_list":["post-1068688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mascotas"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"(dpa) - Dentro de la jaula transportadora: esa es la disposici\u00f3n m\u00e1s segura para mascotas como perros y gatos cuando estos deben ser trasladados en coche. Tanto legalmente como por su propia protecci\u00f3n, s\u00f3lo pueden ser transportados con la seguridad adecuada, explica el Auto Club Europa (ACE). Y esto tambi\u00e9n debe cumplirse en un viaje\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"mascotas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Perros y gatos deben viajar en jaula transportadora en el coche - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"(dpa) - Dentro de la jaula transportadora: esa es la disposici\u00f3n m\u00e1s segura para mascotas como perros y gatos cuando estos deben ser trasladados en coche. Tanto legalmente como por su propia protecci\u00f3n, s\u00f3lo pueden ser transportados con la seguridad adecuada, explica el Auto Club Europa (ACE). Y esto tambi\u00e9n debe cumplirse en un viaje\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"mascotas\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-06-21T23:44:46+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-06-21T23:44:46+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Perros y gatos deben viajar en jaula transportadora en el coche - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(dpa) - Dentro de la jaula transportadora: esa es la disposici\u00f3n m\u00e1s segura para mascotas como perros y gatos cuando estos deben ser trasladados en coche. Tanto legalmente como por su propia protecci\u00f3n, s\u00f3lo pueden ser transportados con la seguridad adecuada, explica el Auto Club Europa (ACE). Y esto tambi\u00e9n debe cumplirse en un viaje\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\\\/#blogposting\",\"name\":\"Perros y gatos deben viajar en jaula transportadora en el coche - El Digital de Asturias\",\"headline\":\"Perros y gatos deben viajar en jaula transportadora en el coche\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1068689},\"datePublished\":\"2020-06-22T01:44:46+02:00\",\"dateModified\":\"2020-06-22T01:44:46+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\\\/#webpage\"},\"articleSection\":\"Mascotas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/#listItem\",\"name\":\"Mascotas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/#listItem\",\"position\":2,\"name\":\"Mascotas\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\\\/#listItem\",\"name\":\"Perros y gatos deben viajar en jaula transportadora en el coche\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\\\/#listItem\",\"position\":3,\"name\":\"Perros y gatos deben viajar en jaula transportadora en el coche\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/#listItem\",\"name\":\"Mascotas\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\\\/\",\"name\":\"Perros y gatos deben viajar en jaula transportadora en el coche - El Digital de Asturias\",\"description\":\"(dpa) - Dentro de la jaula transportadora: esa es la disposici\\u00f3n m\\u00e1s segura para mascotas como perros y gatos cuando estos deben ser trasladados en coche. Tanto legalmente como por su propia protecci\\u00f3n, s\\u00f3lo pueden ser transportados con la seguridad adecuada, explica el Auto Club Europa (ACE). Y esto tambi\\u00e9n debe cumplirse en un viaje\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1068689,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\\\/#mainImage\"},\"datePublished\":\"2020-06-22T01:44:46+02:00\",\"dateModified\":\"2020-06-22T01:44:46+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Perros y gatos deben viajar en jaula transportadora en el coche - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Perros y gatos deben viajar en jaula transportadora en el coche - El Digital de Asturias","description":"(dpa) - Dentro de la jaula transportadora: esa es la disposici\u00f3n m\u00e1s segura para mascotas como perros y gatos cuando estos deben ser trasladados en coche. Tanto legalmente como por su propia protecci\u00f3n, s\u00f3lo pueden ser transportados con la seguridad adecuada, explica el Auto Club Europa (ACE). Y esto tambi\u00e9n debe cumplirse en un viaje","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/","robots":"max-image-preview:large","keywords":"mascotas","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/#blogposting","name":"Perros y gatos deben viajar en jaula transportadora en el coche - El Digital de Asturias","headline":"Perros y gatos deben viajar en jaula transportadora en el coche","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":1068689},"datePublished":"2020-06-22T01:44:46+02:00","dateModified":"2020-06-22T01:44:46+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/#webpage"},"articleSection":"Mascotas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/#listItem","name":"Mascotas"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/#listItem","position":2,"name":"Mascotas","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/#listItem","name":"Perros y gatos deben viajar en jaula transportadora en el coche"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/#listItem","position":3,"name":"Perros y gatos deben viajar en jaula transportadora en el coche","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/#listItem","name":"Mascotas"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/","name":"Perros y gatos deben viajar en jaula transportadora en el coche - El Digital de Asturias","description":"(dpa) - Dentro de la jaula transportadora: esa es la disposici\u00f3n m\u00e1s segura para mascotas como perros y gatos cuando estos deben ser trasladados en coche. Tanto legalmente como por su propia protecci\u00f3n, s\u00f3lo pueden ser transportados con la seguridad adecuada, explica el Auto Club Europa (ACE). Y esto tambi\u00e9n debe cumplirse en un viaje","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":1068689,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/#mainImage"},"datePublished":"2020-06-22T01:44:46+02:00","dateModified":"2020-06-22T01:44:46+02:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Perros y gatos deben viajar en jaula transportadora en el coche - El Digital de Asturias","og:description":"(dpa) - Dentro de la jaula transportadora: esa es la disposici\u00f3n m\u00e1s segura para mascotas como perros y gatos cuando estos deben ser trasladados en coche. Tanto legalmente como por su propia protecci\u00f3n, s\u00f3lo pueden ser transportados con la seguridad adecuada, explica el Auto Club Europa (ACE). Y esto tambi\u00e9n debe cumplirse en un viaje","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/","article:tag":["mascotas"],"article:published_time":"2020-06-21T23:44:46+00:00","article:modified_time":"2020-06-21T23:44:46+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Perros y gatos deben viajar en jaula transportadora en el coche - El Digital de Asturias","twitter:description":"(dpa) - Dentro de la jaula transportadora: esa es la disposici\u00f3n m\u00e1s segura para mascotas como perros y gatos cuando estos deben ser trasladados en coche. Tanto legalmente como por su propia protecci\u00f3n, s\u00f3lo pueden ser transportados con la seguridad adecuada, explica el Auto Club Europa (ACE). Y esto tambi\u00e9n debe cumplirse en un viaje","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"1068688","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-07-11 16:21:52","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 10:47:14","updated":"2026-07-11 16:21:52"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/\" title=\"Mascotas\">Mascotas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/\" title=\"Perros y gatos deben viajar en jaula transportadora en el coche\">Perros y gatos deben viajar en jaula transportadora en el coche<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Mascotas","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/"},{"label":"Perros y gatos deben viajar en jaula transportadora en el coche","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/perros-y-gatos-deben-viajar-en-jaula-transportadora-en-el-coche\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1068688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=1068688"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1068688\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=1068688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=1068688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=1068688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}