{"id":1051803,"date":"2019-12-22T23:35:47","date_gmt":"2019-12-22T23:35:47","guid":{"rendered":"https:\/\/www.eldigitaldeasturias.com\/noticias\/?p=1051803"},"modified":"2019-12-22T23:35:47","modified_gmt":"2019-12-22T23:35:47","slug":"como-elegir-y-recibir-en-casa-al-primer-perro","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/","title":{"rendered":"C\u00f3mo elegir y recibir en casa al primer perro"},"content":{"rendered":"<p>(dpa) &#8211; Ya sea un peque\u00f1o chihuahua, un ovejero alem\u00e1n o un juguet\u00f3n mestizo, los perros son de las mascotas m\u00e1s populares. Pero quien quiera uno, tiene que pensarlo muy bien: dependiendo de la edad del animal, uno asume una responsabilidad por un ser vivo durante muchos a\u00f1os. Y, con ello, los costos.<\/p>\n<figure id=\"attachment_1051804\" aria-describedby=\"caption-attachment-1051804\" style=\"width: 670px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1051804\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2019\/12\/consejos-perros-dpa-360x239.jpg\" alt=\"\" width=\"670\" height=\"445\" \/><figcaption id=\"caption-attachment-1051804\" class=\"wp-caption-text\">Cuando buscamos una mascota, no est\u00e1 de m\u00e1s mirar primero en los hogares de animales. Foto: Inga Kjer\/dpa-tmn<\/figcaption><\/figure>\n<p>Esto es lo que hay que tener en cuenta a la hora de adquirir un perro:<\/p>\n<h3>1. \u00bfQu\u00e9 perro pega mejor con cada persona?<\/h3>\n<p>El tipo ideal de perro depende del tipo de persona que sea el propietario. \u00abHay muchos factores a tener en cuenta\u00bb, dice Melanie Jahn, que desde hace diez a\u00f1os trabaja como cuidadora de perros en un centro de acogida de animales en Berl\u00edn.<\/p>\n<p>Por ejemplo, \u00bfqu\u00e9 tanta actividad deportiva tiene el nuevo propietario? \u00bfDe cu\u00e1nto tiempo libre dispone? Los cachorros, por ejemplo, apenas se pueden dejar solos hasta los seis meses. Adem\u00e1s, hace falta mucha paciencia para ense\u00f1arle a un cachorro a hacer sus necesidades donde corresponde y educarlo.<\/p>\n<p>Los perros adultos, sin embargo, no siempre son adecuados para iniciarse en esto de tener una mascota, explica Jahn. Sobre todo aquellos animales que vienen de una mala experiencia, demoran m\u00e1s en generar un v\u00ednculo de confianza.<\/p>\n<p>Por eso, en este centro de acogida de animales se hacen muchos paseos previos con los potenciales due\u00f1os antes de la decisi\u00f3n final. \u00abSi el perro se alegra cuando estas personas regresan, podemos dejar que se lleven a los animales con la consciencia tranquila\u00bb, dice la mujer.<\/p>\n<h3>2. \u00bfD\u00f3nde puedo encontrar un perro?<\/h3>\n<p>Ya sea un cachorro, un perro de raza o un mestizo, quien quiera una mascota puede buscar en primer lugar en un centro de acogida de animales o en organizaciones protectoras de animales, recomienda Lisa Frankenberger, portavoz de prensa de la organizaci\u00f3n Tasso. \u00abEsos animales ya est\u00e1n ah\u00ed y necesitan un hogar\u00bb.<\/p>\n<p>En el caso de adquirir un cachorro de criadero, hay que tener cuidado ante los posibles casos de tr\u00e1fico ilegal de cachorros. Frankenberger aconseja desestimar peque\u00f1os anuncios y ofertas llamativas. Los criadores serios en general s\u00f3lo ofrecen una o dos razas y un m\u00e1ximo de tres o cuatro camadas por a\u00f1o.<\/p>\n<p>Lo mejor es buscar el animal directamente de manos del vendedor y conocer a la perra madre. As\u00ed se puede controlar m\u00e1s f\u00e1cilmente que el animal est\u00e9 sano. Lo ideal es que los cachorros tengan al menos ocho semanas. Mejor si tienen diez.<\/p>\n<h3>3. \u00bfEst\u00e1 todo preparado para el perro?<\/h3>\n<p>Antes de que el perro llegue al nuevo hogar, deber\u00eda quedar claro qui\u00e9n se har\u00e1 cargo de \u00e9l. No alcanza sacarlo tres veces por d\u00eda para que haga sus necesidades: s\u00f3lo si est\u00e1 entretenido de la manera adecuada el animal genera confianza con sus nuevos propietarios y se siente plenamente agusto.<\/p>\n<p>Para que el animal llegue tranquilo al nuevo hogar, es mejor que amigos y conocidos esperen algunos d\u00edas antes de conocerlo, explica Lisa Frankenberger.<\/p>\n<p>Adem\u00e1s es pr\u00e1ctico disponer al menos ya del equipamiento b\u00e1sico: el collar y la correa, la comida, los recipientes y un canasto o cucha. \u00abLo mejor es establecer un rinc\u00f3n tranquilo para el perro en alguna ubicaci\u00f3n central. As\u00ed puede replegarse cuando quiera y de todas maneras tener todo a la vista\u00bb, dice Melanie Jahn.<\/p>\n<h3>4. \u00bfCu\u00e1nto cuesta un perro?<\/h3>\n<p>Los costos dependen del tama\u00f1o del perro, del volumen y de la calidad del equipamiento, explica Lisa Frankenberger.<\/p>\n<p>B\u00e1sicamente, la Federaci\u00f3n Cinol\u00f3gica Alemana (VDH, seg\u00fan sus siglas en alem\u00e1n) calcula un precio de compra de entre 600 y 1.500 euros (entre 670 y 1.700 d\u00f3lares) por un cachorro de criadero.<\/p>\n<p>Pero tambi\u00e9n hay que calcular la compra de recipientes para comida, canasto y correa m\u00e1s lo que consuma mensualmente en alimento.<\/p>\n<p>Adem\u00e1s, anualmente hay costos fijos por vacunas y desparasitaci\u00f3n y, dependiendo del pa\u00eds, por impuestos y seguro de responsabilidad civil. La inscripci\u00f3n en un registro de mascotas en general es gratuita.<\/p>\n<h3>5. Educaci\u00f3n y v\u00ednculo: As\u00ed funciona la convivencia.<\/h3>\n<p>Para la educaci\u00f3n del perro, Melanie Jahn recomienda un curso en una escuela canina. Para los cachorros esto es especialmente importante para que entrenen \u00f3rdenes y contacto social.<\/p>\n<p>La regla de oro de la educaci\u00f3n canina es: elogiar y no castigar. Un comportamiento correcto debe ser premiado y uno incorrecto, ignorado.<\/p>\n<p><i class=\"lang-es\"><span class=\" readonly\" title=\"\">Por Vera Kraft (dpa)<\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(dpa) &#8211; Ya sea un peque\u00f1o chihuahua, un ovejero alem\u00e1n o un juguet\u00f3n mestizo, los perros son de las mascotas m\u00e1s populares. Pero quien quiera uno, tiene que pensarlo muy bien: dependiendo de la edad del animal, uno asume una responsabilidad por un ser vivo durante muchos a\u00f1os. Y, con ello, los costos. Esto es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1051804,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[598],"tags":[],"class_list":["post-1051803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mascotas"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"(dpa) - Ya sea un peque\u00f1o chihuahua, un ovejero alem\u00e1n o un juguet\u00f3n mestizo, los perros son de las mascotas m\u00e1s populares. Pero quien quiera uno, tiene que pensarlo muy bien: dependiendo de la edad del animal, uno asume una responsabilidad por un ser vivo durante muchos a\u00f1os. Y, con ello, los costos. Esto es\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"mascotas\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"C\u00f3mo elegir y recibir en casa al primer perro - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"(dpa) - Ya sea un peque\u00f1o chihuahua, un ovejero alem\u00e1n o un juguet\u00f3n mestizo, los perros son de las mascotas m\u00e1s populares. Pero quien quiera uno, tiene que pensarlo muy bien: dependiendo de la edad del animal, uno asume una responsabilidad por un ser vivo durante muchos a\u00f1os. Y, con ello, los costos. Esto es\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"mascotas\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-12-22T23:35:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-12-22T23:35:47+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"C\u00f3mo elegir y recibir en casa al primer perro - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(dpa) - Ya sea un peque\u00f1o chihuahua, un ovejero alem\u00e1n o un juguet\u00f3n mestizo, los perros son de las mascotas m\u00e1s populares. Pero quien quiera uno, tiene que pensarlo muy bien: dependiendo de la edad del animal, uno asume una responsabilidad por un ser vivo durante muchos a\u00f1os. Y, con ello, los costos. Esto es\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/como-elegir-y-recibir-en-casa-al-primer-perro\\\/#blogposting\",\"name\":\"C\\u00f3mo elegir y recibir en casa al primer perro - El Digital de Asturias\",\"headline\":\"C\\u00f3mo elegir y recibir en casa al primer perro\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1051804},\"datePublished\":\"2019-12-22T23:35:47+01:00\",\"dateModified\":\"2019-12-22T23:35:47+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/como-elegir-y-recibir-en-casa-al-primer-perro\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/como-elegir-y-recibir-en-casa-al-primer-perro\\\/#webpage\"},\"articleSection\":\"Mascotas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/como-elegir-y-recibir-en-casa-al-primer-perro\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/#listItem\",\"name\":\"Mascotas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/#listItem\",\"position\":2,\"name\":\"Mascotas\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/como-elegir-y-recibir-en-casa-al-primer-perro\\\/#listItem\",\"name\":\"C\\u00f3mo elegir y recibir en casa al primer perro\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/como-elegir-y-recibir-en-casa-al-primer-perro\\\/#listItem\",\"position\":3,\"name\":\"C\\u00f3mo elegir y recibir en casa al primer perro\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/mascotas\\\/#listItem\",\"name\":\"Mascotas\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/como-elegir-y-recibir-en-casa-al-primer-perro\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/como-elegir-y-recibir-en-casa-al-primer-perro\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/como-elegir-y-recibir-en-casa-al-primer-perro\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/como-elegir-y-recibir-en-casa-al-primer-perro\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/como-elegir-y-recibir-en-casa-al-primer-perro\\\/\",\"name\":\"C\\u00f3mo elegir y recibir en casa al primer perro - El Digital de Asturias\",\"description\":\"(dpa) - Ya sea un peque\\u00f1o chihuahua, un ovejero alem\\u00e1n o un juguet\\u00f3n mestizo, los perros son de las mascotas m\\u00e1s populares. Pero quien quiera uno, tiene que pensarlo muy bien: dependiendo de la edad del animal, uno asume una responsabilidad por un ser vivo durante muchos a\\u00f1os. Y, con ello, los costos. Esto es\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/como-elegir-y-recibir-en-casa-al-primer-perro\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1051804,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/como-elegir-y-recibir-en-casa-al-primer-perro\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/como-elegir-y-recibir-en-casa-al-primer-perro\\\/#mainImage\"},\"datePublished\":\"2019-12-22T23:35:47+01:00\",\"dateModified\":\"2019-12-22T23:35:47+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>C\u00f3mo elegir y recibir en casa al primer perro - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"C\u00f3mo elegir y recibir en casa al primer perro - El Digital de Asturias","description":"(dpa) - Ya sea un peque\u00f1o chihuahua, un ovejero alem\u00e1n o un juguet\u00f3n mestizo, los perros son de las mascotas m\u00e1s populares. Pero quien quiera uno, tiene que pensarlo muy bien: dependiendo de la edad del animal, uno asume una responsabilidad por un ser vivo durante muchos a\u00f1os. Y, con ello, los costos. Esto es","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/","robots":"max-image-preview:large","keywords":"mascotas","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/#blogposting","name":"C\u00f3mo elegir y recibir en casa al primer perro - El Digital de Asturias","headline":"C\u00f3mo elegir y recibir en casa al primer perro","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":1051804},"datePublished":"2019-12-22T23:35:47+01:00","dateModified":"2019-12-22T23:35:47+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/#webpage"},"articleSection":"Mascotas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/#listItem","name":"Mascotas"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/#listItem","position":2,"name":"Mascotas","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/#listItem","name":"C\u00f3mo elegir y recibir en casa al primer perro"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/#listItem","position":3,"name":"C\u00f3mo elegir y recibir en casa al primer perro","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/#listItem","name":"Mascotas"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/","name":"C\u00f3mo elegir y recibir en casa al primer perro - El Digital de Asturias","description":"(dpa) - Ya sea un peque\u00f1o chihuahua, un ovejero alem\u00e1n o un juguet\u00f3n mestizo, los perros son de las mascotas m\u00e1s populares. Pero quien quiera uno, tiene que pensarlo muy bien: dependiendo de la edad del animal, uno asume una responsabilidad por un ser vivo durante muchos a\u00f1os. Y, con ello, los costos. Esto es","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":1051804,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/#mainImage"},"datePublished":"2019-12-22T23:35:47+01:00","dateModified":"2019-12-22T23:35:47+01:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"C\u00f3mo elegir y recibir en casa al primer perro - El Digital de Asturias","og:description":"(dpa) - Ya sea un peque\u00f1o chihuahua, un ovejero alem\u00e1n o un juguet\u00f3n mestizo, los perros son de las mascotas m\u00e1s populares. Pero quien quiera uno, tiene que pensarlo muy bien: dependiendo de la edad del animal, uno asume una responsabilidad por un ser vivo durante muchos a\u00f1os. Y, con ello, los costos. Esto es","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/","article:tag":["mascotas"],"article:published_time":"2019-12-22T23:35:47+00:00","article:modified_time":"2019-12-22T23:35:47+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"C\u00f3mo elegir y recibir en casa al primer perro - El Digital de Asturias","twitter:description":"(dpa) - Ya sea un peque\u00f1o chihuahua, un ovejero alem\u00e1n o un juguet\u00f3n mestizo, los perros son de las mascotas m\u00e1s populares. Pero quien quiera uno, tiene que pensarlo muy bien: dependiendo de la edad del animal, uno asume una responsabilidad por un ser vivo durante muchos a\u00f1os. Y, con ello, los costos. Esto es","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"4 minutos"},"aioseo_meta_data":{"post_id":"1051803","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-10-30 07:06:07","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 10:57:29","updated":"2025-10-30 07:06:07"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/\" title=\"Mascotas\">Mascotas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/\" title=\"C\u00f3mo elegir y recibir en casa al primer perro\">C\u00f3mo elegir y recibir en casa al primer perro<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Mascotas","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/mascotas\/"},{"label":"C\u00f3mo elegir y recibir en casa al primer perro","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/como-elegir-y-recibir-en-casa-al-primer-perro\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1051803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=1051803"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1051803\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=1051803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=1051803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=1051803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}