{"id":1016202,"date":"2019-02-06T13:34:55","date_gmt":"2019-02-06T13:34:55","guid":{"rendered":"https:\/\/www.eldigitaldeasturias.com\/noticias\/?p=1016202"},"modified":"2019-02-06T13:35:46","modified_gmt":"2019-02-06T13:35:46","slug":"uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/","title":{"rendered":"USO reclama mayor regulaci\u00f3n en el proceso de subcontrataci\u00f3n"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1016203\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2019\/02\/contratacion-360x203.jpg\" alt=\"\" width=\"360\" height=\"203\" \/>La Uni\u00f3n Sindical Obrera (USO) exigi\u00f3 este mi\u00e9rcoles mediante un comunicado de prensa que se establezca una mayor regulaci\u00f3n de la subcontrataci\u00f3n para evitar que esto se utilice como atajo para mermar las condiciones laborales y salariales.<\/p>\n<p>El comunicado de prensa original expone lo siguiente:<\/p>\n<p>\u201cEl peso de la subcontrataci\u00f3n en la industria espa\u00f1ola creci\u00f3 en un 49% entre 2009 y 2015, a\u00f1o en que la estad\u00edstica proporcionada por el INE dej\u00f3 de ser expl\u00edcita sobre los \u201cgastos en trabajos realizados por otras empresas\u201d. Si seguimos la estad\u00edstica inversa, \u201cingresos por prestaciones de servicios para sector industrial\u201d, podemos comprobar que la subcontrataci\u00f3n sigue en aumento, al crecer en 2.000 millones de euros al cierre de 2017 frente a 2016; es decir, un 4,5%.<\/p>\n<p>Son algunos de los datos que se extraen del informe sobre los \u201cEfectos de la subcontrataci\u00f3n sobre los trabajadores de la industria espa\u00f1ola\u201d y que \u201cnos obligan a acometer un estudio detallado de las consecuencias que el fen\u00f3meno de la subcontrataci\u00f3n est\u00e1 teniendo en las condiciones de trabajo del sector industrial, tanto en salario como en jornada y prevenci\u00f3n de accidentes\u201d, explica Pedro Ayll\u00f3n, secretario general de la Federaci\u00f3n de Industria de USO.<\/p>\n<p>\u201cLa subcontrataci\u00f3n no se emplea en Espa\u00f1a para alguno de sus fines originarios, como encargar ciertas tareas muy espec\u00edficas a otras empresas especializadas, sino para reducir costes. Por eso, la presi\u00f3n que ejerce la empresa contratista para aumentar el margen de beneficio obliga a la empresa contratada a rebajar masa salarial, a aumentar y flexibilizar jornada o a ahorrar en prevenci\u00f3n de riesgos laborales\u201d, expone Ayll\u00f3n. \u201cY es m\u00e1s, por efecto rebote, tambi\u00e9n va socavando los derechos laborales de los trabajadores de la empresa principal ante la amenaza de seguir externalizando carga de trabajo por un coste menor al que ellos suponen. Una amenaza a la que ambas plantillas, principal y subcontratada, se enfrentan cada vez m\u00e1s debilitadas sindicalmente por reducir mediante este troceado el peso de los comit\u00e9s de empresa\u201d, contin\u00faa.<\/p>\n<p>Como medida para limitar los efectos adversos de la subcontrataci\u00f3n, a falta de una mayor concreci\u00f3n legislativa, el secretario de Acci\u00f3n Sindical y Salud Laboral de FI-USO, Ra\u00fal Montoya, propone \u201ctenerlo siempre presente en la negociaci\u00f3n colectiva. Los convenios colectivos de empresa o sectoriales deben incluir en su articulado referencias expresas a la informaci\u00f3n a los representantes legales de los trabajadores de la empresa principal sobre la actividad contratista, blindar la subrogaci\u00f3n de los trabajadores para que no est\u00e9n sometidos al cambio de empresa subcontratada y garantizar las condiciones de convenio tambi\u00e9n para los trabajadores de estas empresas\u201d.<\/p>\n<p>En el estudio, \u201chemos cribado los convenios del metal por provincias y hemos observado que son muy pocos los que hacen alg\u00fan tipo de referencia a la subcontrataci\u00f3n. Por poner un ejemplo, solo 14 de los 51 existentes contemplan el derecho de informaci\u00f3n referente a la subcontrataci\u00f3n\u201d, analiza Luis Matesanz, asesor de FI-USO.<\/p>\n<p>La siniestralidad laboral es otro de los aspectos potenciados por la subcontrataci\u00f3n: \u201cpor diversas causas, tanto porque realizan trabajos m\u00e1s penosos como por una menor inversi\u00f3n de la empresa auxiliar, la Encuesta Nacional de las Condiciones de Trabajo demuestra que los trabajadores subcontratados sufrieron una siniestralidad un 7% superior a los de la empresa principal en cuanto a accidentes de trabajo con asistencia m\u00e9dica o tratamiento\u201d, observa Matesanz.<\/p>\n<p>El caso de las contratas de la miner\u00eda del carb\u00f3n<\/p>\n<p>En cuanto al estudio concreto de un sector, el de la miner\u00eda del carb\u00f3n, \u201cel papel de la subcontrataci\u00f3n ha tenido unos efectos devastadores para los trabajadores que pertenecen a estas empresas subsidiarias y no a las principales, a pesar de que en algunos casos cuentan con la explotaci\u00f3n directa de la unidad de producci\u00f3n. Estos trabajadores, cumpliendo con las mismas condiciones que los mineros de empresas principales, se han quedado desamparados por el nuevo Plan del Carb\u00f3n, a pesar de que desde FI-USO exigimos su inclusi\u00f3n hasta el \u00faltimo d\u00eda de negociaci\u00f3n. Esto no habr\u00eda ocurrido si el Gobierno hubiera cumplido con la que era su demanda de modificar el art\u00edculo 42.1 del Estatuto de los Trabajadores, cuya tramitaci\u00f3n comenz\u00f3 desde la oposici\u00f3n y olvid\u00f3 al llegar al poder. Ese art\u00edculo deber\u00eda garantizar la igualdad para todos los trabajadores ante las mismas condiciones\u201d, concluye el comunicado de prensa de USO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Uni\u00f3n Sindical Obrera (USO) exigi\u00f3 este mi\u00e9rcoles mediante un comunicado de prensa que se establezca una mayor regulaci\u00f3n de la subcontrataci\u00f3n para evitar que esto se utilice como atajo para mermar las condiciones laborales y salariales. El comunicado de prensa original expone lo siguiente: \u201cEl peso de la subcontrataci\u00f3n en la industria espa\u00f1ola creci\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1016203,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[187],"tags":[],"class_list":["post-1016202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Uni\u00f3n Sindical Obrera (USO) exigi\u00f3 este mi\u00e9rcoles mediante un comunicado de prensa que se establezca una mayor regulaci\u00f3n de la subcontrataci\u00f3n para evitar que esto se utilice como atajo para mermar las condiciones laborales y salariales. El comunicado de prensa original expone lo siguiente: \u201cEl peso de la subcontrataci\u00f3n en la industria espa\u00f1ola creci\u00f3\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"econom\u00eda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"USO reclama mayor regulaci\u00f3n en el proceso de subcontrataci\u00f3n - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"La Uni\u00f3n Sindical Obrera (USO) exigi\u00f3 este mi\u00e9rcoles mediante un comunicado de prensa que se establezca una mayor regulaci\u00f3n de la subcontrataci\u00f3n para evitar que esto se utilice como atajo para mermar las condiciones laborales y salariales. El comunicado de prensa original expone lo siguiente: \u201cEl peso de la subcontrataci\u00f3n en la industria espa\u00f1ola creci\u00f3\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"econom\u00eda\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-02-06T13:34:55+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-02-06T13:35:46+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"USO reclama mayor regulaci\u00f3n en el proceso de subcontrataci\u00f3n - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Uni\u00f3n Sindical Obrera (USO) exigi\u00f3 este mi\u00e9rcoles mediante un comunicado de prensa que se establezca una mayor regulaci\u00f3n de la subcontrataci\u00f3n para evitar que esto se utilice como atajo para mermar las condiciones laborales y salariales. El comunicado de prensa original expone lo siguiente: \u201cEl peso de la subcontrataci\u00f3n en la industria espa\u00f1ola creci\u00f3\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\\\/#blogposting\",\"name\":\"USO reclama mayor regulaci\\u00f3n en el proceso de subcontrataci\\u00f3n - El Digital de Asturias\",\"headline\":\"USO reclama mayor regulaci\\u00f3n en el proceso de subcontrataci\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1016203},\"datePublished\":\"2019-02-06T13:34:55+01:00\",\"dateModified\":\"2019-02-06T13:35:46+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\\\/#webpage\"},\"articleSection\":\"Econom\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"name\":\"Econom\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"position\":2,\"name\":\"Econom\\u00eda\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\\\/#listItem\",\"name\":\"USO reclama mayor regulaci\\u00f3n en el proceso de subcontrataci\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\\\/#listItem\",\"position\":3,\"name\":\"USO reclama mayor regulaci\\u00f3n en el proceso de subcontrataci\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"name\":\"Econom\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\\\/\",\"name\":\"USO reclama mayor regulaci\\u00f3n en el proceso de subcontrataci\\u00f3n - El Digital de Asturias\",\"description\":\"La Uni\\u00f3n Sindical Obrera (USO) exigi\\u00f3 este mi\\u00e9rcoles mediante un comunicado de prensa que se establezca una mayor regulaci\\u00f3n de la subcontrataci\\u00f3n para evitar que esto se utilice como atajo para mermar las condiciones laborales y salariales. El comunicado de prensa original expone lo siguiente: \\u201cEl peso de la subcontrataci\\u00f3n en la industria espa\\u00f1ola creci\\u00f3\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1016203,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\\\/#mainImage\"},\"datePublished\":\"2019-02-06T13:34:55+01:00\",\"dateModified\":\"2019-02-06T13:35:46+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>USO reclama mayor regulaci\u00f3n en el proceso de subcontrataci\u00f3n - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"USO reclama mayor regulaci\u00f3n en el proceso de subcontrataci\u00f3n - El Digital de Asturias","description":"La Uni\u00f3n Sindical Obrera (USO) exigi\u00f3 este mi\u00e9rcoles mediante un comunicado de prensa que se establezca una mayor regulaci\u00f3n de la subcontrataci\u00f3n para evitar que esto se utilice como atajo para mermar las condiciones laborales y salariales. El comunicado de prensa original expone lo siguiente: \u201cEl peso de la subcontrataci\u00f3n en la industria espa\u00f1ola creci\u00f3","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/","robots":"max-image-preview:large","keywords":"econom\u00eda","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/#blogposting","name":"USO reclama mayor regulaci\u00f3n en el proceso de subcontrataci\u00f3n - El Digital de Asturias","headline":"USO reclama mayor regulaci\u00f3n en el proceso de subcontrataci\u00f3n","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":1016203},"datePublished":"2019-02-06T13:34:55+01:00","dateModified":"2019-02-06T13:35:46+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/#webpage"},"articleSection":"Econom\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","name":"Econom\u00eda"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","position":2,"name":"Econom\u00eda","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/#listItem","name":"USO reclama mayor regulaci\u00f3n en el proceso de subcontrataci\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/#listItem","position":3,"name":"USO reclama mayor regulaci\u00f3n en el proceso de subcontrataci\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","name":"Econom\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/","name":"USO reclama mayor regulaci\u00f3n en el proceso de subcontrataci\u00f3n - El Digital de Asturias","description":"La Uni\u00f3n Sindical Obrera (USO) exigi\u00f3 este mi\u00e9rcoles mediante un comunicado de prensa que se establezca una mayor regulaci\u00f3n de la subcontrataci\u00f3n para evitar que esto se utilice como atajo para mermar las condiciones laborales y salariales. El comunicado de prensa original expone lo siguiente: \u201cEl peso de la subcontrataci\u00f3n en la industria espa\u00f1ola creci\u00f3","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":1016203,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/#mainImage"},"datePublished":"2019-02-06T13:34:55+01:00","dateModified":"2019-02-06T13:35:46+01:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"USO reclama mayor regulaci\u00f3n en el proceso de subcontrataci\u00f3n - El Digital de Asturias","og:description":"La Uni\u00f3n Sindical Obrera (USO) exigi\u00f3 este mi\u00e9rcoles mediante un comunicado de prensa que se establezca una mayor regulaci\u00f3n de la subcontrataci\u00f3n para evitar que esto se utilice como atajo para mermar las condiciones laborales y salariales. El comunicado de prensa original expone lo siguiente: \u201cEl peso de la subcontrataci\u00f3n en la industria espa\u00f1ola creci\u00f3","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/","article:tag":["econom\u00eda"],"article:published_time":"2019-02-06T13:34:55+00:00","article:modified_time":"2019-02-06T13:35:46+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"USO reclama mayor regulaci\u00f3n en el proceso de subcontrataci\u00f3n - El Digital de Asturias","twitter:description":"La Uni\u00f3n Sindical Obrera (USO) exigi\u00f3 este mi\u00e9rcoles mediante un comunicado de prensa que se establezca una mayor regulaci\u00f3n de la subcontrataci\u00f3n para evitar que esto se utilice como atajo para mermar las condiciones laborales y salariales. El comunicado de prensa original expone lo siguiente: \u201cEl peso de la subcontrataci\u00f3n en la industria espa\u00f1ola creci\u00f3","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"4 minutos"},"aioseo_meta_data":{"post_id":"1016202","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-10-16 01:14:13","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 11:21:15","updated":"2025-10-16 01:14:13"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/\" title=\"Econom\u00eda\">Econom\u00eda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/\" title=\"USO reclama mayor regulaci\u00f3n en el proceso de subcontrataci\u00f3n\">USO reclama mayor regulaci\u00f3n en el proceso de subcontrataci\u00f3n<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Econom\u00eda","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/"},{"label":"USO reclama mayor regulaci\u00f3n en el proceso de subcontrataci\u00f3n","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/uso-reclama-mayor-regulacion-en-el-proceso-de-subcontratacion\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1016202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=1016202"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1016202\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=1016202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=1016202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=1016202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}