{"id":1015717,"date":"2019-02-01T20:01:04","date_gmt":"2019-02-01T20:01:04","guid":{"rendered":"https:\/\/www.eldigitaldeasturias.com\/noticias\/?p=1015717"},"modified":"2019-02-01T20:01:04","modified_gmt":"2019-02-01T20:01:04","slug":"la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/","title":{"rendered":"La tasa de inflaci\u00f3n de la zona euro se modera al 1,4% en enero"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1011340\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2018\/12\/1531812134890billetes_euros1_estandardn-360x212.jpg\" alt=\"\" width=\"360\" height=\"212\" \/>LUXEMBURGO, 1 Feb. 2019 (Europa Press) &#8211;\u00a0La tasa de inflaci\u00f3n interanual de la eurozona se situ\u00f3 en enero en el 1,4%, lo que supone una subida de los precios dos d\u00e9cimas menor que el mes anterior y la m\u00e1s d\u00e9bil desde abril de 2018, seg\u00fan la estimaci\u00f3n preliminar del dato publicada por la oficina europea de estad\u00edstica, Eurostat.<\/p>\n<p>En el caso de Espa\u00f1a, el \u00cdndice de Precios de Consumo Armonizado (IPCA) situ\u00f3 su tasa interanual en el 1% en enero, lo que implica un diferencial de precios de cuatro d\u00e9cimas favorable a la econom\u00eda espa\u00f1ola.<\/p>\n<p>En el primer mes de 2019, el precio de la energ\u00eda registr\u00f3 una subida interanual del 2,6% en la zona euro, mientras que los alimentos frescos se encarecieron un 1,7% y los servicios un 1,6%.<\/p>\n<p>Sin tener en cuenta el impacto de la energ\u00eda, la tasa de inflaci\u00f3n de la zona euro se situ\u00f3 en enero en el 1,2% interanual, mientras que al excluir del \u00edndice la energ\u00eda, los alimentos frescos y el tabaco, la inflaci\u00f3n subyacente fue del 1,1%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LUXEMBURGO, 1 Feb. 2019 (Europa Press) &#8211;\u00a0La tasa de inflaci\u00f3n interanual de la eurozona se situ\u00f3 en enero en el 1,4%, lo que supone una subida de los precios dos d\u00e9cimas menor que el mes anterior y la m\u00e1s d\u00e9bil desde abril de 2018, seg\u00fan la estimaci\u00f3n preliminar del dato publicada por la oficina europea [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1011836,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[187],"tags":[],"class_list":["post-1015717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"LUXEMBURGO, 1 Feb. 2019 (Europa Press) - La tasa de inflaci\u00f3n interanual de la eurozona se situ\u00f3 en enero en el 1,4%, lo que supone una subida de los precios dos d\u00e9cimas menor que el mes anterior y la m\u00e1s d\u00e9bil desde abril de 2018, seg\u00fan la estimaci\u00f3n preliminar del dato publicada por la oficina europea\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"econom\u00eda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La tasa de inflaci\u00f3n de la zona euro se modera al 1,4% en enero - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"LUXEMBURGO, 1 Feb. 2019 (Europa Press) - La tasa de inflaci\u00f3n interanual de la eurozona se situ\u00f3 en enero en el 1,4%, lo que supone una subida de los precios dos d\u00e9cimas menor que el mes anterior y la m\u00e1s d\u00e9bil desde abril de 2018, seg\u00fan la estimaci\u00f3n preliminar del dato publicada por la oficina europea\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"econom\u00eda\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-02-01T20:01:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-02-01T20:01:04+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La tasa de inflaci\u00f3n de la zona euro se modera al 1,4% en enero - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"LUXEMBURGO, 1 Feb. 2019 (Europa Press) - La tasa de inflaci\u00f3n interanual de la eurozona se situ\u00f3 en enero en el 1,4%, lo que supone una subida de los precios dos d\u00e9cimas menor que el mes anterior y la m\u00e1s d\u00e9bil desde abril de 2018, seg\u00fan la estimaci\u00f3n preliminar del dato publicada por la oficina europea\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\\\/#blogposting\",\"name\":\"La tasa de inflaci\\u00f3n de la zona euro se modera al 1,4% en enero - El Digital de Asturias\",\"headline\":\"La tasa de inflaci\\u00f3n de la zona euro se modera al 1,4% en enero\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1011836},\"datePublished\":\"2019-02-01T20:01:04+01:00\",\"dateModified\":\"2019-02-01T20:01:04+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\\\/#webpage\"},\"articleSection\":\"Econom\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"name\":\"Econom\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"position\":2,\"name\":\"Econom\\u00eda\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\\\/#listItem\",\"name\":\"La tasa de inflaci\\u00f3n de la zona euro se modera al 1,4% en enero\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\\\/#listItem\",\"position\":3,\"name\":\"La tasa de inflaci\\u00f3n de la zona euro se modera al 1,4% en enero\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"name\":\"Econom\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\\\/\",\"name\":\"La tasa de inflaci\\u00f3n de la zona euro se modera al 1,4% en enero - El Digital de Asturias\",\"description\":\"LUXEMBURGO, 1 Feb. 2019 (Europa Press) - La tasa de inflaci\\u00f3n interanual de la eurozona se situ\\u00f3 en enero en el 1,4%, lo que supone una subida de los precios dos d\\u00e9cimas menor que el mes anterior y la m\\u00e1s d\\u00e9bil desde abril de 2018, seg\\u00fan la estimaci\\u00f3n preliminar del dato publicada por la oficina europea\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1011836,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\\\/#mainImage\"},\"datePublished\":\"2019-02-01T20:01:04+01:00\",\"dateModified\":\"2019-02-01T20:01:04+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La tasa de inflaci\u00f3n de la zona euro se modera al 1,4% en enero - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"La tasa de inflaci\u00f3n de la zona euro se modera al 1,4% en enero - El Digital de Asturias","description":"LUXEMBURGO, 1 Feb. 2019 (Europa Press) - La tasa de inflaci\u00f3n interanual de la eurozona se situ\u00f3 en enero en el 1,4%, lo que supone una subida de los precios dos d\u00e9cimas menor que el mes anterior y la m\u00e1s d\u00e9bil desde abril de 2018, seg\u00fan la estimaci\u00f3n preliminar del dato publicada por la oficina europea","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/","robots":"max-image-preview:large","keywords":"econom\u00eda","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/#blogposting","name":"La tasa de inflaci\u00f3n de la zona euro se modera al 1,4% en enero - El Digital de Asturias","headline":"La tasa de inflaci\u00f3n de la zona euro se modera al 1,4% en enero","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":1011836},"datePublished":"2019-02-01T20:01:04+01:00","dateModified":"2019-02-01T20:01:04+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/#webpage"},"articleSection":"Econom\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","name":"Econom\u00eda"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","position":2,"name":"Econom\u00eda","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/#listItem","name":"La tasa de inflaci\u00f3n de la zona euro se modera al 1,4% en enero"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/#listItem","position":3,"name":"La tasa de inflaci\u00f3n de la zona euro se modera al 1,4% en enero","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","name":"Econom\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/","name":"La tasa de inflaci\u00f3n de la zona euro se modera al 1,4% en enero - El Digital de Asturias","description":"LUXEMBURGO, 1 Feb. 2019 (Europa Press) - La tasa de inflaci\u00f3n interanual de la eurozona se situ\u00f3 en enero en el 1,4%, lo que supone una subida de los precios dos d\u00e9cimas menor que el mes anterior y la m\u00e1s d\u00e9bil desde abril de 2018, seg\u00fan la estimaci\u00f3n preliminar del dato publicada por la oficina europea","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":1011836,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/#mainImage"},"datePublished":"2019-02-01T20:01:04+01:00","dateModified":"2019-02-01T20:01:04+01:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"La tasa de inflaci\u00f3n de la zona euro se modera al 1,4% en enero - El Digital de Asturias","og:description":"LUXEMBURGO, 1 Feb. 2019 (Europa Press) - La tasa de inflaci\u00f3n interanual de la eurozona se situ\u00f3 en enero en el 1,4%, lo que supone una subida de los precios dos d\u00e9cimas menor que el mes anterior y la m\u00e1s d\u00e9bil desde abril de 2018, seg\u00fan la estimaci\u00f3n preliminar del dato publicada por la oficina europea","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/","article:tag":["econom\u00eda"],"article:published_time":"2019-02-01T20:01:04+00:00","article:modified_time":"2019-02-01T20:01:04+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"La tasa de inflaci\u00f3n de la zona euro se modera al 1,4% en enero - El Digital de Asturias","twitter:description":"LUXEMBURGO, 1 Feb. 2019 (Europa Press) - La tasa de inflaci\u00f3n interanual de la eurozona se situ\u00f3 en enero en el 1,4%, lo que supone una subida de los precios dos d\u00e9cimas menor que el mes anterior y la m\u00e1s d\u00e9bil desde abril de 2018, seg\u00fan la estimaci\u00f3n preliminar del dato publicada por la oficina europea","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"1015717","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-10-15 22:38:16","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 11:21:25","updated":"2025-10-15 22:38:16"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/\" title=\"Econom\u00eda\">Econom\u00eda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/\" title=\"La tasa de inflaci\u00f3n de la zona euro se modera al 1,4% en enero\">La tasa de inflaci\u00f3n de la zona euro se modera al 1,4% en enero<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Econom\u00eda","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/"},{"label":"La tasa de inflaci\u00f3n de la zona euro se modera al 1,4% en enero","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/la-tasa-de-inflacion-de-la-zona-euro-se-modera-al-14-en-enero\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1015717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=1015717"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1015717\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=1015717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=1015717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=1015717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}