{"id":1014309,"date":"2019-01-18T21:17:11","date_gmt":"2019-01-18T21:17:11","guid":{"rendered":"https:\/\/www.eldigitaldeasturias.com\/noticias\/?p=1014309"},"modified":"2019-01-18T21:17:11","modified_gmt":"2019-01-18T21:17:11","slug":"peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom","status":"publish","type":"post","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/","title":{"rendered":"Peter Altmaier alerta del posible fracaso de la fusi\u00f3n Siemens-Alstom"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1014310\" src=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2019\/01\/trenes-empresas-360x238.jpg\" alt=\"\" width=\"360\" height=\"238\" \/>Berl\u00edn, 18 ene (dpa) &#8211; El ministro alem\u00e1n de Econom\u00eda, Peter Altmaier, alert\u00f3 del peligro del fracaso de la proyectada fusi\u00f3n de la divisi\u00f3n de producci\u00f3n de trenes de la firma alemana Siemens con la francesa Alstom.<\/p>\n<p>\u00abNo puedo inmiscuirme en un procedimiento en curso. Pero si Europa quiere salir airosa en la competencia internacional, necesita campeones europeos que puedan estar a la altura para competir con empresas de Estados Unidos o de China y que puedan ganar las licitaciones\u00bb, se\u00f1al\u00f3 en declaraciones a dpa.<\/p>\n<p>El pol\u00edtico democristiano dijo que est\u00e1n en juego el acceso a mercados en terceros pa\u00edses y encargos de 30.000 millones de euros o m\u00e1s (34.000 millones de d\u00f3lares). \u00abUna empresa tiene que tener para ello una cierta dimensi\u00f3n que le permita competir tambi\u00e9n en este segmento del mercado\u00bb, aleg\u00f3.<\/p>\n<p>La Comisi\u00f3n Europea se ha manifestado sumamente cr\u00edtica hacia los planes de fusi\u00f3n. Las autoridades comunitarias temen que la alianza entre los fabricantes del tren franc\u00e9s de alta velocidad TGV y el tren superr\u00e1pido alem\u00e1n ICE distorsione el mercado com\u00fan europeo.<\/p>\n<p>La Comisi\u00f3n demanda a los dos gigantes tecnol\u00f3gicos que se desprendan de ciertas \u00e1reas de negocio en favor de otros competidores, pero ambos grupos se han negado a ceder m\u00e1s a los reclamos de Bruselas. Las compa\u00f1\u00edas aspiran a unir fuerzas para hacer frente especialmente a la competencia de la china CRRC, la mayor firma ferroviaria del mundo.<\/p>\n<p><em>Foto: Marijan Murat\/dpa<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berl\u00edn, 18 ene (dpa) &#8211; El ministro alem\u00e1n de Econom\u00eda, Peter Altmaier, alert\u00f3 del peligro del fracaso de la proyectada fusi\u00f3n de la divisi\u00f3n de producci\u00f3n de trenes de la firma alemana Siemens con la francesa Alstom. \u00abNo puedo inmiscuirme en un procedimiento en curso. Pero si Europa quiere salir airosa en la competencia internacional, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1014310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[187],"tags":[],"class_list":["post-1014309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Berl\u00edn, 18 ene (dpa) - El ministro alem\u00e1n de Econom\u00eda, Peter Altmaier, alert\u00f3 del peligro del fracaso de la proyectada fusi\u00f3n de la divisi\u00f3n de producci\u00f3n de trenes de la firma alemana Siemens con la francesa Alstom. &quot;No puedo inmiscuirme en un procedimiento en curso. Pero si Europa quiere salir airosa en la competencia internacional,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"El Digital de Asturias\"\/>\n\t<meta name=\"google-site-verification\" content=\"UA-38556648-1\" \/>\n\t<meta name=\"msvalidate.01\" content=\"7dfe9f3f1b24437ab69f4f2559babe99\" \/>\n\t<meta name=\"keywords\" content=\"econom\u00eda\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Digital de Asturias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Peter Altmaier alerta del posible fracaso de la fusi\u00f3n Siemens-Alstom - El Digital de Asturias\" \/>\n\t\t<meta property=\"og:description\" content=\"Berl\u00edn, 18 ene (dpa) - El ministro alem\u00e1n de Econom\u00eda, Peter Altmaier, alert\u00f3 del peligro del fracaso de la proyectada fusi\u00f3n de la divisi\u00f3n de producci\u00f3n de trenes de la firma alemana Siemens con la francesa Alstom. &quot;No puedo inmiscuirme en un procedimiento en curso. Pero si Europa quiere salir airosa en la competencia internacional,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/\" \/>\n\t\t<meta property=\"article:tag\" content=\"econom\u00eda\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-01-18T21:17:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-01-18T21:17:11+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/eldigitaldeasturias\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Peter Altmaier alerta del posible fracaso de la fusi\u00f3n Siemens-Alstom - El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Berl\u00edn, 18 ene (dpa) - El ministro alem\u00e1n de Econom\u00eda, Peter Altmaier, alert\u00f3 del peligro del fracaso de la proyectada fusi\u00f3n de la divisi\u00f3n de producci\u00f3n de trenes de la firma alemana Siemens con la francesa Alstom. &quot;No puedo inmiscuirme en un procedimiento en curso. Pero si Europa quiere salir airosa en la competencia internacional,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"El Digital de Asturias\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\\\/#blogposting\",\"name\":\"Peter Altmaier alerta del posible fracaso de la fusi\\u00f3n Siemens-Alstom - El Digital de Asturias\",\"headline\":\"Peter Altmaier alerta del posible fracaso de la fusi\\u00f3n Siemens-Alstom\",\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1014310},\"datePublished\":\"2019-01-18T21:17:11+01:00\",\"dateModified\":\"2019-01-18T21:17:11+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\\\/#webpage\"},\"articleSection\":\"Econom\\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"name\":\"Econom\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"position\":2,\"name\":\"Econom\\u00eda\",\"item\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\\\/#listItem\",\"name\":\"Peter Altmaier alerta del posible fracaso de la fusi\\u00f3n Siemens-Alstom\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\\\/#listItem\",\"position\":3,\"name\":\"Peter Altmaier alerta del posible fracaso de la fusi\\u00f3n Siemens-Alstom\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/category\\\/economia\\\/#listItem\",\"name\":\"Econom\\u00eda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\",\"name\":\"El Digital de Asturias\",\"description\":\"Hemeroteca\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"email\":\"info@eldigitaldeasturias.com\",\"telephone\":\"+34652131393\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/EDA.jpg\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/eldigitaldeasturias\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZP-2wLEB9Rv6erhFmqVnvg\"],\"address\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"san antonio 4\",\"postalCode\":\"33430\",\"addressLocality\":\"Cand\\u00e1s\",\"addressRegion\":\"Asturias\",\"addressCountry\":\"ES\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/\",\"name\":\"El Digital de Asturias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"El Digital de Asturias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\\\/#webpage\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\\\/\",\"name\":\"Peter Altmaier alerta del posible fracaso de la fusi\\u00f3n Siemens-Alstom - El Digital de Asturias\",\"description\":\"Berl\\u00edn, 18 ene (dpa) - El ministro alem\\u00e1n de Econom\\u00eda, Peter Altmaier, alert\\u00f3 del peligro del fracaso de la proyectada fusi\\u00f3n de la divisi\\u00f3n de producci\\u00f3n de trenes de la firma alemana Siemens con la francesa Alstom. \\\"No puedo inmiscuirme en un procedimiento en curso. Pero si Europa quiere salir airosa en la competencia internacional,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":1014310,\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\\\/#mainImage\"},\"datePublished\":\"2019-01-18T21:17:11+01:00\",\"dateModified\":\"2019-01-18T21:17:11+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/\",\"name\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"alternateName\":\"El Digital de Asturias - Diario de actualidad y noticias\",\"description\":\"Hemeroteca\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eldigitaldeasturias.com\\\/noticias\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Peter Altmaier alerta del posible fracaso de la fusi\u00f3n Siemens-Alstom - El Digital de Asturias<\/title>\n\n","aioseo_head_json":{"title":"Peter Altmaier alerta del posible fracaso de la fusi\u00f3n Siemens-Alstom - El Digital de Asturias","description":"Berl\u00edn, 18 ene (dpa) - El ministro alem\u00e1n de Econom\u00eda, Peter Altmaier, alert\u00f3 del peligro del fracaso de la proyectada fusi\u00f3n de la divisi\u00f3n de producci\u00f3n de trenes de la firma alemana Siemens con la francesa Alstom. \"No puedo inmiscuirme en un procedimiento en curso. Pero si Europa quiere salir airosa en la competencia internacional,","canonical_url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/","robots":"max-image-preview:large","keywords":"econom\u00eda","webmasterTools":{"google-site-verification":"UA-38556648-1","msvalidate.01":"7dfe9f3f1b24437ab69f4f2559babe99","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/#blogposting","name":"Peter Altmaier alerta del posible fracaso de la fusi\u00f3n Siemens-Alstom - El Digital de Asturias","headline":"Peter Altmaier alerta del posible fracaso de la fusi\u00f3n Siemens-Alstom","author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"},"image":{"@type":"ImageObject","url":1014310},"datePublished":"2019-01-18T21:17:11+01:00","dateModified":"2019-01-18T21:17:11+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/#webpage"},"isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/#webpage"},"articleSection":"Econom\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","position":1,"name":"Home","item":"https:\/\/www.eldigitaldeasturias.com\/noticias","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","name":"Econom\u00eda"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","position":2,"name":"Econom\u00eda","item":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/#listItem","name":"Peter Altmaier alerta del posible fracaso de la fusi\u00f3n Siemens-Alstom"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/#listItem","position":3,"name":"Peter Altmaier alerta del posible fracaso de la fusi\u00f3n Siemens-Alstom","previousItem":{"@type":"ListItem","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/#listItem","name":"Econom\u00eda"}}]},{"@type":"Organization","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization","name":"El Digital de Asturias","description":"Hemeroteca","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","email":"info@eldigitaldeasturias.com","telephone":"+34652131393","logo":{"@type":"ImageObject","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA.jpg","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/#organizationLogo"},"image":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/eldigitaldeasturias","https:\/\/www.youtube.com\/channel\/UCZP-2wLEB9Rv6erhFmqVnvg"],"address":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#postaladdress","@type":"PostalAddress","streetAddress":"san antonio 4","postalCode":"33430","addressLocality":"Cand\u00e1s","addressRegion":"Asturias","addressCountry":"ES"}},{"@type":"Person","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/","name":"El Digital de Asturias","image":{"@type":"ImageObject","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df2aeffc32bcd13f8d26072ef8a91b623d677766deac7f97ca815868cd41bf5e?s=96&d=mm&r=g","width":96,"height":96,"caption":"El Digital de Asturias"}},{"@type":"WebPage","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/#webpage","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/","name":"Peter Altmaier alerta del posible fracaso de la fusi\u00f3n Siemens-Alstom - El Digital de Asturias","description":"Berl\u00edn, 18 ene (dpa) - El ministro alem\u00e1n de Econom\u00eda, Peter Altmaier, alert\u00f3 del peligro del fracaso de la proyectada fusi\u00f3n de la divisi\u00f3n de producci\u00f3n de trenes de la firma alemana Siemens con la francesa Alstom. \"No puedo inmiscuirme en un procedimiento en curso. Pero si Europa quiere salir airosa en la competencia internacional,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/#breadcrumblist"},"author":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":1014310,"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/#mainImage"},"datePublished":"2019-01-18T21:17:11+01:00","dateModified":"2019-01-18T21:17:11+01:00"},{"@type":"WebSite","@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#website","url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/","name":"El Digital de Asturias - Diario de actualidad y noticias","alternateName":"El Digital de Asturias - Diario de actualidad y noticias","description":"Hemeroteca","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.eldigitaldeasturias.com\/noticias\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Digital de Asturias","og:type":"article","og:title":"Peter Altmaier alerta del posible fracaso de la fusi\u00f3n Siemens-Alstom - El Digital de Asturias","og:description":"Berl\u00edn, 18 ene (dpa) - El ministro alem\u00e1n de Econom\u00eda, Peter Altmaier, alert\u00f3 del peligro del fracaso de la proyectada fusi\u00f3n de la divisi\u00f3n de producci\u00f3n de trenes de la firma alemana Siemens con la francesa Alstom. &quot;No puedo inmiscuirme en un procedimiento en curso. Pero si Europa quiere salir airosa en la competencia internacional,","og:url":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/","article:tag":["econom\u00eda"],"article:published_time":"2019-01-18T21:17:11+00:00","article:modified_time":"2019-01-18T21:17:11+00:00","article:publisher":"https:\/\/facebook.com\/eldigitaldeasturias","twitter:card":"summary_large_image","twitter:title":"Peter Altmaier alerta del posible fracaso de la fusi\u00f3n Siemens-Alstom - El Digital de Asturias","twitter:description":"Berl\u00edn, 18 ene (dpa) - El ministro alem\u00e1n de Econom\u00eda, Peter Altmaier, alert\u00f3 del peligro del fracaso de la proyectada fusi\u00f3n de la divisi\u00f3n de producci\u00f3n de trenes de la firma alemana Siemens con la francesa Alstom. &quot;No puedo inmiscuirme en un procedimiento en curso. Pero si Europa quiere salir airosa en la competencia internacional,","twitter:image":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-content\/uploads\/2020\/12\/EDA-1.jpg","twitter:label1":"Escrito por","twitter:data1":"El Digital de Asturias","twitter:label2":"Tiempo de lectura estimado","twitter:data2":"1 minuto"},"aioseo_meta_data":{"post_id":"1014309","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2025-10-15 15:39:11","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 11:21:59","updated":"2025-10-15 15:39:11"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/\" title=\"Econom\u00eda\">Econom\u00eda<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u2013<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/\" title=\"Peter Altmaier alerta del posible fracaso de la fusi\u00f3n Siemens-Alstom\">Peter Altmaier alerta del posible fracaso de la fusi\u00f3n Siemens-Alstom<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.eldigitaldeasturias.com\/noticias"},{"label":"Econom\u00eda","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/category\/economia\/"},{"label":"Peter Altmaier alerta del posible fracaso de la fusi\u00f3n Siemens-Alstom","link":"https:\/\/www.eldigitaldeasturias.com\/noticias\/peter-altmaier-alerta-del-posible-fracaso-de-la-fusion-siemens-alstom\/"}],"_links":{"self":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1014309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/comments?post=1014309"}],"version-history":[{"count":0,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/posts\/1014309\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/media?parent=1014309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/categories?post=1014309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eldigitaldeasturias.com\/noticias\/wp-json\/wp\/v2\/tags?post=1014309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}